{"id":5291,"date":"2020-03-27T06:23:26","date_gmt":"2020-03-27T06:23:26","guid":{"rendered":"https:\/\/www.dumpsbase.com\/freedumps\/?p=5291"},"modified":"2025-09-22T06:41:31","modified_gmt":"2025-09-22T06:41:31","slug":"updated-cisa-certified-information-systems-auditor-certification-dumps","status":"publish","type":"post","link":"https:\/\/www.dumpsbase.com\/freedumps\/updated-cisa-certified-information-systems-auditor-certification-dumps.html","title":{"rendered":"Updated CISA Certified Information Systems Auditor  Certification Dumps"},"content":{"rendered":"<p>Certified Information Systems Auditor CISA issued by ISACA validate your expertise and get the leverage you need to move up in your career. CISA is world-renowned as the standard of achievement for those who audit, control, monitor and assess an organization\u2019s information technology and business systems. To improve your preparation of ISACA CISA exam, we have updated CISA dumps questions to ensure that you can pass CISA certification exam.<\/p>\n<h2>It is great to test <span style=\"color: #ff0000;\">CISA free dumps<\/span> online first.<\/h2>\n<script>\n  window.fbAsyncInit = function() {\n    FB.init({\n      appId            : '622169541470367',\n      autoLogAppEvents : true,\n      xfbml            : true,\n      version          : 'v3.1'\n    });\n  };\n\n  (function(d, s, id){\n     var js, fjs = d.getElementsByTagName(s)[0];\n     if (d.getElementById(id)) {return;}\n     js = d.createElement(s); js.id = id;\n     js.src = \"https:\/\/connect.facebook.net\/en_US\/sdk.js\";\n     fjs.parentNode.insertBefore(js, fjs);\n   }(document, 'script', 'facebook-jssdk'));\n<\/script><div id=\"watu_quiz\" class=\"quiz-area single-page-quiz\">\n<p><\/p><form action=\"\" method=\"post\" class=\"quiz-form \" id=\"quiz-2259\" >\n<div class='watu-question' id='question-1'><div class='question-content'><p><span class='watu_num'>1. <\/span>A shared resource matrix is a technique commonly used to locate:<\/p>\n<\/div><input type='hidden' name='question_id[]' value='125088' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515302' \/><div class='watu-question-choice'><input type='radio' name='answer-125088[]' id='answer-id-515302' class='answer answer-1  answerof-125088' value='515302' \/>&nbsp;<label for='answer-id-515302' id='answer-label-515302' class=' answer label-1'><span class='answer'>Malicious code<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515303' \/><div class='watu-question-choice'><input type='radio' name='answer-125088[]' id='answer-id-515303' class='answer answer-1  answerof-125088' value='515303' \/>&nbsp;<label for='answer-id-515303' id='answer-label-515303' class=' answer label-1'><span class='answer'>Security flaws<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515304' \/><div class='watu-question-choice'><input type='radio' name='answer-125088[]' id='answer-id-515304' class='answer answer-1  answerof-125088' value='515304' \/>&nbsp;<label for='answer-id-515304' id='answer-label-515304' class=' answer label-1'><span class='answer'>Trap doors<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515305' \/><div class='watu-question-choice'><input type='radio' name='answer-125088[]' id='answer-id-515305' class='answer answer-1  answerof-125088' value='515305' \/>&nbsp;<label for='answer-id-515305' id='answer-label-515305' class=' answer label-1'><span class='answer'>Covert channels<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType1' value='radio' class=''><\/div><div class='watu-question' id='question-2'><div class='question-content'><p><span class='watu_num'>2. <\/span>You are part of a security staff at a highly profitable bank and each day, all traffic on the network is logged for later review. Every Friday when major deposits are made you&#8217;re seeing a series of bits placed in the &quot;Urgent Pointer&quot; field of a TCP packet.<br \/>\n<br \/>This is only 16 bits which isn&#8217;t much but it concerns you because:<\/p>\n<\/div><input type='hidden' name='question_id[]' value='125089' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515306' \/><div class='watu-question-choice'><input type='radio' name='answer-125089[]' id='answer-id-515306' class='answer answer-2  answerof-125089' value='515306' \/>&nbsp;<label for='answer-id-515306' id='answer-label-515306' class=' answer label-2'><span class='answer'>This could be a sign of covert channeling in bank network communications and should be investigated.<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515307' \/><div class='watu-question-choice'><input type='radio' name='answer-125089[]' id='answer-id-515307' class='answer answer-2  answerof-125089' value='515307' \/>&nbsp;<label for='answer-id-515307' id='answer-label-515307' class=' answer label-2'><span class='answer'>It could be a sign of a damaged network cable causing the issue.<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515308' \/><div class='watu-question-choice'><input type='radio' name='answer-125089[]' id='answer-id-515308' class='answer answer-2  answerof-125089' value='515308' \/>&nbsp;<label for='answer-id-515308' id='answer-label-515308' class=' answer label-2'><span class='answer'>It could be a symptom of malfunctioning network card or drivers and the source system should be checked for the problem.<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515309' \/><div class='watu-question-choice'><input type='radio' name='answer-125089[]' id='answer-id-515309' class='answer answer-2  answerof-125089' value='515309' \/>&nbsp;<label for='answer-id-515309' id='answer-label-515309' class=' answer label-2'><span class='answer'>It is normal traffic because sometimes the previous fields 16-bit checksum value can over run into the urgent pointer&#8217;s 16-bit field causing the condition.<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType2' value='radio' class=''><\/div><div class='watu-question' id='question-3'><div class='question-content'><p><span class='watu_num'>3. <\/span>John is the product manager for an information system. His product has undergone under security review by an IS auditor. John has decided to apply appropriate security controls to reduce the security risks suggested by an IS auditor.<br \/>\n<br \/>Which of the following technique is used by John to treat the identified risk provided by an IS auditor?<\/p>\n<\/div><input type='hidden' name='question_id[]' value='125090' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515310' \/><div class='watu-question-choice'><input type='radio' name='answer-125090[]' id='answer-id-515310' class='answer answer-3  answerof-125090' value='515310' \/>&nbsp;<label for='answer-id-515310' id='answer-label-515310' class=' answer label-3'><span class='answer'>Risk Mitigation<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515311' \/><div class='watu-question-choice'><input type='radio' name='answer-125090[]' id='answer-id-515311' class='answer answer-3  answerof-125090' value='515311' \/>&nbsp;<label for='answer-id-515311' id='answer-label-515311' class=' answer label-3'><span class='answer'>Risk Acceptance<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515312' \/><div class='watu-question-choice'><input type='radio' name='answer-125090[]' id='answer-id-515312' class='answer answer-3  answerof-125090' value='515312' \/>&nbsp;<label for='answer-id-515312' id='answer-label-515312' class=' answer label-3'><span class='answer'>Risk Avoidance<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515313' \/><div class='watu-question-choice'><input type='radio' name='answer-125090[]' id='answer-id-515313' class='answer answer-3  answerof-125090' value='515313' \/>&nbsp;<label for='answer-id-515313' id='answer-label-515313' class=' answer label-3'><span class='answer'>Risk transfer<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType3' value='radio' class=''><\/div><div class='watu-question' id='question-4'><div class='question-content'><p><span class='watu_num'>4. <\/span>Sam is the security Manager of a financial institute. Senior management has requested he performs a risk analysis on all critical vulnerabilities reported by an IS auditor. After completing the risk analysis, Sam has observed that for a few of the risks, the cost benefit analysis shows that risk mitigation cost (countermeasures, controls, or safeguard) is more than the potential lost that could be incurred.<br \/>\n<br \/>What kind of a strategy should Sam recommend to the senior management to treat these risks?<\/p>\n<\/div><input type='hidden' name='question_id[]' value='125091' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515314' \/><div class='watu-question-choice'><input type='radio' name='answer-125091[]' id='answer-id-515314' class='answer answer-4  answerof-125091' value='515314' \/>&nbsp;<label for='answer-id-515314' id='answer-label-515314' class=' answer label-4'><span class='answer'>Risk Mitigation<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515315' \/><div class='watu-question-choice'><input type='radio' name='answer-125091[]' id='answer-id-515315' class='answer answer-4  answerof-125091' value='515315' \/>&nbsp;<label for='answer-id-515315' id='answer-label-515315' class=' answer label-4'><span class='answer'>Risk Acceptance<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515316' \/><div class='watu-question-choice'><input type='radio' name='answer-125091[]' id='answer-id-515316' class='answer answer-4  answerof-125091' value='515316' \/>&nbsp;<label for='answer-id-515316' id='answer-label-515316' class=' answer label-4'><span class='answer'>Risk Avoidance<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515317' \/><div class='watu-question-choice'><input type='radio' name='answer-125091[]' id='answer-id-515317' class='answer answer-4  answerof-125091' value='515317' \/>&nbsp;<label for='answer-id-515317' id='answer-label-515317' class=' answer label-4'><span class='answer'>Risk transfer<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType4' value='radio' class=''><\/div><div class='watu-question' id='question-5'><div class='question-content'><p><span class='watu_num'>5. <\/span>Which of the following risk handling technique involves the practice of being proactive so that the risk in question is not realized?<\/p>\n<\/div><input type='hidden' name='question_id[]' value='125092' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515318' \/><div class='watu-question-choice'><input type='radio' name='answer-125092[]' id='answer-id-515318' class='answer answer-5  answerof-125092' value='515318' \/>&nbsp;<label for='answer-id-515318' id='answer-label-515318' class=' answer label-5'><span class='answer'>Risk Mitigation<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515319' \/><div class='watu-question-choice'><input type='radio' name='answer-125092[]' id='answer-id-515319' class='answer answer-5  answerof-125092' value='515319' \/>&nbsp;<label for='answer-id-515319' id='answer-label-515319' class=' answer label-5'><span class='answer'>Risk Acceptance<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515320' \/><div class='watu-question-choice'><input type='radio' name='answer-125092[]' id='answer-id-515320' class='answer answer-5  answerof-125092' value='515320' \/>&nbsp;<label for='answer-id-515320' id='answer-label-515320' class=' answer label-5'><span class='answer'>Risk Avoidance<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515321' \/><div class='watu-question-choice'><input type='radio' name='answer-125092[]' id='answer-id-515321' class='answer answer-5  answerof-125092' value='515321' \/>&nbsp;<label for='answer-id-515321' id='answer-label-515321' class=' answer label-5'><span class='answer'>Risk transfer<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType5' value='radio' class=''><\/div><div class='watu-question' id='question-6'><div class='question-content'><p><span class='watu_num'>6. <\/span>Which of the following control is intended to discourage a potential attacker?<\/p>\n<\/div><input type='hidden' name='question_id[]' value='125093' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515322' \/><div class='watu-question-choice'><input type='radio' name='answer-125093[]' id='answer-id-515322' class='answer answer-6  answerof-125093' value='515322' \/>&nbsp;<label for='answer-id-515322' id='answer-label-515322' class=' answer label-6'><span class='answer'>Deterrent<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515323' \/><div class='watu-question-choice'><input type='radio' name='answer-125093[]' id='answer-id-515323' class='answer answer-6  answerof-125093' value='515323' \/>&nbsp;<label for='answer-id-515323' id='answer-label-515323' class=' answer label-6'><span class='answer'>Preventive<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515324' \/><div class='watu-question-choice'><input type='radio' name='answer-125093[]' id='answer-id-515324' class='answer answer-6  answerof-125093' value='515324' \/>&nbsp;<label for='answer-id-515324' id='answer-label-515324' class=' answer label-6'><span class='answer'>Corrective<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515325' \/><div class='watu-question-choice'><input type='radio' name='answer-125093[]' id='answer-id-515325' class='answer answer-6  answerof-125093' value='515325' \/>&nbsp;<label for='answer-id-515325' id='answer-label-515325' class=' answer label-6'><span class='answer'>Recovery<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType6' value='radio' class=''><\/div><div class='watu-question' id='question-7'><div class='question-content'><p><span class='watu_num'>7. <\/span>Which of the following security control is intended to avoid an incident from occurring?<\/p>\n<\/div><input type='hidden' name='question_id[]' value='125094' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515326' \/><div class='watu-question-choice'><input type='radio' name='answer-125094[]' id='answer-id-515326' class='answer answer-7  answerof-125094' value='515326' \/>&nbsp;<label for='answer-id-515326' id='answer-label-515326' class=' answer label-7'><span class='answer'>Deterrent<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515327' \/><div class='watu-question-choice'><input type='radio' name='answer-125094[]' id='answer-id-515327' class='answer answer-7  answerof-125094' value='515327' \/>&nbsp;<label for='answer-id-515327' id='answer-label-515327' class=' answer label-7'><span class='answer'>Preventive<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515328' \/><div class='watu-question-choice'><input type='radio' name='answer-125094[]' id='answer-id-515328' class='answer answer-7  answerof-125094' value='515328' \/>&nbsp;<label for='answer-id-515328' id='answer-label-515328' class=' answer label-7'><span class='answer'>Corrective<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515329' \/><div class='watu-question-choice'><input type='radio' name='answer-125094[]' id='answer-id-515329' class='answer answer-7  answerof-125094' value='515329' \/>&nbsp;<label for='answer-id-515329' id='answer-label-515329' class=' answer label-7'><span class='answer'>Recovery<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType7' value='radio' class=''><\/div><div class='watu-question' id='question-8'><div class='question-content'><p><span class='watu_num'>8. <\/span>Which of the following control fixes a component or system after an incident has occurred?<\/p>\n<\/div><input type='hidden' name='question_id[]' value='125095' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515330' \/><div class='watu-question-choice'><input type='radio' name='answer-125095[]' id='answer-id-515330' class='answer answer-8  answerof-125095' value='515330' \/>&nbsp;<label for='answer-id-515330' id='answer-label-515330' class=' answer label-8'><span class='answer'>Deterrent<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515331' \/><div class='watu-question-choice'><input type='radio' name='answer-125095[]' id='answer-id-515331' class='answer answer-8  answerof-125095' value='515331' \/>&nbsp;<label for='answer-id-515331' id='answer-label-515331' class=' answer label-8'><span class='answer'>Preventive<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515332' \/><div class='watu-question-choice'><input type='radio' name='answer-125095[]' id='answer-id-515332' class='answer answer-8  answerof-125095' value='515332' \/>&nbsp;<label for='answer-id-515332' id='answer-label-515332' class=' answer label-8'><span class='answer'>Corrective<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515333' \/><div class='watu-question-choice'><input type='radio' name='answer-125095[]' id='answer-id-515333' class='answer answer-8  answerof-125095' value='515333' \/>&nbsp;<label for='answer-id-515333' id='answer-label-515333' class=' answer label-8'><span class='answer'>Recovery<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType8' value='radio' class=''><\/div><div class='watu-question' id='question-9'><div class='question-content'><p><span class='watu_num'>9. <\/span>Which of the following security control is intended to bring environment back to regular operation?<\/p>\n<\/div><input type='hidden' name='question_id[]' value='125096' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515334' \/><div class='watu-question-choice'><input type='checkbox' name='answer-125096[]' id='answer-id-515334' class='answer answer-9  answerof-125096' value='515334' \/>&nbsp;<label for='answer-id-515334' id='answer-label-515334' class=' answer label-9'><span class='answer'>Deterrent<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515335' \/><div class='watu-question-choice'><input type='checkbox' name='answer-125096[]' id='answer-id-515335' class='answer answer-9  answerof-125096' value='515335' \/>&nbsp;<label for='answer-id-515335' id='answer-label-515335' class=' answer label-9'><span class='answer'>Preventive<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515336' \/><div class='watu-question-choice'><input type='checkbox' name='answer-125096[]' id='answer-id-515336' class='answer answer-9  answerof-125096' value='515336' \/>&nbsp;<label for='answer-id-515336' id='answer-label-515336' class=' answer label-9'><span class='answer'>Corrective<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515337' \/><div class='watu-question-choice'><input type='checkbox' name='answer-125096[]' id='answer-id-515337' class='answer answer-9  answerof-125096' value='515337' \/>&nbsp;<label for='answer-id-515337' id='answer-label-515337' class=' answer label-9'><span class='answer'>Recovery<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType9' value='checkbox' class=''><\/div><div class='watu-question' id='question-10'><div class='question-content'><p><span class='watu_num'>10. <\/span>Which of the following control helps to identify an incident\u2019s activities and potentially an intruder?<\/p>\n<\/div><input type='hidden' name='question_id[]' value='125097' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515338' \/><div class='watu-question-choice'><input type='radio' name='answer-125097[]' id='answer-id-515338' class='answer answer-10  answerof-125097' value='515338' \/>&nbsp;<label for='answer-id-515338' id='answer-label-515338' class=' answer label-10'><span class='answer'>Deterrent<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515339' \/><div class='watu-question-choice'><input type='radio' name='answer-125097[]' id='answer-id-515339' class='answer answer-10  answerof-125097' value='515339' \/>&nbsp;<label for='answer-id-515339' id='answer-label-515339' class=' answer label-10'><span class='answer'>Preventive<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515340' \/><div class='watu-question-choice'><input type='radio' name='answer-125097[]' id='answer-id-515340' class='answer answer-10  answerof-125097' value='515340' \/>&nbsp;<label for='answer-id-515340' id='answer-label-515340' class=' answer label-10'><span class='answer'>Detective<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515341' \/><div class='watu-question-choice'><input type='radio' name='answer-125097[]' id='answer-id-515341' class='answer answer-10  answerof-125097' value='515341' \/>&nbsp;<label for='answer-id-515341' id='answer-label-515341' class=' answer label-10'><span class='answer'>Compensating<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType10' value='radio' class=''><\/div><div class='watu-question' id='question-11'><div class='question-content'><p><span class='watu_num'>11. <\/span>Which of the following control provides an alternative measure of control?<\/p>\n<\/div><input type='hidden' name='question_id[]' value='125098' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515342' \/><div class='watu-question-choice'><input type='radio' name='answer-125098[]' id='answer-id-515342' class='answer answer-11  answerof-125098' value='515342' \/>&nbsp;<label for='answer-id-515342' id='answer-label-515342' class=' answer label-11'><span class='answer'>Deterrent<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515343' \/><div class='watu-question-choice'><input type='radio' name='answer-125098[]' id='answer-id-515343' class='answer answer-11  answerof-125098' value='515343' \/>&nbsp;<label for='answer-id-515343' id='answer-label-515343' class=' answer label-11'><span class='answer'>Preventive<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515344' \/><div class='watu-question-choice'><input type='radio' name='answer-125098[]' id='answer-id-515344' class='answer answer-11  answerof-125098' value='515344' \/>&nbsp;<label for='answer-id-515344' id='answer-label-515344' class=' answer label-11'><span class='answer'>Detective<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515345' \/><div class='watu-question-choice'><input type='radio' name='answer-125098[]' id='answer-id-515345' class='answer answer-11  answerof-125098' value='515345' \/>&nbsp;<label for='answer-id-515345' id='answer-label-515345' class=' answer label-11'><span class='answer'>Compensating<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType11' value='radio' class=''><\/div><div class='watu-question' id='question-12'><div class='question-content'><p><span class='watu_num'>12. <\/span>Which of the following is NOT an example of preventive control?<\/p>\n<\/div><input type='hidden' name='question_id[]' value='125099' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515346' \/><div class='watu-question-choice'><input type='radio' name='answer-125099[]' id='answer-id-515346' class='answer answer-12  answerof-125099' value='515346' \/>&nbsp;<label for='answer-id-515346' id='answer-label-515346' class=' answer label-12'><span class='answer'>Physical access control like locks and door<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515347' \/><div class='watu-question-choice'><input type='radio' name='answer-125099[]' id='answer-id-515347' class='answer answer-12  answerof-125099' value='515347' \/>&nbsp;<label for='answer-id-515347' id='answer-label-515347' class=' answer label-12'><span class='answer'>User login screen which allows only authorize user to access website<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515348' \/><div class='watu-question-choice'><input type='radio' name='answer-125099[]' id='answer-id-515348' class='answer answer-12  answerof-125099' value='515348' \/>&nbsp;<label for='answer-id-515348' id='answer-label-515348' class=' answer label-12'><span class='answer'>Encrypt the data so that only authorize user can view the same<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515349' \/><div class='watu-question-choice'><input type='radio' name='answer-125099[]' id='answer-id-515349' class='answer answer-12  answerof-125099' value='515349' \/>&nbsp;<label for='answer-id-515349' id='answer-label-515349' class=' answer label-12'><span class='answer'>Duplicate checking of a calculations<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType12' value='radio' class=''><\/div><div class='watu-question' id='question-13'><div class='question-content'><p><span class='watu_num'>13. <\/span>Which of the following is NOT an example of corrective control?<\/p>\n<\/div><input type='hidden' name='question_id[]' value='125100' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515350' \/><div class='watu-question-choice'><input type='radio' name='answer-125100[]' id='answer-id-515350' class='answer answer-13  answerof-125100' value='515350' \/>&nbsp;<label for='answer-id-515350' id='answer-label-515350' class=' answer label-13'><span class='answer'>OS Upgrade<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515351' \/><div class='watu-question-choice'><input type='radio' name='answer-125100[]' id='answer-id-515351' class='answer answer-13  answerof-125100' value='515351' \/>&nbsp;<label for='answer-id-515351' id='answer-label-515351' class=' answer label-13'><span class='answer'>Backup and restore<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515352' \/><div class='watu-question-choice'><input type='radio' name='answer-125100[]' id='answer-id-515352' class='answer answer-13  answerof-125100' value='515352' \/>&nbsp;<label for='answer-id-515352' id='answer-label-515352' class=' answer label-13'><span class='answer'>Contingency planning<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515353' \/><div class='watu-question-choice'><input type='radio' name='answer-125100[]' id='answer-id-515353' class='answer answer-13  answerof-125100' value='515353' \/>&nbsp;<label for='answer-id-515353' id='answer-label-515353' class=' answer label-13'><span class='answer'>System Monitoring<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType13' value='radio' class=''><\/div><div class='watu-question' id='question-14'><div class='question-content'><p><span class='watu_num'>14. <\/span>Which of the following audit include specific tests of control to demonstrate adherence to specific regulatory or industry standard?<\/p>\n<\/div><input type='hidden' name='question_id[]' value='125101' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515354' \/><div class='watu-question-choice'><input type='checkbox' name='answer-125101[]' id='answer-id-515354' class='answer answer-14  answerof-125101' value='515354' \/>&nbsp;<label for='answer-id-515354' id='answer-label-515354' class=' answer label-14'><span class='answer'>Compliance Audit<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515355' \/><div class='watu-question-choice'><input type='checkbox' name='answer-125101[]' id='answer-id-515355' class='answer answer-14  answerof-125101' value='515355' \/>&nbsp;<label for='answer-id-515355' id='answer-label-515355' class=' answer label-14'><span class='answer'>Financial Audit<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515356' \/><div class='watu-question-choice'><input type='checkbox' name='answer-125101[]' id='answer-id-515356' class='answer answer-14  answerof-125101' value='515356' \/>&nbsp;<label for='answer-id-515356' id='answer-label-515356' class=' answer label-14'><span class='answer'>Operational Audit<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515357' \/><div class='watu-question-choice'><input type='checkbox' name='answer-125101[]' id='answer-id-515357' class='answer answer-14  answerof-125101' value='515357' \/>&nbsp;<label for='answer-id-515357' id='answer-label-515357' class=' answer label-14'><span class='answer'>Forensic audit<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType14' value='checkbox' class=''><\/div><div class='watu-question' id='question-15'><div class='question-content'><p><span class='watu_num'>15. <\/span>Which of the following audit assess accuracy of financial reporting?<\/p>\n<\/div><input type='hidden' name='question_id[]' value='125102' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515358' \/><div class='watu-question-choice'><input type='radio' name='answer-125102[]' id='answer-id-515358' class='answer answer-15  answerof-125102' value='515358' \/>&nbsp;<label for='answer-id-515358' id='answer-label-515358' class=' answer label-15'><span class='answer'>Compliance Audit<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515359' \/><div class='watu-question-choice'><input type='radio' name='answer-125102[]' id='answer-id-515359' class='answer answer-15  answerof-125102' value='515359' \/>&nbsp;<label for='answer-id-515359' id='answer-label-515359' class=' answer label-15'><span class='answer'>Financial Audit<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515360' \/><div class='watu-question-choice'><input type='radio' name='answer-125102[]' id='answer-id-515360' class='answer answer-15  answerof-125102' value='515360' \/>&nbsp;<label for='answer-id-515360' id='answer-label-515360' class=' answer label-15'><span class='answer'>Operational Audit<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515361' \/><div class='watu-question-choice'><input type='radio' name='answer-125102[]' id='answer-id-515361' class='answer answer-15  answerof-125102' value='515361' \/>&nbsp;<label for='answer-id-515361' id='answer-label-515361' class=' answer label-15'><span class='answer'>Forensic audit<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType15' value='radio' class=''><\/div><div class='watu-question' id='question-16'><div class='question-content'><p><span class='watu_num'>16. <\/span>Which of the following audit is mainly designed to evaluate the internal control structure in a given process or area?<\/p>\n<\/div><input type='hidden' name='question_id[]' value='125103' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515362' \/><div class='watu-question-choice'><input type='radio' name='answer-125103[]' id='answer-id-515362' class='answer answer-16  answerof-125103' value='515362' \/>&nbsp;<label for='answer-id-515362' id='answer-label-515362' class=' answer label-16'><span class='answer'>Compliance Audit<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515363' \/><div class='watu-question-choice'><input type='radio' name='answer-125103[]' id='answer-id-515363' class='answer answer-16  answerof-125103' value='515363' \/>&nbsp;<label for='answer-id-515363' id='answer-label-515363' class=' answer label-16'><span class='answer'>Financial Audit<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515364' \/><div class='watu-question-choice'><input type='radio' name='answer-125103[]' id='answer-id-515364' class='answer answer-16  answerof-125103' value='515364' \/>&nbsp;<label for='answer-id-515364' id='answer-label-515364' class=' answer label-16'><span class='answer'>Operational Audit<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515365' \/><div class='watu-question-choice'><input type='radio' name='answer-125103[]' id='answer-id-515365' class='answer answer-16  answerof-125103' value='515365' \/>&nbsp;<label for='answer-id-515365' id='answer-label-515365' class=' answer label-16'><span class='answer'>Forensic audit<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType16' value='radio' class=''><\/div><div class='watu-question' id='question-17'><div class='question-content'><p><span class='watu_num'>17. <\/span>Which of the following audit combines financial and operational audit steps?<\/p>\n<\/div><input type='hidden' name='question_id[]' value='125104' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515366' \/><div class='watu-question-choice'><input type='checkbox' name='answer-125104[]' id='answer-id-515366' class='answer answer-17  answerof-125104' value='515366' \/>&nbsp;<label for='answer-id-515366' id='answer-label-515366' class=' answer label-17'><span class='answer'>Compliance Audit<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515367' \/><div class='watu-question-choice'><input type='checkbox' name='answer-125104[]' id='answer-id-515367' class='answer answer-17  answerof-125104' value='515367' \/>&nbsp;<label for='answer-id-515367' id='answer-label-515367' class=' answer label-17'><span class='answer'>Financial Audit<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515368' \/><div class='watu-question-choice'><input type='checkbox' name='answer-125104[]' id='answer-id-515368' class='answer answer-17  answerof-125104' value='515368' \/>&nbsp;<label for='answer-id-515368' id='answer-label-515368' class=' answer label-17'><span class='answer'>Integrated Audit<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515369' \/><div class='watu-question-choice'><input type='checkbox' name='answer-125104[]' id='answer-id-515369' class='answer answer-17  answerof-125104' value='515369' \/>&nbsp;<label for='answer-id-515369' id='answer-label-515369' class=' answer label-17'><span class='answer'>Forensic audit<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType17' value='checkbox' class=''><\/div><div class='watu-question' id='question-18'><div class='question-content'><p><span class='watu_num'>18. <\/span>Which of the following audit mainly focuses on discovering and disclosing on frauds and crimes?<\/p>\n<\/div><input type='hidden' name='question_id[]' value='125105' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515370' \/><div class='watu-question-choice'><input type='checkbox' name='answer-125105[]' id='answer-id-515370' class='answer answer-18  answerof-125105' value='515370' \/>&nbsp;<label for='answer-id-515370' id='answer-label-515370' class=' answer label-18'><span class='answer'>Compliance Audit<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515371' \/><div class='watu-question-choice'><input type='checkbox' name='answer-125105[]' id='answer-id-515371' class='answer answer-18  answerof-125105' value='515371' \/>&nbsp;<label for='answer-id-515371' id='answer-label-515371' class=' answer label-18'><span class='answer'>Financial Audit<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515372' \/><div class='watu-question-choice'><input type='checkbox' name='answer-125105[]' id='answer-id-515372' class='answer answer-18  answerof-125105' value='515372' \/>&nbsp;<label for='answer-id-515372' id='answer-label-515372' class=' answer label-18'><span class='answer'>Integrated Audit<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515373' \/><div class='watu-question-choice'><input type='checkbox' name='answer-125105[]' id='answer-id-515373' class='answer answer-18  answerof-125105' value='515373' \/>&nbsp;<label for='answer-id-515373' id='answer-label-515373' class=' answer label-18'><span class='answer'>Forensic audit<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType18' value='checkbox' class=''><\/div><div class='watu-question' id='question-19'><div class='question-content'><p><span class='watu_num'>19. <\/span>Which of the following audit risk is related to exposure of a process or entity to be audited without taking into account the control that management has implemented?<\/p>\n<\/div><input type='hidden' name='question_id[]' value='125106' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515374' \/><div class='watu-question-choice'><input type='checkbox' name='answer-125106[]' id='answer-id-515374' class='answer answer-19  answerof-125106' value='515374' \/>&nbsp;<label for='answer-id-515374' id='answer-label-515374' class=' answer label-19'><span class='answer'>Inherent Risk<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515375' \/><div class='watu-question-choice'><input type='checkbox' name='answer-125106[]' id='answer-id-515375' class='answer answer-19  answerof-125106' value='515375' \/>&nbsp;<label for='answer-id-515375' id='answer-label-515375' class=' answer label-19'><span class='answer'>Control Risk<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515376' \/><div class='watu-question-choice'><input type='checkbox' name='answer-125106[]' id='answer-id-515376' class='answer answer-19  answerof-125106' value='515376' \/>&nbsp;<label for='answer-id-515376' id='answer-label-515376' class=' answer label-19'><span class='answer'>Detection Risk<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515377' \/><div class='watu-question-choice'><input type='checkbox' name='answer-125106[]' id='answer-id-515377' class='answer answer-19  answerof-125106' value='515377' \/>&nbsp;<label for='answer-id-515377' id='answer-label-515377' class=' answer label-19'><span class='answer'>Overall Audit Risk<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType19' value='checkbox' class=''><\/div><div class='watu-question' id='question-20'><div class='question-content'><p><span class='watu_num'>20. <\/span>Which of the following audit risk is related to material error exist that would not be prevented or detected on timely basis by the system of internal controls?<\/p>\n<\/div><input type='hidden' name='question_id[]' value='125107' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515378' \/><div class='watu-question-choice'><input type='checkbox' name='answer-125107[]' id='answer-id-515378' class='answer answer-20  answerof-125107' value='515378' \/>&nbsp;<label for='answer-id-515378' id='answer-label-515378' class=' answer label-20'><span class='answer'>Inherent Risk<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515379' \/><div class='watu-question-choice'><input type='checkbox' name='answer-125107[]' id='answer-id-515379' class='answer answer-20  answerof-125107' value='515379' \/>&nbsp;<label for='answer-id-515379' id='answer-label-515379' class=' answer label-20'><span class='answer'>Control Risk<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515380' \/><div class='watu-question-choice'><input type='checkbox' name='answer-125107[]' id='answer-id-515380' class='answer answer-20  answerof-125107' value='515380' \/>&nbsp;<label for='answer-id-515380' id='answer-label-515380' class=' answer label-20'><span class='answer'>Detection Risk<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515381' \/><div class='watu-question-choice'><input type='checkbox' name='answer-125107[]' id='answer-id-515381' class='answer answer-20  answerof-125107' value='515381' \/>&nbsp;<label for='answer-id-515381' id='answer-label-515381' class=' answer label-20'><span class='answer'>Overall Audit Risk<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType20' value='checkbox' class=''><\/div><div class='watu-question' id='question-21'><div class='question-content'><p><span class='watu_num'>21. <\/span>Which of the following audit risk is related to material errors or misstatements that have occurred that will not be detected by an IS auditor?<\/p>\n<\/div><input type='hidden' name='question_id[]' value='125108' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515382' \/><div class='watu-question-choice'><input type='checkbox' name='answer-125108[]' id='answer-id-515382' class='answer answer-21  answerof-125108' value='515382' \/>&nbsp;<label for='answer-id-515382' id='answer-label-515382' class=' answer label-21'><span class='answer'>Inherent Risk<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515383' \/><div class='watu-question-choice'><input type='checkbox' name='answer-125108[]' id='answer-id-515383' class='answer answer-21  answerof-125108' value='515383' \/>&nbsp;<label for='answer-id-515383' id='answer-label-515383' class=' answer label-21'><span class='answer'>Control Risk<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515384' \/><div class='watu-question-choice'><input type='checkbox' name='answer-125108[]' id='answer-id-515384' class='answer answer-21  answerof-125108' value='515384' \/>&nbsp;<label for='answer-id-515384' id='answer-label-515384' class=' answer label-21'><span class='answer'>Detection Risk<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515385' \/><div class='watu-question-choice'><input type='checkbox' name='answer-125108[]' id='answer-id-515385' class='answer answer-21  answerof-125108' value='515385' \/>&nbsp;<label for='answer-id-515385' id='answer-label-515385' class=' answer label-21'><span class='answer'>Overall Audit Risk<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType21' value='checkbox' class=''><\/div><div class='watu-question' id='question-22'><div class='question-content'><p><span class='watu_num'>22. <\/span>Which of the following statement INCORRECTLY describes the Control self-assessment (CSA) approach?<\/p>\n<\/div><input type='hidden' name='question_id[]' value='125109' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='516347' \/><div class='watu-question-choice'><input type='radio' name='answer-125109[]' id='answer-id-516347' class='answer answer-22  answerof-125109' value='516347' \/>&nbsp;<label for='answer-id-516347' id='answer-label-516347' class=' answer label-22'><span class='answer'>CSA is policy or rule driven<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='516348' \/><div class='watu-question-choice'><input type='radio' name='answer-125109[]' id='answer-id-516348' class='answer answer-22  answerof-125109' value='516348' \/>&nbsp;<label for='answer-id-516348' id='answer-label-516348' class=' answer label-22'><span class='answer'>CSA Empowered\/accountable employees<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='516349' \/><div class='watu-question-choice'><input type='radio' name='answer-125109[]' id='answer-id-516349' class='answer answer-22  answerof-125109' value='516349' \/>&nbsp;<label for='answer-id-516349' id='answer-label-516349' class=' answer label-22'><span class='answer'>CSA focuses on continuous improvement\/learning curve<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='516350' \/><div class='watu-question-choice'><input type='radio' name='answer-125109[]' id='answer-id-516350' class='answer answer-22  answerof-125109' value='516350' \/>&nbsp;<label for='answer-id-516350' id='answer-label-516350' class=' answer label-22'><span class='answer'>In CSA, Staffs at all level, in all functions, are the primary control analyst.<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType22' value='radio' class=''><\/div><div class='watu-question' id='question-23'><div class='question-content'><p><span class='watu_num'>23. <\/span>Which of the following statement INCORRECTLY describes the traditional audit approach in comparison to the Control self-assessment approach?<\/p>\n<\/div><input type='hidden' name='question_id[]' value='125110' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515387' \/><div class='watu-question-choice'><input type='checkbox' name='answer-125110[]' id='answer-id-515387' class='answer answer-23  answerof-125110' value='515387' \/>&nbsp;<label for='answer-id-515387' id='answer-label-515387' class=' answer label-23'><span class='answer'>In traditional approach, Staffs at all level, in all functions, are the primary control analyst.<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515388' \/><div class='watu-question-choice'><input type='checkbox' name='answer-125110[]' id='answer-id-515388' class='answer answer-23  answerof-125110' value='515388' \/>&nbsp;<label for='answer-id-515388' id='answer-label-515388' class=' answer label-23'><span class='answer'>Traditional approach assigns duties\/supervises staff<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515389' \/><div class='watu-question-choice'><input type='checkbox' name='answer-125110[]' id='answer-id-515389' class='answer answer-23  answerof-125110' value='515389' \/>&nbsp;<label for='answer-id-515389' id='answer-label-515389' class=' answer label-23'><span class='answer'>Traditional approach is a policy driven approach<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515390' \/><div class='watu-question-choice'><input type='checkbox' name='answer-125110[]' id='answer-id-515390' class='answer answer-23  answerof-125110' value='515390' \/>&nbsp;<label for='answer-id-515390' id='answer-label-515390' class=' answer label-23'><span class='answer'>Traditional approach requires limited employee participations.<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType23' value='checkbox' class=''><\/div><div class='watu-question' id='question-24'><div class='question-content'><p><span class='watu_num'>24. <\/span>Which of the following is the most important benefit of control self-assessment (CSA)?<\/p>\n<\/div><input type='hidden' name='question_id[]' value='125111' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515391' \/><div class='watu-question-choice'><input type='radio' name='answer-125111[]' id='answer-id-515391' class='answer answer-24  answerof-125111' value='515391' \/>&nbsp;<label for='answer-id-515391' id='answer-label-515391' class=' answer label-24'><span class='answer'>CSA is a policy\/rule driven<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515392' \/><div class='watu-question-choice'><input type='radio' name='answer-125111[]' id='answer-id-515392' class='answer answer-24  answerof-125111' value='515392' \/>&nbsp;<label for='answer-id-515392' id='answer-label-515392' class=' answer label-24'><span class='answer'>In CSA approach, risk is identified sooner<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515393' \/><div class='watu-question-choice'><input type='radio' name='answer-125111[]' id='answer-id-515393' class='answer answer-24  answerof-125111' value='515393' \/>&nbsp;<label for='answer-id-515393' id='answer-label-515393' class=' answer label-24'><span class='answer'>CSA requires limited employee participations<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515394' \/><div class='watu-question-choice'><input type='radio' name='answer-125111[]' id='answer-id-515394' class='answer answer-24  answerof-125111' value='515394' \/>&nbsp;<label for='answer-id-515394' id='answer-label-515394' class=' answer label-24'><span class='answer'>In CSA, resources are being used in an effective manner.<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType24' value='radio' class=''><\/div><div class='watu-question' id='question-25'><div class='question-content'><p><span class='watu_num'>25. <\/span>Which of the following testing procedure is used by the auditor during accounting audit to check errors in balance sheet and other financial documentation?<\/p>\n<\/div><input type='hidden' name='question_id[]' value='125112' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515395' \/><div class='watu-question-choice'><input type='radio' name='answer-125112[]' id='answer-id-515395' class='answer answer-25  answerof-125112' value='515395' \/>&nbsp;<label for='answer-id-515395' id='answer-label-515395' class=' answer label-25'><span class='answer'>Compliance testing<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515396' \/><div class='watu-question-choice'><input type='radio' name='answer-125112[]' id='answer-id-515396' class='answer answer-25  answerof-125112' value='515396' \/>&nbsp;<label for='answer-id-515396' id='answer-label-515396' class=' answer label-25'><span class='answer'>Sanity testing<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515397' \/><div class='watu-question-choice'><input type='radio' name='answer-125112[]' id='answer-id-515397' class='answer answer-25  answerof-125112' value='515397' \/>&nbsp;<label for='answer-id-515397' id='answer-label-515397' class=' answer label-25'><span class='answer'>Recovery testing<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515398' \/><div class='watu-question-choice'><input type='radio' name='answer-125112[]' id='answer-id-515398' class='answer answer-25  answerof-125112' value='515398' \/>&nbsp;<label for='answer-id-515398' id='answer-label-515398' class=' answer label-25'><span class='answer'>Substantive testing<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType25' value='radio' class=''><\/div><div class='watu-question' id='question-26'><div class='question-content'><p><span class='watu_num'>26. <\/span>Which of the following testing procedure is used by an auditor to check whether a firm is following the rules and regulations applicable to an activity or practice?<\/p>\n<\/div><input type='hidden' name='question_id[]' value='125113' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515399' \/><div class='watu-question-choice'><input type='radio' name='answer-125113[]' id='answer-id-515399' class='answer answer-26  answerof-125113' value='515399' \/>&nbsp;<label for='answer-id-515399' id='answer-label-515399' class=' answer label-26'><span class='answer'>Compliance testing<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515400' \/><div class='watu-question-choice'><input type='radio' name='answer-125113[]' id='answer-id-515400' class='answer answer-26  answerof-125113' value='515400' \/>&nbsp;<label for='answer-id-515400' id='answer-label-515400' class=' answer label-26'><span class='answer'>Sanity testing<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515401' \/><div class='watu-question-choice'><input type='radio' name='answer-125113[]' id='answer-id-515401' class='answer answer-26  answerof-125113' value='515401' \/>&nbsp;<label for='answer-id-515401' id='answer-label-515401' class=' answer label-26'><span class='answer'>Recovery testing<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515402' \/><div class='watu-question-choice'><input type='radio' name='answer-125113[]' id='answer-id-515402' class='answer answer-26  answerof-125113' value='515402' \/>&nbsp;<label for='answer-id-515402' id='answer-label-515402' class=' answer label-26'><span class='answer'>Substantive testing<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType26' value='radio' class=''><\/div><div class='watu-question' id='question-27'><div class='question-content'><p><span class='watu_num'>27. <\/span>What are the different types of Audits?<\/p>\n<\/div><input type='hidden' name='question_id[]' value='125114' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515403' \/><div class='watu-question-choice'><input type='radio' name='answer-125114[]' id='answer-id-515403' class='answer answer-27  answerof-125114' value='515403' \/>&nbsp;<label for='answer-id-515403' id='answer-label-515403' class=' answer label-27'><span class='answer'>Compliance, financial, operational, forensic and integrated<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515404' \/><div class='watu-question-choice'><input type='radio' name='answer-125114[]' id='answer-id-515404' class='answer answer-27  answerof-125114' value='515404' \/>&nbsp;<label for='answer-id-515404' id='answer-label-515404' class=' answer label-27'><span class='answer'>Compliance, financial, operational, G9 and integrated<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515405' \/><div class='watu-question-choice'><input type='radio' name='answer-125114[]' id='answer-id-515405' class='answer answer-27  answerof-125114' value='515405' \/>&nbsp;<label for='answer-id-515405' id='answer-label-515405' class=' answer label-27'><span class='answer'>Compliance, financial, SA1, forensic and integrated<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515406' \/><div class='watu-question-choice'><input type='radio' name='answer-125114[]' id='answer-id-515406' class='answer answer-27  answerof-125114' value='515406' \/>&nbsp;<label for='answer-id-515406' id='answer-label-515406' class=' answer label-27'><span class='answer'>Compliance, financial, operational, forensic and capability<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType27' value='radio' class=''><\/div><div class='watu-question' id='question-28'><div class='question-content'><p><span class='watu_num'>28. <\/span>Statistical sampling is NOT based on which of the following audit sample techniques?<\/p>\n<\/div><input type='hidden' name='question_id[]' value='125115' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515407' \/><div class='watu-question-choice'><input type='radio' name='answer-125115[]' id='answer-id-515407' class='answer answer-28  answerof-125115' value='515407' \/>&nbsp;<label for='answer-id-515407' id='answer-label-515407' class=' answer label-28'><span class='answer'>Haphazard Sampling<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515408' \/><div class='watu-question-choice'><input type='radio' name='answer-125115[]' id='answer-id-515408' class='answer answer-28  answerof-125115' value='515408' \/>&nbsp;<label for='answer-id-515408' id='answer-label-515408' class=' answer label-28'><span class='answer'>Random Sampling<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515409' \/><div class='watu-question-choice'><input type='radio' name='answer-125115[]' id='answer-id-515409' class='answer answer-28  answerof-125115' value='515409' \/>&nbsp;<label for='answer-id-515409' id='answer-label-515409' class=' answer label-28'><span class='answer'>Cell Sampling<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515410' \/><div class='watu-question-choice'><input type='radio' name='answer-125115[]' id='answer-id-515410' class='answer answer-28  answerof-125115' value='515410' \/>&nbsp;<label for='answer-id-515410' id='answer-label-515410' class=' answer label-28'><span class='answer'>Fixed interval sampling<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType28' value='radio' class=''><\/div><div class='watu-question' id='question-29'><div class='question-content'><p><span class='watu_num'>29. <\/span>An organization performs nightly backups but does not have a formal policy. An IS auditor should FIRST:<\/p>\n<\/div><input type='hidden' name='question_id[]' value='125116' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515411' \/><div class='watu-question-choice'><input type='radio' name='answer-125116[]' id='answer-id-515411' class='answer answer-29  answerof-125116' value='515411' \/>&nbsp;<label for='answer-id-515411' id='answer-label-515411' class=' answer label-29'><span class='answer'>evaluate current backup procedures<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515412' \/><div class='watu-question-choice'><input type='radio' name='answer-125116[]' id='answer-id-515412' class='answer answer-29  answerof-125116' value='515412' \/>&nbsp;<label for='answer-id-515412' id='answer-label-515412' class=' answer label-29'><span class='answer'>escalate to senior management<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515413' \/><div class='watu-question-choice'><input type='radio' name='answer-125116[]' id='answer-id-515413' class='answer answer-29  answerof-125116' value='515413' \/>&nbsp;<label for='answer-id-515413' id='answer-label-515413' class=' answer label-29'><span class='answer'>document a policy for the organization<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515414' \/><div class='watu-question-choice'><input type='radio' name='answer-125116[]' id='answer-id-515414' class='answer answer-29  answerof-125116' value='515414' \/>&nbsp;<label for='answer-id-515414' id='answer-label-515414' class=' answer label-29'><span class='answer'>recommend automated backup<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType29' value='radio' class=''><\/div><div class='watu-question' id='question-30'><div class='question-content'><p><span class='watu_num'>30. <\/span>An IS auditor reviewing an organization\u2019s data privacy controls observes that privacy notices do not clearly state how the organization uses customer data for its processing operations.<br \/>\n<br \/>Which of the following data protection principles MUST be implemented to address this gap?<\/p>\n<\/div><input type='hidden' name='question_id[]' value='125117' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515415' \/><div class='watu-question-choice'><input type='radio' name='answer-125117[]' id='answer-id-515415' class='answer answer-30  answerof-125117' value='515415' \/>&nbsp;<label for='answer-id-515415' id='answer-label-515415' class=' answer label-30'><span class='answer'>Maintenance of data integrity<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515416' \/><div class='watu-question-choice'><input type='radio' name='answer-125117[]' id='answer-id-515416' class='answer answer-30  answerof-125117' value='515416' \/>&nbsp;<label for='answer-id-515416' id='answer-label-515416' class=' answer label-30'><span class='answer'>Access to collected data<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515417' \/><div class='watu-question-choice'><input type='radio' name='answer-125117[]' id='answer-id-515417' class='answer answer-30  answerof-125117' value='515417' \/>&nbsp;<label for='answer-id-515417' id='answer-label-515417' class=' answer label-30'><span class='answer'>Retention of consent documentation<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515418' \/><div class='watu-question-choice'><input type='radio' name='answer-125117[]' id='answer-id-515418' class='answer answer-30  answerof-125117' value='515418' \/>&nbsp;<label for='answer-id-515418' id='answer-label-515418' class=' answer label-30'><span class='answer'>Purpose for data collection<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType30' value='radio' class=''><\/div><div class='watu-question' id='question-31'><div class='question-content'><p><span class='watu_num'>31. <\/span>An IS auditor discovers that validation controls in a web application have been moved from the server side into the browser to boost performance. This would MOST likely increase the risk of a successful attack by:<\/p>\n<\/div><input type='hidden' name='question_id[]' value='125118' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515419' \/><div class='watu-question-choice'><input type='radio' name='answer-125118[]' id='answer-id-515419' class='answer answer-31  answerof-125118' value='515419' \/>&nbsp;<label for='answer-id-515419' id='answer-label-515419' class=' answer label-31'><span class='answer'>phishing<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515420' \/><div class='watu-question-choice'><input type='radio' name='answer-125118[]' id='answer-id-515420' class='answer answer-31  answerof-125118' value='515420' \/>&nbsp;<label for='answer-id-515420' id='answer-label-515420' class=' answer label-31'><span class='answer'>structured query language (SQL) injection<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515421' \/><div class='watu-question-choice'><input type='radio' name='answer-125118[]' id='answer-id-515421' class='answer answer-31  answerof-125118' value='515421' \/>&nbsp;<label for='answer-id-515421' id='answer-label-515421' class=' answer label-31'><span class='answer'>denial of service<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515422' \/><div class='watu-question-choice'><input type='radio' name='answer-125118[]' id='answer-id-515422' class='answer answer-31  answerof-125118' value='515422' \/>&nbsp;<label for='answer-id-515422' id='answer-label-515422' class=' answer label-31'><span class='answer'>buffer overflow<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType31' value='radio' class=''><\/div><div class='watu-question' id='question-32'><div class='question-content'><p><span class='watu_num'>32. <\/span>In a follow-up audit, an IS auditor notes that management has addressed the original findings in a different way than originally agreed upon. The auditor should FIRST:<\/p>\n<\/div><input type='hidden' name='question_id[]' value='125119' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515423' \/><div class='watu-question-choice'><input type='radio' name='answer-125119[]' id='answer-id-515423' class='answer answer-32  answerof-125119' value='515423' \/>&nbsp;<label for='answer-id-515423' id='answer-label-515423' class=' answer label-32'><span class='answer'>mark the recommendation as satisfied and close the finding<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515424' \/><div class='watu-question-choice'><input type='radio' name='answer-125119[]' id='answer-id-515424' class='answer answer-32  answerof-125119' value='515424' \/>&nbsp;<label for='answer-id-515424' id='answer-label-515424' class=' answer label-32'><span class='answer'>verify if management\u2019s action mitigates the identified risk<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515425' \/><div class='watu-question-choice'><input type='radio' name='answer-125119[]' id='answer-id-515425' class='answer answer-32  answerof-125119' value='515425' \/>&nbsp;<label for='answer-id-515425' id='answer-label-515425' class=' answer label-32'><span class='answer'>re-perform the audit to assess the changed control environment<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515426' \/><div class='watu-question-choice'><input type='radio' name='answer-125119[]' id='answer-id-515426' class='answer answer-32  answerof-125119' value='515426' \/>&nbsp;<label for='answer-id-515426' id='answer-label-515426' class=' answer label-32'><span class='answer'>escalate the deviation to the audit committee<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType32' value='radio' class=''><\/div><div class='watu-question' id='question-33'><div class='question-content'><p><span class='watu_num'>33. <\/span>An organization is considering outsourcing the processing of customer insurance claims. An IS auditor notes that customer data will be sent offshore for processing.<br \/>\n<br \/>Which of the following would be the BEST way to address the risk of exposing customer data?<\/p>\n<\/div><input type='hidden' name='question_id[]' value='125120' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515427' \/><div class='watu-question-choice'><input type='radio' name='answer-125120[]' id='answer-id-515427' class='answer answer-33  answerof-125120' value='515427' \/>&nbsp;<label for='answer-id-515427' id='answer-label-515427' class=' answer label-33'><span class='answer'>Require background checks on all service provider personnel involved in the processing of data.<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515428' \/><div class='watu-question-choice'><input type='radio' name='answer-125120[]' id='answer-id-515428' class='answer answer-33  answerof-125120' value='515428' \/>&nbsp;<label for='answer-id-515428' id='answer-label-515428' class=' answer label-33'><span class='answer'>Recommend the use of a service provider within the same country as the organization.<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515429' \/><div class='watu-question-choice'><input type='radio' name='answer-125120[]' id='answer-id-515429' class='answer answer-33  answerof-125120' value='515429' \/>&nbsp;<label for='answer-id-515429' id='answer-label-515429' class=' answer label-33'><span class='answer'>Consider whether the service provider has the ability to meet service level agreements.<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515430' \/><div class='watu-question-choice'><input type='radio' name='answer-125120[]' id='answer-id-515430' class='answer answer-33  answerof-125120' value='515430' \/>&nbsp;<label for='answer-id-515430' id='answer-label-515430' class=' answer label-33'><span class='answer'>Assess whether the service provider meets the organization\u2019s data protection policies.<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType33' value='radio' class=''><\/div><div class='watu-question' id='question-34'><div class='question-content'><p><span class='watu_num'>34. <\/span>An IS audit team is evaluating the documentation related to the most recent application user-access review performed by IT and business management. It is determined the user list was not system-generated.<br \/>\n<br \/>Which of the following should be the GREATEST concern?<\/p>\n<\/div><input type='hidden' name='question_id[]' value='125121' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515431' \/><div class='watu-question-choice'><input type='radio' name='answer-125121[]' id='answer-id-515431' class='answer answer-34  answerof-125121' value='515431' \/>&nbsp;<label for='answer-id-515431' id='answer-label-515431' class=' answer label-34'><span class='answer'>Source of the user list reviewed<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515432' \/><div class='watu-question-choice'><input type='radio' name='answer-125121[]' id='answer-id-515432' class='answer answer-34  answerof-125121' value='515432' \/>&nbsp;<label for='answer-id-515432' id='answer-label-515432' class=' answer label-34'><span class='answer'>Availability of the user list reviewed<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515433' \/><div class='watu-question-choice'><input type='radio' name='answer-125121[]' id='answer-id-515433' class='answer answer-34  answerof-125121' value='515433' \/>&nbsp;<label for='answer-id-515433' id='answer-label-515433' class=' answer label-34'><span class='answer'>Confidentiality of the user list reviewed<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515434' \/><div class='watu-question-choice'><input type='radio' name='answer-125121[]' id='answer-id-515434' class='answer answer-34  answerof-125121' value='515434' \/>&nbsp;<label for='answer-id-515434' id='answer-label-515434' class=' answer label-34'><span class='answer'>Completeness of the user list reviewed<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType34' value='radio' class=''><\/div><div class='watu-question' id='question-35'><div class='question-content'><p><span class='watu_num'>35. <\/span>Which of the following should an IS auditor determine FIRST when evaluating additional hardware required to support the acquisition of a new accounting system?<\/p>\n<\/div><input type='hidden' name='question_id[]' value='125122' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515435' \/><div class='watu-question-choice'><input type='radio' name='answer-125122[]' id='answer-id-515435' class='answer answer-35  answerof-125122' value='515435' \/>&nbsp;<label for='answer-id-515435' id='answer-label-515435' class=' answer label-35'><span class='answer'>A training program has been developed to support the new accounting system.<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515436' \/><div class='watu-question-choice'><input type='radio' name='answer-125122[]' id='answer-id-515436' class='answer answer-35  answerof-125122' value='515436' \/>&nbsp;<label for='answer-id-515436' id='answer-label-515436' class=' answer label-35'><span class='answer'>The supplier has experience supporting accounting systems.<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515437' \/><div class='watu-question-choice'><input type='radio' name='answer-125122[]' id='answer-id-515437' class='answer answer-35  answerof-125122' value='515437' \/>&nbsp;<label for='answer-id-515437' id='answer-label-515437' class=' answer label-35'><span class='answer'>The hardware specified will be compliant with the current IT strategy.<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515438' \/><div class='watu-question-choice'><input type='radio' name='answer-125122[]' id='answer-id-515438' class='answer answer-35  answerof-125122' value='515438' \/>&nbsp;<label for='answer-id-515438' id='answer-label-515438' class=' answer label-35'><span class='answer'>The hardware will be installed in a secure and environmentally controlled area.<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType35' value='radio' class=''><\/div><div class='watu-question' id='question-36'><div class='question-content'><p><span class='watu_num'>36. <\/span>A company requires that all program change requests (PCRs) be approved and all modifications be automatically logged.<br \/>\n<br \/>Which of the following IS audit procedures will BEST determine whether unauthorized changes have been made to production programs?<\/p>\n<\/div><input type='hidden' name='question_id[]' value='125123' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515439' \/><div class='watu-question-choice'><input type='radio' name='answer-125123[]' id='answer-id-515439' class='answer answer-36  answerof-125123' value='515439' \/>&nbsp;<label for='answer-id-515439' id='answer-label-515439' class=' answer label-36'><span class='answer'>Review a sample of PCRs for proper approval throughout the program change process.<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515440' \/><div class='watu-question-choice'><input type='radio' name='answer-125123[]' id='answer-id-515440' class='answer answer-36  answerof-125123' value='515440' \/>&nbsp;<label for='answer-id-515440' id='answer-label-515440' class=' answer label-36'><span class='answer'>Trace a sample of program changes from the log to completed PCR forms.<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515441' \/><div class='watu-question-choice'><input type='radio' name='answer-125123[]' id='answer-id-515441' class='answer answer-36  answerof-125123' value='515441' \/>&nbsp;<label for='answer-id-515441' id='answer-label-515441' class=' answer label-36'><span class='answer'>Use source code comparison software to determine whether any changes have been made to a sample of programs since the last audit date.<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515442' \/><div class='watu-question-choice'><input type='radio' name='answer-125123[]' id='answer-id-515442' class='answer answer-36  answerof-125123' value='515442' \/>&nbsp;<label for='answer-id-515442' id='answer-label-515442' class=' answer label-36'><span class='answer'>Trace a sample of complete PCR forms to the log of all program changes.<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType36' value='radio' class=''><\/div><div class='watu-question' id='question-37'><div class='question-content'><p><span class='watu_num'>37. <\/span>An IS auditor submitted audit reports and scheduled a follow-up audit engagement with a client. The client has requested to engage the services of the same auditor to develop enhanced controls.<br \/>\n<br \/>What is the GREATEST concern with this request?<\/p>\n<\/div><input type='hidden' name='question_id[]' value='125124' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515443' \/><div class='watu-question-choice'><input type='radio' name='answer-125124[]' id='answer-id-515443' class='answer answer-37  answerof-125124' value='515443' \/>&nbsp;<label for='answer-id-515443' id='answer-label-515443' class=' answer label-37'><span class='answer'>It would require the approval of the audit manager.<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515444' \/><div class='watu-question-choice'><input type='radio' name='answer-125124[]' id='answer-id-515444' class='answer answer-37  answerof-125124' value='515444' \/>&nbsp;<label for='answer-id-515444' id='answer-label-515444' class=' answer label-37'><span class='answer'>It would be beyond the original audit scope.<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515445' \/><div class='watu-question-choice'><input type='radio' name='answer-125124[]' id='answer-id-515445' class='answer answer-37  answerof-125124' value='515445' \/>&nbsp;<label for='answer-id-515445' id='answer-label-515445' class=' answer label-37'><span class='answer'>It would a possible conflict of interest.<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515446' \/><div class='watu-question-choice'><input type='radio' name='answer-125124[]' id='answer-id-515446' class='answer answer-37  answerof-125124' value='515446' \/>&nbsp;<label for='answer-id-515446' id='answer-label-515446' class=' answer label-37'><span class='answer'>It would require a change to the audit plan.<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType37' value='radio' class=''><\/div><div class='watu-question' id='question-38'><div class='question-content'><p><span class='watu_num'>38. <\/span>An IS auditor is evaluating the completeness of privacy procedures involving personally identifiable information (PII).<br \/>\n<br \/>Which of the following is MOST important for the auditor to verify is included in the procedures?<\/p>\n<\/div><input type='hidden' name='question_id[]' value='125125' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515447' \/><div class='watu-question-choice'><input type='radio' name='answer-125125[]' id='answer-id-515447' class='answer answer-38  answerof-125125' value='515447' \/>&nbsp;<label for='answer-id-515447' id='answer-label-515447' class=' answer label-38'><span class='answer'>Regulatory requirements for protecting PII<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515448' \/><div class='watu-question-choice'><input type='radio' name='answer-125125[]' id='answer-id-515448' class='answer answer-38  answerof-125125' value='515448' \/>&nbsp;<label for='answer-id-515448' id='answer-label-515448' class=' answer label-38'><span class='answer'>The organization\u2019s definition of PII<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515449' \/><div class='watu-question-choice'><input type='radio' name='answer-125125[]' id='answer-id-515449' class='answer answer-38  answerof-125125' value='515449' \/>&nbsp;<label for='answer-id-515449' id='answer-label-515449' class=' answer label-38'><span class='answer'>Encryption requirements for transmitting PII externally<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515450' \/><div class='watu-question-choice'><input type='radio' name='answer-125125[]' id='answer-id-515450' class='answer answer-38  answerof-125125' value='515450' \/>&nbsp;<label for='answer-id-515450' id='answer-label-515450' class=' answer label-38'><span class='answer'>A description of how PII is masked within key systems<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType38' value='radio' class=''><\/div><div class='watu-question' id='question-39'><div class='question-content'><p><span class='watu_num'>39. <\/span>The risk that the IS auditor will not find an error that has occurred is identified by which of the following terms?<\/p>\n<\/div><input type='hidden' name='question_id[]' value='125126' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515451' \/><div class='watu-question-choice'><input type='radio' name='answer-125126[]' id='answer-id-515451' class='answer answer-39  answerof-125126' value='515451' \/>&nbsp;<label for='answer-id-515451' id='answer-label-515451' class=' answer label-39'><span class='answer'>Control<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515452' \/><div class='watu-question-choice'><input type='radio' name='answer-125126[]' id='answer-id-515452' class='answer answer-39  answerof-125126' value='515452' \/>&nbsp;<label for='answer-id-515452' id='answer-label-515452' class=' answer label-39'><span class='answer'>Prevention<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515453' \/><div class='watu-question-choice'><input type='radio' name='answer-125126[]' id='answer-id-515453' class='answer answer-39  answerof-125126' value='515453' \/>&nbsp;<label for='answer-id-515453' id='answer-label-515453' class=' answer label-39'><span class='answer'>Inherent<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515454' \/><div class='watu-question-choice'><input type='radio' name='answer-125126[]' id='answer-id-515454' class='answer answer-39  answerof-125126' value='515454' \/>&nbsp;<label for='answer-id-515454' id='answer-label-515454' class=' answer label-39'><span class='answer'>Detection<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType39' value='radio' class=''><\/div><div class='watu-question' id='question-40'><div class='question-content'><p><span class='watu_num'>40. <\/span>An IS auditor finds that application servers had inconsistent security settings leading to potential vulnerabilities.<br \/>\n<br \/>Which of the following is the BEST recommendation by the IS auditor?<\/p>\n<\/div><input type='hidden' name='question_id[]' value='125127' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515455' \/><div class='watu-question-choice'><input type='radio' name='answer-125127[]' id='answer-id-515455' class='answer answer-40  answerof-125127' value='515455' \/>&nbsp;<label for='answer-id-515455' id='answer-label-515455' class=' answer label-40'><span class='answer'>Improve the change management process<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515456' \/><div class='watu-question-choice'><input type='radio' name='answer-125127[]' id='answer-id-515456' class='answer answer-40  answerof-125127' value='515456' \/>&nbsp;<label for='answer-id-515456' id='answer-label-515456' class=' answer label-40'><span class='answer'>Perform a configuration review<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515457' \/><div class='watu-question-choice'><input type='radio' name='answer-125127[]' id='answer-id-515457' class='answer answer-40  answerof-125127' value='515457' \/>&nbsp;<label for='answer-id-515457' id='answer-label-515457' class=' answer label-40'><span class='answer'>Establish security metrics<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515458' \/><div class='watu-question-choice'><input type='radio' name='answer-125127[]' id='answer-id-515458' class='answer answer-40  answerof-125127' value='515458' \/>&nbsp;<label for='answer-id-515458' id='answer-label-515458' class=' answer label-40'><span class='answer'>Perform a penetration test<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType40' value='radio' class=''><\/div><div class='watu-question' id='question-41'><div class='question-content'><p><span class='watu_num'>41. <\/span>An IS auditor reviewing a new application for compliance with information privacy principles should be the MOST concerned with:<\/p>\n<\/div><input type='hidden' name='question_id[]' value='125128' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515459' \/><div class='watu-question-choice'><input type='radio' name='answer-125128[]' id='answer-id-515459' class='answer answer-41  answerof-125128' value='515459' \/>&nbsp;<label for='answer-id-515459' id='answer-label-515459' class=' answer label-41'><span class='answer'>nonrepudiation<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515460' \/><div class='watu-question-choice'><input type='radio' name='answer-125128[]' id='answer-id-515460' class='answer answer-41  answerof-125128' value='515460' \/>&nbsp;<label for='answer-id-515460' id='answer-label-515460' class=' answer label-41'><span class='answer'>collection limitation<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515461' \/><div class='watu-question-choice'><input type='radio' name='answer-125128[]' id='answer-id-515461' class='answer answer-41  answerof-125128' value='515461' \/>&nbsp;<label for='answer-id-515461' id='answer-label-515461' class=' answer label-41'><span class='answer'>availability<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515462' \/><div class='watu-question-choice'><input type='radio' name='answer-125128[]' id='answer-id-515462' class='answer answer-41  answerof-125128' value='515462' \/>&nbsp;<label for='answer-id-515462' id='answer-label-515462' class=' answer label-41'><span class='answer'>awareness<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType41' value='radio' class=''><\/div><div class='watu-question' id='question-42'><div class='question-content'><p><span class='watu_num'>42. <\/span>Which of the following is the PRIMARY reason for an IS auditor to issue an interim audit report?<\/p>\n<\/div><input type='hidden' name='question_id[]' value='125129' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515463' \/><div class='watu-question-choice'><input type='radio' name='answer-125129[]' id='answer-id-515463' class='answer answer-42  answerof-125129' value='515463' \/>&nbsp;<label for='answer-id-515463' id='answer-label-515463' class=' answer label-42'><span class='answer'>To avoid issuing a final audit report<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515464' \/><div class='watu-question-choice'><input type='radio' name='answer-125129[]' id='answer-id-515464' class='answer answer-42  answerof-125129' value='515464' \/>&nbsp;<label for='answer-id-515464' id='answer-label-515464' class=' answer label-42'><span class='answer'>To enable the auditor to complete the engagement in a timely manner<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515465' \/><div class='watu-question-choice'><input type='radio' name='answer-125129[]' id='answer-id-515465' class='answer answer-42  answerof-125129' value='515465' \/>&nbsp;<label for='answer-id-515465' id='answer-label-515465' class=' answer label-42'><span class='answer'>To provide feedback to the auditee for timely remediation<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515466' \/><div class='watu-question-choice'><input type='radio' name='answer-125129[]' id='answer-id-515466' class='answer answer-42  answerof-125129' value='515466' \/>&nbsp;<label for='answer-id-515466' id='answer-label-515466' class=' answer label-42'><span class='answer'>To provide follow-up opportunity during the audit<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType42' value='radio' class=''><\/div><div class='watu-question' id='question-43'><div class='question-content'><p><span class='watu_num'>43. <\/span>Which of the following conditions would be of MOST concern to an IS auditor assessing the risk of a successful brute force attack encrypted data at rest?<\/p>\n<\/div><input type='hidden' name='question_id[]' value='125130' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515467' \/><div class='watu-question-choice'><input type='radio' name='answer-125130[]' id='answer-id-515467' class='answer answer-43  answerof-125130' value='515467' \/>&nbsp;<label for='answer-id-515467' id='answer-label-515467' class=' answer label-43'><span class='answer'>Use of symmetric encryption<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515468' \/><div class='watu-question-choice'><input type='radio' name='answer-125130[]' id='answer-id-515468' class='answer answer-43  answerof-125130' value='515468' \/>&nbsp;<label for='answer-id-515468' id='answer-label-515468' class=' answer label-43'><span class='answer'>Use of asymmetric encryption<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515469' \/><div class='watu-question-choice'><input type='radio' name='answer-125130[]' id='answer-id-515469' class='answer answer-43  answerof-125130' value='515469' \/>&nbsp;<label for='answer-id-515469' id='answer-label-515469' class=' answer label-43'><span class='answer'>Random key generation<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515470' \/><div class='watu-question-choice'><input type='radio' name='answer-125130[]' id='answer-id-515470' class='answer answer-43  answerof-125130' value='515470' \/>&nbsp;<label for='answer-id-515470' id='answer-label-515470' class=' answer label-43'><span class='answer'>Short key length<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType43' value='radio' class=''><\/div><div class='watu-question' id='question-44'><div class='question-content'><p><span class='watu_num'>44. <\/span>In which of the following SDLC phases would the IS auditor expect to find that controls have been incorporated into system specifications?<\/p>\n<\/div><input type='hidden' name='question_id[]' value='125131' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515471' \/><div class='watu-question-choice'><input type='radio' name='answer-125131[]' id='answer-id-515471' class='answer answer-44  answerof-125131' value='515471' \/>&nbsp;<label for='answer-id-515471' id='answer-label-515471' class=' answer label-44'><span class='answer'>Development<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515472' \/><div class='watu-question-choice'><input type='radio' name='answer-125131[]' id='answer-id-515472' class='answer answer-44  answerof-125131' value='515472' \/>&nbsp;<label for='answer-id-515472' id='answer-label-515472' class=' answer label-44'><span class='answer'>Implementation<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515473' \/><div class='watu-question-choice'><input type='radio' name='answer-125131[]' id='answer-id-515473' class='answer answer-44  answerof-125131' value='515473' \/>&nbsp;<label for='answer-id-515473' id='answer-label-515473' class=' answer label-44'><span class='answer'>Design<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515474' \/><div class='watu-question-choice'><input type='radio' name='answer-125131[]' id='answer-id-515474' class='answer answer-44  answerof-125131' value='515474' \/>&nbsp;<label for='answer-id-515474' id='answer-label-515474' class=' answer label-44'><span class='answer'>Feasibility<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType44' value='radio' class=''><\/div><div class='watu-question' id='question-45'><div class='question-content'><p><span class='watu_num'>45. <\/span>An IS auditor has been invited to join an IT project team responsible for building and deploying a new digital customer marketing platform.<br \/>\n<br \/>Which of the following is the BEST way for the auditor to support this project while maintaining independence?<\/p>\n<\/div><input type='hidden' name='question_id[]' value='125132' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515475' \/><div class='watu-question-choice'><input type='radio' name='answer-125132[]' id='answer-id-515475' class='answer answer-45  answerof-125132' value='515475' \/>&nbsp;<label for='answer-id-515475' id='answer-label-515475' class=' answer label-45'><span class='answer'>Develop selection criteria for potential digital technology vendors.<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515476' \/><div class='watu-question-choice'><input type='radio' name='answer-125132[]' id='answer-id-515476' class='answer answer-45  answerof-125132' value='515476' \/>&nbsp;<label for='answer-id-515476' id='answer-label-515476' class=' answer label-45'><span class='answer'>Conduct an industry peer benchmarking exercise and advise on alternative solutions.<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515477' \/><div class='watu-question-choice'><input type='radio' name='answer-125132[]' id='answer-id-515477' class='answer answer-45  answerof-125132' value='515477' \/>&nbsp;<label for='answer-id-515477' id='answer-label-515477' class=' answer label-45'><span class='answer'>Conduct a risk assessment of the proposed initiative.<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515478' \/><div class='watu-question-choice'><input type='radio' name='answer-125132[]' id='answer-id-515478' class='answer answer-45  answerof-125132' value='515478' \/>&nbsp;<label for='answer-id-515478' id='answer-label-515478' class=' answer label-45'><span class='answer'>Design controls based on current regulatory requirements for digital technologies.<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType45' value='radio' class=''><\/div><div class='watu-question' id='question-46'><div class='question-content'><p><span class='watu_num'>46. <\/span>An IS auditor observes a system performance monitoring tool which states that a server critical to the organization averages high CPU utilization across a cluster of four virtual servers throughout the audit period. To determine if further investigation is required, an IS auditor should review:<\/p>\n<\/div><input type='hidden' name='question_id[]' value='125133' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515479' \/><div class='watu-question-choice'><input type='radio' name='answer-125133[]' id='answer-id-515479' class='answer answer-46  answerof-125133' value='515479' \/>&nbsp;<label for='answer-id-515479' id='answer-label-515479' class=' answer label-46'><span class='answer'>the system process activity log<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515480' \/><div class='watu-question-choice'><input type='radio' name='answer-125133[]' id='answer-id-515480' class='answer answer-46  answerof-125133' value='515480' \/>&nbsp;<label for='answer-id-515480' id='answer-label-515480' class=' answer label-46'><span class='answer'>system baselines<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515481' \/><div class='watu-question-choice'><input type='radio' name='answer-125133[]' id='answer-id-515481' class='answer answer-46  answerof-125133' value='515481' \/>&nbsp;<label for='answer-id-515481' id='answer-label-515481' class=' answer label-46'><span class='answer'>the number of CPUs allocated to each virtual machine<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515482' \/><div class='watu-question-choice'><input type='radio' name='answer-125133[]' id='answer-id-515482' class='answer answer-46  answerof-125133' value='515482' \/>&nbsp;<label for='answer-id-515482' id='answer-label-515482' class=' answer label-46'><span class='answer'>organizational objectives<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType46' value='radio' class=''><\/div><div class='watu-question' id='question-47'><div class='question-content'><p><span class='watu_num'>47. <\/span>An IS auditor has discovered that a cloud-based application was not included in an application inventory that was used to confirm the scope of an audit. The business process owner explained that the application will be audited by a third party in the next year.<br \/>\n<br \/>The auditor\u2019s NEXT step should be to:<\/p>\n<\/div><input type='hidden' name='question_id[]' value='125134' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515483' \/><div class='watu-question-choice'><input type='radio' name='answer-125134[]' id='answer-id-515483' class='answer answer-47  answerof-125134' value='515483' \/>&nbsp;<label for='answer-id-515483' id='answer-label-515483' class=' answer label-47'><span class='answer'>evaluate the impact of the cloud application on the audit scope<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515484' \/><div class='watu-question-choice'><input type='radio' name='answer-125134[]' id='answer-id-515484' class='answer answer-47  answerof-125134' value='515484' \/>&nbsp;<label for='answer-id-515484' id='answer-label-515484' class=' answer label-47'><span class='answer'>revise the audit scope to include the cloud-based application<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515485' \/><div class='watu-question-choice'><input type='radio' name='answer-125134[]' id='answer-id-515485' class='answer answer-47  answerof-125134' value='515485' \/>&nbsp;<label for='answer-id-515485' id='answer-label-515485' class=' answer label-47'><span class='answer'>review the audit report when performed by the third party<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515486' \/><div class='watu-question-choice'><input type='radio' name='answer-125134[]' id='answer-id-515486' class='answer answer-47  answerof-125134' value='515486' \/>&nbsp;<label for='answer-id-515486' id='answer-label-515486' class=' answer label-47'><span class='answer'>report the control deficiency to senior management<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType47' value='radio' class=''><\/div><div class='watu-question' id='question-48'><div class='question-content'><p><span class='watu_num'>48. <\/span>Which of the following should MOST concern an IS auditor reviewing an intrusion detection system (IDS)?<\/p>\n<\/div><input type='hidden' name='question_id[]' value='125135' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515487' \/><div class='watu-question-choice'><input type='radio' name='answer-125135[]' id='answer-id-515487' class='answer answer-48  answerof-125135' value='515487' \/>&nbsp;<label for='answer-id-515487' id='answer-label-515487' class=' answer label-48'><span class='answer'>Number of false-negatives<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515488' \/><div class='watu-question-choice'><input type='radio' name='answer-125135[]' id='answer-id-515488' class='answer answer-48  answerof-125135' value='515488' \/>&nbsp;<label for='answer-id-515488' id='answer-label-515488' class=' answer label-48'><span class='answer'>Number of false-positives<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515489' \/><div class='watu-question-choice'><input type='radio' name='answer-125135[]' id='answer-id-515489' class='answer answer-48  answerof-125135' value='515489' \/>&nbsp;<label for='answer-id-515489' id='answer-label-515489' class=' answer label-48'><span class='answer'>Legitimate traffic blocked by the system<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515490' \/><div class='watu-question-choice'><input type='radio' name='answer-125135[]' id='answer-id-515490' class='answer answer-48  answerof-125135' value='515490' \/>&nbsp;<label for='answer-id-515490' id='answer-label-515490' class=' answer label-48'><span class='answer'>Reliability of IDS logs<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType48' value='radio' class=''><\/div><div class='watu-question' id='question-49'><div class='question-content'><p><span class='watu_num'>49. <\/span>Multiple invoices are usually received for individual purchase orders, since purchase orders require staggered delivery dates.<br \/>\n<br \/>Which of the following is the BEST audit technique to test for duplicate payments?<\/p>\n<\/div><input type='hidden' name='question_id[]' value='125136' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515491' \/><div class='watu-question-choice'><input type='radio' name='answer-125136[]' id='answer-id-515491' class='answer answer-49  answerof-125136' value='515491' \/>&nbsp;<label for='answer-id-515491' id='answer-label-515491' class=' answer label-49'><span class='answer'>Run the data on the software programs used to process supplier payments.<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515492' \/><div class='watu-question-choice'><input type='radio' name='answer-125136[]' id='answer-id-515492' class='answer answer-49  answerof-125136' value='515492' \/>&nbsp;<label for='answer-id-515492' id='answer-label-515492' class=' answer label-49'><span class='answer'>Use generalized audit software on the invoice transaction file.<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515493' \/><div class='watu-question-choice'><input type='radio' name='answer-125136[]' id='answer-id-515493' class='answer answer-49  answerof-125136' value='515493' \/>&nbsp;<label for='answer-id-515493' id='answer-label-515493' class=' answer label-49'><span class='answer'>Run the data on the software programs used to process purchase orders.<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515494' \/><div class='watu-question-choice'><input type='radio' name='answer-125136[]' id='answer-id-515494' class='answer answer-49  answerof-125136' value='515494' \/>&nbsp;<label for='answer-id-515494' id='answer-label-515494' class=' answer label-49'><span class='answer'>Use generalized audit software on the purchase order transaction file.<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType49' value='radio' class=''><\/div><div class='watu-question' id='question-50'><div class='question-content'><p><span class='watu_num'>50. <\/span>An IS auditor considering the risks associated with spooling sensitive reports for off-line printing will be the MOST concerned that:<\/p>\n<\/div><input type='hidden' name='question_id[]' value='125137' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515495' \/><div class='watu-question-choice'><input type='radio' name='answer-125137[]' id='answer-id-515495' class='answer answer-50  answerof-125137' value='515495' \/>&nbsp;<label for='answer-id-515495' id='answer-label-515495' class=' answer label-50'><span class='answer'>data can easily be read by operators<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515496' \/><div class='watu-question-choice'><input type='radio' name='answer-125137[]' id='answer-id-515496' class='answer answer-50  answerof-125137' value='515496' \/>&nbsp;<label for='answer-id-515496' id='answer-label-515496' class=' answer label-50'><span class='answer'>data can more easily be amended by unauthorized persons<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515497' \/><div class='watu-question-choice'><input type='radio' name='answer-125137[]' id='answer-id-515497' class='answer answer-50  answerof-125137' value='515497' \/>&nbsp;<label for='answer-id-515497' id='answer-label-515497' class=' answer label-50'><span class='answer'>unauthorized copies of reports can be printed<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515498' \/><div class='watu-question-choice'><input type='radio' name='answer-125137[]' id='answer-id-515498' class='answer answer-50  answerof-125137' value='515498' \/>&nbsp;<label for='answer-id-515498' id='answer-label-515498' class=' answer label-50'><span class='answer'>output will be lost if the system should fail<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType50' value='radio' class=''><\/div><div class='watu-question' id='question-51'><div class='question-content'><p><span class='watu_num'>51. <\/span>In a data center audit, an IS auditor finds that the humidity level is very low.<br \/>\n<br \/>The IS auditor would be MOST concerned because of an expected increase in:<\/p>\n<\/div><input type='hidden' name='question_id[]' value='125138' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515499' \/><div class='watu-question-choice'><input type='radio' name='answer-125138[]' id='answer-id-515499' class='answer answer-51  answerof-125138' value='515499' \/>&nbsp;<label for='answer-id-515499' id='answer-label-515499' class=' answer label-51'><span class='answer'>employee discomfort<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515500' \/><div class='watu-question-choice'><input type='radio' name='answer-125138[]' id='answer-id-515500' class='answer answer-51  answerof-125138' value='515500' \/>&nbsp;<label for='answer-id-515500' id='answer-label-515500' class=' answer label-51'><span class='answer'>risk of fire<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515501' \/><div class='watu-question-choice'><input type='radio' name='answer-125138[]' id='answer-id-515501' class='answer answer-51  answerof-125138' value='515501' \/>&nbsp;<label for='answer-id-515501' id='answer-label-515501' class=' answer label-51'><span class='answer'>static electricity problems<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515502' \/><div class='watu-question-choice'><input type='radio' name='answer-125138[]' id='answer-id-515502' class='answer answer-51  answerof-125138' value='515502' \/>&nbsp;<label for='answer-id-515502' id='answer-label-515502' class=' answer label-51'><span class='answer'>backup tape failures<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType51' value='radio' class=''><\/div><div class='watu-question' id='question-52'><div class='question-content'><p><span class='watu_num'>52. <\/span>Before concluding that internal controls can be relied upon, the IS auditor should:<\/p>\n<\/div><input type='hidden' name='question_id[]' value='125139' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515503' \/><div class='watu-question-choice'><input type='radio' name='answer-125139[]' id='answer-id-515503' class='answer answer-52  answerof-125139' value='515503' \/>&nbsp;<label for='answer-id-515503' id='answer-label-515503' class=' answer label-52'><span class='answer'>discuss the internal control weaknesses with the auditee<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515504' \/><div class='watu-question-choice'><input type='radio' name='answer-125139[]' id='answer-id-515504' class='answer answer-52  answerof-125139' value='515504' \/>&nbsp;<label for='answer-id-515504' id='answer-label-515504' class=' answer label-52'><span class='answer'>document application controls<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515505' \/><div class='watu-question-choice'><input type='radio' name='answer-125139[]' id='answer-id-515505' class='answer answer-52  answerof-125139' value='515505' \/>&nbsp;<label for='answer-id-515505' id='answer-label-515505' class=' answer label-52'><span class='answer'>conduct tests of compliance<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515506' \/><div class='watu-question-choice'><input type='radio' name='answer-125139[]' id='answer-id-515506' class='answer answer-52  answerof-125139' value='515506' \/>&nbsp;<label for='answer-id-515506' id='answer-label-515506' class=' answer label-52'><span class='answer'>document the system of internal control<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType52' value='radio' class=''><\/div><div class='watu-question' id='question-53'><div class='question-content'><p><span class='watu_num'>53. <\/span>The IS auditor has identified a potential fraud perpetrated by the network administrator.<br \/>\n<br \/>The IS auditor should:<\/p>\n<\/div><input type='hidden' name='question_id[]' value='125140' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515507' \/><div class='watu-question-choice'><input type='radio' name='answer-125140[]' id='answer-id-515507' class='answer answer-53  answerof-125140' value='515507' \/>&nbsp;<label for='answer-id-515507' id='answer-label-515507' class=' answer label-53'><span class='answer'>issue a report to ensure a timely resolution<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515508' \/><div class='watu-question-choice'><input type='radio' name='answer-125140[]' id='answer-id-515508' class='answer answer-53  answerof-125140' value='515508' \/>&nbsp;<label for='answer-id-515508' id='answer-label-515508' class=' answer label-53'><span class='answer'>review the audit finding with the audit committee prior to any other discussions<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515509' \/><div class='watu-question-choice'><input type='radio' name='answer-125140[]' id='answer-id-515509' class='answer answer-53  answerof-125140' value='515509' \/>&nbsp;<label for='answer-id-515509' id='answer-label-515509' class=' answer label-53'><span class='answer'>perform more detailed tests prior to disclosing the audit results<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515510' \/><div class='watu-question-choice'><input type='radio' name='answer-125140[]' id='answer-id-515510' class='answer answer-53  answerof-125140' value='515510' \/>&nbsp;<label for='answer-id-515510' id='answer-label-515510' class=' answer label-53'><span class='answer'>share the potential audit finding with the security administrator<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType53' value='radio' class=''><\/div><div class='watu-question' id='question-54'><div class='question-content'><p><span class='watu_num'>54. <\/span>Which of the following should an IS auditor review FIRST when planning a customer data privacy audit?<\/p>\n<\/div><input type='hidden' name='question_id[]' value='125141' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515511' \/><div class='watu-question-choice'><input type='radio' name='answer-125141[]' id='answer-id-515511' class='answer answer-54  answerof-125141' value='515511' \/>&nbsp;<label for='answer-id-515511' id='answer-label-515511' class=' answer label-54'><span class='answer'>Legal and compliance requirements<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515512' \/><div class='watu-question-choice'><input type='radio' name='answer-125141[]' id='answer-id-515512' class='answer answer-54  answerof-125141' value='515512' \/>&nbsp;<label for='answer-id-515512' id='answer-label-515512' class=' answer label-54'><span class='answer'>Customer agreements<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515513' \/><div class='watu-question-choice'><input type='radio' name='answer-125141[]' id='answer-id-515513' class='answer answer-54  answerof-125141' value='515513' \/>&nbsp;<label for='answer-id-515513' id='answer-label-515513' class=' answer label-54'><span class='answer'>Organizational policies and procedures<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515514' \/><div class='watu-question-choice'><input type='radio' name='answer-125141[]' id='answer-id-515514' class='answer answer-54  answerof-125141' value='515514' \/>&nbsp;<label for='answer-id-515514' id='answer-label-515514' class=' answer label-54'><span class='answer'>Data classification<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType54' value='radio' class=''><\/div><div class='watu-question' id='question-55'><div class='question-content'><p><span class='watu_num'>55. <\/span>Which of the following should be of MOST concern to an IS auditor reviewing the public key infrastructure (PKI) for enterprise e-mail?<\/p>\n<\/div><input type='hidden' name='question_id[]' value='125142' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515515' \/><div class='watu-question-choice'><input type='radio' name='answer-125142[]' id='answer-id-515515' class='answer answer-55  answerof-125142' value='515515' \/>&nbsp;<label for='answer-id-515515' id='answer-label-515515' class=' answer label-55'><span class='answer'>The private key certificate has not been updated.<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515516' \/><div class='watu-question-choice'><input type='radio' name='answer-125142[]' id='answer-id-515516' class='answer answer-55  answerof-125142' value='515516' \/>&nbsp;<label for='answer-id-515516' id='answer-label-515516' class=' answer label-55'><span class='answer'>The certificate revocation list has not been updated.<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515517' \/><div class='watu-question-choice'><input type='radio' name='answer-125142[]' id='answer-id-515517' class='answer answer-55  answerof-125142' value='515517' \/>&nbsp;<label for='answer-id-515517' id='answer-label-515517' class=' answer label-55'><span class='answer'>The certificate practice statement has not been published.<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515518' \/><div class='watu-question-choice'><input type='radio' name='answer-125142[]' id='answer-id-515518' class='answer answer-55  answerof-125142' value='515518' \/>&nbsp;<label for='answer-id-515518' id='answer-label-515518' class=' answer label-55'><span class='answer'>The PKI policy has not been updated within the last year.<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType55' value='radio' class=''><\/div><div class='watu-question' id='question-56'><div class='question-content'><p><span class='watu_num'>56. <\/span>Which of the following should be established FIRST when initiating a control self-assessment program in a small organization?<\/p>\n<\/div><input type='hidden' name='question_id[]' value='125143' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515519' \/><div class='watu-question-choice'><input type='radio' name='answer-125143[]' id='answer-id-515519' class='answer answer-56  answerof-125143' value='515519' \/>&nbsp;<label for='answer-id-515519' id='answer-label-515519' class=' answer label-56'><span class='answer'>Control baselines<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515520' \/><div class='watu-question-choice'><input type='radio' name='answer-125143[]' id='answer-id-515520' class='answer answer-56  answerof-125143' value='515520' \/>&nbsp;<label for='answer-id-515520' id='answer-label-515520' class=' answer label-56'><span class='answer'>Client questionnaires<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515521' \/><div class='watu-question-choice'><input type='radio' name='answer-125143[]' id='answer-id-515521' class='answer answer-56  answerof-125143' value='515521' \/>&nbsp;<label for='answer-id-515521' id='answer-label-515521' class=' answer label-56'><span class='answer'>External consultants<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515522' \/><div class='watu-question-choice'><input type='radio' name='answer-125143[]' id='answer-id-515522' class='answer answer-56  answerof-125143' value='515522' \/>&nbsp;<label for='answer-id-515522' id='answer-label-515522' class=' answer label-56'><span class='answer'>Facilitated workshops<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType56' value='radio' class=''><\/div><div class='watu-question' id='question-57'><div class='question-content'><p><span class='watu_num'>57. <\/span>What is an IS auditor\u2019s BEST course of action if informed by a business unit\u2019s representatives that they are too busy to cooperate with a scheduled audit?<\/p>\n<\/div><input type='hidden' name='question_id[]' value='125144' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515523' \/><div class='watu-question-choice'><input type='radio' name='answer-125144[]' id='answer-id-515523' class='answer answer-57  answerof-125144' value='515523' \/>&nbsp;<label for='answer-id-515523' id='answer-label-515523' class=' answer label-57'><span class='answer'>Reschedule the audit for a time more convenient to the business unit.<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515524' \/><div class='watu-question-choice'><input type='radio' name='answer-125144[]' id='answer-id-515524' class='answer answer-57  answerof-125144' value='515524' \/>&nbsp;<label for='answer-id-515524' id='answer-label-515524' class=' answer label-57'><span class='answer'>Notify the chief audit executive who can negotiate with the head of the business unit.<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515525' \/><div class='watu-question-choice'><input type='radio' name='answer-125144[]' id='answer-id-515525' class='answer answer-57  answerof-125144' value='515525' \/>&nbsp;<label for='answer-id-515525' id='answer-label-515525' class=' answer label-57'><span class='answer'>Begin the audit regardless and insist on cooperation from the business unit.<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515526' \/><div class='watu-question-choice'><input type='radio' name='answer-125144[]' id='answer-id-515526' class='answer answer-57  answerof-125144' value='515526' \/>&nbsp;<label for='answer-id-515526' id='answer-label-515526' class=' answer label-57'><span class='answer'>Notify the audit committee immediately and request they direct the audit begin on schedule.<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType57' value='radio' class=''><\/div><div class='watu-question' id='question-58'><div class='question-content'><p><span class='watu_num'>58. <\/span>An IS auditor has completed an audit of an organization\u2019s accounts payable system.<br \/>\n<br \/>Which of the following should be rated as the HIGHEST risk in the audit report and requires immediate remediation?<\/p>\n<\/div><input type='hidden' name='question_id[]' value='125145' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515527' \/><div class='watu-question-choice'><input type='radio' name='answer-125145[]' id='answer-id-515527' class='answer answer-58  answerof-125145' value='515527' \/>&nbsp;<label for='answer-id-515527' id='answer-label-515527' class=' answer label-58'><span class='answer'>Lack of segregation of duty controls for reconciliation of payment transactions<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515528' \/><div class='watu-question-choice'><input type='radio' name='answer-125145[]' id='answer-id-515528' class='answer answer-58  answerof-125145' value='515528' \/>&nbsp;<label for='answer-id-515528' id='answer-label-515528' class=' answer label-58'><span class='answer'>Lack of segregation of duty controls for removal of vendor records<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515529' \/><div class='watu-question-choice'><input type='radio' name='answer-125145[]' id='answer-id-515529' class='answer answer-58  answerof-125145' value='515529' \/>&nbsp;<label for='answer-id-515529' id='answer-label-515529' class=' answer label-58'><span class='answer'>Lack of segregation of duty controls for updating the vendor master file<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515530' \/><div class='watu-question-choice'><input type='radio' name='answer-125145[]' id='answer-id-515530' class='answer answer-58  answerof-125145' value='515530' \/>&nbsp;<label for='answer-id-515530' id='answer-label-515530' class=' answer label-58'><span class='answer'>Lack of segregation of duty controls for reversing payment transactions<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType58' value='radio' class=''><\/div><div class='watu-question' id='question-59'><div class='question-content'><p><span class='watu_num'>59. <\/span>An IS auditor is planning on utilizing attribute sampling to determine the error rate for health care claims processed.<br \/>\n<br \/>Which of the following factors will cause the sample size to decrease?<\/p>\n<\/div><input type='hidden' name='question_id[]' value='125146' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515531' \/><div class='watu-question-choice'><input type='radio' name='answer-125146[]' id='answer-id-515531' class='answer answer-59  answerof-125146' value='515531' \/>&nbsp;<label for='answer-id-515531' id='answer-label-515531' class=' answer label-59'><span class='answer'>Population size increase<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515532' \/><div class='watu-question-choice'><input type='radio' name='answer-125146[]' id='answer-id-515532' class='answer answer-59  answerof-125146' value='515532' \/>&nbsp;<label for='answer-id-515532' id='answer-label-515532' class=' answer label-59'><span class='answer'>Expected error rate increase<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515533' \/><div class='watu-question-choice'><input type='radio' name='answer-125146[]' id='answer-id-515533' class='answer answer-59  answerof-125146' value='515533' \/>&nbsp;<label for='answer-id-515533' id='answer-label-515533' class=' answer label-59'><span class='answer'>Acceptable risk level decrease<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515534' \/><div class='watu-question-choice'><input type='radio' name='answer-125146[]' id='answer-id-515534' class='answer answer-59  answerof-125146' value='515534' \/>&nbsp;<label for='answer-id-515534' id='answer-label-515534' class=' answer label-59'><span class='answer'>Tolerate error rate increase<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType59' value='radio' class=''><\/div><div class='watu-question' id='question-60'><div class='question-content'><p><span class='watu_num'>60. <\/span>Which of the following is the PRIMARY benefit of using an integrated audit approach?<\/p>\n<\/div><input type='hidden' name='question_id[]' value='125147' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515535' \/><div class='watu-question-choice'><input type='radio' name='answer-125147[]' id='answer-id-515535' class='answer answer-60  answerof-125147' value='515535' \/>&nbsp;<label for='answer-id-515535' id='answer-label-515535' class=' answer label-60'><span class='answer'>Higher acceptance of the findings from the audited business areas<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515536' \/><div class='watu-question-choice'><input type='radio' name='answer-125147[]' id='answer-id-515536' class='answer answer-60  answerof-125147' value='515536' \/>&nbsp;<label for='answer-id-515536' id='answer-label-515536' class=' answer label-60'><span class='answer'>The avoidance of duplicated work and redundant recommendations<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515537' \/><div class='watu-question-choice'><input type='radio' name='answer-125147[]' id='answer-id-515537' class='answer answer-60  answerof-125147' value='515537' \/>&nbsp;<label for='answer-id-515537' id='answer-label-515537' class=' answer label-60'><span class='answer'>Enhanced allocation of resources and reduced audit costs<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515538' \/><div class='watu-question-choice'><input type='radio' name='answer-125147[]' id='answer-id-515538' class='answer answer-60  answerof-125147' value='515538' \/>&nbsp;<label for='answer-id-515538' id='answer-label-515538' class=' answer label-60'><span class='answer'>A holistic perspective of overall risk and a better understanding of controls<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType60' value='radio' class=''><\/div><div class='watu-question' id='question-61'><div class='question-content'><p><span class='watu_num'>61. <\/span>Which of the following is an analytical review procedure for a payroll system?<\/p>\n<\/div><input type='hidden' name='question_id[]' value='125148' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515539' \/><div class='watu-question-choice'><input type='radio' name='answer-125148[]' id='answer-id-515539' class='answer answer-61  answerof-125148' value='515539' \/>&nbsp;<label for='answer-id-515539' id='answer-label-515539' class=' answer label-61'><span class='answer'>Performing penetration attempts on the payroll system<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515540' \/><div class='watu-question-choice'><input type='radio' name='answer-125148[]' id='answer-id-515540' class='answer answer-61  answerof-125148' value='515540' \/>&nbsp;<label for='answer-id-515540' id='answer-label-515540' class=' answer label-61'><span class='answer'>Evaluating the performance of the payroll system, using benchmarking software<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515541' \/><div class='watu-question-choice'><input type='radio' name='answer-125148[]' id='answer-id-515541' class='answer answer-61  answerof-125148' value='515541' \/>&nbsp;<label for='answer-id-515541' id='answer-label-515541' class=' answer label-61'><span class='answer'>Performing reasonableness tests by multiplying the number of employees by the average wage rate<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515542' \/><div class='watu-question-choice'><input type='radio' name='answer-125148[]' id='answer-id-515542' class='answer answer-61  answerof-125148' value='515542' \/>&nbsp;<label for='answer-id-515542' id='answer-label-515542' class=' answer label-61'><span class='answer'>Testing hours reported on time sheets<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType61' value='radio' class=''><\/div><div class='watu-question' id='question-62'><div class='question-content'><p><span class='watu_num'>62. <\/span>An IS auditor observes that the CEO has full access to the enterprise resource planning (ERP) system. The IS auditor should FIRST:<\/p>\n<\/div><input type='hidden' name='question_id[]' value='125149' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515543' \/><div class='watu-question-choice'><input type='radio' name='answer-125149[]' id='answer-id-515543' class='answer answer-62  answerof-125149' value='515543' \/>&nbsp;<label for='answer-id-515543' id='answer-label-515543' class=' answer label-62'><span class='answer'>accept the level of access provided as appropriate<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515544' \/><div class='watu-question-choice'><input type='radio' name='answer-125149[]' id='answer-id-515544' class='answer answer-62  answerof-125149' value='515544' \/>&nbsp;<label for='answer-id-515544' id='answer-label-515544' class=' answer label-62'><span class='answer'>recommend that the privilege be removed<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515545' \/><div class='watu-question-choice'><input type='radio' name='answer-125149[]' id='answer-id-515545' class='answer answer-62  answerof-125149' value='515545' \/>&nbsp;<label for='answer-id-515545' id='answer-label-515545' class=' answer label-62'><span class='answer'>ignore the observation as not being material to the review<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515546' \/><div class='watu-question-choice'><input type='radio' name='answer-125149[]' id='answer-id-515546' class='answer answer-62  answerof-125149' value='515546' \/>&nbsp;<label for='answer-id-515546' id='answer-label-515546' class=' answer label-62'><span class='answer'>document the finding as a potential risk<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType62' value='radio' class=''><\/div><div class='watu-question' id='question-63'><div class='question-content'><p><span class='watu_num'>63. <\/span>Two servers are deployed in a cluster to run a mission-critical application.<br \/>\n<br \/>To determine whether the system has been designed for optimal efficiency, the IS auditor should verify that:<\/p>\n<\/div><input type='hidden' name='question_id[]' value='125150' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515547' \/><div class='watu-question-choice'><input type='radio' name='answer-125150[]' id='answer-id-515547' class='answer answer-63  answerof-125150' value='515547' \/>&nbsp;<label for='answer-id-515547' id='answer-label-515547' class=' answer label-63'><span class='answer'>the security features in the operating system are all enabled<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515548' \/><div class='watu-question-choice'><input type='radio' name='answer-125150[]' id='answer-id-515548' class='answer answer-63  answerof-125150' value='515548' \/>&nbsp;<label for='answer-id-515548' id='answer-label-515548' class=' answer label-63'><span class='answer'>the number of disks in the cluster meets minimum requirements<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515549' \/><div class='watu-question-choice'><input type='radio' name='answer-125150[]' id='answer-id-515549' class='answer answer-63  answerof-125150' value='515549' \/>&nbsp;<label for='answer-id-515549' id='answer-label-515549' class=' answer label-63'><span class='answer'>the two servers are of exactly the same configuration<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515550' \/><div class='watu-question-choice'><input type='radio' name='answer-125150[]' id='answer-id-515550' class='answer answer-63  answerof-125150' value='515550' \/>&nbsp;<label for='answer-id-515550' id='answer-label-515550' class=' answer label-63'><span class='answer'>load balancing between the servers has been implemented<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType63' value='radio' class=''><\/div><div class='watu-question' id='question-64'><div class='question-content'><p><span class='watu_num'>64. <\/span>The GREATEST risk when performing data normalization is:<\/p>\n<\/div><input type='hidden' name='question_id[]' value='125151' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515551' \/><div class='watu-question-choice'><input type='radio' name='answer-125151[]' id='answer-id-515551' class='answer answer-64  answerof-125151' value='515551' \/>&nbsp;<label for='answer-id-515551' id='answer-label-515551' class=' answer label-64'><span class='answer'>the increased complexity of the data model<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515552' \/><div class='watu-question-choice'><input type='radio' name='answer-125151[]' id='answer-id-515552' class='answer answer-64  answerof-125151' value='515552' \/>&nbsp;<label for='answer-id-515552' id='answer-label-515552' class=' answer label-64'><span class='answer'>duplication of audit logs<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515553' \/><div class='watu-question-choice'><input type='radio' name='answer-125151[]' id='answer-id-515553' class='answer answer-64  answerof-125151' value='515553' \/>&nbsp;<label for='answer-id-515553' id='answer-label-515553' class=' answer label-64'><span class='answer'>reduced data redundancy<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515554' \/><div class='watu-question-choice'><input type='radio' name='answer-125151[]' id='answer-id-515554' class='answer answer-64  answerof-125151' value='515554' \/>&nbsp;<label for='answer-id-515554' id='answer-label-515554' class=' answer label-64'><span class='answer'>decreased performance<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType64' value='radio' class=''><\/div><div class='watu-question' id='question-65'><div class='question-content'><p><span class='watu_num'>65. <\/span>An IS auditor has found that a vendor has gone out of business and the escrow has an older version of the source code.<br \/>\n<br \/>What is the auditor\u2019s BEST recommendation for the organization?<\/p>\n<\/div><input type='hidden' name='question_id[]' value='125152' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515555' \/><div class='watu-question-choice'><input type='radio' name='answer-125152[]' id='answer-id-515555' class='answer answer-65  answerof-125152' value='515555' \/>&nbsp;<label for='answer-id-515555' id='answer-label-515555' class=' answer label-65'><span class='answer'>Continue using the existing application since it meets the current requirements<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515556' \/><div class='watu-question-choice'><input type='radio' name='answer-125152[]' id='answer-id-515556' class='answer answer-65  answerof-125152' value='515556' \/>&nbsp;<label for='answer-id-515556' id='answer-label-515556' class=' answer label-65'><span class='answer'>Prepare a maintenance plan that will support the application using the existing code<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515557' \/><div class='watu-question-choice'><input type='radio' name='answer-125152[]' id='answer-id-515557' class='answer answer-65  answerof-125152' value='515557' \/>&nbsp;<label for='answer-id-515557' id='answer-label-515557' class=' answer label-65'><span class='answer'>Bring the escrow version up to date<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515558' \/><div class='watu-question-choice'><input type='radio' name='answer-125152[]' id='answer-id-515558' class='answer answer-65  answerof-125152' value='515558' \/>&nbsp;<label for='answer-id-515558' id='answer-label-515558' class=' answer label-65'><span class='answer'>Undertake an analysis to determine the business risk<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType65' value='radio' class=''><\/div><div class='watu-question' id='question-66'><div class='question-content'><p><span class='watu_num'>66. <\/span>Which of the following is the BEST way to evaluate the effectiveness of access controls to an internal network?<\/p>\n<\/div><input type='hidden' name='question_id[]' value='125153' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515559' \/><div class='watu-question-choice'><input type='radio' name='answer-125153[]' id='answer-id-515559' class='answer answer-66  answerof-125153' value='515559' \/>&nbsp;<label for='answer-id-515559' id='answer-label-515559' class=' answer label-66'><span class='answer'>Perform a system penetration test<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515560' \/><div class='watu-question-choice'><input type='radio' name='answer-125153[]' id='answer-id-515560' class='answer answer-66  answerof-125153' value='515560' \/>&nbsp;<label for='answer-id-515560' id='answer-label-515560' class=' answer label-66'><span class='answer'>Test compliance with operating procedures<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515561' \/><div class='watu-question-choice'><input type='radio' name='answer-125153[]' id='answer-id-515561' class='answer answer-66  answerof-125153' value='515561' \/>&nbsp;<label for='answer-id-515561' id='answer-label-515561' class=' answer label-66'><span class='answer'>Review access rights<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515562' \/><div class='watu-question-choice'><input type='radio' name='answer-125153[]' id='answer-id-515562' class='answer answer-66  answerof-125153' value='515562' \/>&nbsp;<label for='answer-id-515562' id='answer-label-515562' class=' answer label-66'><span class='answer'>Review router configuration tables<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType66' value='radio' class=''><\/div><div class='watu-question' id='question-67'><div class='question-content'><p><span class='watu_num'>67. <\/span>An IS auditor finds a number of system accounts that do not have documented approvals.<br \/>\n<br \/>Which of the following should be performed FIRST by the auditor?<\/p>\n<\/div><input type='hidden' name='question_id[]' value='125154' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515563' \/><div class='watu-question-choice'><input type='radio' name='answer-125154[]' id='answer-id-515563' class='answer answer-67  answerof-125154' value='515563' \/>&nbsp;<label for='answer-id-515563' id='answer-label-515563' class=' answer label-67'><span class='answer'>Have the accounts removed immediately<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515564' \/><div class='watu-question-choice'><input type='radio' name='answer-125154[]' id='answer-id-515564' class='answer answer-67  answerof-125154' value='515564' \/>&nbsp;<label for='answer-id-515564' id='answer-label-515564' class=' answer label-67'><span class='answer'>Obtain sign-off on the accounts from the application owner<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515565' \/><div class='watu-question-choice'><input type='radio' name='answer-125154[]' id='answer-id-515565' class='answer answer-67  answerof-125154' value='515565' \/>&nbsp;<label for='answer-id-515565' id='answer-label-515565' class=' answer label-67'><span class='answer'>Document a finding and report an ineffective account provisioning control<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515566' \/><div class='watu-question-choice'><input type='radio' name='answer-125154[]' id='answer-id-515566' class='answer answer-67  answerof-125154' value='515566' \/>&nbsp;<label for='answer-id-515566' id='answer-label-515566' class=' answer label-67'><span class='answer'>Determine the purpose and risk of the accounts<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType67' value='radio' class=''><\/div><div class='watu-question' id='question-68'><div class='question-content'><p><span class='watu_num'>68. <\/span>An IS auditor is a member of an application development team that is selecting software.<br \/>\n<br \/>Which of the following would impair the auditor\u2019s independence?<\/p>\n<\/div><input type='hidden' name='question_id[]' value='125155' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515567' \/><div class='watu-question-choice'><input type='radio' name='answer-125155[]' id='answer-id-515567' class='answer answer-68  answerof-125155' value='515567' \/>&nbsp;<label for='answer-id-515567' id='answer-label-515567' class=' answer label-68'><span class='answer'>Verifying the weighting of each selection criteria<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515568' \/><div class='watu-question-choice'><input type='radio' name='answer-125155[]' id='answer-id-515568' class='answer answer-68  answerof-125155' value='515568' \/>&nbsp;<label for='answer-id-515568' id='answer-label-515568' class=' answer label-68'><span class='answer'>Approving the vendor selection methodology<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515569' \/><div class='watu-question-choice'><input type='radio' name='answer-125155[]' id='answer-id-515569' class='answer answer-68  answerof-125155' value='515569' \/>&nbsp;<label for='answer-id-515569' id='answer-label-515569' class=' answer label-68'><span class='answer'>Reviewing the request for proposal (RFP)<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515570' \/><div class='watu-question-choice'><input type='radio' name='answer-125155[]' id='answer-id-515570' class='answer answer-68  answerof-125155' value='515570' \/>&nbsp;<label for='answer-id-515570' id='answer-label-515570' class=' answer label-68'><span class='answer'>Witnessing the vendor selection process<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType68' value='radio' class=''><\/div><div class='watu-question' id='question-69'><div class='question-content'><p><span class='watu_num'>69. <\/span>An internal control audit has revealed a control deficiency related to a legacy system where the compensating controls no longer appear to be effective.<br \/>\n<br \/>Which of the following would BEST help the information security manager determine the security requirements to resolve the control deficiency?<\/p>\n<\/div><input type='hidden' name='question_id[]' value='125156' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515571' \/><div class='watu-question-choice'><input type='radio' name='answer-125156[]' id='answer-id-515571' class='answer answer-69  answerof-125156' value='515571' \/>&nbsp;<label for='answer-id-515571' id='answer-label-515571' class=' answer label-69'><span class='answer'>Cost-benefit analysis<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515572' \/><div class='watu-question-choice'><input type='radio' name='answer-125156[]' id='answer-id-515572' class='answer answer-69  answerof-125156' value='515572' \/>&nbsp;<label for='answer-id-515572' id='answer-label-515572' class=' answer label-69'><span class='answer'>Gap analysis<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515573' \/><div class='watu-question-choice'><input type='radio' name='answer-125156[]' id='answer-id-515573' class='answer answer-69  answerof-125156' value='515573' \/>&nbsp;<label for='answer-id-515573' id='answer-label-515573' class=' answer label-69'><span class='answer'>Risk assessment<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515574' \/><div class='watu-question-choice'><input type='radio' name='answer-125156[]' id='answer-id-515574' class='answer answer-69  answerof-125156' value='515574' \/>&nbsp;<label for='answer-id-515574' id='answer-label-515574' class=' answer label-69'><span class='answer'>Business case<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType69' value='radio' class=''><\/div><div class='watu-question' id='question-70'><div class='question-content'><p><span class='watu_num'>70. <\/span>An audit of the quality management system (QMS) begins with an evaluation of the:<\/p>\n<\/div><input type='hidden' name='question_id[]' value='125157' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515575' \/><div class='watu-question-choice'><input type='radio' name='answer-125157[]' id='answer-id-515575' class='answer answer-70  answerof-125157' value='515575' \/>&nbsp;<label for='answer-id-515575' id='answer-label-515575' class=' answer label-70'><span class='answer'>organization\u2019s QMS policy<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515576' \/><div class='watu-question-choice'><input type='radio' name='answer-125157[]' id='answer-id-515576' class='answer answer-70  answerof-125157' value='515576' \/>&nbsp;<label for='answer-id-515576' id='answer-label-515576' class=' answer label-70'><span class='answer'>sequence and interaction of QMS processes<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515577' \/><div class='watu-question-choice'><input type='radio' name='answer-125157[]' id='answer-id-515577' class='answer answer-70  answerof-125157' value='515577' \/>&nbsp;<label for='answer-id-515577' id='answer-label-515577' class=' answer label-70'><span class='answer'>QMS processes and their application<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515578' \/><div class='watu-question-choice'><input type='radio' name='answer-125157[]' id='answer-id-515578' class='answer answer-70  answerof-125157' value='515578' \/>&nbsp;<label for='answer-id-515578' id='answer-label-515578' class=' answer label-70'><span class='answer'>QMS document control procedures<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType70' value='radio' class=''><\/div><div class='watu-question' id='question-71'><div class='question-content'><p><span class='watu_num'>71. <\/span>An IS auditor has completed an audit on the organization\u2019s IT strategic planning process.<br \/>\n<br \/>Which of the following findings should be given the HIGHEST priority?<\/p>\n<\/div><input type='hidden' name='question_id[]' value='125158' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515579' \/><div class='watu-question-choice'><input type='radio' name='answer-125158[]' id='answer-id-515579' class='answer answer-71  answerof-125158' value='515579' \/>&nbsp;<label for='answer-id-515579' id='answer-label-515579' class=' answer label-71'><span class='answer'>The IT strategic plan was completed prior to the formulation of the business strategic plan<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515580' \/><div class='watu-question-choice'><input type='radio' name='answer-125158[]' id='answer-id-515580' class='answer answer-71  answerof-125158' value='515580' \/>&nbsp;<label for='answer-id-515580' id='answer-label-515580' class=' answer label-71'><span class='answer'>Assumptions in the IT strategic plan have not been communicated to business stakeholders<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515581' \/><div class='watu-question-choice'><input type='radio' name='answer-125158[]' id='answer-id-515581' class='answer answer-71  answerof-125158' value='515581' \/>&nbsp;<label for='answer-id-515581' id='answer-label-515581' class=' answer label-71'><span class='answer'>The IT strategic plan was formulated based on the current IT capabilities<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515582' \/><div class='watu-question-choice'><input type='radio' name='answer-125158[]' id='answer-id-515582' class='answer answer-71  answerof-125158' value='515582' \/>&nbsp;<label for='answer-id-515582' id='answer-label-515582' class=' answer label-71'><span class='answer'>The IT strategic plan does not include resource requirements for implementation<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType71' value='radio' class=''><\/div><div class='watu-question' id='question-72'><div class='question-content'><p><span class='watu_num'>72. <\/span>Which of the following would provide the BEST evidence of successfully completed batch uploads?<\/p>\n<\/div><input type='hidden' name='question_id[]' value='125159' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515583' \/><div class='watu-question-choice'><input type='radio' name='answer-125159[]' id='answer-id-515583' class='answer answer-72  answerof-125159' value='515583' \/>&nbsp;<label for='answer-id-515583' id='answer-label-515583' class=' answer label-72'><span class='answer'>Sign-off on the batch journal<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515584' \/><div class='watu-question-choice'><input type='radio' name='answer-125159[]' id='answer-id-515584' class='answer answer-72  answerof-125159' value='515584' \/>&nbsp;<label for='answer-id-515584' id='answer-label-515584' class=' answer label-72'><span class='answer'>Using sequence controls<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515585' \/><div class='watu-question-choice'><input type='radio' name='answer-125159[]' id='answer-id-515585' class='answer answer-72  answerof-125159' value='515585' \/>&nbsp;<label for='answer-id-515585' id='answer-label-515585' class=' answer label-72'><span class='answer'>Enforcing batch cut-off times<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515586' \/><div class='watu-question-choice'><input type='radio' name='answer-125159[]' id='answer-id-515586' class='answer answer-72  answerof-125159' value='515586' \/>&nbsp;<label for='answer-id-515586' id='answer-label-515586' class=' answer label-72'><span class='answer'>Reviewing process logs<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType72' value='radio' class=''><\/div><div class='watu-question' id='question-73'><div class='question-content'><p><span class='watu_num'>73. <\/span>An IS auditor is conducting a review of a healthcare organization\u2019s IT policies for handling medical records.<br \/>\n<br \/>Which of the following is MOST important to verify?<\/p>\n<\/div><input type='hidden' name='question_id[]' value='125160' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515587' \/><div class='watu-question-choice'><input type='radio' name='answer-125160[]' id='answer-id-515587' class='answer answer-73  answerof-125160' value='515587' \/>&nbsp;<label for='answer-id-515587' id='answer-label-515587' class=' answer label-73'><span class='answer'>A documented policy approval process is in place<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515588' \/><div class='watu-question-choice'><input type='radio' name='answer-125160[]' id='answer-id-515588' class='answer answer-73  answerof-125160' value='515588' \/>&nbsp;<label for='answer-id-515588' id='answer-label-515588' class=' answer label-73'><span class='answer'>Policy writing standards are consistent<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515589' \/><div class='watu-question-choice'><input type='radio' name='answer-125160[]' id='answer-id-515589' class='answer answer-73  answerof-125160' value='515589' \/>&nbsp;<label for='answer-id-515589' id='answer-label-515589' class=' answer label-73'><span class='answer'>The policies comply with regulatory requirements<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515590' \/><div class='watu-question-choice'><input type='radio' name='answer-125160[]' id='answer-id-515590' class='answer answer-73  answerof-125160' value='515590' \/>&nbsp;<label for='answer-id-515590' id='answer-label-515590' class=' answer label-73'><span class='answer'>IT personnel receive ongoing policy training<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType73' value='radio' class=''><\/div><div class='watu-question' id='question-74'><div class='question-content'><p><span class='watu_num'>74. <\/span>Audit management has just completed the annual audit plan for the upcoming year, which consists entirely of high-risk processes.<br \/>\n<br \/>However, it is determined that there are insufficient resources to execute the plan.<br \/>\n<br \/>What should be done NEXT?<\/p>\n<\/div><input type='hidden' name='question_id[]' value='125161' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515591' \/><div class='watu-question-choice'><input type='radio' name='answer-125161[]' id='answer-id-515591' class='answer answer-74  answerof-125161' value='515591' \/>&nbsp;<label for='answer-id-515591' id='answer-label-515591' class=' answer label-74'><span class='answer'>Remove audits from the annual plan to better match the number of resources available<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515592' \/><div class='watu-question-choice'><input type='radio' name='answer-125161[]' id='answer-id-515592' class='answer answer-74  answerof-125161' value='515592' \/>&nbsp;<label for='answer-id-515592' id='answer-label-515592' class=' answer label-74'><span class='answer'>Reduce the scope of the audits to better match the number of resources available<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515593' \/><div class='watu-question-choice'><input type='radio' name='answer-125161[]' id='answer-id-515593' class='answer answer-74  answerof-125161' value='515593' \/>&nbsp;<label for='answer-id-515593' id='answer-label-515593' class=' answer label-74'><span class='answer'>Present the annual plan to the audit committee and ask for more resources<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515594' \/><div class='watu-question-choice'><input type='radio' name='answer-125161[]' id='answer-id-515594' class='answer answer-74  answerof-125161' value='515594' \/>&nbsp;<label for='answer-id-515594' id='answer-label-515594' class=' answer label-74'><span class='answer'>Review the audit plan and defer some audits to the subsequent year<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType74' value='radio' class=''><\/div><div class='watu-question' id='question-75'><div class='question-content'><p><span class='watu_num'>75. <\/span>If concurrent update transactions to an account are not processed properly, which of the following will be affected?<\/p>\n<\/div><input type='hidden' name='question_id[]' value='125162' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515595' \/><div class='watu-question-choice'><input type='radio' name='answer-125162[]' id='answer-id-515595' class='answer answer-75  answerof-125162' value='515595' \/>&nbsp;<label for='answer-id-515595' id='answer-label-515595' class=' answer label-75'><span class='answer'>Integrity<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515596' \/><div class='watu-question-choice'><input type='radio' name='answer-125162[]' id='answer-id-515596' class='answer answer-75  answerof-125162' value='515596' \/>&nbsp;<label for='answer-id-515596' id='answer-label-515596' class=' answer label-75'><span class='answer'>Confidentiality<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515597' \/><div class='watu-question-choice'><input type='radio' name='answer-125162[]' id='answer-id-515597' class='answer answer-75  answerof-125162' value='515597' \/>&nbsp;<label for='answer-id-515597' id='answer-label-515597' class=' answer label-75'><span class='answer'>Availability<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515598' \/><div class='watu-question-choice'><input type='radio' name='answer-125162[]' id='answer-id-515598' class='answer answer-75  answerof-125162' value='515598' \/>&nbsp;<label for='answer-id-515598' id='answer-label-515598' class=' answer label-75'><span class='answer'>Accountability<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType75' value='radio' class=''><\/div><div class='watu-question' id='question-76'><div class='question-content'><p><span class='watu_num'>76. <\/span>When conducting a review of security incident management, an IS auditor found there are no defined escalation processes. All incidents are managed by the service desk.<br \/>\n<br \/>Which of the following should be the auditor\u2019s PRIMARY concern?<\/p>\n<\/div><input type='hidden' name='question_id[]' value='125163' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515599' \/><div class='watu-question-choice'><input type='radio' name='answer-125163[]' id='answer-id-515599' class='answer answer-76  answerof-125163' value='515599' \/>&nbsp;<label for='answer-id-515599' id='answer-label-515599' class=' answer label-76'><span class='answer'>Inefficient use of service desk resources<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515600' \/><div class='watu-question-choice'><input type='radio' name='answer-125163[]' id='answer-id-515600' class='answer answer-76  answerof-125163' value='515600' \/>&nbsp;<label for='answer-id-515600' id='answer-label-515600' class=' answer label-76'><span class='answer'>Management\u2019s lack of high impact incidents<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515601' \/><div class='watu-question-choice'><input type='radio' name='answer-125163[]' id='answer-id-515601' class='answer answer-76  answerof-125163' value='515601' \/>&nbsp;<label for='answer-id-515601' id='answer-label-515601' class=' answer label-76'><span class='answer'>Delays in resolving low priority trouble tickets<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515602' \/><div class='watu-question-choice'><input type='radio' name='answer-125163[]' id='answer-id-515602' class='answer answer-76  answerof-125163' value='515602' \/>&nbsp;<label for='answer-id-515602' id='answer-label-515602' class=' answer label-76'><span class='answer'>Management\u2019s inability to follow up on incident resolution<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType76' value='radio' class=''><\/div><div class='watu-question' id='question-77'><div class='question-content'><p><span class='watu_num'>77. <\/span>Which of the following should an IS auditor be MOST concerned with during a post-implementation review?<\/p>\n<\/div><input type='hidden' name='question_id[]' value='125164' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515603' \/><div class='watu-question-choice'><input type='radio' name='answer-125164[]' id='answer-id-515603' class='answer answer-77  answerof-125164' value='515603' \/>&nbsp;<label for='answer-id-515603' id='answer-label-515603' class=' answer label-77'><span class='answer'>The system does not have a maintenance plan<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515604' \/><div class='watu-question-choice'><input type='radio' name='answer-125164[]' id='answer-id-515604' class='answer answer-77  answerof-125164' value='515604' \/>&nbsp;<label for='answer-id-515604' id='answer-label-515604' class=' answer label-77'><span class='answer'>The system contains several minor defects<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515605' \/><div class='watu-question-choice'><input type='radio' name='answer-125164[]' id='answer-id-515605' class='answer answer-77  answerof-125164' value='515605' \/>&nbsp;<label for='answer-id-515605' id='answer-label-515605' class=' answer label-77'><span class='answer'>The system was over budget by 15%<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515606' \/><div class='watu-question-choice'><input type='radio' name='answer-125164[]' id='answer-id-515606' class='answer answer-77  answerof-125164' value='515606' \/>&nbsp;<label for='answer-id-515606' id='answer-label-515606' class=' answer label-77'><span class='answer'>The system deployment was delayed by three weeks<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType77' value='radio' class=''><\/div><div class='watu-question' id='question-78'><div class='question-content'><p><span class='watu_num'>78. <\/span>An IS auditor is reviewing a bank\u2019s service level agreement (SLA) with a third-party provider that hosts the bank\u2019s secondary data center.<br \/>\n<br \/>Which of the following findings should be of GREATEST concern to the auditor?<\/p>\n<\/div><input type='hidden' name='question_id[]' value='125165' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515607' \/><div class='watu-question-choice'><input type='radio' name='answer-125165[]' id='answer-id-515607' class='answer answer-78  answerof-125165' value='515607' \/>&nbsp;<label for='answer-id-515607' id='answer-label-515607' class=' answer label-78'><span class='answer'>The recovery point objective (RPO) has a shorter duration than documented in the disaster recovery plan<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515608' \/><div class='watu-question-choice'><input type='radio' name='answer-125165[]' id='answer-id-515608' class='answer answer-78  answerof-125165' value='515608' \/>&nbsp;<label for='answer-id-515608' id='answer-label-515608' class=' answer label-78'><span class='answer'>The recovery time objective (RTO) has a longer duration than documented in the disaster recovery plan<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515609' \/><div class='watu-question-choice'><input type='radio' name='answer-125165[]' id='answer-id-515609' class='answer answer-78  answerof-125165' value='515609' \/>&nbsp;<label for='answer-id-515609' id='answer-label-515609' class=' answer label-78'><span class='answer'>Backup data is hosted online only<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515610' \/><div class='watu-question-choice'><input type='radio' name='answer-125165[]' id='answer-id-515610' class='answer answer-78  answerof-125165' value='515610' \/>&nbsp;<label for='answer-id-515610' id='answer-label-515610' class=' answer label-78'><span class='answer'>The SLA has not been reviewed in more than a year<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType78' value='radio' class=''><\/div><div class='watu-question' id='question-79'><div class='question-content'><p><span class='watu_num'>79. <\/span>Which of the following is the MOST appropriate responsibility of an IS auditor involved in a data center renovation project?<\/p>\n<\/div><input type='hidden' name='question_id[]' value='125166' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515611' \/><div class='watu-question-choice'><input type='radio' name='answer-125166[]' id='answer-id-515611' class='answer answer-79  answerof-125166' value='515611' \/>&nbsp;<label for='answer-id-515611' id='answer-label-515611' class=' answer label-79'><span class='answer'>Performing independent reviews of responsible parties engaged in the project<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515612' \/><div class='watu-question-choice'><input type='radio' name='answer-125166[]' id='answer-id-515612' class='answer answer-79  answerof-125166' value='515612' \/>&nbsp;<label for='answer-id-515612' id='answer-label-515612' class=' answer label-79'><span class='answer'>Ensuring the project progresses as scheduled and milestones are achieved<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515613' \/><div class='watu-question-choice'><input type='radio' name='answer-125166[]' id='answer-id-515613' class='answer answer-79  answerof-125166' value='515613' \/>&nbsp;<label for='answer-id-515613' id='answer-label-515613' class=' answer label-79'><span class='answer'>Performing day-to-day activities to ensure the successful completion of the project<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515614' \/><div class='watu-question-choice'><input type='radio' name='answer-125166[]' id='answer-id-515614' class='answer answer-79  answerof-125166' value='515614' \/>&nbsp;<label for='answer-id-515614' id='answer-label-515614' class=' answer label-79'><span class='answer'>Providing sign off on the design of controls for the data center<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType79' value='radio' class=''><\/div><div class='watu-question' id='question-80'><div class='question-content'><p><span class='watu_num'>80. <\/span>Which of the following is MOST important for an IS auditor to determine when reviewing how the organization\u2019s incident response team handles devices that may be involved in criminal activity?<\/p>\n<\/div><input type='hidden' name='question_id[]' value='125167' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515615' \/><div class='watu-question-choice'><input type='radio' name='answer-125167[]' id='answer-id-515615' class='answer answer-80  answerof-125167' value='515615' \/>&nbsp;<label for='answer-id-515615' id='answer-label-515615' class=' answer label-80'><span class='answer'>Whether devices are checked for malicious applications<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515616' \/><div class='watu-question-choice'><input type='radio' name='answer-125167[]' id='answer-id-515616' class='answer answer-80  answerof-125167' value='515616' \/>&nbsp;<label for='answer-id-515616' id='answer-label-515616' class=' answer label-80'><span class='answer'>Whether the access logs are checked before seizing the devices<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515617' \/><div class='watu-question-choice'><input type='radio' name='answer-125167[]' id='answer-id-515617' class='answer answer-80  answerof-125167' value='515617' \/>&nbsp;<label for='answer-id-515617' id='answer-label-515617' class=' answer label-80'><span class='answer'>Whether users have knowledge of their devices being examined<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515618' \/><div class='watu-question-choice'><input type='radio' name='answer-125167[]' id='answer-id-515618' class='answer answer-80  answerof-125167' value='515618' \/>&nbsp;<label for='answer-id-515618' id='answer-label-515618' class=' answer label-80'><span class='answer'>Whether there is a chain of custody for the devices<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType80' value='radio' class=''><\/div><div class='watu-question' id='question-81'><div class='question-content'><p><span class='watu_num'>81. <\/span>During a follow-up audit, an IS auditor learns the organization implemented an automated process instead of the originally agreed upon enhancement of the manual process.<br \/>\n<br \/>The auditor should:<\/p>\n<\/div><input type='hidden' name='question_id[]' value='125168' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515619' \/><div class='watu-question-choice'><input type='radio' name='answer-125168[]' id='answer-id-515619' class='answer answer-81  answerof-125168' value='515619' \/>&nbsp;<label for='answer-id-515619' id='answer-label-515619' class=' answer label-81'><span class='answer'>report the finding that recommendations were not acted upon<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515620' \/><div class='watu-question-choice'><input type='radio' name='answer-125168[]' id='answer-id-515620' class='answer answer-81  answerof-125168' value='515620' \/>&nbsp;<label for='answer-id-515620' id='answer-label-515620' class=' answer label-81'><span class='answer'>perform a cost-benefit analysis on the new process<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515621' \/><div class='watu-question-choice'><input type='radio' name='answer-125168[]' id='answer-id-515621' class='answer answer-81  answerof-125168' value='515621' \/>&nbsp;<label for='answer-id-515621' id='answer-label-515621' class=' answer label-81'><span class='answer'>verify that the new process satisfies control objectives<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515622' \/><div class='watu-question-choice'><input type='radio' name='answer-125168[]' id='answer-id-515622' class='answer answer-81  answerof-125168' value='515622' \/>&nbsp;<label for='answer-id-515622' id='answer-label-515622' class=' answer label-81'><span class='answer'>report the recommendation as implemented<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType81' value='radio' class=''><\/div><div class='watu-question' id='question-82'><div class='question-content'><p><span class='watu_num'>82. <\/span>During a privileged access review, an IS auditor observes many help desk employees have privileges within systems not required for their job functions.<br \/>\n<br \/>Implementing which of the following would have prevented this situation?<\/p>\n<\/div><input type='hidden' name='question_id[]' value='125169' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515623' \/><div class='watu-question-choice'><input type='radio' name='answer-125169[]' id='answer-id-515623' class='answer answer-82  answerof-125169' value='515623' \/>&nbsp;<label for='answer-id-515623' id='answer-label-515623' class=' answer label-82'><span class='answer'>Separation of duties<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515624' \/><div class='watu-question-choice'><input type='radio' name='answer-125169[]' id='answer-id-515624' class='answer answer-82  answerof-125169' value='515624' \/>&nbsp;<label for='answer-id-515624' id='answer-label-515624' class=' answer label-82'><span class='answer'>Multi-factor authentication<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515625' \/><div class='watu-question-choice'><input type='radio' name='answer-125169[]' id='answer-id-515625' class='answer answer-82  answerof-125169' value='515625' \/>&nbsp;<label for='answer-id-515625' id='answer-label-515625' class=' answer label-82'><span class='answer'>Least privilege access<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515626' \/><div class='watu-question-choice'><input type='radio' name='answer-125169[]' id='answer-id-515626' class='answer answer-82  answerof-125169' value='515626' \/>&nbsp;<label for='answer-id-515626' id='answer-label-515626' class=' answer label-82'><span class='answer'>Privileged access reviews<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType82' value='radio' class=''><\/div><div class='watu-question' id='question-83'><div class='question-content'><p><span class='watu_num'>83. <\/span>Management disagrees with a finding in a draft audit report and provides supporting documentation.<br \/>\n<br \/>Which of the following should be the IS auditor\u2019s NEXT course of action?<\/p>\n<\/div><input type='hidden' name='question_id[]' value='125170' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515627' \/><div class='watu-question-choice'><input type='radio' name='answer-125170[]' id='answer-id-515627' class='answer answer-83  answerof-125170' value='515627' \/>&nbsp;<label for='answer-id-515627' id='answer-label-515627' class=' answer label-83'><span class='answer'>Document management\u2019s disagreement in the final report<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515628' \/><div class='watu-question-choice'><input type='radio' name='answer-125170[]' id='answer-id-515628' class='answer answer-83  answerof-125170' value='515628' \/>&nbsp;<label for='answer-id-515628' id='answer-label-515628' class=' answer label-83'><span class='answer'>Evaluate the supporting documentation<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515629' \/><div class='watu-question-choice'><input type='radio' name='answer-125170[]' id='answer-id-515629' class='answer answer-83  answerof-125170' value='515629' \/>&nbsp;<label for='answer-id-515629' id='answer-label-515629' class=' answer label-83'><span class='answer'>Escalate the issue with supporting documentation to senior management<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515630' \/><div class='watu-question-choice'><input type='radio' name='answer-125170[]' id='answer-id-515630' class='answer answer-83  answerof-125170' value='515630' \/>&nbsp;<label for='answer-id-515630' id='answer-label-515630' class=' answer label-83'><span class='answer'>Finalize the draft audit report without changes<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType83' value='radio' class=''><\/div><div class='watu-question' id='question-84'><div class='question-content'><p><span class='watu_num'>84. <\/span>Which of the following audit techniques is MOST appropriate for verifying application program controls?<\/p>\n<\/div><input type='hidden' name='question_id[]' value='125171' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515631' \/><div class='watu-question-choice'><input type='radio' name='answer-125171[]' id='answer-id-515631' class='answer answer-84  answerof-125171' value='515631' \/>&nbsp;<label for='answer-id-515631' id='answer-label-515631' class=' answer label-84'><span class='answer'>Statistical sampling<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515632' \/><div class='watu-question-choice'><input type='radio' name='answer-125171[]' id='answer-id-515632' class='answer answer-84  answerof-125171' value='515632' \/>&nbsp;<label for='answer-id-515632' id='answer-label-515632' class=' answer label-84'><span class='answer'>Code review<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515633' \/><div class='watu-question-choice'><input type='radio' name='answer-125171[]' id='answer-id-515633' class='answer answer-84  answerof-125171' value='515633' \/>&nbsp;<label for='answer-id-515633' id='answer-label-515633' class=' answer label-84'><span class='answer'>Confirmation of accounts<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515634' \/><div class='watu-question-choice'><input type='radio' name='answer-125171[]' id='answer-id-515634' class='answer answer-84  answerof-125171' value='515634' \/>&nbsp;<label for='answer-id-515634' id='answer-label-515634' class=' answer label-84'><span class='answer'>Use of test data<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType84' value='radio' class=''><\/div><div class='watu-question' id='question-85'><div class='question-content'><p><span class='watu_num'>85. <\/span>A business has requested an IS audit to determine whether information stored in an application system is adequately protected.<br \/>\n<br \/>Which of the following is the MOST important action before the audit work begins?<\/p>\n<\/div><input type='hidden' name='question_id[]' value='125172' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515635' \/><div class='watu-question-choice'><input type='radio' name='answer-125172[]' id='answer-id-515635' class='answer answer-85  answerof-125172' value='515635' \/>&nbsp;<label for='answer-id-515635' id='answer-label-515635' class=' answer label-85'><span class='answer'>Establish control objectives<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515636' \/><div class='watu-question-choice'><input type='radio' name='answer-125172[]' id='answer-id-515636' class='answer answer-85  answerof-125172' value='515636' \/>&nbsp;<label for='answer-id-515636' id='answer-label-515636' class=' answer label-85'><span class='answer'>Conduct a vulnerability analysis<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515637' \/><div class='watu-question-choice'><input type='radio' name='answer-125172[]' id='answer-id-515637' class='answer answer-85  answerof-125172' value='515637' \/>&nbsp;<label for='answer-id-515637' id='answer-label-515637' class=' answer label-85'><span class='answer'>Perform penetration testing<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515638' \/><div class='watu-question-choice'><input type='radio' name='answer-125172[]' id='answer-id-515638' class='answer answer-85  answerof-125172' value='515638' \/>&nbsp;<label for='answer-id-515638' id='answer-label-515638' class=' answer label-85'><span class='answer'>Review remediation reports<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType85' value='radio' class=''><\/div><div class='watu-question' id='question-86'><div class='question-content'><p><span class='watu_num'>86. <\/span>Which audit technique provides the GREATEST assurance that incident management procedures are effective?<\/p>\n<\/div><input type='hidden' name='question_id[]' value='125173' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515639' \/><div class='watu-question-choice'><input type='radio' name='answer-125173[]' id='answer-id-515639' class='answer answer-86  answerof-125173' value='515639' \/>&nbsp;<label for='answer-id-515639' id='answer-label-515639' class=' answer label-86'><span class='answer'>Determining whether incidents are categorized and addressed<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515640' \/><div class='watu-question-choice'><input type='radio' name='answer-125173[]' id='answer-id-515640' class='answer answer-86  answerof-125173' value='515640' \/>&nbsp;<label for='answer-id-515640' id='answer-label-515640' class=' answer label-86'><span class='answer'>Performing comprehensive vulnerability scanning and penetration testing<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515641' \/><div class='watu-question-choice'><input type='radio' name='answer-125173[]' id='answer-id-515641' class='answer answer-86  answerof-125173' value='515641' \/>&nbsp;<label for='answer-id-515641' id='answer-label-515641' class=' answer label-86'><span class='answer'>Comparing incident management procedures to best practices<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515642' \/><div class='watu-question-choice'><input type='radio' name='answer-125173[]' id='answer-id-515642' class='answer answer-86  answerof-125173' value='515642' \/>&nbsp;<label for='answer-id-515642' id='answer-label-515642' class=' answer label-86'><span class='answer'>Evaluating end-user satisfaction survey results<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType86' value='radio' class=''><\/div><div class='watu-question' id='question-87'><div class='question-content'><p><span class='watu_num'>87. <\/span>Which of the following findings would be of MOST concern to an IS auditor performing a review of an end-user developed application that generates financial statements?<\/p>\n<\/div><input type='hidden' name='question_id[]' value='125174' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515643' \/><div class='watu-question-choice'><input type='radio' name='answer-125174[]' id='answer-id-515643' class='answer answer-87  answerof-125174' value='515643' \/>&nbsp;<label for='answer-id-515643' id='answer-label-515643' class=' answer label-87'><span class='answer'>The application is not sufficiently supported by the IT department<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515644' \/><div class='watu-question-choice'><input type='radio' name='answer-125174[]' id='answer-id-515644' class='answer answer-87  answerof-125174' value='515644' \/>&nbsp;<label for='answer-id-515644' id='answer-label-515644' class=' answer label-87'><span class='answer'>There is not adequate training in the use of the application<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515645' \/><div class='watu-question-choice'><input type='radio' name='answer-125174[]' id='answer-id-515645' class='answer answer-87  answerof-125174' value='515645' \/>&nbsp;<label for='answer-id-515645' id='answer-label-515645' class=' answer label-87'><span class='answer'>There is no adequate user license for the application<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515646' \/><div class='watu-question-choice'><input type='radio' name='answer-125174[]' id='answer-id-515646' class='answer answer-87  answerof-125174' value='515646' \/>&nbsp;<label for='answer-id-515646' id='answer-label-515646' class=' answer label-87'><span class='answer'>There is no control to ensure accuracy of the processed data<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType87' value='radio' class=''><\/div><div class='watu-question' id='question-88'><div class='question-content'><p><span class='watu_num'>88. <\/span>An organization plans to deploy Wi-Fi location analytics to count the number of shoppers per day across its various retail outlets.<br \/>\n<br \/>What should the IS auditor recommend as the FIRST course of action by IT management?<\/p>\n<\/div><input type='hidden' name='question_id[]' value='125175' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515647' \/><div class='watu-question-choice'><input type='radio' name='answer-125175[]' id='answer-id-515647' class='answer answer-88  answerof-125175' value='515647' \/>&nbsp;<label for='answer-id-515647' id='answer-label-515647' class=' answer label-88'><span class='answer'>Conduct a privacy impact assessment<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515648' \/><div class='watu-question-choice'><input type='radio' name='answer-125175[]' id='answer-id-515648' class='answer answer-88  answerof-125175' value='515648' \/>&nbsp;<label for='answer-id-515648' id='answer-label-515648' class=' answer label-88'><span class='answer'>Mask media access control (MAC) addresses<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515649' \/><div class='watu-question-choice'><input type='radio' name='answer-125175[]' id='answer-id-515649' class='answer answer-88  answerof-125175' value='515649' \/>&nbsp;<label for='answer-id-515649' id='answer-label-515649' class=' answer label-88'><span class='answer'>Survey shoppers for feedback<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515650' \/><div class='watu-question-choice'><input type='radio' name='answer-125175[]' id='answer-id-515650' class='answer answer-88  answerof-125175' value='515650' \/>&nbsp;<label for='answer-id-515650' id='answer-label-515650' class=' answer label-88'><span class='answer'>Develop a privacy notice to be displayed to shoppers<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType88' value='radio' class=''><\/div><div class='watu-question' id='question-89'><div class='question-content'><p><span class='watu_num'>89. <\/span>An IS auditor discovered abnormalities in a monthly report generated from a system upgraded six months ago.<br \/>\n<br \/>Which of the following should be the auditor\u2019s FIRST course of action?<\/p>\n<\/div><input type='hidden' name='question_id[]' value='125176' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515651' \/><div class='watu-question-choice'><input type='radio' name='answer-125176[]' id='answer-id-515651' class='answer answer-89  answerof-125176' value='515651' \/>&nbsp;<label for='answer-id-515651' id='answer-label-515651' class=' answer label-89'><span class='answer'>Inspect source code for proof of abnormalities<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515652' \/><div class='watu-question-choice'><input type='radio' name='answer-125176[]' id='answer-id-515652' class='answer answer-89  answerof-125176' value='515652' \/>&nbsp;<label for='answer-id-515652' id='answer-label-515652' class=' answer label-89'><span class='answer'>Perform a change management review of the system<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515653' \/><div class='watu-question-choice'><input type='radio' name='answer-125176[]' id='answer-id-515653' class='answer answer-89  answerof-125176' value='515653' \/>&nbsp;<label for='answer-id-515653' id='answer-label-515653' class=' answer label-89'><span class='answer'>Schedule an access review of the system<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515654' \/><div class='watu-question-choice'><input type='radio' name='answer-125176[]' id='answer-id-515654' class='answer answer-89  answerof-125176' value='515654' \/>&nbsp;<label for='answer-id-515654' id='answer-label-515654' class=' answer label-89'><span class='answer'>Determine the impact of abnormalities in the report<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType89' value='radio' class=''><\/div><div class='watu-question' id='question-90'><div class='question-content'><p><span class='watu_num'>90. <\/span>When auditing the effectiveness of a biometric system, which of the following indicators would be MOST important to review?<\/p>\n<\/div><input type='hidden' name='question_id[]' value='125177' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515655' \/><div class='watu-question-choice'><input type='radio' name='answer-125177[]' id='answer-id-515655' class='answer answer-90  answerof-125177' value='515655' \/>&nbsp;<label for='answer-id-515655' id='answer-label-515655' class=' answer label-90'><span class='answer'>False negatives<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515656' \/><div class='watu-question-choice'><input type='radio' name='answer-125177[]' id='answer-id-515656' class='answer answer-90  answerof-125177' value='515656' \/>&nbsp;<label for='answer-id-515656' id='answer-label-515656' class=' answer label-90'><span class='answer'>False acceptance rate<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515657' \/><div class='watu-question-choice'><input type='radio' name='answer-125177[]' id='answer-id-515657' class='answer answer-90  answerof-125177' value='515657' \/>&nbsp;<label for='answer-id-515657' id='answer-label-515657' class=' answer label-90'><span class='answer'>Failure to enroll rate<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515658' \/><div class='watu-question-choice'><input type='radio' name='answer-125177[]' id='answer-id-515658' class='answer answer-90  answerof-125177' value='515658' \/>&nbsp;<label for='answer-id-515658' id='answer-label-515658' class=' answer label-90'><span class='answer'>System response time<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType90' value='radio' class=''><\/div><div class='watu-question' id='question-91'><div class='question-content'><p><span class='watu_num'>91. <\/span>An IS auditor conducting audit follow-up activities learns that some previously agreed-upon corrective actions have not been taken and that the associated risk has been accepted by senior management.<br \/>\n<br \/>If the auditor disagrees with management\u2019s decision, what is the BEST way to address the situation?<\/p>\n<\/div><input type='hidden' name='question_id[]' value='125178' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515659' \/><div class='watu-question-choice'><input type='radio' name='answer-125178[]' id='answer-id-515659' class='answer answer-91  answerof-125178' value='515659' \/>&nbsp;<label for='answer-id-515659' id='answer-label-515659' class=' answer label-91'><span class='answer'>Repeat the audit with audit scope only covering areas with accepted risks<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515660' \/><div class='watu-question-choice'><input type='radio' name='answer-125178[]' id='answer-id-515660' class='answer answer-91  answerof-125178' value='515660' \/>&nbsp;<label for='answer-id-515660' id='answer-label-515660' class=' answer label-91'><span class='answer'>Report the issue to the chief audit executive for resolution<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515661' \/><div class='watu-question-choice'><input type='radio' name='answer-125178[]' id='answer-id-515661' class='answer answer-91  answerof-125178' value='515661' \/>&nbsp;<label for='answer-id-515661' id='answer-label-515661' class=' answer label-91'><span class='answer'>Recommend new corrective actions to mitigate the accepted risk<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515662' \/><div class='watu-question-choice'><input type='radio' name='answer-125178[]' id='answer-id-515662' class='answer answer-91  answerof-125178' value='515662' \/>&nbsp;<label for='answer-id-515662' id='answer-label-515662' class=' answer label-91'><span class='answer'>Take no action since management\u2019s decision has been made<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType91' value='radio' class=''><\/div><div class='watu-question' id='question-92'><div class='question-content'><p><span class='watu_num'>92. <\/span>During a security audit, an IS auditor is tasked with reviewing log entries obtained from an enterprise intrusion prevention system (IPS).<br \/>\n<br \/>Which type of risk would be associated with the potential for the auditor to miss a sequence of logged events that could indicate an error in the IPS configuration?<\/p>\n<\/div><input type='hidden' name='question_id[]' value='125179' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515663' \/><div class='watu-question-choice'><input type='radio' name='answer-125179[]' id='answer-id-515663' class='answer answer-92  answerof-125179' value='515663' \/>&nbsp;<label for='answer-id-515663' id='answer-label-515663' class=' answer label-92'><span class='answer'>Inherent risk<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515664' \/><div class='watu-question-choice'><input type='radio' name='answer-125179[]' id='answer-id-515664' class='answer answer-92  answerof-125179' value='515664' \/>&nbsp;<label for='answer-id-515664' id='answer-label-515664' class=' answer label-92'><span class='answer'>Sampling risk<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515665' \/><div class='watu-question-choice'><input type='radio' name='answer-125179[]' id='answer-id-515665' class='answer answer-92  answerof-125179' value='515665' \/>&nbsp;<label for='answer-id-515665' id='answer-label-515665' class=' answer label-92'><span class='answer'>Control risk<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515666' \/><div class='watu-question-choice'><input type='radio' name='answer-125179[]' id='answer-id-515666' class='answer answer-92  answerof-125179' value='515666' \/>&nbsp;<label for='answer-id-515666' id='answer-label-515666' class=' answer label-92'><span class='answer'>Detection risk<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType92' value='radio' class=''><\/div><div class='watu-question' id='question-93'><div class='question-content'><p><span class='watu_num'>93. <\/span>An organization is concerned about duplicate vendor payments on a complex system with a high volume of transactions.<br \/>\n<br \/>Which of the following would be MOST helpful to an IS auditor to determine whether duplicate vendor payments exist?<\/p>\n<\/div><input type='hidden' name='question_id[]' value='125180' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515667' \/><div class='watu-question-choice'><input type='radio' name='answer-125180[]' id='answer-id-515667' class='answer answer-93  answerof-125180' value='515667' \/>&nbsp;<label for='answer-id-515667' id='answer-label-515667' class=' answer label-93'><span class='answer'>Computer-assisted technique<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515668' \/><div class='watu-question-choice'><input type='radio' name='answer-125180[]' id='answer-id-515668' class='answer answer-93  answerof-125180' value='515668' \/>&nbsp;<label for='answer-id-515668' id='answer-label-515668' class=' answer label-93'><span class='answer'>Stop-and-go testing<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515669' \/><div class='watu-question-choice'><input type='radio' name='answer-125180[]' id='answer-id-515669' class='answer answer-93  answerof-125180' value='515669' \/>&nbsp;<label for='answer-id-515669' id='answer-label-515669' class=' answer label-93'><span class='answer'>Statistical sampling<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515670' \/><div class='watu-question-choice'><input type='radio' name='answer-125180[]' id='answer-id-515670' class='answer answer-93  answerof-125180' value='515670' \/>&nbsp;<label for='answer-id-515670' id='answer-label-515670' class=' answer label-93'><span class='answer'>Judgmental sampling<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType93' value='radio' class=''><\/div><div class='watu-question' id='question-94'><div class='question-content'><p><span class='watu_num'>94. <\/span>The MAIN benefit of using an integrated test facility (ITF) as an online auditing technique is that it enables:<\/p>\n<\/div><input type='hidden' name='question_id[]' value='125181' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515671' \/><div class='watu-question-choice'><input type='radio' name='answer-125181[]' id='answer-id-515671' class='answer answer-94  answerof-125181' value='515671' \/>&nbsp;<label for='answer-id-515671' id='answer-label-515671' class=' answer label-94'><span class='answer'>a cost-effective approach to application controls audit<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515672' \/><div class='watu-question-choice'><input type='radio' name='answer-125181[]' id='answer-id-515672' class='answer answer-94  answerof-125181' value='515672' \/>&nbsp;<label for='answer-id-515672' id='answer-label-515672' class=' answer label-94'><span class='answer'>auditors to investigate fraudulent transactions<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515673' \/><div class='watu-question-choice'><input type='radio' name='answer-125181[]' id='answer-id-515673' class='answer answer-94  answerof-125181' value='515673' \/>&nbsp;<label for='answer-id-515673' id='answer-label-515673' class=' answer label-94'><span class='answer'>auditors to test without impacting production data<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515674' \/><div class='watu-question-choice'><input type='radio' name='answer-125181[]' id='answer-id-515674' class='answer answer-94  answerof-125181' value='515674' \/>&nbsp;<label for='answer-id-515674' id='answer-label-515674' class=' answer label-94'><span class='answer'>the integration of financial and audit tests<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType94' value='radio' class=''><\/div><div class='watu-question' id='question-95'><div class='question-content'><p><span class='watu_num'>95. <\/span>When evaluating the ability of a disaster recovery plan to enable the recovery of IT processing capabilities, it is MOST important for the IS auditor to verify the plan is:<\/p>\n<\/div><input type='hidden' name='question_id[]' value='125182' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515675' \/><div class='watu-question-choice'><input type='radio' name='answer-125182[]' id='answer-id-515675' class='answer answer-95  answerof-125182' value='515675' \/>&nbsp;<label for='answer-id-515675' id='answer-label-515675' class=' answer label-95'><span class='answer'>stored at an offsite location<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515676' \/><div class='watu-question-choice'><input type='radio' name='answer-125182[]' id='answer-id-515676' class='answer answer-95  answerof-125182' value='515676' \/>&nbsp;<label for='answer-id-515676' id='answer-label-515676' class=' answer label-95'><span class='answer'>communicated to department heads<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515677' \/><div class='watu-question-choice'><input type='radio' name='answer-125182[]' id='answer-id-515677' class='answer answer-95  answerof-125182' value='515677' \/>&nbsp;<label for='answer-id-515677' id='answer-label-515677' class=' answer label-95'><span class='answer'>regularly reviewed<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515678' \/><div class='watu-question-choice'><input type='radio' name='answer-125182[]' id='answer-id-515678' class='answer answer-95  answerof-125182' value='515678' \/>&nbsp;<label for='answer-id-515678' id='answer-label-515678' class=' answer label-95'><span class='answer'>periodically tested<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType95' value='radio' class=''><\/div><div class='watu-question' id='question-96'><div class='question-content'><p><span class='watu_num'>96. <\/span>An IS auditor is analyzing a sample of accesses recorded on the system log of an application. The auditor intends to launch an intensive investigation if one exception is found.<br \/>\n<br \/>Which sampling method would be appropriate?<\/p>\n<\/div><input type='hidden' name='question_id[]' value='125183' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515679' \/><div class='watu-question-choice'><input type='radio' name='answer-125183[]' id='answer-id-515679' class='answer answer-96  answerof-125183' value='515679' \/>&nbsp;<label for='answer-id-515679' id='answer-label-515679' class=' answer label-96'><span class='answer'>Discovery sampling<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515680' \/><div class='watu-question-choice'><input type='radio' name='answer-125183[]' id='answer-id-515680' class='answer answer-96  answerof-125183' value='515680' \/>&nbsp;<label for='answer-id-515680' id='answer-label-515680' class=' answer label-96'><span class='answer'>Variable sampling<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515681' \/><div class='watu-question-choice'><input type='radio' name='answer-125183[]' id='answer-id-515681' class='answer answer-96  answerof-125183' value='515681' \/>&nbsp;<label for='answer-id-515681' id='answer-label-515681' class=' answer label-96'><span class='answer'>Stratified sampling<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515682' \/><div class='watu-question-choice'><input type='radio' name='answer-125183[]' id='answer-id-515682' class='answer answer-96  answerof-125183' value='515682' \/>&nbsp;<label for='answer-id-515682' id='answer-label-515682' class=' answer label-96'><span class='answer'>Judgmental sampling<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType96' value='radio' class=''><\/div><div class='watu-question' id='question-97'><div class='question-content'><p><span class='watu_num'>97. <\/span>Assessments of critical information systems are based on a cyclical audit plan that has not been updated for several years.<br \/>\n<br \/>Which of the following should the IS auditor recommend to BEST address this situation?<\/p>\n<\/div><input type='hidden' name='question_id[]' value='125184' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515683' \/><div class='watu-question-choice'><input type='radio' name='answer-125184[]' id='answer-id-515683' class='answer answer-97  answerof-125184' value='515683' \/>&nbsp;<label for='answer-id-515683' id='answer-label-515683' class=' answer label-97'><span class='answer'>Use a revolving set of audit plans to cover all systems<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515684' \/><div class='watu-question-choice'><input type='radio' name='answer-125184[]' id='answer-id-515684' class='answer answer-97  answerof-125184' value='515684' \/>&nbsp;<label for='answer-id-515684' id='answer-label-515684' class=' answer label-97'><span class='answer'>Update the audit plan quarterly to account for delays and deferrals of periodic reviews<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515685' \/><div class='watu-question-choice'><input type='radio' name='answer-125184[]' id='answer-id-515685' class='answer answer-97  answerof-125184' value='515685' \/>&nbsp;<label for='answer-id-515685' id='answer-label-515685' class=' answer label-97'><span class='answer'>Regularly validate the audit plan against business risks<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515686' \/><div class='watu-question-choice'><input type='radio' name='answer-125184[]' id='answer-id-515686' class='answer answer-97  answerof-125184' value='515686' \/>&nbsp;<label for='answer-id-515686' id='answer-label-515686' class=' answer label-97'><span class='answer'>Do not include periodic reviews in detail as part of the audit plan<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType97' value='radio' class=''><\/div><div class='watu-question' id='question-98'><div class='question-content'><p><span class='watu_num'>98. <\/span>An IS auditor is assessing risk associated with peer-to-peer file sharing within an organization.<br \/>\n<br \/>Which of the following should be of GREATEST concern?<\/p>\n<\/div><input type='hidden' name='question_id[]' value='125185' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515687' \/><div class='watu-question-choice'><input type='radio' name='answer-125185[]' id='answer-id-515687' class='answer answer-98  answerof-125185' value='515687' \/>&nbsp;<label for='answer-id-515687' id='answer-label-515687' class=' answer label-98'><span class='answer'>File-sharing policies have not been reviewed since last year<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515688' \/><div class='watu-question-choice'><input type='radio' name='answer-125185[]' id='answer-id-515688' class='answer answer-98  answerof-125185' value='515688' \/>&nbsp;<label for='answer-id-515688' id='answer-label-515688' class=' answer label-98'><span class='answer'>Only some employees are required to attend security awareness training<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515689' \/><div class='watu-question-choice'><input type='radio' name='answer-125185[]' id='answer-id-515689' class='answer answer-98  answerof-125185' value='515689' \/>&nbsp;<label for='answer-id-515689' id='answer-label-515689' class=' answer label-98'><span class='answer'>Not all devices are running antivirus programs<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515690' \/><div class='watu-question-choice'><input type='radio' name='answer-125185[]' id='answer-id-515690' class='answer answer-98  answerof-125185' value='515690' \/>&nbsp;<label for='answer-id-515690' id='answer-label-515690' class=' answer label-98'><span class='answer'>The organization does not have an efficient patch management process<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType98' value='radio' class=''><\/div><div class='watu-question' id='question-99'><div class='question-content'><p><span class='watu_num'>99. <\/span>An IS auditor is reviewing an organization\u2019s incident management processes and procedures. which of the following observations should be the auditor\u2019s GREATEST concern?<\/p>\n<\/div><input type='hidden' name='question_id[]' value='125186' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515691' \/><div class='watu-question-choice'><input type='radio' name='answer-125186[]' id='answer-id-515691' class='answer answer-99  answerof-125186' value='515691' \/>&nbsp;<label for='answer-id-515691' id='answer-label-515691' class=' answer label-99'><span class='answer'>Ineffective incident classification<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515692' \/><div class='watu-question-choice'><input type='radio' name='answer-125186[]' id='answer-id-515692' class='answer answer-99  answerof-125186' value='515692' \/>&nbsp;<label for='answer-id-515692' id='answer-label-515692' class=' answer label-99'><span class='answer'>Ineffective incident prioritization<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515693' \/><div class='watu-question-choice'><input type='radio' name='answer-125186[]' id='answer-id-515693' class='answer answer-99  answerof-125186' value='515693' \/>&nbsp;<label for='answer-id-515693' id='answer-label-515693' class=' answer label-99'><span class='answer'>Ineffective incident detection<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515694' \/><div class='watu-question-choice'><input type='radio' name='answer-125186[]' id='answer-id-515694' class='answer answer-99  answerof-125186' value='515694' \/>&nbsp;<label for='answer-id-515694' id='answer-label-515694' class=' answer label-99'><span class='answer'>Ineffective post-incident review<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType99' value='radio' class=''><\/div><div class='watu-question' id='question-100'><div class='question-content'><p><span class='watu_num'>100. <\/span>During an IS audit, is discovered that security configurations differ across the organization\u2019s virtual server farm.<br \/>\n<br \/>Which of the following is the IS auditor\u2019s BEST recommendation for improving the control environment?<\/p>\n<\/div><input type='hidden' name='question_id[]' value='125187' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515695' \/><div class='watu-question-choice'><input type='radio' name='answer-125187[]' id='answer-id-515695' class='answer answer-100  answerof-125187' value='515695' \/>&nbsp;<label for='answer-id-515695' id='answer-label-515695' class=' answer label-100'><span class='answer'>Conduct an independent review of each server\u2019s security configuration<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515696' \/><div class='watu-question-choice'><input type='radio' name='answer-125187[]' id='answer-id-515696' class='answer answer-100  answerof-125187' value='515696' \/>&nbsp;<label for='answer-id-515696' id='answer-label-515696' class=' answer label-100'><span class='answer'>Implement a security configuration baseline for virtual servers<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515697' \/><div class='watu-question-choice'><input type='radio' name='answer-125187[]' id='answer-id-515697' class='answer answer-100  answerof-125187' value='515697' \/>&nbsp;<label for='answer-id-515697' id='answer-label-515697' class=' answer label-100'><span class='answer'>Implement security monitoring controls for high-risk virtual servers<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515698' \/><div class='watu-question-choice'><input type='radio' name='answer-125187[]' id='answer-id-515698' class='answer answer-100  answerof-125187' value='515698' \/>&nbsp;<label for='answer-id-515698' id='answer-label-515698' class=' answer label-100'><span class='answer'>Conduct a standard patch management review across the virtual server farm<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType100' value='radio' class=''><\/div><div class='watu-question' id='question-101'><div class='question-content'><p><span class='watu_num'>101. <\/span>A senior auditor is reviewing work papers prepared by a junior auditor indicating that a finding was removed after the auditee said they corrected the problem.<br \/>\n<br \/>Which of the following would be the MOST appropriate course of action for the senior auditor?<\/p>\n<\/div><input type='hidden' name='question_id[]' value='125188' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515699' \/><div class='watu-question-choice'><input type='radio' name='answer-125188[]' id='answer-id-515699' class='answer answer-101  answerof-125188' value='515699' \/>&nbsp;<label for='answer-id-515699' id='answer-label-515699' class=' answer label-101'><span class='answer'>Approve the work papers as written<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515700' \/><div class='watu-question-choice'><input type='radio' name='answer-125188[]' id='answer-id-515700' class='answer answer-101  answerof-125188' value='515700' \/>&nbsp;<label for='answer-id-515700' id='answer-label-515700' class=' answer label-101'><span class='answer'>Refer the issue to the audit director<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515701' \/><div class='watu-question-choice'><input type='radio' name='answer-125188[]' id='answer-id-515701' class='answer answer-101  answerof-125188' value='515701' \/>&nbsp;<label for='answer-id-515701' id='answer-label-515701' class=' answer label-101'><span class='answer'>Have the finding reinstated<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515702' \/><div class='watu-question-choice'><input type='radio' name='answer-125188[]' id='answer-id-515702' class='answer answer-101  answerof-125188' value='515702' \/>&nbsp;<label for='answer-id-515702' id='answer-label-515702' class=' answer label-101'><span class='answer'>Ask the auditee to retest<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType101' value='radio' class=''><\/div><div class='watu-question' id='question-102'><div class='question-content'><p><span class='watu_num'>102. <\/span>An IS auditor is conducting a pre-implementation review to determine a new system\u2019s production readiness. The auditor\u2019s PRIMARY concern should be whether:<\/p>\n<\/div><input type='hidden' name='question_id[]' value='125189' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515703' \/><div class='watu-question-choice'><input type='radio' name='answer-125189[]' id='answer-id-515703' class='answer answer-102  answerof-125189' value='515703' \/>&nbsp;<label for='answer-id-515703' id='answer-label-515703' class=' answer label-102'><span class='answer'>the project adhered to the budget and target date<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515704' \/><div class='watu-question-choice'><input type='radio' name='answer-125189[]' id='answer-id-515704' class='answer answer-102  answerof-125189' value='515704' \/>&nbsp;<label for='answer-id-515704' id='answer-label-515704' class=' answer label-102'><span class='answer'>users were involved in the quality assurance (QA) testing<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515705' \/><div class='watu-question-choice'><input type='radio' name='answer-125189[]' id='answer-id-515705' class='answer answer-102  answerof-125189' value='515705' \/>&nbsp;<label for='answer-id-515705' id='answer-label-515705' class=' answer label-102'><span class='answer'>there are unresolved high-risk items<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515706' \/><div class='watu-question-choice'><input type='radio' name='answer-125189[]' id='answer-id-515706' class='answer answer-102  answerof-125189' value='515706' \/>&nbsp;<label for='answer-id-515706' id='answer-label-515706' class=' answer label-102'><span class='answer'>benefits realization has been evidenced<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType102' value='radio' class=''><\/div><div class='watu-question' id='question-103'><div class='question-content'><p><span class='watu_num'>103. <\/span>An IS auditor reviewing the threat assessment for a data center would be MOST concerned if:<\/p>\n<\/div><input type='hidden' name='question_id[]' value='125190' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515707' \/><div class='watu-question-choice'><input type='radio' name='answer-125190[]' id='answer-id-515707' class='answer answer-103  answerof-125190' value='515707' \/>&nbsp;<label for='answer-id-515707' id='answer-label-515707' class=' answer label-103'><span class='answer'>all identified threats relate to external entities<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515708' \/><div class='watu-question-choice'><input type='radio' name='answer-125190[]' id='answer-id-515708' class='answer answer-103  answerof-125190' value='515708' \/>&nbsp;<label for='answer-id-515708' id='answer-label-515708' class=' answer label-103'><span class='answer'>some of the identified threats are unlikely to occur<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515709' \/><div class='watu-question-choice'><input type='radio' name='answer-125190[]' id='answer-id-515709' class='answer answer-103  answerof-125190' value='515709' \/>&nbsp;<label for='answer-id-515709' id='answer-label-515709' class=' answer label-103'><span class='answer'>neighboring organizations\u2019 operations have been included<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515710' \/><div class='watu-question-choice'><input type='radio' name='answer-125190[]' id='answer-id-515710' class='answer answer-103  answerof-125190' value='515710' \/>&nbsp;<label for='answer-id-515710' id='answer-label-515710' class=' answer label-103'><span class='answer'>the exercise was completed by local management<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType103' value='radio' class=''><\/div><div class='watu-question' id='question-104'><div class='question-content'><p><span class='watu_num'>104. <\/span>When following up on a data breach, an IS auditor finds a system administrator may have compromised the chain of custody.<br \/>\n<br \/>Which of the following should the system administrator have done FIRST to preserve the evidence?<\/p>\n<\/div><input type='hidden' name='question_id[]' value='125191' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515711' \/><div class='watu-question-choice'><input type='radio' name='answer-125191[]' id='answer-id-515711' class='answer answer-104  answerof-125191' value='515711' \/>&nbsp;<label for='answer-id-515711' id='answer-label-515711' class=' answer label-104'><span class='answer'>Perform forensic discovery<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515712' \/><div class='watu-question-choice'><input type='radio' name='answer-125191[]' id='answer-id-515712' class='answer answer-104  answerof-125191' value='515712' \/>&nbsp;<label for='answer-id-515712' id='answer-label-515712' class=' answer label-104'><span class='answer'>Notify key stakeholders<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515713' \/><div class='watu-question-choice'><input type='radio' name='answer-125191[]' id='answer-id-515713' class='answer answer-104  answerof-125191' value='515713' \/>&nbsp;<label for='answer-id-515713' id='answer-label-515713' class=' answer label-104'><span class='answer'>Quarantine the system<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515714' \/><div class='watu-question-choice'><input type='radio' name='answer-125191[]' id='answer-id-515714' class='answer answer-104  answerof-125191' value='515714' \/>&nbsp;<label for='answer-id-515714' id='answer-label-515714' class=' answer label-104'><span class='answer'>Notify the incident response team<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType104' value='radio' class=''><\/div><div class='watu-question' id='question-105'><div class='question-content'><p><span class='watu_num'>105. <\/span>Which of the following should an IS auditor verify when auditing the effectiveness of virus protection?<\/p>\n<\/div><input type='hidden' name='question_id[]' value='125192' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515715' \/><div class='watu-question-choice'><input type='radio' name='answer-125192[]' id='answer-id-515715' class='answer answer-105  answerof-125192' value='515715' \/>&nbsp;<label for='answer-id-515715' id='answer-label-515715' class=' answer label-105'><span class='answer'>Frequency of IDS log reviews<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515716' \/><div class='watu-question-choice'><input type='radio' name='answer-125192[]' id='answer-id-515716' class='answer answer-105  answerof-125192' value='515716' \/>&nbsp;<label for='answer-id-515716' id='answer-label-515716' class=' answer label-105'><span class='answer'>Currency of software patch application<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515717' \/><div class='watu-question-choice'><input type='radio' name='answer-125192[]' id='answer-id-515717' class='answer answer-105  answerof-125192' value='515717' \/>&nbsp;<label for='answer-id-515717' id='answer-label-515717' class=' answer label-105'><span class='answer'>Schedule for migration to production<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515718' \/><div class='watu-question-choice'><input type='radio' name='answer-125192[]' id='answer-id-515718' class='answer answer-105  answerof-125192' value='515718' \/>&nbsp;<label for='answer-id-515718' id='answer-label-515718' class=' answer label-105'><span class='answer'>Frequency of external Internet access<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType105' value='radio' class=''><\/div><div class='watu-question' id='question-106'><div class='question-content'><p><span class='watu_num'>106. <\/span>Which of the following should be reviewed FIRST when planning an IS audit?<\/p>\n<\/div><input type='hidden' name='question_id[]' value='125193' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515719' \/><div class='watu-question-choice'><input type='radio' name='answer-125193[]' id='answer-id-515719' class='answer answer-106  answerof-125193' value='515719' \/>&nbsp;<label for='answer-id-515719' id='answer-label-515719' class=' answer label-106'><span class='answer'>Recent financial information<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515720' \/><div class='watu-question-choice'><input type='radio' name='answer-125193[]' id='answer-id-515720' class='answer answer-106  answerof-125193' value='515720' \/>&nbsp;<label for='answer-id-515720' id='answer-label-515720' class=' answer label-106'><span class='answer'>Annual business unit budget<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515721' \/><div class='watu-question-choice'><input type='radio' name='answer-125193[]' id='answer-id-515721' class='answer answer-106  answerof-125193' value='515721' \/>&nbsp;<label for='answer-id-515721' id='answer-label-515721' class=' answer label-106'><span class='answer'>IS audit standards<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515722' \/><div class='watu-question-choice'><input type='radio' name='answer-125193[]' id='answer-id-515722' class='answer answer-106  answerof-125193' value='515722' \/>&nbsp;<label for='answer-id-515722' id='answer-label-515722' class=' answer label-106'><span class='answer'>The business environment<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType106' value='radio' class=''><\/div><div class='watu-question' id='question-107'><div class='question-content'><p><span class='watu_num'>107. <\/span>An IS auditor is evaluating a virtual server environment and learns that the production server, development server, and management console are housed in the same physical host.<br \/>\n<br \/>What should be the auditor\u2019s PRIMARY concern?<\/p>\n<\/div><input type='hidden' name='question_id[]' value='125194' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515723' \/><div class='watu-question-choice'><input type='radio' name='answer-125194[]' id='answer-id-515723' class='answer answer-107  answerof-125194' value='515723' \/>&nbsp;<label for='answer-id-515723' id='answer-label-515723' class=' answer label-107'><span class='answer'>The physical host is a single point of failure<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515724' \/><div class='watu-question-choice'><input type='radio' name='answer-125194[]' id='answer-id-515724' class='answer answer-107  answerof-125194' value='515724' \/>&nbsp;<label for='answer-id-515724' id='answer-label-515724' class=' answer label-107'><span class='answer'>The management console is a single point of failure<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515725' \/><div class='watu-question-choice'><input type='radio' name='answer-125194[]' id='answer-id-515725' class='answer answer-107  answerof-125194' value='515725' \/>&nbsp;<label for='answer-id-515725' id='answer-label-515725' class=' answer label-107'><span class='answer'>The development server and management console share the same host<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515726' \/><div class='watu-question-choice'><input type='radio' name='answer-125194[]' id='answer-id-515726' class='answer answer-107  answerof-125194' value='515726' \/>&nbsp;<label for='answer-id-515726' id='answer-label-515726' class=' answer label-107'><span class='answer'>The development and production servers share the same host<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType107' value='radio' class=''><\/div><div class='watu-question' id='question-108'><div class='question-content'><p><span class='watu_num'>108. <\/span>An organization\u2019s disposal policy emphasizes obtaining maximum value for surplus IT media. The IS auditor should obtain assurance that:<\/p>\n<\/div><input type='hidden' name='question_id[]' value='125195' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515727' \/><div class='watu-question-choice'><input type='radio' name='answer-125195[]' id='answer-id-515727' class='answer answer-108  answerof-125195' value='515727' \/>&nbsp;<label for='answer-id-515727' id='answer-label-515727' class=' answer label-108'><span class='answer'>the media is returned to the vendor for credit<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515728' \/><div class='watu-question-choice'><input type='radio' name='answer-125195[]' id='answer-id-515728' class='answer answer-108  answerof-125195' value='515728' \/>&nbsp;<label for='answer-id-515728' id='answer-label-515728' class=' answer label-108'><span class='answer'>any existing data is removed before disposal<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515729' \/><div class='watu-question-choice'><input type='radio' name='answer-125195[]' id='answer-id-515729' class='answer answer-108  answerof-125195' value='515729' \/>&nbsp;<label for='answer-id-515729' id='answer-label-515729' class=' answer label-108'><span class='answer'>identification labels are removed<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515730' \/><div class='watu-question-choice'><input type='radio' name='answer-125195[]' id='answer-id-515730' class='answer answer-108  answerof-125195' value='515730' \/>&nbsp;<label for='answer-id-515730' id='answer-label-515730' class=' answer label-108'><span class='answer'>the media is recycled to other groups within the organization<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType108' value='radio' class=''><\/div><div class='watu-question' id='question-109'><div class='question-content'><p><span class='watu_num'>109. <\/span>An auditor notes the administrator user ID is shared among three financial managers to perform month-end updates.<br \/>\n<br \/>Which of the following is the BEST recommendation to ensure the administrator ID in the financial system is controlled effectively?<\/p>\n<\/div><input type='hidden' name='question_id[]' value='125196' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515731' \/><div class='watu-question-choice'><input type='radio' name='answer-125196[]' id='answer-id-515731' class='answer answer-109  answerof-125196' value='515731' \/>&nbsp;<label for='answer-id-515731' id='answer-label-515731' class=' answer label-109'><span class='answer'>Implement use of individual software tokens<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515732' \/><div class='watu-question-choice'><input type='radio' name='answer-125196[]' id='answer-id-515732' class='answer answer-109  answerof-125196' value='515732' \/>&nbsp;<label for='answer-id-515732' id='answer-label-515732' class=' answer label-109'><span class='answer'>Conduct employee awareness training<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515733' \/><div class='watu-question-choice'><input type='radio' name='answer-125196[]' id='answer-id-515733' class='answer answer-109  answerof-125196' value='515733' \/>&nbsp;<label for='answer-id-515733' id='answer-label-515733' class=' answer label-109'><span class='answer'>Institute user ID logging and monitoring<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515734' \/><div class='watu-question-choice'><input type='radio' name='answer-125196[]' id='answer-id-515734' class='answer answer-109  answerof-125196' value='515734' \/>&nbsp;<label for='answer-id-515734' id='answer-label-515734' class=' answer label-109'><span class='answer'>Ensure data in the financial systems has been classified<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType109' value='radio' class=''><\/div><div class='watu-question' id='question-110'><div class='question-content'><p><span class='watu_num'>110. <\/span>Which of the following is MOST important for an IS auditor to verify after finding repeated unauthorized access attempts were recorded on a security report?<\/p>\n<\/div><input type='hidden' name='question_id[]' value='125197' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515735' \/><div class='watu-question-choice'><input type='radio' name='answer-125197[]' id='answer-id-515735' class='answer answer-110  answerof-125197' value='515735' \/>&nbsp;<label for='answer-id-515735' id='answer-label-515735' class=' answer label-110'><span class='answer'>Password reset requests have been confirmed as legitimate<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515736' \/><div class='watu-question-choice'><input type='radio' name='answer-125197[]' id='answer-id-515736' class='answer answer-110  answerof-125197' value='515736' \/>&nbsp;<label for='answer-id-515736' id='answer-label-515736' class=' answer label-110'><span class='answer'>There is evidence that the incident was investigated<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515737' \/><div class='watu-question-choice'><input type='radio' name='answer-125197[]' id='answer-id-515737' class='answer answer-110  answerof-125197' value='515737' \/>&nbsp;<label for='answer-id-515737' id='answer-label-515737' class=' answer label-110'><span class='answer'>System configuration changes are properly tracked<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515738' \/><div class='watu-question-choice'><input type='radio' name='answer-125197[]' id='answer-id-515738' class='answer answer-110  answerof-125197' value='515738' \/>&nbsp;<label for='answer-id-515738' id='answer-label-515738' class=' answer label-110'><span class='answer'>A comprehensive access policy has been established<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType110' value='radio' class=''><\/div><div class='watu-question' id='question-111'><div class='question-content'><p><span class='watu_num'>111. <\/span>An IS auditor is involved with a project and finds an IT project stakeholder wants to make a change that could affect both the project scope and schedule.<br \/>\n<br \/>Which of the following would be the MOST appropriate action for the project manager with respect to the change request?<\/p>\n<\/div><input type='hidden' name='question_id[]' value='125198' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515739' \/><div class='watu-question-choice'><input type='radio' name='answer-125198[]' id='answer-id-515739' class='answer answer-111  answerof-125198' value='515739' \/>&nbsp;<label for='answer-id-515739' id='answer-label-515739' class=' answer label-111'><span class='answer'>Recommend to the project sponsor whether to approve the change<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515740' \/><div class='watu-question-choice'><input type='radio' name='answer-125198[]' id='answer-id-515740' class='answer answer-111  answerof-125198' value='515740' \/>&nbsp;<label for='answer-id-515740' id='answer-label-515740' class=' answer label-111'><span class='answer'>Modify the project plan as a result of the change<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515741' \/><div class='watu-question-choice'><input type='radio' name='answer-125198[]' id='answer-id-515741' class='answer answer-111  answerof-125198' value='515741' \/>&nbsp;<label for='answer-id-515741' id='answer-label-515741' class=' answer label-111'><span class='answer'>Evaluate the impact of the change<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515742' \/><div class='watu-question-choice'><input type='radio' name='answer-125198[]' id='answer-id-515742' class='answer answer-111  answerof-125198' value='515742' \/>&nbsp;<label for='answer-id-515742' id='answer-label-515742' class=' answer label-111'><span class='answer'>Ignore out-of-scope requests<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType111' value='radio' class=''><\/div><div class='watu-question' id='question-112'><div class='question-content'><p><span class='watu_num'>112. <\/span>Which of the following should an IS auditor expect to see in a network vulnerability assessment?<\/p>\n<\/div><input type='hidden' name='question_id[]' value='125199' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515743' \/><div class='watu-question-choice'><input type='radio' name='answer-125199[]' id='answer-id-515743' class='answer answer-112  answerof-125199' value='515743' \/>&nbsp;<label for='answer-id-515743' id='answer-label-515743' class=' answer label-112'><span class='answer'>Misconfiguration and missing updates<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515744' \/><div class='watu-question-choice'><input type='radio' name='answer-125199[]' id='answer-id-515744' class='answer answer-112  answerof-125199' value='515744' \/>&nbsp;<label for='answer-id-515744' id='answer-label-515744' class=' answer label-112'><span class='answer'>Malicious software and spyware<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515745' \/><div class='watu-question-choice'><input type='radio' name='answer-125199[]' id='answer-id-515745' class='answer answer-112  answerof-125199' value='515745' \/>&nbsp;<label for='answer-id-515745' id='answer-label-515745' class=' answer label-112'><span class='answer'>Security design flaws<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515746' \/><div class='watu-question-choice'><input type='radio' name='answer-125199[]' id='answer-id-515746' class='answer answer-112  answerof-125199' value='515746' \/>&nbsp;<label for='answer-id-515746' id='answer-label-515746' class=' answer label-112'><span class='answer'>Zero-day vulnerabilities<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType112' value='radio' class=''><\/div><div class='watu-question' id='question-113'><div class='question-content'><p><span class='watu_num'>113. <\/span>An IS auditor is evaluating the security of an organization\u2019s data backup process, which includes the transmission of daily incremental backups to a dedicated offsite server.<br \/>\n<br \/>Which of the following findings poses the GREATEST risk to the organization?<\/p>\n<\/div><input type='hidden' name='question_id[]' value='125200' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515747' \/><div class='watu-question-choice'><input type='radio' name='answer-125200[]' id='answer-id-515747' class='answer answer-113  answerof-125200' value='515747' \/>&nbsp;<label for='answer-id-515747' id='answer-label-515747' class=' answer label-113'><span class='answer'>Backup transmissions are not encrypted<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515748' \/><div class='watu-question-choice'><input type='radio' name='answer-125200[]' id='answer-id-515748' class='answer answer-113  answerof-125200' value='515748' \/>&nbsp;<label for='answer-id-515748' id='answer-label-515748' class=' answer label-113'><span class='answer'>Backup transmissions occasionally fail<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515749' \/><div class='watu-question-choice'><input type='radio' name='answer-125200[]' id='answer-id-515749' class='answer answer-113  answerof-125200' value='515749' \/>&nbsp;<label for='answer-id-515749' id='answer-label-515749' class=' answer label-113'><span class='answer'>Data recovery testing is conducted once per year<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515750' \/><div class='watu-question-choice'><input type='radio' name='answer-125200[]' id='answer-id-515750' class='answer answer-113  answerof-125200' value='515750' \/>&nbsp;<label for='answer-id-515750' id='answer-label-515750' class=' answer label-113'><span class='answer'>The archived data log is incomplete<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType113' value='radio' class=''><\/div><div class='watu-question' id='question-114'><div class='question-content'><p><span class='watu_num'>114. <\/span>When continuous monitoring systems are being implemented, an IS auditor should FIRST identify:<\/p>\n<\/div><input type='hidden' name='question_id[]' value='125201' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515751' \/><div class='watu-question-choice'><input type='radio' name='answer-125201[]' id='answer-id-515751' class='answer answer-114  answerof-125201' value='515751' \/>&nbsp;<label for='answer-id-515751' id='answer-label-515751' class=' answer label-114'><span class='answer'>the location and format of output files<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515752' \/><div class='watu-question-choice'><input type='radio' name='answer-125201[]' id='answer-id-515752' class='answer answer-114  answerof-125201' value='515752' \/>&nbsp;<label for='answer-id-515752' id='answer-label-515752' class=' answer label-114'><span class='answer'>applications that provide the highest financial risk<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515753' \/><div class='watu-question-choice'><input type='radio' name='answer-125201[]' id='answer-id-515753' class='answer answer-114  answerof-125201' value='515753' \/>&nbsp;<label for='answer-id-515753' id='answer-label-515753' class=' answer label-114'><span class='answer'>high-risk areas within the organization<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515754' \/><div class='watu-question-choice'><input type='radio' name='answer-125201[]' id='answer-id-515754' class='answer answer-114  answerof-125201' value='515754' \/>&nbsp;<label for='answer-id-515754' id='answer-label-515754' class=' answer label-114'><span class='answer'>the controls on which to focus<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType114' value='radio' class=''><\/div><div class='watu-question' id='question-115'><div class='question-content'><p><span class='watu_num'>115. <\/span>During a follow-up audit, an IS auditor concludes that a previously identified issue has not been adequately remediated. The auditee insists the risk has been addressed. The auditor should:<\/p>\n<\/div><input type='hidden' name='question_id[]' value='125202' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515755' \/><div class='watu-question-choice'><input type='radio' name='answer-125202[]' id='answer-id-515755' class='answer answer-115  answerof-125202' value='515755' \/>&nbsp;<label for='answer-id-515755' id='answer-label-515755' class=' answer label-115'><span class='answer'>recommend an independent assessment by a third party<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515756' \/><div class='watu-question-choice'><input type='radio' name='answer-125202[]' id='answer-id-515756' class='answer answer-115  answerof-125202' value='515756' \/>&nbsp;<label for='answer-id-515756' id='answer-label-515756' class=' answer label-115'><span class='answer'>report the disagreement according to established procedures<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515757' \/><div class='watu-question-choice'><input type='radio' name='answer-125202[]' id='answer-id-515757' class='answer answer-115  answerof-125202' value='515757' \/>&nbsp;<label for='answer-id-515757' id='answer-label-515757' class=' answer label-115'><span class='answer'>follow-up on the finding next year<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515758' \/><div class='watu-question-choice'><input type='radio' name='answer-125202[]' id='answer-id-515758' class='answer answer-115  answerof-125202' value='515758' \/>&nbsp;<label for='answer-id-515758' id='answer-label-515758' class=' answer label-115'><span class='answer'>accept the auditee\u2019s position and close the finding<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType115' value='radio' class=''><\/div><div class='watu-question' id='question-116'><div class='question-content'><p><span class='watu_num'>116. <\/span>An organization allows employee use of personal mobile devices for corporate email.<br \/>\n<br \/>Which of the following should be the GREATEST IS audit concern?<\/p>\n<\/div><input type='hidden' name='question_id[]' value='125203' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515759' \/><div class='watu-question-choice'><input type='radio' name='answer-125203[]' id='answer-id-515759' class='answer answer-116  answerof-125203' value='515759' \/>&nbsp;<label for='answer-id-515759' id='answer-label-515759' class=' answer label-116'><span class='answer'>Email forwarding to private devices requires excessive network bandwidth<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515760' \/><div class='watu-question-choice'><input type='radio' name='answer-125203[]' id='answer-id-515760' class='answer answer-116  answerof-125203' value='515760' \/>&nbsp;<label for='answer-id-515760' id='answer-label-515760' class=' answer label-116'><span class='answer'>There is no corporate policy for the acceptable use of private devices<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515761' \/><div class='watu-question-choice'><input type='radio' name='answer-125203[]' id='answer-id-515761' class='answer answer-116  answerof-125203' value='515761' \/>&nbsp;<label for='answer-id-515761' id='answer-label-515761' class=' answer label-116'><span class='answer'>There is no adequate tracking of the working time spent out-of-hours<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515762' \/><div class='watu-question-choice'><input type='radio' name='answer-125203[]' id='answer-id-515762' class='answer answer-116  answerof-125203' value='515762' \/>&nbsp;<label for='answer-id-515762' id='answer-label-515762' class=' answer label-116'><span class='answer'>The help desk is not able to fully support different kinds of private devices<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType116' value='radio' class=''><\/div><div class='watu-question' id='question-117'><div class='question-content'><p><span class='watu_num'>117. <\/span>Which of the following findings would be of GREATEST concern to an IS auditor reviewing an organization\u2019s newly implemented online security awareness program?<\/p>\n<\/div><input type='hidden' name='question_id[]' value='125204' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515763' \/><div class='watu-question-choice'><input type='radio' name='answer-125204[]' id='answer-id-515763' class='answer answer-117  answerof-125204' value='515763' \/>&nbsp;<label for='answer-id-515763' id='answer-label-515763' class=' answer label-117'><span class='answer'>Only new employees are required to attend the program<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515764' \/><div class='watu-question-choice'><input type='radio' name='answer-125204[]' id='answer-id-515764' class='answer answer-117  answerof-125204' value='515764' \/>&nbsp;<label for='answer-id-515764' id='answer-label-515764' class=' answer label-117'><span class='answer'>The timing for program updates has not been determined<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515765' \/><div class='watu-question-choice'><input type='radio' name='answer-125204[]' id='answer-id-515765' class='answer answer-117  answerof-125204' value='515765' \/>&nbsp;<label for='answer-id-515765' id='answer-label-515765' class=' answer label-117'><span class='answer'>Metrics have not been established to assess training results<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515766' \/><div class='watu-question-choice'><input type='radio' name='answer-125204[]' id='answer-id-515766' class='answer answer-117  answerof-125204' value='515766' \/>&nbsp;<label for='answer-id-515766' id='answer-label-515766' class=' answer label-117'><span class='answer'>Employees do not receive immediate notification of results<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType117' value='radio' class=''><\/div><div class='watu-question' id='question-118'><div class='question-content'><p><span class='watu_num'>118. <\/span>What would be of GREATEST concern to an IS auditor observing shared key cards being utilized to access an organization\u2019s data center?<\/p>\n<\/div><input type='hidden' name='question_id[]' value='125205' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515767' \/><div class='watu-question-choice'><input type='radio' name='answer-125205[]' id='answer-id-515767' class='answer answer-118  answerof-125205' value='515767' \/>&nbsp;<label for='answer-id-515767' id='answer-label-515767' class=' answer label-118'><span class='answer'>The lack of a multi-factor authentication system<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515768' \/><div class='watu-question-choice'><input type='radio' name='answer-125205[]' id='answer-id-515768' class='answer answer-118  answerof-125205' value='515768' \/>&nbsp;<label for='answer-id-515768' id='answer-label-515768' class=' answer label-118'><span class='answer'>The inability to identify who has entered the data center<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515769' \/><div class='watu-question-choice'><input type='radio' name='answer-125205[]' id='answer-id-515769' class='answer answer-118  answerof-125205' value='515769' \/>&nbsp;<label for='answer-id-515769' id='answer-label-515769' class=' answer label-118'><span class='answer'>The inability to track the number of misplaced cards<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515770' \/><div class='watu-question-choice'><input type='radio' name='answer-125205[]' id='answer-id-515770' class='answer answer-118  answerof-125205' value='515770' \/>&nbsp;<label for='answer-id-515770' id='answer-label-515770' class=' answer label-118'><span class='answer'>The lack of enforcement of organizational policy and procedures<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType118' value='radio' class=''><\/div><div class='watu-question' id='question-119'><div class='question-content'><p><span class='watu_num'>119. <\/span>Which of the following is MOST important for an IS auditor to ensure is included in a global organization\u2019s online data privacy notification to customers?<\/p>\n<\/div><input type='hidden' name='question_id[]' value='125206' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515771' \/><div class='watu-question-choice'><input type='radio' name='answer-125206[]' id='answer-id-515771' class='answer answer-119  answerof-125206' value='515771' \/>&nbsp;<label for='answer-id-515771' id='answer-label-515771' class=' answer label-119'><span class='answer'>Consequences to the organization for mishandling the data<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515772' \/><div class='watu-question-choice'><input type='radio' name='answer-125206[]' id='answer-id-515772' class='answer answer-119  answerof-125206' value='515772' \/>&nbsp;<label for='answer-id-515772' id='answer-label-515772' class=' answer label-119'><span class='answer'>Consent terms including the purpose of data collection<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515773' \/><div class='watu-question-choice'><input type='radio' name='answer-125206[]' id='answer-id-515773' class='answer answer-119  answerof-125206' value='515773' \/>&nbsp;<label for='answer-id-515773' id='answer-label-515773' class=' answer label-119'><span class='answer'>Contact information for reporting violations of consent<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515774' \/><div class='watu-question-choice'><input type='radio' name='answer-125206[]' id='answer-id-515774' class='answer answer-119  answerof-125206' value='515774' \/>&nbsp;<label for='answer-id-515774' id='answer-label-515774' class=' answer label-119'><span class='answer'>Industry standards for data breach notification<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType119' value='radio' class=''><\/div><div class='watu-question' id='question-120'><div class='question-content'><p><span class='watu_num'>120. <\/span>While planning a security audit, an IS auditor is made aware of a security review carried out by external consultants. It is MOST important for the auditor to:<\/p>\n<\/div><input type='hidden' name='question_id[]' value='125207' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515775' \/><div class='watu-question-choice'><input type='radio' name='answer-125207[]' id='answer-id-515775' class='answer answer-120  answerof-125207' value='515775' \/>&nbsp;<label for='answer-id-515775' id='answer-label-515775' class=' answer label-120'><span class='answer'>re-perform the security review.<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515776' \/><div class='watu-question-choice'><input type='radio' name='answer-125207[]' id='answer-id-515776' class='answer answer-120  answerof-125207' value='515776' \/>&nbsp;<label for='answer-id-515776' id='answer-label-515776' class=' answer label-120'><span class='answer'>accept the findings and conclusions of the consultants.<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515777' \/><div class='watu-question-choice'><input type='radio' name='answer-125207[]' id='answer-id-515777' class='answer answer-120  answerof-125207' value='515777' \/>&nbsp;<label for='answer-id-515777' id='answer-label-515777' class=' answer label-120'><span class='answer'>review similar reports issued by the consultants.<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515778' \/><div class='watu-question-choice'><input type='radio' name='answer-125207[]' id='answer-id-515778' class='answer answer-120  answerof-125207' value='515778' \/>&nbsp;<label for='answer-id-515778' id='answer-label-515778' class=' answer label-120'><span class='answer'>assess the objectivity and competence of the consultants.<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType120' value='radio' class=''><\/div><div class='watu-question' id='question-121'><div class='question-content'><p><span class='watu_num'>121. <\/span>Which of the following is the BEST IS audit strategy?<\/p>\n<\/div><input type='hidden' name='question_id[]' value='125208' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515779' \/><div class='watu-question-choice'><input type='radio' name='answer-125208[]' id='answer-id-515779' class='answer answer-121  answerof-125208' value='515779' \/>&nbsp;<label for='answer-id-515779' id='answer-label-515779' class=' answer label-121'><span class='answer'>Perform audits based on impact and probability of error and failure.<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515780' \/><div class='watu-question-choice'><input type='radio' name='answer-125208[]' id='answer-id-515780' class='answer answer-121  answerof-125208' value='515780' \/>&nbsp;<label for='answer-id-515780' id='answer-label-515780' class=' answer label-121'><span class='answer'>Cycle general control and application audits over a two-year period.<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515781' \/><div class='watu-question-choice'><input type='radio' name='answer-125208[]' id='answer-id-515781' class='answer answer-121  answerof-125208' value='515781' \/>&nbsp;<label for='answer-id-515781' id='answer-label-515781' class=' answer label-121'><span class='answer'>Conduct general control audits annually and application audits in alternating years.<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515782' \/><div class='watu-question-choice'><input type='radio' name='answer-125208[]' id='answer-id-515782' class='answer answer-121  answerof-125208' value='515782' \/>&nbsp;<label for='answer-id-515782' id='answer-label-515782' class=' answer label-121'><span class='answer'>Limit audits to new application system developments.<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType121' value='radio' class=''><\/div><div class='watu-question' id='question-122'><div class='question-content'><p><span class='watu_num'>122. <\/span>Which of the following is MOST important for an IS auditor to review when evaluating the effectiveness of an organization\u2019s incident response process?<\/p>\n<\/div><input type='hidden' name='question_id[]' value='125209' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515783' \/><div class='watu-question-choice'><input type='radio' name='answer-125209[]' id='answer-id-515783' class='answer answer-122  answerof-125209' value='515783' \/>&nbsp;<label for='answer-id-515783' id='answer-label-515783' class=' answer label-122'><span class='answer'>Past incident response actions<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515784' \/><div class='watu-question-choice'><input type='radio' name='answer-125209[]' id='answer-id-515784' class='answer answer-122  answerof-125209' value='515784' \/>&nbsp;<label for='answer-id-515784' id='answer-label-515784' class=' answer label-122'><span class='answer'>Incident response staff experience and qualifications<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515785' \/><div class='watu-question-choice'><input type='radio' name='answer-125209[]' id='answer-id-515785' class='answer answer-122  answerof-125209' value='515785' \/>&nbsp;<label for='answer-id-515785' id='answer-label-515785' class=' answer label-122'><span class='answer'>Results from management testing of incident response procedures<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515786' \/><div class='watu-question-choice'><input type='radio' name='answer-125209[]' id='answer-id-515786' class='answer answer-122  answerof-125209' value='515786' \/>&nbsp;<label for='answer-id-515786' id='answer-label-515786' class=' answer label-122'><span class='answer'>Incident response roles and responsibilities<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType122' value='radio' class=''><\/div><div class='watu-question' id='question-123'><div class='question-content'><p><span class='watu_num'>123. <\/span>Which of the following observations would an IS auditor consider the GREATEST risk when conducting an audit of a virtual server farm for potential software vulnerabilities?<\/p>\n<\/div><input type='hidden' name='question_id[]' value='125210' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515787' \/><div class='watu-question-choice'><input type='radio' name='answer-125210[]' id='answer-id-515787' class='answer answer-123  answerof-125210' value='515787' \/>&nbsp;<label for='answer-id-515787' id='answer-label-515787' class=' answer label-123'><span class='answer'>The hypervisor is updated quarterly.<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515788' \/><div class='watu-question-choice'><input type='radio' name='answer-125210[]' id='answer-id-515788' class='answer answer-123  answerof-125210' value='515788' \/>&nbsp;<label for='answer-id-515788' id='answer-label-515788' class=' answer label-123'><span class='answer'>Guest operating systems are updated monthly.<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515789' \/><div class='watu-question-choice'><input type='radio' name='answer-125210[]' id='answer-id-515789' class='answer answer-123  answerof-125210' value='515789' \/>&nbsp;<label for='answer-id-515789' id='answer-label-515789' class=' answer label-123'><span class='answer'>Antivirus software has been implemented on the guest operating system only.<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515790' \/><div class='watu-question-choice'><input type='radio' name='answer-125210[]' id='answer-id-515790' class='answer answer-123  answerof-125210' value='515790' \/>&nbsp;<label for='answer-id-515790' id='answer-label-515790' class=' answer label-123'><span class='answer'>A variety of guest operating systems operate on one virtual server.<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType123' value='radio' class=''><\/div><div class='watu-question' id='question-124'><div class='question-content'><p><span class='watu_num'>124. <\/span>An internal audit department recently established a quality assurance (QA) program.<br \/>\n<br \/>Which of the following activities is MOST important to include as part of the QA program requirements?<\/p>\n<\/div><input type='hidden' name='question_id[]' value='125211' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515791' \/><div class='watu-question-choice'><input type='radio' name='answer-125211[]' id='answer-id-515791' class='answer answer-124  answerof-125211' value='515791' \/>&nbsp;<label for='answer-id-515791' id='answer-label-515791' class=' answer label-124'><span class='answer'>Ongoing monitoring of the audit activities<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515792' \/><div class='watu-question-choice'><input type='radio' name='answer-125211[]' id='answer-id-515792' class='answer answer-124  answerof-125211' value='515792' \/>&nbsp;<label for='answer-id-515792' id='answer-label-515792' class=' answer label-124'><span class='answer'>Analysis of user satisfaction reports from business lines.<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515793' \/><div class='watu-question-choice'><input type='radio' name='answer-125211[]' id='answer-id-515793' class='answer answer-124  answerof-125211' value='515793' \/>&nbsp;<label for='answer-id-515793' id='answer-label-515793' class=' answer label-124'><span class='answer'>Feedback from internal audit staff<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515794' \/><div class='watu-question-choice'><input type='radio' name='answer-125211[]' id='answer-id-515794' class='answer answer-124  answerof-125211' value='515794' \/>&nbsp;<label for='answer-id-515794' id='answer-label-515794' class=' answer label-124'><span class='answer'>Long-term internal audit resource planning<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType124' value='radio' class=''><\/div><div class='watu-question' id='question-125'><div class='question-content'><p><span class='watu_num'>125. <\/span>An IS auditor is mapping controls to risk for an accounts payable system.<br \/>\n<br \/>What is the BEST control to detect errors in the system?<\/p>\n<\/div><input type='hidden' name='question_id[]' value='125212' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515795' \/><div class='watu-question-choice'><input type='radio' name='answer-125212[]' id='answer-id-515795' class='answer answer-125  answerof-125212' value='515795' \/>&nbsp;<label for='answer-id-515795' id='answer-label-515795' class=' answer label-125'><span class='answer'>Alignment of the process to business objectives<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515796' \/><div class='watu-question-choice'><input type='radio' name='answer-125212[]' id='answer-id-515796' class='answer answer-125  answerof-125212' value='515796' \/>&nbsp;<label for='answer-id-515796' id='answer-label-515796' class=' answer label-125'><span class='answer'>Quality control review of new payments<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515797' \/><div class='watu-question-choice'><input type='radio' name='answer-125212[]' id='answer-id-515797' class='answer answer-125  answerof-125212' value='515797' \/>&nbsp;<label for='answer-id-515797' id='answer-label-515797' class=' answer label-125'><span class='answer'>Management approval of payments<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515798' \/><div class='watu-question-choice'><input type='radio' name='answer-125212[]' id='answer-id-515798' class='answer answer-125  answerof-125212' value='515798' \/>&nbsp;<label for='answer-id-515798' id='answer-label-515798' class=' answer label-125'><span class='answer'>Input validation<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType125' value='radio' class=''><\/div><div class='watu-question' id='question-126'><div class='question-content'><p><span class='watu_num'>126. <\/span>When auditing a quality assurance plan, an IS auditor should be MOST concerned if the:<\/p>\n<\/div><input type='hidden' name='question_id[]' value='125213' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515799' \/><div class='watu-question-choice'><input type='radio' name='answer-125213[]' id='answer-id-515799' class='answer answer-126  answerof-125213' value='515799' \/>&nbsp;<label for='answer-id-515799' id='answer-label-515799' class=' answer label-126'><span class='answer'>quality assurance function is separate from the programming function.<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515800' \/><div class='watu-question-choice'><input type='radio' name='answer-125213[]' id='answer-id-515800' class='answer answer-126  answerof-125213' value='515800' \/>&nbsp;<label for='answer-id-515800' id='answer-label-515800' class=' answer label-126'><span class='answer'>SDLC is coupled with the quality assurance plan.<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515801' \/><div class='watu-question-choice'><input type='radio' name='answer-125213[]' id='answer-id-515801' class='answer answer-126  answerof-125213' value='515801' \/>&nbsp;<label for='answer-id-515801' id='answer-label-515801' class=' answer label-126'><span class='answer'>quality assurance function is periodically reviewed by internal audit.<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515802' \/><div class='watu-question-choice'><input type='radio' name='answer-125213[]' id='answer-id-515802' class='answer answer-126  answerof-125213' value='515802' \/>&nbsp;<label for='answer-id-515802' id='answer-label-515802' class=' answer label-126'><span class='answer'>scope of quality assurance activities is undefined.<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType126' value='radio' class=''><\/div><div class='watu-question' id='question-127'><div class='question-content'><p><span class='watu_num'>127. <\/span>The PRIMARY reason for an IS auditor to use data analytics techniques is to reduce which type of audit risk?<\/p>\n<\/div><input type='hidden' name='question_id[]' value='125214' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515803' \/><div class='watu-question-choice'><input type='radio' name='answer-125214[]' id='answer-id-515803' class='answer answer-127  answerof-125214' value='515803' \/>&nbsp;<label for='answer-id-515803' id='answer-label-515803' class=' answer label-127'><span class='answer'>Technology risk<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515804' \/><div class='watu-question-choice'><input type='radio' name='answer-125214[]' id='answer-id-515804' class='answer answer-127  answerof-125214' value='515804' \/>&nbsp;<label for='answer-id-515804' id='answer-label-515804' class=' answer label-127'><span class='answer'>Inherent risk<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515805' \/><div class='watu-question-choice'><input type='radio' name='answer-125214[]' id='answer-id-515805' class='answer answer-127  answerof-125214' value='515805' \/>&nbsp;<label for='answer-id-515805' id='answer-label-515805' class=' answer label-127'><span class='answer'>Detection risk<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515806' \/><div class='watu-question-choice'><input type='radio' name='answer-125214[]' id='answer-id-515806' class='answer answer-127  answerof-125214' value='515806' \/>&nbsp;<label for='answer-id-515806' id='answer-label-515806' class=' answer label-127'><span class='answer'>Control risk<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType127' value='radio' class=''><\/div><div class='watu-question' id='question-128'><div class='question-content'><p><span class='watu_num'>128. <\/span>An IS audit manager has been asked to perform a quality review on an audit that the same manager also supervised.<br \/>\n<br \/>Which of the following is the manager\u2019s BEST response to this situation?<\/p>\n<\/div><input type='hidden' name='question_id[]' value='125215' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515807' \/><div class='watu-question-choice'><input type='radio' name='answer-125215[]' id='answer-id-515807' class='answer answer-128  answerof-125215' value='515807' \/>&nbsp;<label for='answer-id-515807' id='answer-label-515807' class=' answer label-128'><span class='answer'>Notify the audit committee of the situation.<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515808' \/><div class='watu-question-choice'><input type='radio' name='answer-125215[]' id='answer-id-515808' class='answer answer-128  answerof-125215' value='515808' \/>&nbsp;<label for='answer-id-515808' id='answer-label-515808' class=' answer label-128'><span class='answer'>Escalate the situation to senior audit leadership.<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515809' \/><div class='watu-question-choice'><input type='radio' name='answer-125215[]' id='answer-id-515809' class='answer answer-128  answerof-125215' value='515809' \/>&nbsp;<label for='answer-id-515809' id='answer-label-515809' class=' answer label-128'><span class='answer'>Determine whether audit evidence supports audit conclusions.<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515810' \/><div class='watu-question-choice'><input type='radio' name='answer-125215[]' id='answer-id-515810' class='answer answer-128  answerof-125215' value='515810' \/>&nbsp;<label for='answer-id-515810' id='answer-label-515810' class=' answer label-128'><span class='answer'>Discuss with the audit team to understand how conclusions were reached.<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType128' value='radio' class=''><\/div><div class='watu-question' id='question-129'><div class='question-content'><p><span class='watu_num'>129. <\/span>While reviewing similar issues in an organization\u2019s help desk system, an IS auditor finds that they were analyzed independently and resolved differently. This situation MOST likely indicates a deficiency in:<\/p>\n<\/div><input type='hidden' name='question_id[]' value='125216' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515811' \/><div class='watu-question-choice'><input type='radio' name='answer-125216[]' id='answer-id-515811' class='answer answer-129  answerof-125216' value='515811' \/>&nbsp;<label for='answer-id-515811' id='answer-label-515811' class=' answer label-129'><span class='answer'>IT service level management.<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515812' \/><div class='watu-question-choice'><input type='radio' name='answer-125216[]' id='answer-id-515812' class='answer answer-129  answerof-125216' value='515812' \/>&nbsp;<label for='answer-id-515812' id='answer-label-515812' class=' answer label-129'><span class='answer'>change management.<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515813' \/><div class='watu-question-choice'><input type='radio' name='answer-125216[]' id='answer-id-515813' class='answer answer-129  answerof-125216' value='515813' \/>&nbsp;<label for='answer-id-515813' id='answer-label-515813' class=' answer label-129'><span class='answer'>configuration management.<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515814' \/><div class='watu-question-choice'><input type='radio' name='answer-125216[]' id='answer-id-515814' class='answer answer-129  answerof-125216' value='515814' \/>&nbsp;<label for='answer-id-515814' id='answer-label-515814' class=' answer label-129'><span class='answer'>problem management.<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType129' value='radio' class=''><\/div><div class='watu-question' id='question-130'><div class='question-content'><p><span class='watu_num'>130. <\/span>An auditor is creating an audit program in which the objective is to establish the adequacy of personal data privacy controls in a payroll process.<br \/>\n<br \/>Which of the following would be MOST important to include?<\/p>\n<\/div><input type='hidden' name='question_id[]' value='125217' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515815' \/><div class='watu-question-choice'><input type='radio' name='answer-125217[]' id='answer-id-515815' class='answer answer-130  answerof-125217' value='515815' \/>&nbsp;<label for='answer-id-515815' id='answer-label-515815' class=' answer label-130'><span class='answer'>Approval of data changes<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515816' \/><div class='watu-question-choice'><input type='radio' name='answer-125217[]' id='answer-id-515816' class='answer answer-130  answerof-125217' value='515816' \/>&nbsp;<label for='answer-id-515816' id='answer-label-515816' class=' answer label-130'><span class='answer'>Audit logging of administrative user activity<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515817' \/><div class='watu-question-choice'><input type='radio' name='answer-125217[]' id='answer-id-515817' class='answer answer-130  answerof-125217' value='515817' \/>&nbsp;<label for='answer-id-515817' id='answer-label-515817' class=' answer label-130'><span class='answer'>Segregation of duties controls<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515818' \/><div class='watu-question-choice'><input type='radio' name='answer-125217[]' id='answer-id-515818' class='answer answer-130  answerof-125217' value='515818' \/>&nbsp;<label for='answer-id-515818' id='answer-label-515818' class=' answer label-130'><span class='answer'>User access provisioning<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType130' value='radio' class=''><\/div><div class='watu-question' id='question-131'><div class='question-content'><p><span class='watu_num'>131. <\/span>An IS auditor auditing the effectiveness of utilizing a hot site will MOST likely:<\/p>\n<\/div><input type='hidden' name='question_id[]' value='125218' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515819' \/><div class='watu-question-choice'><input type='radio' name='answer-125218[]' id='answer-id-515819' class='answer answer-131  answerof-125218' value='515819' \/>&nbsp;<label for='answer-id-515819' id='answer-label-515819' class=' answer label-131'><span class='answer'>review reciprocal agreements.<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515820' \/><div class='watu-question-choice'><input type='radio' name='answer-125218[]' id='answer-id-515820' class='answer answer-131  answerof-125218' value='515820' \/>&nbsp;<label for='answer-id-515820' id='answer-label-515820' class=' answer label-131'><span class='answer'>review logical access controls.<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515821' \/><div class='watu-question-choice'><input type='radio' name='answer-125218[]' id='answer-id-515821' class='answer answer-131  answerof-125218' value='515821' \/>&nbsp;<label for='answer-id-515821' id='answer-label-515821' class=' answer label-131'><span class='answer'>evaluate physical access controls.<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515822' \/><div class='watu-question-choice'><input type='radio' name='answer-125218[]' id='answer-id-515822' class='answer answer-131  answerof-125218' value='515822' \/>&nbsp;<label for='answer-id-515822' id='answer-label-515822' class=' answer label-131'><span class='answer'>analyze system restoration procedures.<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType131' value='radio' class=''><\/div><div class='watu-question' id='question-132'><div class='question-content'><p><span class='watu_num'>132. <\/span>An IS auditor has assessed a payroll service provider\u2019s security policy and finds significant topics are missing.<br \/>\n<br \/>Which of the following is the auditor\u2019s BEST course of action?<\/p>\n<\/div><input type='hidden' name='question_id[]' value='125219' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515823' \/><div class='watu-question-choice'><input type='radio' name='answer-125219[]' id='answer-id-515823' class='answer answer-132  answerof-125219' value='515823' \/>&nbsp;<label for='answer-id-515823' id='answer-label-515823' class=' answer label-132'><span class='answer'>Recommend the service provider update their policy.<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515824' \/><div class='watu-question-choice'><input type='radio' name='answer-125219[]' id='answer-id-515824' class='answer answer-132  answerof-125219' value='515824' \/>&nbsp;<label for='answer-id-515824' id='answer-label-515824' class=' answer label-132'><span class='answer'>Notify the service provider of the discrepancies.<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515825' \/><div class='watu-question-choice'><input type='radio' name='answer-125219[]' id='answer-id-515825' class='answer answer-132  answerof-125219' value='515825' \/>&nbsp;<label for='answer-id-515825' id='answer-label-515825' class=' answer label-132'><span class='answer'>Report the risk to internal management.<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515826' \/><div class='watu-question-choice'><input type='radio' name='answer-125219[]' id='answer-id-515826' class='answer answer-132  answerof-125219' value='515826' \/>&nbsp;<label for='answer-id-515826' id='answer-label-515826' class=' answer label-132'><span class='answer'>Recommend replacement of the service provider.<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType132' value='radio' class=''><\/div><div class='watu-question' id='question-133'><div class='question-content'><p><span class='watu_num'>133. <\/span>While reviewing a hot site, the IS auditor discovers that one type of hardware platform is not installed. The IS auditor should FIRST:<\/p>\n<\/div><input type='hidden' name='question_id[]' value='125220' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515827' \/><div class='watu-question-choice'><input type='radio' name='answer-125220[]' id='answer-id-515827' class='answer answer-133  answerof-125220' value='515827' \/>&nbsp;<label for='answer-id-515827' id='answer-label-515827' class=' answer label-133'><span class='answer'>recommend the purchase and installation of hardware at the hot site.<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515828' \/><div class='watu-question-choice'><input type='radio' name='answer-125220[]' id='answer-id-515828' class='answer answer-133  answerof-125220' value='515828' \/>&nbsp;<label for='answer-id-515828' id='answer-label-515828' class=' answer label-133'><span class='answer'>report the finding immediately to senior IS management.<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515829' \/><div class='watu-question-choice'><input type='radio' name='answer-125220[]' id='answer-id-515829' class='answer answer-133  answerof-125220' value='515829' \/>&nbsp;<label for='answer-id-515829' id='answer-label-515829' class=' answer label-133'><span class='answer'>determine the business impact of the absence of the hardware.<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515830' \/><div class='watu-question-choice'><input type='radio' name='answer-125220[]' id='answer-id-515830' class='answer answer-133  answerof-125220' value='515830' \/>&nbsp;<label for='answer-id-515830' id='answer-label-515830' class=' answer label-133'><span class='answer'>establish the lead time for delivery of a new machine.<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType133' value='radio' class=''><\/div><div class='watu-question' id='question-134'><div class='question-content'><p><span class='watu_num'>134. <\/span>An IS auditor is reviewing the upgrading of an operating system.<br \/>\n<br \/>Which of the following would be the GREATEST audit concern?<\/p>\n<\/div><input type='hidden' name='question_id[]' value='125221' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515831' \/><div class='watu-question-choice'><input type='radio' name='answer-125221[]' id='answer-id-515831' class='answer answer-134  answerof-125221' value='515831' \/>&nbsp;<label for='answer-id-515831' id='answer-label-515831' class=' answer label-134'><span class='answer'>The lack of release notes<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515832' \/><div class='watu-question-choice'><input type='radio' name='answer-125221[]' id='answer-id-515832' class='answer answer-134  answerof-125221' value='515832' \/>&nbsp;<label for='answer-id-515832' id='answer-label-515832' class=' answer label-134'><span class='answer'>The lack of change control<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515833' \/><div class='watu-question-choice'><input type='radio' name='answer-125221[]' id='answer-id-515833' class='answer answer-134  answerof-125221' value='515833' \/>&nbsp;<label for='answer-id-515833' id='answer-label-515833' class=' answer label-134'><span class='answer'>The lack of malware protection<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515834' \/><div class='watu-question-choice'><input type='radio' name='answer-125221[]' id='answer-id-515834' class='answer answer-134  answerof-125221' value='515834' \/>&nbsp;<label for='answer-id-515834' id='answer-label-515834' class=' answer label-134'><span class='answer'>The lack of activity logging<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType134' value='radio' class=''><\/div><div class='watu-question' id='question-135'><div class='question-content'><p><span class='watu_num'>135. <\/span>An IS auditor has been asked to assess the security of a recently migrated database system that contains personal and financial data for a bank\u2019s customers.<br \/>\n<br \/>Which of the following controls is MOST important for the auditor to confirm it in place?<\/p>\n<\/div><input type='hidden' name='question_id[]' value='125222' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515835' \/><div class='watu-question-choice'><input type='radio' name='answer-125222[]' id='answer-id-515835' class='answer answer-135  answerof-125222' value='515835' \/>&nbsp;<label for='answer-id-515835' id='answer-label-515835' class=' answer label-135'><span class='answer'>The default configurations have been changed.<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515836' \/><div class='watu-question-choice'><input type='radio' name='answer-125222[]' id='answer-id-515836' class='answer answer-135  answerof-125222' value='515836' \/>&nbsp;<label for='answer-id-515836' id='answer-label-515836' class=' answer label-135'><span class='answer'>All tables in the database are normalized.<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515837' \/><div class='watu-question-choice'><input type='radio' name='answer-125222[]' id='answer-id-515837' class='answer answer-135  answerof-125222' value='515837' \/>&nbsp;<label for='answer-id-515837' id='answer-label-515837' class=' answer label-135'><span class='answer'>The service port used by the database server has been changed.<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515838' \/><div class='watu-question-choice'><input type='radio' name='answer-125222[]' id='answer-id-515838' class='answer answer-135  answerof-125222' value='515838' \/>&nbsp;<label for='answer-id-515838' id='answer-label-515838' class=' answer label-135'><span class='answer'>The default administration account is used after changing the account password.<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType135' value='radio' class=''><\/div><div class='watu-question' id='question-136'><div class='question-content'><p><span class='watu_num'>136. <\/span>Which of the following is the MOST important determining factor when establishing appropriate timeframes for follow-up activities related to audit findings?<\/p>\n<\/div><input type='hidden' name='question_id[]' value='125223' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515839' \/><div class='watu-question-choice'><input type='radio' name='answer-125223[]' id='answer-id-515839' class='answer answer-136  answerof-125223' value='515839' \/>&nbsp;<label for='answer-id-515839' id='answer-label-515839' class=' answer label-136'><span class='answer'>Peak activity periods for the business<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515840' \/><div class='watu-question-choice'><input type='radio' name='answer-125223[]' id='answer-id-515840' class='answer answer-136  answerof-125223' value='515840' \/>&nbsp;<label for='answer-id-515840' id='answer-label-515840' class=' answer label-136'><span class='answer'>Remediation dates included in management responses<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515841' \/><div class='watu-question-choice'><input type='radio' name='answer-125223[]' id='answer-id-515841' class='answer answer-136  answerof-125223' value='515841' \/>&nbsp;<label for='answer-id-515841' id='answer-label-515841' class=' answer label-136'><span class='answer'>Availability of IS audit resources<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515842' \/><div class='watu-question-choice'><input type='radio' name='answer-125223[]' id='answer-id-515842' class='answer answer-136  answerof-125223' value='515842' \/>&nbsp;<label for='answer-id-515842' id='answer-label-515842' class=' answer label-136'><span class='answer'>Complexity of business processes identified in the audit<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType136' value='radio' class=''><\/div><div class='watu-question' id='question-137'><div class='question-content'><p><span class='watu_num'>137. <\/span>An IS auditor has obtained a large data set containing multiple fields and non-numeric data for analysis.<br \/>\n<br \/>Which of the following activities will MOST improve the quality of conclusions derived from the use of a data analytics tool for this audit?<\/p>\n<\/div><input type='hidden' name='question_id[]' value='125224' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515843' \/><div class='watu-question-choice'><input type='radio' name='answer-125224[]' id='answer-id-515843' class='answer answer-137  answerof-125224' value='515843' \/>&nbsp;<label for='answer-id-515843' id='answer-label-515843' class=' answer label-137'><span class='answer'>Data anonymization<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515844' \/><div class='watu-question-choice'><input type='radio' name='answer-125224[]' id='answer-id-515844' class='answer answer-137  answerof-125224' value='515844' \/>&nbsp;<label for='answer-id-515844' id='answer-label-515844' class=' answer label-137'><span class='answer'>Data classification<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515845' \/><div class='watu-question-choice'><input type='radio' name='answer-125224[]' id='answer-id-515845' class='answer answer-137  answerof-125224' value='515845' \/>&nbsp;<label for='answer-id-515845' id='answer-label-515845' class=' answer label-137'><span class='answer'>Data stratification<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515846' \/><div class='watu-question-choice'><input type='radio' name='answer-125224[]' id='answer-id-515846' class='answer answer-137  answerof-125224' value='515846' \/>&nbsp;<label for='answer-id-515846' id='answer-label-515846' class=' answer label-137'><span class='answer'>Data preparation<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType137' value='radio' class=''><\/div><div class='watu-question' id='question-138'><div class='question-content'><p><span class='watu_num'>138. <\/span>Which of the following is the MOST important requirement for an IS auditor to evaluate when reviewing a transmission of personally identifiable information between two organizations?<\/p>\n<\/div><input type='hidden' name='question_id[]' value='125225' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515847' \/><div class='watu-question-choice'><input type='radio' name='answer-125225[]' id='answer-id-515847' class='answer answer-138  answerof-125225' value='515847' \/>&nbsp;<label for='answer-id-515847' id='answer-label-515847' class=' answer label-138'><span class='answer'>Completeness<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515848' \/><div class='watu-question-choice'><input type='radio' name='answer-125225[]' id='answer-id-515848' class='answer answer-138  answerof-125225' value='515848' \/>&nbsp;<label for='answer-id-515848' id='answer-label-515848' class=' answer label-138'><span class='answer'>Timeliness<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515849' \/><div class='watu-question-choice'><input type='radio' name='answer-125225[]' id='answer-id-515849' class='answer answer-138  answerof-125225' value='515849' \/>&nbsp;<label for='answer-id-515849' id='answer-label-515849' class=' answer label-138'><span class='answer'>Necessity<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515850' \/><div class='watu-question-choice'><input type='radio' name='answer-125225[]' id='answer-id-515850' class='answer answer-138  answerof-125225' value='515850' \/>&nbsp;<label for='answer-id-515850' id='answer-label-515850' class=' answer label-138'><span class='answer'>Accuracy<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType138' value='radio' class=''><\/div><div class='watu-question' id='question-139'><div class='question-content'><p><span class='watu_num'>139. <\/span>An IS auditor reviewed the business case for a proposed investment to virtualize an organization\u2019s server infrastructure.<br \/>\n<br \/>Which of the following is MOST likely to be included among the benefits in the project proposal?<\/p>\n<\/div><input type='hidden' name='question_id[]' value='125226' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515851' \/><div class='watu-question-choice'><input type='radio' name='answer-125226[]' id='answer-id-515851' class='answer answer-139  answerof-125226' value='515851' \/>&nbsp;<label for='answer-id-515851' id='answer-label-515851' class=' answer label-139'><span class='answer'>Fewer operating system licenses<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515852' \/><div class='watu-question-choice'><input type='radio' name='answer-125226[]' id='answer-id-515852' class='answer answer-139  answerof-125226' value='515852' \/>&nbsp;<label for='answer-id-515852' id='answer-label-515852' class=' answer label-139'><span class='answer'>Better efficiency of logical resources<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515853' \/><div class='watu-question-choice'><input type='radio' name='answer-125226[]' id='answer-id-515853' class='answer answer-139  answerof-125226' value='515853' \/>&nbsp;<label for='answer-id-515853' id='answer-label-515853' class=' answer label-139'><span class='answer'>Reduced hardware footprint<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515854' \/><div class='watu-question-choice'><input type='radio' name='answer-125226[]' id='answer-id-515854' class='answer answer-139  answerof-125226' value='515854' \/>&nbsp;<label for='answer-id-515854' id='answer-label-515854' class=' answer label-139'><span class='answer'>Less memory and storage space<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType139' value='radio' class=''><\/div><div class='watu-question' id='question-140'><div class='question-content'><p><span class='watu_num'>140. <\/span>Which of the following is the BEST way to facilitate proper follow-up for audit findings?<\/p>\n<\/div><input type='hidden' name='question_id[]' value='125227' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515855' \/><div class='watu-question-choice'><input type='radio' name='answer-125227[]' id='answer-id-515855' class='answer answer-140  answerof-125227' value='515855' \/>&nbsp;<label for='answer-id-515855' id='answer-label-515855' class=' answer label-140'><span class='answer'>Schedule a follow-up audit for two weeks after the initial audit was completed.<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515856' \/><div class='watu-question-choice'><input type='radio' name='answer-125227[]' id='answer-id-515856' class='answer answer-140  answerof-125227' value='515856' \/>&nbsp;<label for='answer-id-515856' id='answer-label-515856' class=' answer label-140'><span class='answer'>Conduct a surprise audit to determine whether remediation is in progress.<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515857' \/><div class='watu-question-choice'><input type='radio' name='answer-125227[]' id='answer-id-515857' class='answer answer-140  answerof-125227' value='515857' \/>&nbsp;<label for='answer-id-515857' id='answer-label-515857' class=' answer label-140'><span class='answer'>Conduct a follow-up audit when findings escalate to incidents.<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515858' \/><div class='watu-question-choice'><input type='radio' name='answer-125227[]' id='answer-id-515858' class='answer answer-140  answerof-125227' value='515858' \/>&nbsp;<label for='answer-id-515858' id='answer-label-515858' class=' answer label-140'><span class='answer'>Schedule a follow-up audit based on remediation due dates.<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType140' value='radio' class=''><\/div><div class='watu-question' id='question-141'><div class='question-content'><p><span class='watu_num'>141. <\/span>Which of the following would be the MOST efficient audit approach, given that a compliance-based approach was adopted in the previous year?<\/p>\n<\/div><input type='hidden' name='question_id[]' value='125228' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515859' \/><div class='watu-question-choice'><input type='radio' name='answer-125228[]' id='answer-id-515859' class='answer answer-141  answerof-125228' value='515859' \/>&nbsp;<label for='answer-id-515859' id='answer-label-515859' class=' answer label-141'><span class='answer'>Validate all applications using test data.<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515860' \/><div class='watu-question-choice'><input type='radio' name='answer-125228[]' id='answer-id-515860' class='answer answer-141  answerof-125228' value='515860' \/>&nbsp;<label for='answer-id-515860' id='answer-label-515860' class=' answer label-141'><span class='answer'>Interview systems personnel to evaluate all automated controls.<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515861' \/><div class='watu-question-choice'><input type='radio' name='answer-125228[]' id='answer-id-515861' class='answer answer-141  answerof-125228' value='515861' \/>&nbsp;<label for='answer-id-515861' id='answer-label-515861' class=' answer label-141'><span class='answer'>Evaluate the controls surrounding changes to programs.<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515862' \/><div class='watu-question-choice'><input type='radio' name='answer-125228[]' id='answer-id-515862' class='answer answer-141  answerof-125228' value='515862' \/>&nbsp;<label for='answer-id-515862' id='answer-label-515862' class=' answer label-141'><span class='answer'>Perform a review of significant transactions posted within the system.<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType141' value='radio' class=''><\/div><div class='watu-question' id='question-142'><div class='question-content'><p><span class='watu_num'>142. <\/span>An IS auditor will be testing accounts payable controls by performing data analytics on the entire population transactions.<br \/>\n<br \/>Which of the following is MOST important for the auditor to confirm when sourcing the population data?<\/p>\n<\/div><input type='hidden' name='question_id[]' value='125229' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515863' \/><div class='watu-question-choice'><input type='radio' name='answer-125229[]' id='answer-id-515863' class='answer answer-142  answerof-125229' value='515863' \/>&nbsp;<label for='answer-id-515863' id='answer-label-515863' class=' answer label-142'><span class='answer'>There is no privacy information in the data.<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515864' \/><div class='watu-question-choice'><input type='radio' name='answer-125229[]' id='answer-id-515864' class='answer answer-142  answerof-125229' value='515864' \/>&nbsp;<label for='answer-id-515864' id='answer-label-515864' class=' answer label-142'><span class='answer'>The data analysis tools have been recently updated.<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515865' \/><div class='watu-question-choice'><input type='radio' name='answer-125229[]' id='answer-id-515865' class='answer answer-142  answerof-125229' value='515865' \/>&nbsp;<label for='answer-id-515865' id='answer-label-515865' class=' answer label-142'><span class='answer'>The data can be obtained in a timely manner.<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515866' \/><div class='watu-question-choice'><input type='radio' name='answer-125229[]' id='answer-id-515866' class='answer answer-142  answerof-125229' value='515866' \/>&nbsp;<label for='answer-id-515866' id='answer-label-515866' class=' answer label-142'><span class='answer'>The data is taken directly from the system.<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType142' value='radio' class=''><\/div><div class='watu-question' id='question-143'><div class='question-content'><p><span class='watu_num'>143. <\/span>Which of the following should the IS auditor use to BEST determine whether a project has met its business objectives?<\/p>\n<\/div><input type='hidden' name='question_id[]' value='125230' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515867' \/><div class='watu-question-choice'><input type='radio' name='answer-125230[]' id='answer-id-515867' class='answer answer-143  answerof-125230' value='515867' \/>&nbsp;<label for='answer-id-515867' id='answer-label-515867' class=' answer label-143'><span class='answer'>Earned-value analysis<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515868' \/><div class='watu-question-choice'><input type='radio' name='answer-125230[]' id='answer-id-515868' class='answer answer-143  answerof-125230' value='515868' \/>&nbsp;<label for='answer-id-515868' id='answer-label-515868' class=' answer label-143'><span class='answer'>Completed project plan<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515869' \/><div class='watu-question-choice'><input type='radio' name='answer-125230[]' id='answer-id-515869' class='answer answer-143  answerof-125230' value='515869' \/>&nbsp;<label for='answer-id-515869' id='answer-label-515869' class=' answer label-143'><span class='answer'>Issues log with resolutions<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515870' \/><div class='watu-question-choice'><input type='radio' name='answer-125230[]' id='answer-id-515870' class='answer answer-143  answerof-125230' value='515870' \/>&nbsp;<label for='answer-id-515870' id='answer-label-515870' class=' answer label-143'><span class='answer'>Benefits realization document<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType143' value='radio' class=''><\/div><div class='watu-question' id='question-144'><div class='question-content'><p><span class='watu_num'>144. <\/span>An IS auditor is observing transaction processing and notes that a high-priority update job ran out of sequence.<br \/>\n<br \/>What is the MOST significant risk from this observation?<\/p>\n<\/div><input type='hidden' name='question_id[]' value='125231' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515871' \/><div class='watu-question-choice'><input type='radio' name='answer-125231[]' id='answer-id-515871' class='answer answer-144  answerof-125231' value='515871' \/>&nbsp;<label for='answer-id-515871' id='answer-label-515871' class=' answer label-144'><span class='answer'>Previous jobs may have failed.<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515872' \/><div class='watu-question-choice'><input type='radio' name='answer-125231[]' id='answer-id-515872' class='answer answer-144  answerof-125231' value='515872' \/>&nbsp;<label for='answer-id-515872' id='answer-label-515872' class=' answer label-144'><span class='answer'>The job may not have run to completion.<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515873' \/><div class='watu-question-choice'><input type='radio' name='answer-125231[]' id='answer-id-515873' class='answer answer-144  answerof-125231' value='515873' \/>&nbsp;<label for='answer-id-515873' id='answer-label-515873' class=' answer label-144'><span class='answer'>Daily schedules may not be accurate.<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515874' \/><div class='watu-question-choice'><input type='radio' name='answer-125231[]' id='answer-id-515874' class='answer answer-144  answerof-125231' value='515874' \/>&nbsp;<label for='answer-id-515874' id='answer-label-515874' class=' answer label-144'><span class='answer'>The job competes with invalid data.<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType144' value='radio' class=''><\/div><div class='watu-question' id='question-145'><div class='question-content'><p><span class='watu_num'>145. <\/span>Which of the following would be best suited to oversee the development of an information security policy?<\/p>\n<\/div><input type='hidden' name='question_id[]' value='125232' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515875' \/><div class='watu-question-choice'><input type='radio' name='answer-125232[]' id='answer-id-515875' class='answer answer-145  answerof-125232' value='515875' \/>&nbsp;<label for='answer-id-515875' id='answer-label-515875' class=' answer label-145'><span class='answer'>System Administrators<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515876' \/><div class='watu-question-choice'><input type='radio' name='answer-125232[]' id='answer-id-515876' class='answer answer-145  answerof-125232' value='515876' \/>&nbsp;<label for='answer-id-515876' id='answer-label-515876' class=' answer label-145'><span class='answer'>End User<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515877' \/><div class='watu-question-choice'><input type='radio' name='answer-125232[]' id='answer-id-515877' class='answer answer-145  answerof-125232' value='515877' \/>&nbsp;<label for='answer-id-515877' id='answer-label-515877' class=' answer label-145'><span class='answer'>Security Officers<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515878' \/><div class='watu-question-choice'><input type='radio' name='answer-125232[]' id='answer-id-515878' class='answer answer-145  answerof-125232' value='515878' \/>&nbsp;<label for='answer-id-515878' id='answer-label-515878' class=' answer label-145'><span class='answer'>Security administrators<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType145' value='radio' class=''><\/div><div class='watu-question' id='question-146'><div class='question-content'><p><span class='watu_num'>146. <\/span>Which of the following is the MOST important aspect relating to employee termination?<\/p>\n<\/div><input type='hidden' name='question_id[]' value='125233' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515879' \/><div class='watu-question-choice'><input type='radio' name='answer-125233[]' id='answer-id-515879' class='answer answer-146  answerof-125233' value='515879' \/>&nbsp;<label for='answer-id-515879' id='answer-label-515879' class=' answer label-146'><span class='answer'>The details of employee have been removed from active payroll files.<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515880' \/><div class='watu-question-choice'><input type='radio' name='answer-125233[]' id='answer-id-515880' class='answer answer-146  answerof-125233' value='515880' \/>&nbsp;<label for='answer-id-515880' id='answer-label-515880' class=' answer label-146'><span class='answer'>Company property provided to the employee has been returned.<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515881' \/><div class='watu-question-choice'><input type='radio' name='answer-125233[]' id='answer-id-515881' class='answer answer-146  answerof-125233' value='515881' \/>&nbsp;<label for='answer-id-515881' id='answer-label-515881' class=' answer label-146'><span class='answer'>User ID and passwords of the employee have been deleted.<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515882' \/><div class='watu-question-choice'><input type='radio' name='answer-125233[]' id='answer-id-515882' class='answer answer-146  answerof-125233' value='515882' \/>&nbsp;<label for='answer-id-515882' id='answer-label-515882' class=' answer label-146'><span class='answer'>The appropriate company staff are notified about the termination.<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType146' value='radio' class=''><\/div><div class='watu-question' id='question-147'><div class='question-content'><p><span class='watu_num'>147. <\/span>In which of the following cloud computing service model are applications hosted by the service provider and made available to the customers over a network?<\/p>\n<\/div><input type='hidden' name='question_id[]' value='125234' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515883' \/><div class='watu-question-choice'><input type='radio' name='answer-125234[]' id='answer-id-515883' class='answer answer-147  answerof-125234' value='515883' \/>&nbsp;<label for='answer-id-515883' id='answer-label-515883' class=' answer label-147'><span class='answer'>Software as a service<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515884' \/><div class='watu-question-choice'><input type='radio' name='answer-125234[]' id='answer-id-515884' class='answer answer-147  answerof-125234' value='515884' \/>&nbsp;<label for='answer-id-515884' id='answer-label-515884' class=' answer label-147'><span class='answer'>Data as a service<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515885' \/><div class='watu-question-choice'><input type='radio' name='answer-125234[]' id='answer-id-515885' class='answer answer-147  answerof-125234' value='515885' \/>&nbsp;<label for='answer-id-515885' id='answer-label-515885' class=' answer label-147'><span class='answer'>Platform as a service<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515886' \/><div class='watu-question-choice'><input type='radio' name='answer-125234[]' id='answer-id-515886' class='answer answer-147  answerof-125234' value='515886' \/>&nbsp;<label for='answer-id-515886' id='answer-label-515886' class=' answer label-147'><span class='answer'>Infrastructure as a service<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType147' value='radio' class=''><\/div><div class='watu-question' id='question-148'><div class='question-content'><p><span class='watu_num'>148. <\/span>Which of the following cloud computing service model provides a way to rent operating systems, storage and network capacity over the Internet?<\/p>\n<\/div><input type='hidden' name='question_id[]' value='125235' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515887' \/><div class='watu-question-choice'><input type='radio' name='answer-125235[]' id='answer-id-515887' class='answer answer-148  answerof-125235' value='515887' \/>&nbsp;<label for='answer-id-515887' id='answer-label-515887' class=' answer label-148'><span class='answer'>Software as a service<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515888' \/><div class='watu-question-choice'><input type='radio' name='answer-125235[]' id='answer-id-515888' class='answer answer-148  answerof-125235' value='515888' \/>&nbsp;<label for='answer-id-515888' id='answer-label-515888' class=' answer label-148'><span class='answer'>Data as a service<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515889' \/><div class='watu-question-choice'><input type='radio' name='answer-125235[]' id='answer-id-515889' class='answer answer-148  answerof-125235' value='515889' \/>&nbsp;<label for='answer-id-515889' id='answer-label-515889' class=' answer label-148'><span class='answer'>Platform as a service<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515890' \/><div class='watu-question-choice'><input type='radio' name='answer-125235[]' id='answer-id-515890' class='answer answer-148  answerof-125235' value='515890' \/>&nbsp;<label for='answer-id-515890' id='answer-label-515890' class=' answer label-148'><span class='answer'>Infrastructure as a service<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType148' value='radio' class=''><\/div><div class='watu-question' id='question-149'><div class='question-content'><p><span class='watu_num'>149. <\/span>Which of the following cloud computing service model is a provision model in which an organization outsources the equipment used to support operations, including storage, hardware, servers and networking components?<\/p>\n<\/div><input type='hidden' name='question_id[]' value='125236' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515891' \/><div class='watu-question-choice'><input type='radio' name='answer-125236[]' id='answer-id-515891' class='answer answer-149  answerof-125236' value='515891' \/>&nbsp;<label for='answer-id-515891' id='answer-label-515891' class=' answer label-149'><span class='answer'>Software as a service<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515892' \/><div class='watu-question-choice'><input type='radio' name='answer-125236[]' id='answer-id-515892' class='answer answer-149  answerof-125236' value='515892' \/>&nbsp;<label for='answer-id-515892' id='answer-label-515892' class=' answer label-149'><span class='answer'>Data as a service<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515893' \/><div class='watu-question-choice'><input type='radio' name='answer-125236[]' id='answer-id-515893' class='answer answer-149  answerof-125236' value='515893' \/>&nbsp;<label for='answer-id-515893' id='answer-label-515893' class=' answer label-149'><span class='answer'>Platform as a service<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515894' \/><div class='watu-question-choice'><input type='radio' name='answer-125236[]' id='answer-id-515894' class='answer answer-149  answerof-125236' value='515894' \/>&nbsp;<label for='answer-id-515894' id='answer-label-515894' class=' answer label-149'><span class='answer'>Infrastructure as a service<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType149' value='radio' class=''><\/div><div class='watu-question' id='question-150'><div class='question-content'><p><span class='watu_num'>150. <\/span>Which of the following cloud deployment model operates solely for an organization?<\/p>\n<\/div><input type='hidden' name='question_id[]' value='125237' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515895' \/><div class='watu-question-choice'><input type='radio' name='answer-125237[]' id='answer-id-515895' class='answer answer-150  answerof-125237' value='515895' \/>&nbsp;<label for='answer-id-515895' id='answer-label-515895' class=' answer label-150'><span class='answer'>Private Cloud<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515896' \/><div class='watu-question-choice'><input type='radio' name='answer-125237[]' id='answer-id-515896' class='answer answer-150  answerof-125237' value='515896' \/>&nbsp;<label for='answer-id-515896' id='answer-label-515896' class=' answer label-150'><span class='answer'>Community Cloud<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515897' \/><div class='watu-question-choice'><input type='radio' name='answer-125237[]' id='answer-id-515897' class='answer answer-150  answerof-125237' value='515897' \/>&nbsp;<label for='answer-id-515897' id='answer-label-515897' class=' answer label-150'><span class='answer'>Public Cloud<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515898' \/><div class='watu-question-choice'><input type='radio' name='answer-125237[]' id='answer-id-515898' class='answer answer-150  answerof-125237' value='515898' \/>&nbsp;<label for='answer-id-515898' id='answer-label-515898' class=' answer label-150'><span class='answer'>Hybrid Cloud<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType150' value='radio' class=''><\/div><div class='watu-question' id='question-151'><div class='question-content'><p><span class='watu_num'>151. <\/span>Which of the following cloud deployment model can be shared by several organizations?<\/p>\n<\/div><input type='hidden' name='question_id[]' value='125238' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515899' \/><div class='watu-question-choice'><input type='radio' name='answer-125238[]' id='answer-id-515899' class='answer answer-151  answerof-125238' value='515899' \/>&nbsp;<label for='answer-id-515899' id='answer-label-515899' class=' answer label-151'><span class='answer'>Private Cloud<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515900' \/><div class='watu-question-choice'><input type='radio' name='answer-125238[]' id='answer-id-515900' class='answer answer-151  answerof-125238' value='515900' \/>&nbsp;<label for='answer-id-515900' id='answer-label-515900' class=' answer label-151'><span class='answer'>Community Cloud<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515901' \/><div class='watu-question-choice'><input type='radio' name='answer-125238[]' id='answer-id-515901' class='answer answer-151  answerof-125238' value='515901' \/>&nbsp;<label for='answer-id-515901' id='answer-label-515901' class=' answer label-151'><span class='answer'>Public Cloud<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515902' \/><div class='watu-question-choice'><input type='radio' name='answer-125238[]' id='answer-id-515902' class='answer answer-151  answerof-125238' value='515902' \/>&nbsp;<label for='answer-id-515902' id='answer-label-515902' class=' answer label-151'><span class='answer'>Hybrid Cloud<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType151' value='radio' class=''><\/div><div class='watu-question' id='question-152'><div class='question-content'><p><span class='watu_num'>152. <\/span>Which of the following cloud deployment model is provisioned for open use by the general public?<\/p>\n<\/div><input type='hidden' name='question_id[]' value='125239' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515903' \/><div class='watu-question-choice'><input type='radio' name='answer-125239[]' id='answer-id-515903' class='answer answer-152  answerof-125239' value='515903' \/>&nbsp;<label for='answer-id-515903' id='answer-label-515903' class=' answer label-152'><span class='answer'>Private Cloud<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515904' \/><div class='watu-question-choice'><input type='radio' name='answer-125239[]' id='answer-id-515904' class='answer answer-152  answerof-125239' value='515904' \/>&nbsp;<label for='answer-id-515904' id='answer-label-515904' class=' answer label-152'><span class='answer'>Community Cloud<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515905' \/><div class='watu-question-choice'><input type='radio' name='answer-125239[]' id='answer-id-515905' class='answer answer-152  answerof-125239' value='515905' \/>&nbsp;<label for='answer-id-515905' id='answer-label-515905' class=' answer label-152'><span class='answer'>Public Cloud<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515906' \/><div class='watu-question-choice'><input type='radio' name='answer-125239[]' id='answer-id-515906' class='answer answer-152  answerof-125239' value='515906' \/>&nbsp;<label for='answer-id-515906' id='answer-label-515906' class=' answer label-152'><span class='answer'>Hybrid Cloud<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType152' value='radio' class=''><\/div><div class='watu-question' id='question-153'><div class='question-content'><p><span class='watu_num'>153. <\/span>Which of the following cloud deployment model is formed by the composition of two or more cloud deployment mode?<\/p>\n<\/div><input type='hidden' name='question_id[]' value='125240' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515907' \/><div class='watu-question-choice'><input type='radio' name='answer-125240[]' id='answer-id-515907' class='answer answer-153  answerof-125240' value='515907' \/>&nbsp;<label for='answer-id-515907' id='answer-label-515907' class=' answer label-153'><span class='answer'>Private Cloud<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515908' \/><div class='watu-question-choice'><input type='radio' name='answer-125240[]' id='answer-id-515908' class='answer answer-153  answerof-125240' value='515908' \/>&nbsp;<label for='answer-id-515908' id='answer-label-515908' class=' answer label-153'><span class='answer'>Community Cloud<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515909' \/><div class='watu-question-choice'><input type='radio' name='answer-125240[]' id='answer-id-515909' class='answer answer-153  answerof-125240' value='515909' \/>&nbsp;<label for='answer-id-515909' id='answer-label-515909' class=' answer label-153'><span class='answer'>Public Cloud<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515910' \/><div class='watu-question-choice'><input type='radio' name='answer-125240[]' id='answer-id-515910' class='answer answer-153  answerof-125240' value='515910' \/>&nbsp;<label for='answer-id-515910' id='answer-label-515910' class=' answer label-153'><span class='answer'>Hybrid Cloud<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType153' value='radio' class=''><\/div><div class='watu-question' id='question-154'><div class='question-content'><p><span class='watu_num'>154. <\/span>Which of the following step of PDCA establishes the objectives and processes necessary to deliver results in accordance with the expected output?<\/p>\n<\/div><input type='hidden' name='question_id[]' value='125241' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515911' \/><div class='watu-question-choice'><input type='radio' name='answer-125241[]' id='answer-id-515911' class='answer answer-154  answerof-125241' value='515911' \/>&nbsp;<label for='answer-id-515911' id='answer-label-515911' class=' answer label-154'><span class='answer'>Plan<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515912' \/><div class='watu-question-choice'><input type='radio' name='answer-125241[]' id='answer-id-515912' class='answer answer-154  answerof-125241' value='515912' \/>&nbsp;<label for='answer-id-515912' id='answer-label-515912' class=' answer label-154'><span class='answer'>Do<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515913' \/><div class='watu-question-choice'><input type='radio' name='answer-125241[]' id='answer-id-515913' class='answer answer-154  answerof-125241' value='515913' \/>&nbsp;<label for='answer-id-515913' id='answer-label-515913' class=' answer label-154'><span class='answer'>Check<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515914' \/><div class='watu-question-choice'><input type='radio' name='answer-125241[]' id='answer-id-515914' class='answer answer-154  answerof-125241' value='515914' \/>&nbsp;<label for='answer-id-515914' id='answer-label-515914' class=' answer label-154'><span class='answer'>Act<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType154' value='radio' class=''><\/div><div class='watu-question' id='question-155'><div class='question-content'><p><span class='watu_num'>155. <\/span>Which of the following step of PDCA implement the plan, execute the process and make product?<\/p>\n<\/div><input type='hidden' name='question_id[]' value='125242' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515915' \/><div class='watu-question-choice'><input type='radio' name='answer-125242[]' id='answer-id-515915' class='answer answer-155  answerof-125242' value='515915' \/>&nbsp;<label for='answer-id-515915' id='answer-label-515915' class=' answer label-155'><span class='answer'>Plan<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515916' \/><div class='watu-question-choice'><input type='radio' name='answer-125242[]' id='answer-id-515916' class='answer answer-155  answerof-125242' value='515916' \/>&nbsp;<label for='answer-id-515916' id='answer-label-515916' class=' answer label-155'><span class='answer'>Do<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515917' \/><div class='watu-question-choice'><input type='radio' name='answer-125242[]' id='answer-id-515917' class='answer answer-155  answerof-125242' value='515917' \/>&nbsp;<label for='answer-id-515917' id='answer-label-515917' class=' answer label-155'><span class='answer'>Check<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515918' \/><div class='watu-question-choice'><input type='radio' name='answer-125242[]' id='answer-id-515918' class='answer answer-155  answerof-125242' value='515918' \/>&nbsp;<label for='answer-id-515918' id='answer-label-515918' class=' answer label-155'><span class='answer'>Act<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType155' value='radio' class=''><\/div><div class='watu-question' id='question-156'><div class='question-content'><p><span class='watu_num'>156. <\/span>Which of the following step of PDCA study the actual result and compares it against the expected result?<\/p>\n<\/div><input type='hidden' name='question_id[]' value='125243' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515919' \/><div class='watu-question-choice'><input type='radio' name='answer-125243[]' id='answer-id-515919' class='answer answer-156  answerof-125243' value='515919' \/>&nbsp;<label for='answer-id-515919' id='answer-label-515919' class=' answer label-156'><span class='answer'>Plan<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515920' \/><div class='watu-question-choice'><input type='radio' name='answer-125243[]' id='answer-id-515920' class='answer answer-156  answerof-125243' value='515920' \/>&nbsp;<label for='answer-id-515920' id='answer-label-515920' class=' answer label-156'><span class='answer'>Do<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515921' \/><div class='watu-question-choice'><input type='radio' name='answer-125243[]' id='answer-id-515921' class='answer answer-156  answerof-125243' value='515921' \/>&nbsp;<label for='answer-id-515921' id='answer-label-515921' class=' answer label-156'><span class='answer'>Check<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515922' \/><div class='watu-question-choice'><input type='radio' name='answer-125243[]' id='answer-id-515922' class='answer answer-156  answerof-125243' value='515922' \/>&nbsp;<label for='answer-id-515922' id='answer-label-515922' class=' answer label-156'><span class='answer'>Act<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType156' value='radio' class=''><\/div><div class='watu-question' id='question-157'><div class='question-content'><p><span class='watu_num'>157. <\/span>Which of the following step of PDCA request a corrective actions on significant differences between the actual versus the planned result?<\/p>\n<\/div><input type='hidden' name='question_id[]' value='125244' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515923' \/><div class='watu-question-choice'><input type='radio' name='answer-125244[]' id='answer-id-515923' class='answer answer-157  answerof-125244' value='515923' \/>&nbsp;<label for='answer-id-515923' id='answer-label-515923' class=' answer label-157'><span class='answer'>Plan<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515924' \/><div class='watu-question-choice'><input type='radio' name='answer-125244[]' id='answer-id-515924' class='answer answer-157  answerof-125244' value='515924' \/>&nbsp;<label for='answer-id-515924' id='answer-label-515924' class=' answer label-157'><span class='answer'>Do<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515925' \/><div class='watu-question-choice'><input type='radio' name='answer-125244[]' id='answer-id-515925' class='answer answer-157  answerof-125244' value='515925' \/>&nbsp;<label for='answer-id-515925' id='answer-label-515925' class=' answer label-157'><span class='answer'>Check<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515926' \/><div class='watu-question-choice'><input type='radio' name='answer-125244[]' id='answer-id-515926' class='answer answer-157  answerof-125244' value='515926' \/>&nbsp;<label for='answer-id-515926' id='answer-label-515926' class=' answer label-157'><span class='answer'>Act<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType157' value='radio' class=''><\/div><div class='watu-question' id='question-158'><div class='question-content'><p><span class='watu_num'>158. <\/span>Which of the following answer specifies the correct sequence of levels within the Capability Maturity Model (CMM)?<\/p>\n<\/div><input type='hidden' name='question_id[]' value='125245' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515927' \/><div class='watu-question-choice'><input type='radio' name='answer-125245[]' id='answer-id-515927' class='answer answer-158  answerof-125245' value='515927' \/>&nbsp;<label for='answer-id-515927' id='answer-label-515927' class=' answer label-158'><span class='answer'>Initial, Managed, Defined, Quantitatively managed, optimized<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515928' \/><div class='watu-question-choice'><input type='radio' name='answer-125245[]' id='answer-id-515928' class='answer answer-158  answerof-125245' value='515928' \/>&nbsp;<label for='answer-id-515928' id='answer-label-515928' class=' answer label-158'><span class='answer'>Initial, Managed, Defined, optimized, Quantitatively managed<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515929' \/><div class='watu-question-choice'><input type='radio' name='answer-125245[]' id='answer-id-515929' class='answer answer-158  answerof-125245' value='515929' \/>&nbsp;<label for='answer-id-515929' id='answer-label-515929' class=' answer label-158'><span class='answer'>Initial, Defined, Managed, Quantitatively managed, optimized<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515930' \/><div class='watu-question-choice'><input type='radio' name='answer-125245[]' id='answer-id-515930' class='answer answer-158  answerof-125245' value='515930' \/>&nbsp;<label for='answer-id-515930' id='answer-label-515930' class=' answer label-158'><span class='answer'>Initial, Managed, Quantitatively managed, Defined, optimized<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType158' value='radio' class=''><\/div><div class='watu-question' id='question-159'><div class='question-content'><p><span class='watu_num'>159. <\/span>Which of the following dynamic interaction of a Business Model for Information Security (BMIS) is a pattern of behaviors, effects, assumptions, attitude and ways of doing things?<\/p>\n<\/div><input type='hidden' name='question_id[]' value='125246' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515931' \/><div class='watu-question-choice'><input type='radio' name='answer-125246[]' id='answer-id-515931' class='answer answer-159  answerof-125246' value='515931' \/>&nbsp;<label for='answer-id-515931' id='answer-label-515931' class=' answer label-159'><span class='answer'>Governing<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515932' \/><div class='watu-question-choice'><input type='radio' name='answer-125246[]' id='answer-id-515932' class='answer answer-159  answerof-125246' value='515932' \/>&nbsp;<label for='answer-id-515932' id='answer-label-515932' class=' answer label-159'><span class='answer'>Culture<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515933' \/><div class='watu-question-choice'><input type='radio' name='answer-125246[]' id='answer-id-515933' class='answer answer-159  answerof-125246' value='515933' \/>&nbsp;<label for='answer-id-515933' id='answer-label-515933' class=' answer label-159'><span class='answer'>Enabling and support<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515934' \/><div class='watu-question-choice'><input type='radio' name='answer-125246[]' id='answer-id-515934' class='answer answer-159  answerof-125246' value='515934' \/>&nbsp;<label for='answer-id-515934' id='answer-label-515934' class=' answer label-159'><span class='answer'>Emergence<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType159' value='radio' class=''><\/div><div class='watu-question' id='question-160'><div class='question-content'><p><span class='watu_num'>160. <\/span>Which of the following dynamic interaction of a Business Model for Information Security (BMIS) is a place to introduce possible solutions such as feedback loops; alignment with process improvement; and consideration of emergent issues in system design life cycle, change control, and risk management?<\/p>\n<\/div><input type='hidden' name='question_id[]' value='125247' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515935' \/><div class='watu-question-choice'><input type='radio' name='answer-125247[]' id='answer-id-515935' class='answer answer-160  answerof-125247' value='515935' \/>&nbsp;<label for='answer-id-515935' id='answer-label-515935' class=' answer label-160'><span class='answer'>Governing<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515936' \/><div class='watu-question-choice'><input type='radio' name='answer-125247[]' id='answer-id-515936' class='answer answer-160  answerof-125247' value='515936' \/>&nbsp;<label for='answer-id-515936' id='answer-label-515936' class=' answer label-160'><span class='answer'>Culture<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515937' \/><div class='watu-question-choice'><input type='radio' name='answer-125247[]' id='answer-id-515937' class='answer answer-160  answerof-125247' value='515937' \/>&nbsp;<label for='answer-id-515937' id='answer-label-515937' class=' answer label-160'><span class='answer'>Enabling and support<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515938' \/><div class='watu-question-choice'><input type='radio' name='answer-125247[]' id='answer-id-515938' class='answer answer-160  answerof-125247' value='515938' \/>&nbsp;<label for='answer-id-515938' id='answer-label-515938' class=' answer label-160'><span class='answer'>Emergence<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType160' value='radio' class=''><\/div><div class='watu-question' id='question-161'><div class='question-content'><p><span class='watu_num'>161. <\/span>A maturity model can be used to aid the implementation of IT governance by identifying:<\/p>\n<\/div><input type='hidden' name='question_id[]' value='125248' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515939' \/><div class='watu-question-choice'><input type='radio' name='answer-125248[]' id='answer-id-515939' class='answer answer-161  answerof-125248' value='515939' \/>&nbsp;<label for='answer-id-515939' id='answer-label-515939' class=' answer label-161'><span class='answer'>critical success factors<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515940' \/><div class='watu-question-choice'><input type='radio' name='answer-125248[]' id='answer-id-515940' class='answer answer-161  answerof-125248' value='515940' \/>&nbsp;<label for='answer-id-515940' id='answer-label-515940' class=' answer label-161'><span class='answer'>performance drivers<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515941' \/><div class='watu-question-choice'><input type='radio' name='answer-125248[]' id='answer-id-515941' class='answer answer-161  answerof-125248' value='515941' \/>&nbsp;<label for='answer-id-515941' id='answer-label-515941' class=' answer label-161'><span class='answer'>improvement opportunities<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515942' \/><div class='watu-question-choice'><input type='radio' name='answer-125248[]' id='answer-id-515942' class='answer answer-161  answerof-125248' value='515942' \/>&nbsp;<label for='answer-id-515942' id='answer-label-515942' class=' answer label-161'><span class='answer'>accountabilities<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType161' value='radio' class=''><\/div><div class='watu-question' id='question-162'><div class='question-content'><p><span class='watu_num'>162. <\/span>The effectiveness of an information security governance framework will BEST be enhanced if:<\/p>\n<\/div><input type='hidden' name='question_id[]' value='125249' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515943' \/><div class='watu-question-choice'><input type='radio' name='answer-125249[]' id='answer-id-515943' class='answer answer-162  answerof-125249' value='515943' \/>&nbsp;<label for='answer-id-515943' id='answer-label-515943' class=' answer label-162'><span class='answer'>consultants review the information security governance framework<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515944' \/><div class='watu-question-choice'><input type='radio' name='answer-125249[]' id='answer-id-515944' class='answer answer-162  answerof-125249' value='515944' \/>&nbsp;<label for='answer-id-515944' id='answer-label-515944' class=' answer label-162'><span class='answer'>a culture of legal and regulatory compliance is promoted by management<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515945' \/><div class='watu-question-choice'><input type='radio' name='answer-125249[]' id='answer-id-515945' class='answer answer-162  answerof-125249' value='515945' \/>&nbsp;<label for='answer-id-515945' id='answer-label-515945' class=' answer label-162'><span class='answer'>IS auditors are empowered to evaluate governance activities<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515946' \/><div class='watu-question-choice'><input type='radio' name='answer-125249[]' id='answer-id-515946' class='answer answer-162  answerof-125249' value='515946' \/>&nbsp;<label for='answer-id-515946' id='answer-label-515946' class=' answer label-162'><span class='answer'>risk management is built into operational and strategic activities<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType162' value='radio' class=''><\/div><div class='watu-question' id='question-163'><div class='question-content'><p><span class='watu_num'>163. <\/span>Which of the following is the MOST important requirement for the successful implementation of security governance?<\/p>\n<\/div><input type='hidden' name='question_id[]' value='125250' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515947' \/><div class='watu-question-choice'><input type='radio' name='answer-125250[]' id='answer-id-515947' class='answer answer-163  answerof-125250' value='515947' \/>&nbsp;<label for='answer-id-515947' id='answer-label-515947' class=' answer label-163'><span class='answer'>Aligning to an international security framework<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515948' \/><div class='watu-question-choice'><input type='radio' name='answer-125250[]' id='answer-id-515948' class='answer answer-163  answerof-125250' value='515948' \/>&nbsp;<label for='answer-id-515948' id='answer-label-515948' class=' answer label-163'><span class='answer'>Mapping to organizational strategies<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515949' \/><div class='watu-question-choice'><input type='radio' name='answer-125250[]' id='answer-id-515949' class='answer answer-163  answerof-125250' value='515949' \/>&nbsp;<label for='answer-id-515949' id='answer-label-515949' class=' answer label-163'><span class='answer'>Implementing a security balanced scorecard<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515950' \/><div class='watu-question-choice'><input type='radio' name='answer-125250[]' id='answer-id-515950' class='answer answer-163  answerof-125250' value='515950' \/>&nbsp;<label for='answer-id-515950' id='answer-label-515950' class=' answer label-163'><span class='answer'>Performing an enterprise-wide risk assessment<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType163' value='radio' class=''><\/div><div class='watu-question' id='question-164'><div class='question-content'><p><span class='watu_num'>164. <\/span>Which of the following BEST demonstrates effective information security management within an organization?<\/p>\n<\/div><input type='hidden' name='question_id[]' value='125251' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515951' \/><div class='watu-question-choice'><input type='radio' name='answer-125251[]' id='answer-id-515951' class='answer answer-164  answerof-125251' value='515951' \/>&nbsp;<label for='answer-id-515951' id='answer-label-515951' class=' answer label-164'><span class='answer'>Employees support decisions made by information security management.<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515952' \/><div class='watu-question-choice'><input type='radio' name='answer-125251[]' id='answer-id-515952' class='answer answer-164  answerof-125251' value='515952' \/>&nbsp;<label for='answer-id-515952' id='answer-label-515952' class=' answer label-164'><span class='answer'>Excessive risk exposure in one department can be absorbed by other departments.<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515953' \/><div class='watu-question-choice'><input type='radio' name='answer-125251[]' id='answer-id-515953' class='answer answer-164  answerof-125251' value='515953' \/>&nbsp;<label for='answer-id-515953' id='answer-label-515953' class=' answer label-164'><span class='answer'>Information security governance is incorporated into organizational governance.<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515954' \/><div class='watu-question-choice'><input type='radio' name='answer-125251[]' id='answer-id-515954' class='answer answer-164  answerof-125251' value='515954' \/>&nbsp;<label for='answer-id-515954' id='answer-label-515954' class=' answer label-164'><span class='answer'>Control ownership is assigned to parties who can accept losses related to control failure.<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType164' value='radio' class=''><\/div><div class='watu-question' id='question-165'><div class='question-content'><p><span class='watu_num'>165. <\/span>A multinational organization is introducing a security governance framework. The information security manager\u2019s concern is that regional security practices differ.<br \/>\n<br \/>Which of the following should be evaluated FIRST?<\/p>\n<\/div><input type='hidden' name='question_id[]' value='125252' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515955' \/><div class='watu-question-choice'><input type='radio' name='answer-125252[]' id='answer-id-515955' class='answer answer-165  answerof-125252' value='515955' \/>&nbsp;<label for='answer-id-515955' id='answer-label-515955' class=' answer label-165'><span class='answer'>Local regulatory requirements<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515956' \/><div class='watu-question-choice'><input type='radio' name='answer-125252[]' id='answer-id-515956' class='answer answer-165  answerof-125252' value='515956' \/>&nbsp;<label for='answer-id-515956' id='answer-label-515956' class=' answer label-165'><span class='answer'>Local IT requirements<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515957' \/><div class='watu-question-choice'><input type='radio' name='answer-125252[]' id='answer-id-515957' class='answer answer-165  answerof-125252' value='515957' \/>&nbsp;<label for='answer-id-515957' id='answer-label-515957' class=' answer label-165'><span class='answer'>Cross-border data mobility<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515958' \/><div class='watu-question-choice'><input type='radio' name='answer-125252[]' id='answer-id-515958' class='answer answer-165  answerof-125252' value='515958' \/>&nbsp;<label for='answer-id-515958' id='answer-label-515958' class=' answer label-165'><span class='answer'>Corporate security objectives<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType165' value='radio' class=''><\/div><div class='watu-question' id='question-166'><div class='question-content'><p><span class='watu_num'>166. <\/span>When facilitating the alignment of corporate governance and information security governance, which of the following is the MOST important role of an organization\u2019s security steering committee?<\/p>\n<\/div><input type='hidden' name='question_id[]' value='125253' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515959' \/><div class='watu-question-choice'><input type='radio' name='answer-125253[]' id='answer-id-515959' class='answer answer-166  answerof-125253' value='515959' \/>&nbsp;<label for='answer-id-515959' id='answer-label-515959' class=' answer label-166'><span class='answer'>Obtaining support for the integration from business owners<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515960' \/><div class='watu-question-choice'><input type='radio' name='answer-125253[]' id='answer-id-515960' class='answer answer-166  answerof-125253' value='515960' \/>&nbsp;<label for='answer-id-515960' id='answer-label-515960' class=' answer label-166'><span class='answer'>Obtaining approval for the information security budget<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515961' \/><div class='watu-question-choice'><input type='radio' name='answer-125253[]' id='answer-id-515961' class='answer answer-166  answerof-125253' value='515961' \/>&nbsp;<label for='answer-id-515961' id='answer-label-515961' class=' answer label-166'><span class='answer'>Evaluating and reporting the degree of integration<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515962' \/><div class='watu-question-choice'><input type='radio' name='answer-125253[]' id='answer-id-515962' class='answer answer-166  answerof-125253' value='515962' \/>&nbsp;<label for='answer-id-515962' id='answer-label-515962' class=' answer label-166'><span class='answer'>Defining metrics to demonstrate alignment<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType166' value='radio' class=''><\/div><div class='watu-question' id='question-167'><div class='question-content'><p><span class='watu_num'>167. <\/span>Which of the following is a PRIMARY responsibility of an information security governance committee?<\/p>\n<\/div><input type='hidden' name='question_id[]' value='125254' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515963' \/><div class='watu-question-choice'><input type='radio' name='answer-125254[]' id='answer-id-515963' class='answer answer-167  answerof-125254' value='515963' \/>&nbsp;<label for='answer-id-515963' id='answer-label-515963' class=' answer label-167'><span class='answer'>Approving the purchase of information security technologies<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515964' \/><div class='watu-question-choice'><input type='radio' name='answer-125254[]' id='answer-id-515964' class='answer answer-167  answerof-125254' value='515964' \/>&nbsp;<label for='answer-id-515964' id='answer-label-515964' class=' answer label-167'><span class='answer'>Approving the information security awareness training strategy<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515965' \/><div class='watu-question-choice'><input type='radio' name='answer-125254[]' id='answer-id-515965' class='answer answer-167  answerof-125254' value='515965' \/>&nbsp;<label for='answer-id-515965' id='answer-label-515965' class=' answer label-167'><span class='answer'>Reviewing the information security strategy<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515966' \/><div class='watu-question-choice'><input type='radio' name='answer-125254[]' id='answer-id-515966' class='answer answer-167  answerof-125254' value='515966' \/>&nbsp;<label for='answer-id-515966' id='answer-label-515966' class=' answer label-167'><span class='answer'>Analyzing information security policy compliance reviews<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType167' value='radio' class=''><\/div><div class='watu-question' id='question-168'><div class='question-content'><p><span class='watu_num'>168. <\/span>What is the MOST effective way to ensure security policies and procedures are up-to-date?<\/p>\n<\/div><input type='hidden' name='question_id[]' value='125255' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515967' \/><div class='watu-question-choice'><input type='radio' name='answer-125255[]' id='answer-id-515967' class='answer answer-168  answerof-125255' value='515967' \/>&nbsp;<label for='answer-id-515967' id='answer-label-515967' class=' answer label-168'><span class='answer'>Verify security requirements are being identified and consistently applied.<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515968' \/><div class='watu-question-choice'><input type='radio' name='answer-125255[]' id='answer-id-515968' class='answer answer-168  answerof-125255' value='515968' \/>&nbsp;<label for='answer-id-515968' id='answer-label-515968' class=' answer label-168'><span class='answer'>Align the organization\u2019s security practices with industry standards and best practice.<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515969' \/><div class='watu-question-choice'><input type='radio' name='answer-125255[]' id='answer-id-515969' class='answer answer-168  answerof-125255' value='515969' \/>&nbsp;<label for='answer-id-515969' id='answer-label-515969' class=' answer label-168'><span class='answer'>Define and document senior management\u2019s vision for the direction of the security<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515970' \/><div class='watu-question-choice'><input type='radio' name='answer-125255[]' id='answer-id-515970' class='answer answer-168  answerof-125255' value='515970' \/>&nbsp;<label for='answer-id-515970' id='answer-label-515970' class=' answer label-168'><span class='answer'>Prevent security documentation audit issues from being raised<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType168' value='radio' class=''><\/div><div class='watu-question' id='question-169'><div class='question-content'><p><span class='watu_num'>169. <\/span>Which of the following is the PRIMARY advantage of having an established information security governance framework in place when an organization is adopting emerging technologies?<\/p>\n<\/div><input type='hidden' name='question_id[]' value='125256' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515971' \/><div class='watu-question-choice'><input type='radio' name='answer-125256[]' id='answer-id-515971' class='answer answer-169  answerof-125256' value='515971' \/>&nbsp;<label for='answer-id-515971' id='answer-label-515971' class=' answer label-169'><span class='answer'>An emerging technologies strategy would be in place<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515972' \/><div class='watu-question-choice'><input type='radio' name='answer-125256[]' id='answer-id-515972' class='answer answer-169  answerof-125256' value='515972' \/>&nbsp;<label for='answer-id-515972' id='answer-label-515972' class=' answer label-169'><span class='answer'>A cost-benefit analysis process would be easier to perform<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515973' \/><div class='watu-question-choice'><input type='radio' name='answer-125256[]' id='answer-id-515973' class='answer answer-169  answerof-125256' value='515973' \/>&nbsp;<label for='answer-id-515973' id='answer-label-515973' class=' answer label-169'><span class='answer'>An effective security risk management process is established<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515974' \/><div class='watu-question-choice'><input type='radio' name='answer-125256[]' id='answer-id-515974' class='answer answer-169  answerof-125256' value='515974' \/>&nbsp;<label for='answer-id-515974' id='answer-label-515974' class=' answer label-169'><span class='answer'>End-user acceptance of emerging technologies has been established<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType169' value='radio' class=''><\/div><div class='watu-question' id='question-170'><div class='question-content'><p><span class='watu_num'>170. <\/span>From a risk management perspective, which of the following is MOST important to be tracked in continuous monitoring?<\/p>\n<\/div><input type='hidden' name='question_id[]' value='125257' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515975' \/><div class='watu-question-choice'><input type='radio' name='answer-125257[]' id='answer-id-515975' class='answer answer-170  answerof-125257' value='515975' \/>&nbsp;<label for='answer-id-515975' id='answer-label-515975' class=' answer label-170'><span class='answer'>Number of prevented attacks<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515976' \/><div class='watu-question-choice'><input type='radio' name='answer-125257[]' id='answer-id-515976' class='answer answer-170  answerof-125257' value='515976' \/>&nbsp;<label for='answer-id-515976' id='answer-label-515976' class=' answer label-170'><span class='answer'>Changes in the threat environment<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515977' \/><div class='watu-question-choice'><input type='radio' name='answer-125257[]' id='answer-id-515977' class='answer answer-170  answerof-125257' value='515977' \/>&nbsp;<label for='answer-id-515977' id='answer-label-515977' class=' answer label-170'><span class='answer'>Changes in user privileges<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515978' \/><div class='watu-question-choice'><input type='radio' name='answer-125257[]' id='answer-id-515978' class='answer answer-170  answerof-125257' value='515978' \/>&nbsp;<label for='answer-id-515978' id='answer-label-515978' class=' answer label-170'><span class='answer'>Number of failed logins<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType170' value='radio' class=''><\/div><div class='watu-question' id='question-171'><div class='question-content'><p><span class='watu_num'>171. <\/span>Which of the following should be the PRIMARY objective of an information security governance framework?<\/p>\n<\/div><input type='hidden' name='question_id[]' value='125258' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515979' \/><div class='watu-question-choice'><input type='radio' name='answer-125258[]' id='answer-id-515979' class='answer answer-171  answerof-125258' value='515979' \/>&nbsp;<label for='answer-id-515979' id='answer-label-515979' class=' answer label-171'><span class='answer'>Increase the organization\u2019s return on security investment.<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515980' \/><div class='watu-question-choice'><input type='radio' name='answer-125258[]' id='answer-id-515980' class='answer answer-171  answerof-125258' value='515980' \/>&nbsp;<label for='answer-id-515980' id='answer-label-515980' class=' answer label-171'><span class='answer'>Provide a baseline for optimizing the security profile of the organization.<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515981' \/><div class='watu-question-choice'><input type='radio' name='answer-125258[]' id='answer-id-515981' class='answer answer-171  answerof-125258' value='515981' \/>&nbsp;<label for='answer-id-515981' id='answer-label-515981' class=' answer label-171'><span class='answer'>Ensure that users comply with the organization\u2019s information security policies.<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515982' \/><div class='watu-question-choice'><input type='radio' name='answer-125258[]' id='answer-id-515982' class='answer answer-171  answerof-125258' value='515982' \/>&nbsp;<label for='answer-id-515982' id='answer-label-515982' class=' answer label-171'><span class='answer'>Demonstrate compliance with industry best practices to external stakeholders.<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType171' value='radio' class=''><\/div><div class='watu-question' id='question-172'><div class='question-content'><p><span class='watu_num'>172. <\/span>An organization has developed mature risk management practices that are followed across all departments.<br \/>\n<br \/>What is the MOST effective way for the audit team to leverage this risk management maturity?<\/p>\n<\/div><input type='hidden' name='question_id[]' value='125259' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515983' \/><div class='watu-question-choice'><input type='radio' name='answer-125259[]' id='answer-id-515983' class='answer answer-172  answerof-125259' value='515983' \/>&nbsp;<label for='answer-id-515983' id='answer-label-515983' class=' answer label-172'><span class='answer'>Facilitating audit risk identification and evaluation workshops<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515984' \/><div class='watu-question-choice'><input type='radio' name='answer-125259[]' id='answer-id-515984' class='answer answer-172  answerof-125259' value='515984' \/>&nbsp;<label for='answer-id-515984' id='answer-label-515984' class=' answer label-172'><span class='answer'>Implementing risk responses on management\u2019s behalf<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515985' \/><div class='watu-question-choice'><input type='radio' name='answer-125259[]' id='answer-id-515985' class='answer answer-172  answerof-125259' value='515985' \/>&nbsp;<label for='answer-id-515985' id='answer-label-515985' class=' answer label-172'><span class='answer'>Providing assurances to management regarding risk<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515986' \/><div class='watu-question-choice'><input type='radio' name='answer-125259[]' id='answer-id-515986' class='answer answer-172  answerof-125259' value='515986' \/>&nbsp;<label for='answer-id-515986' id='answer-label-515986' class=' answer label-172'><span class='answer'>Integrating the risk register for audit planning purposes<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType172' value='radio' class=''><\/div><div class='watu-question' id='question-173'><div class='question-content'><p><span class='watu_num'>173. <\/span>Which of the following findings would be of GREATEST concern to an IS auditor performing an information security audit of critical server log management activities?<\/p>\n<\/div><input type='hidden' name='question_id[]' value='125260' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515987' \/><div class='watu-question-choice'><input type='radio' name='answer-125260[]' id='answer-id-515987' class='answer answer-173  answerof-125260' value='515987' \/>&nbsp;<label for='answer-id-515987' id='answer-label-515987' class=' answer label-173'><span class='answer'>Log records can be overwritten before being reviewed.<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515988' \/><div class='watu-question-choice'><input type='radio' name='answer-125260[]' id='answer-id-515988' class='answer answer-173  answerof-125260' value='515988' \/>&nbsp;<label for='answer-id-515988' id='answer-label-515988' class=' answer label-173'><span class='answer'>Logging procedures are insufficiently documented.<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515989' \/><div class='watu-question-choice'><input type='radio' name='answer-125260[]' id='answer-id-515989' class='answer answer-173  answerof-125260' value='515989' \/>&nbsp;<label for='answer-id-515989' id='answer-label-515989' class=' answer label-173'><span class='answer'>Log records are dynamically into different servers.<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515990' \/><div class='watu-question-choice'><input type='radio' name='answer-125260[]' id='answer-id-515990' class='answer answer-173  answerof-125260' value='515990' \/>&nbsp;<label for='answer-id-515990' id='answer-label-515990' class=' answer label-173'><span class='answer'>Logs are monitored using manual processes.<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType173' value='radio' class=''><\/div><div class='watu-question' id='question-174'><div class='question-content'><p><span class='watu_num'>174. <\/span>The BEST way to validate whether a malicious act has actually occurred in an application is to review:<\/p>\n<\/div><input type='hidden' name='question_id[]' value='125261' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515991' \/><div class='watu-question-choice'><input type='radio' name='answer-125261[]' id='answer-id-515991' class='answer answer-174  answerof-125261' value='515991' \/>&nbsp;<label for='answer-id-515991' id='answer-label-515991' class=' answer label-174'><span class='answer'>segregation of duties<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515992' \/><div class='watu-question-choice'><input type='radio' name='answer-125261[]' id='answer-id-515992' class='answer answer-174  answerof-125261' value='515992' \/>&nbsp;<label for='answer-id-515992' id='answer-label-515992' class=' answer label-174'><span class='answer'>access controls<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515993' \/><div class='watu-question-choice'><input type='radio' name='answer-125261[]' id='answer-id-515993' class='answer answer-174  answerof-125261' value='515993' \/>&nbsp;<label for='answer-id-515993' id='answer-label-515993' class=' answer label-174'><span class='answer'>activity logs<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515994' \/><div class='watu-question-choice'><input type='radio' name='answer-125261[]' id='answer-id-515994' class='answer answer-174  answerof-125261' value='515994' \/>&nbsp;<label for='answer-id-515994' id='answer-label-515994' class=' answer label-174'><span class='answer'>change management logs<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType174' value='radio' class=''><\/div><div class='watu-question' id='question-175'><div class='question-content'><p><span class='watu_num'>175. <\/span>A vulnerability in which of the following virtual systems would be of GREATEST concern to the IS auditor?<\/p>\n<\/div><input type='hidden' name='question_id[]' value='125262' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515995' \/><div class='watu-question-choice'><input type='radio' name='answer-125262[]' id='answer-id-515995' class='answer answer-175  answerof-125262' value='515995' \/>&nbsp;<label for='answer-id-515995' id='answer-label-515995' class=' answer label-175'><span class='answer'>The virtual machine management server<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515996' \/><div class='watu-question-choice'><input type='radio' name='answer-125262[]' id='answer-id-515996' class='answer answer-175  answerof-125262' value='515996' \/>&nbsp;<label for='answer-id-515996' id='answer-label-515996' class=' answer label-175'><span class='answer'>The virtual file server<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515997' \/><div class='watu-question-choice'><input type='radio' name='answer-125262[]' id='answer-id-515997' class='answer answer-175  answerof-125262' value='515997' \/>&nbsp;<label for='answer-id-515997' id='answer-label-515997' class=' answer label-175'><span class='answer'>The virtual application server<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515998' \/><div class='watu-question-choice'><input type='radio' name='answer-125262[]' id='answer-id-515998' class='answer answer-175  answerof-125262' value='515998' \/>&nbsp;<label for='answer-id-515998' id='answer-label-515998' class=' answer label-175'><span class='answer'>The virtual antivirus server<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType175' value='radio' class=''><\/div><div class='watu-question' id='question-176'><div class='question-content'><p><span class='watu_num'>176. <\/span>An IS auditor finds that application servers had inconsistent configurations leading to potential security vulnerabilities.<br \/>\n<br \/>Which of the following should the auditor recommend FIRST?<\/p>\n<\/div><input type='hidden' name='question_id[]' value='125263' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='515999' \/><div class='watu-question-choice'><input type='radio' name='answer-125263[]' id='answer-id-515999' class='answer answer-176  answerof-125263' value='515999' \/>&nbsp;<label for='answer-id-515999' id='answer-label-515999' class=' answer label-176'><span class='answer'>Enforce server baseline standards.<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='516000' \/><div class='watu-question-choice'><input type='radio' name='answer-125263[]' id='answer-id-516000' class='answer answer-176  answerof-125263' value='516000' \/>&nbsp;<label for='answer-id-516000' id='answer-label-516000' class=' answer label-176'><span class='answer'>Improve change management processes using a workflow tool.<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='516001' \/><div class='watu-question-choice'><input type='radio' name='answer-125263[]' id='answer-id-516001' class='answer answer-176  answerof-125263' value='516001' \/>&nbsp;<label for='answer-id-516001' id='answer-label-516001' class=' answer label-176'><span class='answer'>Hold the application owner accountable for monitoring metrics.<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='516002' \/><div class='watu-question-choice'><input type='radio' name='answer-125263[]' id='answer-id-516002' class='answer answer-176  answerof-125263' value='516002' \/>&nbsp;<label for='answer-id-516002' id='answer-label-516002' class=' answer label-176'><span class='answer'>Use a single vendor for the application servers.<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType176' value='radio' class=''><\/div><div class='watu-question' id='question-177'><div class='question-content'><p><span class='watu_num'>177. <\/span>Implementing a strong password policy is part of an organization\u2019s information security strategy for the year. A business unit believes the strategy may adversely affect a client\u2019s adoption of a recently developed mobile application and has decided not to implement the policy.<br \/>\n<br \/>Which of the following would be the information security manager\u2019s BEST course of action?<\/p>\n<\/div><input type='hidden' name='question_id[]' value='125264' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='516003' \/><div class='watu-question-choice'><input type='radio' name='answer-125264[]' id='answer-id-516003' class='answer answer-177  answerof-125264' value='516003' \/>&nbsp;<label for='answer-id-516003' id='answer-label-516003' class=' answer label-177'><span class='answer'>Analyze the risk and impact of not implementing the policy<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='516004' \/><div class='watu-question-choice'><input type='radio' name='answer-125264[]' id='answer-id-516004' class='answer answer-177  answerof-125264' value='516004' \/>&nbsp;<label for='answer-id-516004' id='answer-label-516004' class=' answer label-177'><span class='answer'>Develop and implement a password policy for the mobile application<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='516005' \/><div class='watu-question-choice'><input type='radio' name='answer-125264[]' id='answer-id-516005' class='answer answer-177  answerof-125264' value='516005' \/>&nbsp;<label for='answer-id-516005' id='answer-label-516005' class=' answer label-177'><span class='answer'>Escalate non-implementation of the policy to senior management<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='516006' \/><div class='watu-question-choice'><input type='radio' name='answer-125264[]' id='answer-id-516006' class='answer answer-177  answerof-125264' value='516006' \/>&nbsp;<label for='answer-id-516006' id='answer-label-516006' class=' answer label-177'><span class='answer'>Benchmark with similar mobile applications to identify gaps<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType177' value='radio' class=''><\/div><div class='watu-question' id='question-178'><div class='question-content'><p><span class='watu_num'>178. <\/span>In a multinational organization, local security regulations should be implemented over global security policy because:<\/p>\n<\/div><input type='hidden' name='question_id[]' value='125265' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='516007' \/><div class='watu-question-choice'><input type='radio' name='answer-125265[]' id='answer-id-516007' class='answer answer-178  answerof-125265' value='516007' \/>&nbsp;<label for='answer-id-516007' id='answer-label-516007' class=' answer label-178'><span class='answer'>global security policies include unnecessary controls for local businesses<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='516008' \/><div class='watu-question-choice'><input type='radio' name='answer-125265[]' id='answer-id-516008' class='answer answer-178  answerof-125265' value='516008' \/>&nbsp;<label for='answer-id-516008' id='answer-label-516008' class=' answer label-178'><span class='answer'>business objectives are defined by local business unit managers<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='516009' \/><div class='watu-question-choice'><input type='radio' name='answer-125265[]' id='answer-id-516009' class='answer answer-178  answerof-125265' value='516009' \/>&nbsp;<label for='answer-id-516009' id='answer-label-516009' class=' answer label-178'><span class='answer'>requirements of local regulations take precedence<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='516010' \/><div class='watu-question-choice'><input type='radio' name='answer-125265[]' id='answer-id-516010' class='answer answer-178  answerof-125265' value='516010' \/>&nbsp;<label for='answer-id-516010' id='answer-label-516010' class=' answer label-178'><span class='answer'>deploying awareness of local regulations is more practical than of global policy<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType178' value='radio' class=''><\/div><div class='watu-question' id='question-179'><div class='question-content'><p><span class='watu_num'>179. <\/span>Which of the following is a step in establishing a security policy?<\/p>\n<\/div><input type='hidden' name='question_id[]' value='125266' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='516011' \/><div class='watu-question-choice'><input type='radio' name='answer-125266[]' id='answer-id-516011' class='answer answer-179  answerof-125266' value='516011' \/>&nbsp;<label for='answer-id-516011' id='answer-label-516011' class=' answer label-179'><span class='answer'>Developing platform-level security baselines.<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='516012' \/><div class='watu-question-choice'><input type='radio' name='answer-125266[]' id='answer-id-516012' class='answer answer-179  answerof-125266' value='516012' \/>&nbsp;<label for='answer-id-516012' id='answer-label-516012' class=' answer label-179'><span class='answer'>Developing configurations parameters for the network,<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='516013' \/><div class='watu-question-choice'><input type='radio' name='answer-125266[]' id='answer-id-516013' class='answer answer-179  answerof-125266' value='516013' \/>&nbsp;<label for='answer-id-516013' id='answer-label-516013' class=' answer label-179'><span class='answer'>Implementing a process for developing and maintaining the policy.<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='516014' \/><div class='watu-question-choice'><input type='radio' name='answer-125266[]' id='answer-id-516014' class='answer answer-179  answerof-125266' value='516014' \/>&nbsp;<label for='answer-id-516014' id='answer-label-516014' class=' answer label-179'><span class='answer'>Creating a RACI matrix.<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType179' value='radio' class=''><\/div><div class='watu-question' id='question-180'><div class='question-content'><p><span class='watu_num'>180. <\/span>A large number of exceptions to an organization\u2019s information security standards have been granted after senior management approved a bring your own device (BYOD) program.<br \/>\n<br \/>To address this situation, it is MOST important for the information security manage to:<\/p>\n<\/div><input type='hidden' name='question_id[]' value='125267' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='516015' \/><div class='watu-question-choice'><input type='radio' name='answer-125267[]' id='answer-id-516015' class='answer answer-180  answerof-125267' value='516015' \/>&nbsp;<label for='answer-id-516015' id='answer-label-516015' class=' answer label-180'><span class='answer'>introduce strong authentication on devices<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='516016' \/><div class='watu-question-choice'><input type='radio' name='answer-125267[]' id='answer-id-516016' class='answer answer-180  answerof-125267' value='516016' \/>&nbsp;<label for='answer-id-516016' id='answer-label-516016' class=' answer label-180'><span class='answer'>reject new exception requests<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='516017' \/><div class='watu-question-choice'><input type='radio' name='answer-125267[]' id='answer-id-516017' class='answer answer-180  answerof-125267' value='516017' \/>&nbsp;<label for='answer-id-516017' id='answer-label-516017' class=' answer label-180'><span class='answer'>require authorization to wipe lost devices<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='516018' \/><div class='watu-question-choice'><input type='radio' name='answer-125267[]' id='answer-id-516018' class='answer answer-180  answerof-125267' value='516018' \/>&nbsp;<label for='answer-id-516018' id='answer-label-516018' class=' answer label-180'><span class='answer'>update the information security policy<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType180' value='radio' class=''><\/div><div class='watu-question' id='question-181'><div class='question-content'><p><span class='watu_num'>181. <\/span>Which of the following is MOST important for the IS auditor to verify when reviewing the development process of a security policy?<\/p>\n<\/div><input type='hidden' name='question_id[]' value='125268' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='516019' \/><div class='watu-question-choice'><input type='radio' name='answer-125268[]' id='answer-id-516019' class='answer answer-181  answerof-125268' value='516019' \/>&nbsp;<label for='answer-id-516019' id='answer-label-516019' class=' answer label-181'><span class='answer'>Evidence of active involvement of key stakeholders<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='516020' \/><div class='watu-question-choice'><input type='radio' name='answer-125268[]' id='answer-id-516020' class='answer answer-181  answerof-125268' value='516020' \/>&nbsp;<label for='answer-id-516020' id='answer-label-516020' class=' answer label-181'><span class='answer'>Output from the enterprise\u2019s risk management system<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='516021' \/><div class='watu-question-choice'><input type='radio' name='answer-125268[]' id='answer-id-516021' class='answer answer-181  answerof-125268' value='516021' \/>&nbsp;<label for='answer-id-516021' id='answer-label-516021' class=' answer label-181'><span class='answer'>Identification of the control framework<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='516022' \/><div class='watu-question-choice'><input type='radio' name='answer-125268[]' id='answer-id-516022' class='answer answer-181  answerof-125268' value='516022' \/>&nbsp;<label for='answer-id-516022' id='answer-label-516022' class=' answer label-181'><span class='answer'>Evidence of management approval<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType181' value='radio' class=''><\/div><div class='watu-question' id='question-182'><div class='question-content'><p><span class='watu_num'>182. <\/span>Which of the following should be the PRIMARY reason to establish a social media policy for all employees?<\/p>\n<\/div><input type='hidden' name='question_id[]' value='125269' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='516023' \/><div class='watu-question-choice'><input type='radio' name='answer-125269[]' id='answer-id-516023' class='answer answer-182  answerof-125269' value='516023' \/>&nbsp;<label for='answer-id-516023' id='answer-label-516023' class=' answer label-182'><span class='answer'>To publish acceptable messages to be used by employees when posting<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='516024' \/><div class='watu-question-choice'><input type='radio' name='answer-125269[]' id='answer-id-516024' class='answer answer-182  answerof-125269' value='516024' \/>&nbsp;<label for='answer-id-516024' id='answer-label-516024' class=' answer label-182'><span class='answer'>To raise awareness and provide guidance about social media risks<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='516025' \/><div class='watu-question-choice'><input type='radio' name='answer-125269[]' id='answer-id-516025' class='answer answer-182  answerof-125269' value='516025' \/>&nbsp;<label for='answer-id-516025' id='answer-label-516025' class=' answer label-182'><span class='answer'>To restrict access to social media during business hours to maintain productivity<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='516026' \/><div class='watu-question-choice'><input type='radio' name='answer-125269[]' id='answer-id-516026' class='answer answer-182  answerof-125269' value='516026' \/>&nbsp;<label for='answer-id-516026' id='answer-label-516026' class=' answer label-182'><span class='answer'>To prevent negative public social media postings and comments<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType182' value='radio' class=''><\/div><div class='watu-question' id='question-183'><div class='question-content'><p><span class='watu_num'>183. <\/span>An internal IS auditor discovers that a service organization did not notify its customers following a data breach.<br \/>\n<br \/>Which of the following should the auditor do FIRST?<\/p>\n<\/div><input type='hidden' name='question_id[]' value='125270' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='516027' \/><div class='watu-question-choice'><input type='radio' name='answer-125270[]' id='answer-id-516027' class='answer answer-183  answerof-125270' value='516027' \/>&nbsp;<label for='answer-id-516027' id='answer-label-516027' class=' answer label-183'><span class='answer'>Notify audit management of the finding.<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='516028' \/><div class='watu-question-choice'><input type='radio' name='answer-125270[]' id='answer-id-516028' class='answer answer-183  answerof-125270' value='516028' \/>&nbsp;<label for='answer-id-516028' id='answer-label-516028' class=' answer label-183'><span class='answer'>Report the finding to regulatory authorities.<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='516029' \/><div class='watu-question-choice'><input type='radio' name='answer-125270[]' id='answer-id-516029' class='answer answer-183  answerof-125270' value='516029' \/>&nbsp;<label for='answer-id-516029' id='answer-label-516029' class=' answer label-183'><span class='answer'>Notify the service organization\u2019s customers.<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='516030' \/><div class='watu-question-choice'><input type='radio' name='answer-125270[]' id='answer-id-516030' class='answer answer-183  answerof-125270' value='516030' \/>&nbsp;<label for='answer-id-516030' id='answer-label-516030' class=' answer label-183'><span class='answer'>Require the service organization to notify its customers.<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType183' value='radio' class=''><\/div><div class='watu-question' id='question-184'><div class='question-content'><p><span class='watu_num'>184. <\/span>A small organization is experiencing rapid growth and plans to create a new information security policy.<br \/>\n<br \/>Which of the following is MOST relevant to creating the policy?<\/p>\n<\/div><input type='hidden' name='question_id[]' value='125271' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='516031' \/><div class='watu-question-choice'><input type='radio' name='answer-125271[]' id='answer-id-516031' class='answer answer-184  answerof-125271' value='516031' \/>&nbsp;<label for='answer-id-516031' id='answer-label-516031' class=' answer label-184'><span class='answer'>Industry standards<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='516032' \/><div class='watu-question-choice'><input type='radio' name='answer-125271[]' id='answer-id-516032' class='answer answer-184  answerof-125271' value='516032' \/>&nbsp;<label for='answer-id-516032' id='answer-label-516032' class=' answer label-184'><span class='answer'>The business impact analysis<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='516033' \/><div class='watu-question-choice'><input type='radio' name='answer-125271[]' id='answer-id-516033' class='answer answer-184  answerof-125271' value='516033' \/>&nbsp;<label for='answer-id-516033' id='answer-label-516033' class=' answer label-184'><span class='answer'>The business objectives<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='516034' \/><div class='watu-question-choice'><input type='radio' name='answer-125271[]' id='answer-id-516034' class='answer answer-184  answerof-125271' value='516034' \/>&nbsp;<label for='answer-id-516034' id='answer-label-516034' class=' answer label-184'><span class='answer'>Previous audit recommendations<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType184' value='radio' class=''><\/div><div class='watu-question' id='question-185'><div class='question-content'><p><span class='watu_num'>185. <\/span>A CEO requests access to corporate documents from a mobile device that does not comply with organizational policy. The information security manager should FIRST:<\/p>\n<\/div><input type='hidden' name='question_id[]' value='125272' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='516035' \/><div class='watu-question-choice'><input type='radio' name='answer-125272[]' id='answer-id-516035' class='answer answer-185  answerof-125272' value='516035' \/>&nbsp;<label for='answer-id-516035' id='answer-label-516035' class=' answer label-185'><span class='answer'>evaluate the business risk<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='516036' \/><div class='watu-question-choice'><input type='radio' name='answer-125272[]' id='answer-id-516036' class='answer answer-185  answerof-125272' value='516036' \/>&nbsp;<label for='answer-id-516036' id='answer-label-516036' class=' answer label-185'><span class='answer'>evaluate a third-party solution<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='516037' \/><div class='watu-question-choice'><input type='radio' name='answer-125272[]' id='answer-id-516037' class='answer answer-185  answerof-125272' value='516037' \/>&nbsp;<label for='answer-id-516037' id='answer-label-516037' class=' answer label-185'><span class='answer'>initiate an exception approval process<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='516038' \/><div class='watu-question-choice'><input type='radio' name='answer-125272[]' id='answer-id-516038' class='answer answer-185  answerof-125272' value='516038' \/>&nbsp;<label for='answer-id-516038' id='answer-label-516038' class=' answer label-185'><span class='answer'>deploy additional security controls<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType185' value='radio' class=''><\/div><div class='watu-question' id='question-186'><div class='question-content'><p><span class='watu_num'>186. <\/span>Which of the following is MOST important to consider when developing a bring your own device (BYOD) policy?<\/p>\n<\/div><input type='hidden' name='question_id[]' value='125273' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='516039' \/><div class='watu-question-choice'><input type='radio' name='answer-125273[]' id='answer-id-516039' class='answer answer-186  answerof-125273' value='516039' \/>&nbsp;<label for='answer-id-516039' id='answer-label-516039' class=' answer label-186'><span class='answer'>Supported operating systems<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='516040' \/><div class='watu-question-choice'><input type='radio' name='answer-125273[]' id='answer-id-516040' class='answer answer-186  answerof-125273' value='516040' \/>&nbsp;<label for='answer-id-516040' id='answer-label-516040' class=' answer label-186'><span class='answer'>Procedure for accessing the network<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='516041' \/><div class='watu-question-choice'><input type='radio' name='answer-125273[]' id='answer-id-516041' class='answer answer-186  answerof-125273' value='516041' \/>&nbsp;<label for='answer-id-516041' id='answer-label-516041' class=' answer label-186'><span class='answer'>Application download restrictions<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='516042' \/><div class='watu-question-choice'><input type='radio' name='answer-125273[]' id='answer-id-516042' class='answer answer-186  answerof-125273' value='516042' \/>&nbsp;<label for='answer-id-516042' id='answer-label-516042' class=' answer label-186'><span class='answer'>Remote wipe procedures<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType186' value='radio' class=''><\/div><div class='watu-question' id='question-187'><div class='question-content'><p><span class='watu_num'>187. <\/span>An information security team has discovered that users are sharing a login account to an application with sensitive information, in violation of the access policy. Business management indicates that the practice creates operational efficiencies. The information security manager\u2019s BEST course of action should be to:<\/p>\n<\/div><input type='hidden' name='question_id[]' value='125274' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='516043' \/><div class='watu-question-choice'><input type='radio' name='answer-125274[]' id='answer-id-516043' class='answer answer-187  answerof-125274' value='516043' \/>&nbsp;<label for='answer-id-516043' id='answer-label-516043' class=' answer label-187'><span class='answer'>modify the policy<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='516044' \/><div class='watu-question-choice'><input type='radio' name='answer-125274[]' id='answer-id-516044' class='answer answer-187  answerof-125274' value='516044' \/>&nbsp;<label for='answer-id-516044' id='answer-label-516044' class=' answer label-187'><span class='answer'>present the risk to senior management<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='516045' \/><div class='watu-question-choice'><input type='radio' name='answer-125274[]' id='answer-id-516045' class='answer answer-187  answerof-125274' value='516045' \/>&nbsp;<label for='answer-id-516045' id='answer-label-516045' class=' answer label-187'><span class='answer'>enforce the policy<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='516046' \/><div class='watu-question-choice'><input type='radio' name='answer-125274[]' id='answer-id-516046' class='answer answer-187  answerof-125274' value='516046' \/>&nbsp;<label for='answer-id-516046' id='answer-label-516046' class=' answer label-187'><span class='answer'>create an exception for the deviation<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType187' value='radio' class=''><\/div><div class='watu-question' id='question-188'><div class='question-content'><p><span class='watu_num'>188. <\/span>A policy has been established requiring users to install mobile device management (MDM) software on their personal devices.<br \/>\n<br \/>Which of the following would BEST mitigate the risk created by noncompliance with this policy?<\/p>\n<\/div><input type='hidden' name='question_id[]' value='125275' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='516047' \/><div class='watu-question-choice'><input type='radio' name='answer-125275[]' id='answer-id-516047' class='answer answer-188  answerof-125275' value='516047' \/>&nbsp;<label for='answer-id-516047' id='answer-label-516047' class=' answer label-188'><span class='answer'>Issuing warnings and documenting noncompliance<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='516048' \/><div class='watu-question-choice'><input type='radio' name='answer-125275[]' id='answer-id-516048' class='answer answer-188  answerof-125275' value='516048' \/>&nbsp;<label for='answer-id-516048' id='answer-label-516048' class=' answer label-188'><span class='answer'>Disabling remote access from the mobile device<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='516049' \/><div class='watu-question-choice'><input type='radio' name='answer-125275[]' id='answer-id-516049' class='answer answer-188  answerof-125275' value='516049' \/>&nbsp;<label for='answer-id-516049' id='answer-label-516049' class=' answer label-188'><span class='answer'>Issuing company-configured mobile devices<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='516050' \/><div class='watu-question-choice'><input type='radio' name='answer-125275[]' id='answer-id-516050' class='answer answer-188  answerof-125275' value='516050' \/>&nbsp;<label for='answer-id-516050' id='answer-label-516050' class=' answer label-188'><span class='answer'>Requiring users to sign-off on terms and conditions<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType188' value='radio' class=''><\/div><div class='watu-question' id='question-189'><div class='question-content'><p><span class='watu_num'>189. <\/span>To address the issue that performance pressures on IT may conflict with information security controls, it is MOST important that:<\/p>\n<\/div><input type='hidden' name='question_id[]' value='125276' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='516051' \/><div class='watu-question-choice'><input type='radio' name='answer-125276[]' id='answer-id-516051' class='answer answer-189  answerof-125276' value='516051' \/>&nbsp;<label for='answer-id-516051' id='answer-label-516051' class=' answer label-189'><span class='answer'>the security policy is changed to accommodate IT performance pressure<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='516052' \/><div class='watu-question-choice'><input type='radio' name='answer-125276[]' id='answer-id-516052' class='answer answer-189  answerof-125276' value='516052' \/>&nbsp;<label for='answer-id-516052' id='answer-label-516052' class=' answer label-189'><span class='answer'>noncompliance issues are reported senior management<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='516053' \/><div class='watu-question-choice'><input type='radio' name='answer-125276[]' id='answer-id-516053' class='answer answer-189  answerof-125276' value='516053' \/>&nbsp;<label for='answer-id-516053' id='answer-label-516053' class=' answer label-189'><span class='answer'>senior management provides guidance and dispute resolution<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='516054' \/><div class='watu-question-choice'><input type='radio' name='answer-125276[]' id='answer-id-516054' class='answer answer-189  answerof-125276' value='516054' \/>&nbsp;<label for='answer-id-516054' id='answer-label-516054' class=' answer label-189'><span class='answer'>information security management understands business performance issues<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType189' value='radio' class=''><\/div><div class='watu-question' id='question-190'><div class='question-content'><p><span class='watu_num'>190. <\/span>The objectives of business process improvement should PRIMARILY include:<\/p>\n<\/div><input type='hidden' name='question_id[]' value='125277' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='516055' \/><div class='watu-question-choice'><input type='radio' name='answer-125277[]' id='answer-id-516055' class='answer answer-190  answerof-125277' value='516055' \/>&nbsp;<label for='answer-id-516055' id='answer-label-516055' class=' answer label-190'><span class='answer'>minimal impact on staff<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='516056' \/><div class='watu-question-choice'><input type='radio' name='answer-125277[]' id='answer-id-516056' class='answer answer-190  answerof-125277' value='516056' \/>&nbsp;<label for='answer-id-516056' id='answer-label-516056' class=' answer label-190'><span class='answer'>incremental changes in productivity<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='516057' \/><div class='watu-question-choice'><input type='radio' name='answer-125277[]' id='answer-id-516057' class='answer answer-190  answerof-125277' value='516057' \/>&nbsp;<label for='answer-id-516057' id='answer-label-516057' class=' answer label-190'><span class='answer'>changes of organizational boundaries<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='516058' \/><div class='watu-question-choice'><input type='radio' name='answer-125277[]' id='answer-id-516058' class='answer answer-190  answerof-125277' value='516058' \/>&nbsp;<label for='answer-id-516058' id='answer-label-516058' class=' answer label-190'><span class='answer'>performance optimization<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType190' value='radio' class=''><\/div><div class='watu-question' id='question-191'><div class='question-content'><p><span class='watu_num'>191. <\/span>During a review of the IT strategic plan, an IS auditor finds several IT initiatives focused on delivering new systems and technology are not aligned with the organization\u2019s strategy. Witch of the following would be the IS auditor\u2019s BEST recommendation?<\/p>\n<\/div><input type='hidden' name='question_id[]' value='125278' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='516059' \/><div class='watu-question-choice'><input type='radio' name='answer-125278[]' id='answer-id-516059' class='answer answer-191  answerof-125278' value='516059' \/>&nbsp;<label for='answer-id-516059' id='answer-label-516059' class=' answer label-191'><span class='answer'>Reassess the return on investment for the IT initiatives<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='516060' \/><div class='watu-question-choice'><input type='radio' name='answer-125278[]' id='answer-id-516060' class='answer answer-191  answerof-125278' value='516060' \/>&nbsp;<label for='answer-id-516060' id='answer-label-516060' class=' answer label-191'><span class='answer'>Modify IT initiatives that do not map to business strategies<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='516061' \/><div class='watu-question-choice'><input type='radio' name='answer-125278[]' id='answer-id-516061' class='answer answer-191  answerof-125278' value='516061' \/>&nbsp;<label for='answer-id-516061' id='answer-label-516061' class=' answer label-191'><span class='answer'>Utilize a balanced scorecard to align IT initiatives to business strategies<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='516062' \/><div class='watu-question-choice'><input type='radio' name='answer-125278[]' id='answer-id-516062' class='answer answer-191  answerof-125278' value='516062' \/>&nbsp;<label for='answer-id-516062' id='answer-label-516062' class=' answer label-191'><span class='answer'>Reassess IT initiatives that do not map business strategies<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType191' value='radio' class=''><\/div><div class='watu-question' id='question-192'><div class='question-content'><p><span class='watu_num'>192. <\/span>An organization has outsourced some of its subprocesses to a service provider. When scoping the audit of the provider, the organization\u2019s internal auditor should FIRST:<\/p>\n<\/div><input type='hidden' name='question_id[]' value='125279' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='516063' \/><div class='watu-question-choice'><input type='radio' name='answer-125279[]' id='answer-id-516063' class='answer answer-192  answerof-125279' value='516063' \/>&nbsp;<label for='answer-id-516063' id='answer-label-516063' class=' answer label-192'><span class='answer'>evaluate operational controls of the provider<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='516064' \/><div class='watu-question-choice'><input type='radio' name='answer-125279[]' id='answer-id-516064' class='answer answer-192  answerof-125279' value='516064' \/>&nbsp;<label for='answer-id-516064' id='answer-label-516064' class=' answer label-192'><span class='answer'>discuss audit objectives with the provider<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='516065' \/><div class='watu-question-choice'><input type='radio' name='answer-125279[]' id='answer-id-516065' class='answer answer-192  answerof-125279' value='516065' \/>&nbsp;<label for='answer-id-516065' id='answer-label-516065' class=' answer label-192'><span class='answer'>review internal audit reports of the provider<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='516066' \/><div class='watu-question-choice'><input type='radio' name='answer-125279[]' id='answer-id-516066' class='answer answer-192  answerof-125279' value='516066' \/>&nbsp;<label for='answer-id-516066' id='answer-label-516066' class=' answer label-192'><span class='answer'>review the contract with the provider<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType192' value='radio' class=''><\/div><div class='watu-question' id='question-193'><div class='question-content'><p><span class='watu_num'>193. <\/span>An organization was severely impacted after an advanced persistent threat (APT) attack. Afterwards, it was found that the initial breach happened a month prior to the attack. Management\u2019s GREATEST concern should be:<\/p>\n<\/div><input type='hidden' name='question_id[]' value='125280' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='516067' \/><div class='watu-question-choice'><input type='radio' name='answer-125280[]' id='answer-id-516067' class='answer answer-193  answerof-125280' value='516067' \/>&nbsp;<label for='answer-id-516067' id='answer-label-516067' class=' answer label-193'><span class='answer'>results of the past internal penetration test<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='516068' \/><div class='watu-question-choice'><input type='radio' name='answer-125280[]' id='answer-id-516068' class='answer answer-193  answerof-125280' value='516068' \/>&nbsp;<label for='answer-id-516068' id='answer-label-516068' class=' answer label-193'><span class='answer'>the effectiveness of monitoring processes<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='516069' \/><div class='watu-question-choice'><input type='radio' name='answer-125280[]' id='answer-id-516069' class='answer answer-193  answerof-125280' value='516069' \/>&nbsp;<label for='answer-id-516069' id='answer-label-516069' class=' answer label-193'><span class='answer'>the installation of critical security patches<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='516070' \/><div class='watu-question-choice'><input type='radio' name='answer-125280[]' id='answer-id-516070' class='answer answer-193  answerof-125280' value='516070' \/>&nbsp;<label for='answer-id-516070' id='answer-label-516070' class=' answer label-193'><span class='answer'>external firewall policies<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType193' value='radio' class=''><\/div><div class='watu-question' id='question-194'><div class='question-content'><p><span class='watu_num'>194. <\/span>Software quality assurance (QA) reviews are planned as part of system development. At which stage in the development process should the first review be initiated?<\/p>\n<\/div><input type='hidden' name='question_id[]' value='125281' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='516071' \/><div class='watu-question-choice'><input type='radio' name='answer-125281[]' id='answer-id-516071' class='answer answer-194  answerof-125281' value='516071' \/>&nbsp;<label for='answer-id-516071' id='answer-label-516071' class=' answer label-194'><span class='answer'>At pre-implementation planning<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='516072' \/><div class='watu-question-choice'><input type='radio' name='answer-125281[]' id='answer-id-516072' class='answer answer-194  answerof-125281' value='516072' \/>&nbsp;<label for='answer-id-516072' id='answer-label-516072' class=' answer label-194'><span class='answer'>As a part of the user requirements definition<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='516073' \/><div class='watu-question-choice'><input type='radio' name='answer-125281[]' id='answer-id-516073' class='answer answer-194  answerof-125281' value='516073' \/>&nbsp;<label for='answer-id-516073' id='answer-label-516073' class=' answer label-194'><span class='answer'>Immediately prior to user acceptance testing<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='516074' \/><div class='watu-question-choice'><input type='radio' name='answer-125281[]' id='answer-id-516074' class='answer answer-194  answerof-125281' value='516074' \/>&nbsp;<label for='answer-id-516074' id='answer-label-516074' class=' answer label-194'><span class='answer'>During the feasibility study<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType194' value='radio' class=''><\/div><div class='watu-question' id='question-195'><div class='question-content'><p><span class='watu_num'>195. <\/span>An organization has made a strategic decision to split into separate operating entities to improve profitability.<br \/>\n<br \/>However, the IT infrastructure remains shared between the entities.<br \/>\n<br \/>Which of the following would BEST help to ensure that IS audit still covers key risk areas within the IT environment as part of its annual plan?<\/p>\n<\/div><input type='hidden' name='question_id[]' value='125282' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='516075' \/><div class='watu-question-choice'><input type='radio' name='answer-125282[]' id='answer-id-516075' class='answer answer-195  answerof-125282' value='516075' \/>&nbsp;<label for='answer-id-516075' id='answer-label-516075' class=' answer label-195'><span class='answer'>Increasing the frequency of risk-based IS audits for each business entity<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='516076' \/><div class='watu-question-choice'><input type='radio' name='answer-125282[]' id='answer-id-516076' class='answer answer-195  answerof-125282' value='516076' \/>&nbsp;<label for='answer-id-516076' id='answer-label-516076' class=' answer label-195'><span class='answer'>Revising IS audit plans to focus on IT changes introduced after the split<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='516077' \/><div class='watu-question-choice'><input type='radio' name='answer-125282[]' id='answer-id-516077' class='answer answer-195  answerof-125282' value='516077' \/>&nbsp;<label for='answer-id-516077' id='answer-label-516077' class=' answer label-195'><span class='answer'>Conducting an audit of newly introduced IT policies and procedures<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='516078' \/><div class='watu-question-choice'><input type='radio' name='answer-125282[]' id='answer-id-516078' class='answer answer-195  answerof-125282' value='516078' \/>&nbsp;<label for='answer-id-516078' id='answer-label-516078' class=' answer label-195'><span class='answer'>Developing a risk-based plan considering each entity\u2019s business processes<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType195' value='radio' class=''><\/div><div class='watu-question' id='question-196'><div class='question-content'><p><span class='watu_num'>196. <\/span>An IS auditor determines that an online retailer processing credit card information does not have a data classification process. The auditor\u2019s NEXT step should be to:<\/p>\n<\/div><input type='hidden' name='question_id[]' value='125283' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='516079' \/><div class='watu-question-choice'><input type='radio' name='answer-125283[]' id='answer-id-516079' class='answer answer-196  answerof-125283' value='516079' \/>&nbsp;<label for='answer-id-516079' id='answer-label-516079' class=' answer label-196'><span class='answer'>recommend encryption of all sensitive data at rest<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='516080' \/><div class='watu-question-choice'><input type='radio' name='answer-125283[]' id='answer-id-516080' class='answer answer-196  answerof-125283' value='516080' \/>&nbsp;<label for='answer-id-516080' id='answer-label-516080' class=' answer label-196'><span class='answer'>determine existing controls around sensitive data<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='516081' \/><div class='watu-question-choice'><input type='radio' name='answer-125283[]' id='answer-id-516081' class='answer answer-196  answerof-125283' value='516081' \/>&nbsp;<label for='answer-id-516081' id='answer-label-516081' class=' answer label-196'><span class='answer'>recommend the implementation of data loss prevention (DLP) tools<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='516082' \/><div class='watu-question-choice'><input type='radio' name='answer-125283[]' id='answer-id-516082' class='answer answer-196  answerof-125283' value='516082' \/>&nbsp;<label for='answer-id-516082' id='answer-label-516082' class=' answer label-196'><span class='answer'>inquire if there have been any data loss incidents<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType196' value='radio' class=''><\/div><div class='watu-question' id='question-197'><div class='question-content'><p><span class='watu_num'>197. <\/span>An IS auditor is reviewing an organization\u2019s network vulnerability scan results.<br \/>\n<br \/>Which of the following processes would the scan results MOST likely feed into?<\/p>\n<\/div><input type='hidden' name='question_id[]' value='125285' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='516083' \/><div class='watu-question-choice'><input type='radio' name='answer-125285[]' id='answer-id-516083' class='answer answer-197  answerof-125285' value='516083' \/>&nbsp;<label for='answer-id-516083' id='answer-label-516083' class=' answer label-197'><span class='answer'>Firewall maintenance<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='516085' \/><div class='watu-question-choice'><input type='radio' name='answer-125285[]' id='answer-id-516085' class='answer answer-197  answerof-125285' value='516085' \/>&nbsp;<label for='answer-id-516085' id='answer-label-516085' class=' answer label-197'><span class='answer'>Patch management<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='516087' \/><div class='watu-question-choice'><input type='radio' name='answer-125285[]' id='answer-id-516087' class='answer answer-197  answerof-125285' value='516087' \/>&nbsp;<label for='answer-id-516087' id='answer-label-516087' class=' answer label-197'><span class='answer'>Incident response<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='516089' \/><div class='watu-question-choice'><input type='radio' name='answer-125285[]' id='answer-id-516089' class='answer answer-197  answerof-125285' value='516089' \/>&nbsp;<label for='answer-id-516089' id='answer-label-516089' class=' answer label-197'><span class='answer'>Traffic management<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType197' value='radio' class=''><\/div><div class='watu-question' id='question-198'><div class='question-content'><p><span class='watu_num'>198. <\/span>A core business unit relies on an effective legacy system that does not meet the current security standards and threatens the enterprise network.<br \/>\n<br \/>Which of the following is the BEST course of action to address the situation?<\/p>\n<\/div><input type='hidden' name='question_id[]' value='125286' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='516091' \/><div class='watu-question-choice'><input type='radio' name='answer-125286[]' id='answer-id-516091' class='answer answer-198  answerof-125286' value='516091' \/>&nbsp;<label for='answer-id-516091' id='answer-label-516091' class=' answer label-198'><span class='answer'>Require that new systems that can meet the standards be implemented.<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='516093' \/><div class='watu-question-choice'><input type='radio' name='answer-125286[]' id='answer-id-516093' class='answer answer-198  answerof-125286' value='516093' \/>&nbsp;<label for='answer-id-516093' id='answer-label-516093' class=' answer label-198'><span class='answer'>Document the deficiencies in the risk register.<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='516095' \/><div class='watu-question-choice'><input type='radio' name='answer-125286[]' id='answer-id-516095' class='answer answer-198  answerof-125286' value='516095' \/>&nbsp;<label for='answer-id-516095' id='answer-label-516095' class=' answer label-198'><span class='answer'>Develop processes to compensate for the deficiencies.<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='516097' \/><div class='watu-question-choice'><input type='radio' name='answer-125286[]' id='answer-id-516097' class='answer answer-198  answerof-125286' value='516097' \/>&nbsp;<label for='answer-id-516097' id='answer-label-516097' class=' answer label-198'><span class='answer'>Disconnect the legacy system from the rest of the network.<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType198' value='radio' class=''><\/div><div class='watu-question' id='question-199'><div class='question-content'><p><span class='watu_num'>199. <\/span>Which of the following would BEST enable effective decision-making?<\/p>\n<\/div><input type='hidden' name='question_id[]' value='125288' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='516099' \/><div class='watu-question-choice'><input type='radio' name='answer-125288[]' id='answer-id-516099' class='answer answer-199  answerof-125288' value='516099' \/>&nbsp;<label for='answer-id-516099' id='answer-label-516099' class=' answer label-199'><span class='answer'>Annualized loss estimates determined from past security events.<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='516101' \/><div class='watu-question-choice'><input type='radio' name='answer-125288[]' id='answer-id-516101' class='answer answer-199  answerof-125288' value='516101' \/>&nbsp;<label for='answer-id-516101' id='answer-label-516101' class=' answer label-199'><span class='answer'>A universally applied list of generic threats impacts, and vulnerabilities<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='516103' \/><div class='watu-question-choice'><input type='radio' name='answer-125288[]' id='answer-id-516103' class='answer answer-199  answerof-125288' value='516103' \/>&nbsp;<label for='answer-id-516103' id='answer-label-516103' class=' answer label-199'><span class='answer'>Formalized acceptance of risk analysis by business management<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='516105' \/><div class='watu-question-choice'><input type='radio' name='answer-125288[]' id='answer-id-516105' class='answer answer-199  answerof-125288' value='516105' \/>&nbsp;<label for='answer-id-516105' id='answer-label-516105' class=' answer label-199'><span class='answer'>A consistent process to analyze new and historical information risk<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType199' value='radio' class=''><\/div><div class='watu-question' id='question-200'><div class='question-content'><p><span class='watu_num'>200. <\/span>A critical server for a hospital has been encrypted by ransomware. The hospital is unable to function effectively without this server.<br \/>\n<br \/>Which of the following would MOST effectively allow the hospital to avoid paying the ransom?<\/p>\n<\/div><input type='hidden' name='question_id[]' value='125290' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='516107' \/><div class='watu-question-choice'><input type='radio' name='answer-125290[]' id='answer-id-516107' class='answer answer-200  answerof-125290' value='516107' \/>&nbsp;<label for='answer-id-516107' id='answer-label-516107' class=' answer label-200'><span class='answer'>A continual server replication process<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='516109' \/><div class='watu-question-choice'><input type='radio' name='answer-125290[]' id='answer-id-516109' class='answer answer-200  answerof-125290' value='516109' \/>&nbsp;<label for='answer-id-516109' id='answer-label-516109' class=' answer label-200'><span class='answer'>A property tested offline backup system<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='516111' \/><div class='watu-question-choice'><input type='radio' name='answer-125290[]' id='answer-id-516111' class='answer answer-200  answerof-125290' value='516111' \/>&nbsp;<label for='answer-id-516111' id='answer-label-516111' class=' answer label-200'><span class='answer'>A property configured firewall<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='516113' \/><div class='watu-question-choice'><input type='radio' name='answer-125290[]' id='answer-id-516113' class='answer answer-200  answerof-125290' value='516113' \/>&nbsp;<label for='answer-id-516113' id='answer-label-516113' class=' answer label-200'><span class='answer'>Employee training on ransomware<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType200' value='radio' class=''><\/div><div class='watu-question' id='question-201'><div class='question-content'><p><span class='watu_num'>201. <\/span>Which of the following security processes will BEST prevent the exploitation of system vulnerabilities?<\/p>\n<\/div><input type='hidden' name='question_id[]' value='125292' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='516115' \/><div class='watu-question-choice'><input type='radio' name='answer-125292[]' id='answer-id-516115' class='answer answer-201  answerof-125292' value='516115' \/>&nbsp;<label for='answer-id-516115' id='answer-label-516115' class=' answer label-201'><span class='answer'>Patch management<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='516117' \/><div class='watu-question-choice'><input type='radio' name='answer-125292[]' id='answer-id-516117' class='answer answer-201  answerof-125292' value='516117' \/>&nbsp;<label for='answer-id-516117' id='answer-label-516117' class=' answer label-201'><span class='answer'>Log monitoring<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='516119' \/><div class='watu-question-choice'><input type='radio' name='answer-125292[]' id='answer-id-516119' class='answer answer-201  answerof-125292' value='516119' \/>&nbsp;<label for='answer-id-516119' id='answer-label-516119' class=' answer label-201'><span class='answer'>Antivirus software<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='516121' \/><div class='watu-question-choice'><input type='radio' name='answer-125292[]' id='answer-id-516121' class='answer answer-201  answerof-125292' value='516121' \/>&nbsp;<label for='answer-id-516121' id='answer-label-516121' class=' answer label-201'><span class='answer'>Intrusion detection<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType201' value='radio' class=''><\/div><div style='display:none' id='question-202'><br \/><div class='question-content'><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.dumpsbase.com\/freedumps\/wp-content\/plugins\/watu\/loading.gif\" width=\"16\" height=\"16\" alt=\"Loading ...\" title=\"Loading ...\" \/>&nbsp;Loading &#8230;<\/div><\/div><br \/>\n<input type=\"button\" name=\"action\" onclick=\"Watu.submitResult()\" id=\"action-button\" value=\"Submit\"  class=\"watu-submit-button\" \/>\n<input type=\"hidden\" name=\"no_ajax\" value=\"0\"><input type=\"hidden\" name=\"quiz_id\" value=\"2259\" \/>\n<input type=\"hidden\" id=\"watuStartTime\" name=\"start_time\" value=\"2026-07-15 07:42:40\" \/>\n<\/form>\n<\/div>\n<div id=\"watu-loading-result\" style=\"display:none;\">\n\t<p align=\"center\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.dumpsbase.com\/freedumps\/wp-content\/plugins\/watu\/loading.gif\" width=\"16\" height=\"16\" alt=\"Loading\" title=\"Loading\" \/><\/p>\n<\/div>\t\n<script type=\"text\/javascript\">\nvar exam_id=0;\nvar question_ids='';\nvar watuURL='';\njQuery(function($){\nquestion_ids = \"125088,125089,125090,125091,125092,125093,125094,125095,125096,125097,125098,125099,125100,125101,125102,125103,125104,125105,125106,125107,125108,125109,125110,125111,125112,125113,125114,125115,125116,125117,125118,125119,125120,125121,125122,125123,125124,125125,125126,125127,125128,125129,125130,125131,125132,125133,125134,125135,125136,125137,125138,125139,125140,125141,125142,125143,125144,125145,125146,125147,125148,125149,125150,125151,125152,125153,125154,125155,125156,125157,125158,125159,125160,125161,125162,125163,125164,125165,125166,125167,125168,125169,125170,125171,125172,125173,125174,125175,125176,125177,125178,125179,125180,125181,125182,125183,125184,125185,125186,125187,125188,125189,125190,125191,125192,125193,125194,125195,125196,125197,125198,125199,125200,125201,125202,125203,125204,125205,125206,125207,125208,125209,125210,125211,125212,125213,125214,125215,125216,125217,125218,125219,125220,125221,125222,125223,125224,125225,125226,125227,125228,125229,125230,125231,125232,125233,125234,125235,125236,125237,125238,125239,125240,125241,125242,125243,125244,125245,125246,125247,125248,125249,125250,125251,125252,125253,125254,125255,125256,125257,125258,125259,125260,125261,125262,125263,125264,125265,125266,125267,125268,125269,125270,125271,125272,125273,125274,125275,125276,125277,125278,125279,125280,125281,125282,125283,125285,125286,125288,125290,125292\";\nexam_id = 2259;\nWatu.exam_id = exam_id;\nWatu.qArr = question_ids.split(',');\nWatu.post_id = 5291;\nWatu.singlePage = '1';\nWatu.hAppID = \"0.10994800 1784101360\";\nwatuURL = \"https:\/\/www.dumpsbase.com\/freedumps\/wp-admin\/admin-ajax.php\";\nWatu.noAlertUnanswered = 0;\n});\n<\/script>\n","protected":false},"excerpt":{"rendered":"<p>Certified Information Systems Auditor CISA issued by ISACA validate your expertise and get the leverage you need to move up in your career. CISA is world-renowned as the standard of achievement for those who audit, control, monitor and assess an organization\u2019s information technology and business systems. To improve your preparation of ISACA CISA exam, we [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[430,429],"tags":[3595,3603,3599,8620,3598,8619],"class_list":["post-5291","post","type-post","status-publish","format-standard","hentry","category-cisa-certificaton","category-isaca","tag-cisa","tag-cisa-dumps","tag-cisa-dumps-questions","tag-cisa-exam-dumps","tag-cisa-exam-questions","tag-cisa-free-dumps"],"_links":{"self":[{"href":"https:\/\/www.dumpsbase.com\/freedumps\/wp-json\/wp\/v2\/posts\/5291","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dumpsbase.com\/freedumps\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dumpsbase.com\/freedumps\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.dumpsbase.com\/freedumps\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dumpsbase.com\/freedumps\/wp-json\/wp\/v2\/comments?post=5291"}],"version-history":[{"count":1,"href":"https:\/\/www.dumpsbase.com\/freedumps\/wp-json\/wp\/v2\/posts\/5291\/revisions"}],"predecessor-version":[{"id":5292,"href":"https:\/\/www.dumpsbase.com\/freedumps\/wp-json\/wp\/v2\/posts\/5291\/revisions\/5292"}],"wp:attachment":[{"href":"https:\/\/www.dumpsbase.com\/freedumps\/wp-json\/wp\/v2\/media?parent=5291"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dumpsbase.com\/freedumps\/wp-json\/wp\/v2\/categories?post=5291"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dumpsbase.com\/freedumps\/wp-json\/wp\/v2\/tags?post=5291"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}