{"id":4544,"date":"2019-10-22T07:52:52","date_gmt":"2019-10-22T07:52:52","guid":{"rendered":"https:\/\/www.dumpsbase.com\/freedumps\/?p=4544"},"modified":"2019-10-22T07:52:59","modified_gmt":"2019-10-22T07:52:59","slug":"board-certified-behavior-analyst-bcba-certification-dumps","status":"publish","type":"post","link":"https:\/\/www.dumpsbase.com\/freedumps\/board-certified-behavior-analyst-bcba-certification-dumps.html","title":{"rendered":"Board Certified Behavior Analyst BCBA Certification Dumps"},"content":{"rendered":"\n<p>The Board Certified Behavior Analyst\u00ae (BCBA\u00ae) is a graduate-level certification in behavior analysis. Professionals who are certified at the BCBA level are independent practitioners who provide behavior-analytic services. Board Certified Behavior Analyst BCBA Certification Dumps online is valid for passing your BCBA exam in the first attempt.\u00a0<\/p>\n<h2><span style=\"color: #0000ff;\">Board Certified Behavior Analyst BCBA Certification Dumps<\/span><\/h2>\n<script>\n  window.fbAsyncInit = function() {\n    FB.init({\n      appId            : '622169541470367',\n      autoLogAppEvents : true,\n      xfbml            : true,\n      version          : 'v3.1'\n    });\n  };\n\n  (function(d, s, id){\n     var js, fjs = d.getElementsByTagName(s)[0];\n     if (d.getElementById(id)) {return;}\n     js = d.createElement(s); js.id = id;\n     js.src = \"https:\/\/connect.facebook.net\/en_US\/sdk.js\";\n     fjs.parentNode.insertBefore(js, fjs);\n   }(document, 'script', 'facebook-jssdk'));\n<\/script><div id=\"watu_quiz\" class=\"quiz-area single-page-quiz\">\n<p><\/p><form action=\"\" method=\"post\" class=\"quiz-form \" id=\"quiz-1914\" >\n<div class='watu-question' id='question-1'><div class='question-content'><p><span class='watu_num'>1. <\/span>A behavior analyst is adhering to which underlying assumption of behavior analysis when she conducts several tests of her treatment before she writes it in a formal behavior program?<\/p>\n<\/div><input type='hidden' name='question_id[]' value='111298' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='459953' \/><div class='watu-question-choice'><input type='radio' name='answer-111298[]' id='answer-id-459953' class='answer answer-1  answerof-111298' value='459953' \/>&nbsp;<label for='answer-id-459953' id='answer-label-459953' class=' answer label-1'><span class='answer'>Determinism<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='459954' \/><div class='watu-question-choice'><input type='radio' name='answer-111298[]' id='answer-id-459954' class='answer answer-1  answerof-111298' value='459954' \/>&nbsp;<label for='answer-id-459954' id='answer-label-459954' class=' answer label-1'><span class='answer'>Law of parsimony<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='459955' \/><div class='watu-question-choice'><input type='radio' name='answer-111298[]' id='answer-id-459955' class='answer answer-1  answerof-111298' value='459955' \/>&nbsp;<label for='answer-id-459955' id='answer-label-459955' class=' answer label-1'><span class='answer'>Empiricism<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='459956' \/><div class='watu-question-choice'><input type='radio' name='answer-111298[]' id='answer-id-459956' class='answer answer-1  answerof-111298' value='459956' \/>&nbsp;<label for='answer-id-459956' id='answer-label-459956' class=' answer label-1'><span class='answer'>None of the above<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType1' value='radio' class=''><\/div><div class='watu-question' id='question-2'><div class='question-content'><p><span class='watu_num'>2. <\/span>Providing a complete description of one\u2019s procedures in a behavior analytic study of classroom management techniques is adhering to which dimensions of behavior analysis?<\/p>\n<\/div><input type='hidden' name='question_id[]' value='111299' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='459957' \/><div class='watu-question-choice'><input type='radio' name='answer-111299[]' id='answer-id-459957' class='answer answer-2  answerof-111299' value='459957' \/>&nbsp;<label for='answer-id-459957' id='answer-label-459957' class=' answer label-2'><span class='answer'>Conceptually systematic<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='459958' \/><div class='watu-question-choice'><input type='radio' name='answer-111299[]' id='answer-id-459958' class='answer answer-2  answerof-111299' value='459958' \/>&nbsp;<label for='answer-id-459958' id='answer-label-459958' class=' answer label-2'><span class='answer'>Applied<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='459959' \/><div class='watu-question-choice'><input type='radio' name='answer-111299[]' id='answer-id-459959' class='answer answer-2  answerof-111299' value='459959' \/>&nbsp;<label for='answer-id-459959' id='answer-label-459959' class=' answer label-2'><span class='answer'>Technological<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='459960' \/><div class='watu-question-choice'><input type='radio' name='answer-111299[]' id='answer-id-459960' class='answer answer-2  answerof-111299' value='459960' \/>&nbsp;<label for='answer-id-459960' id='answer-label-459960' class=' answer label-2'><span class='answer'>Analytic<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType2' value='radio' class=''><\/div><div class='watu-question' id='question-3'><div class='question-content'><p><span class='watu_num'>3. <\/span>Describing behavior program procedures in terms of the basic principles of behavior is adhering to which dimension of behavior analysis?<\/p>\n<\/div><input type='hidden' name='question_id[]' value='111300' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='459961' \/><div class='watu-question-choice'><input type='radio' name='answer-111300[]' id='answer-id-459961' class='answer answer-3  answerof-111300' value='459961' \/>&nbsp;<label for='answer-id-459961' id='answer-label-459961' class=' answer label-3'><span class='answer'>Conceptually systematic<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='459962' \/><div class='watu-question-choice'><input type='radio' name='answer-111300[]' id='answer-id-459962' class='answer answer-3  answerof-111300' value='459962' \/>&nbsp;<label for='answer-id-459962' id='answer-label-459962' class=' answer label-3'><span class='answer'>Applied<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='459963' \/><div class='watu-question-choice'><input type='radio' name='answer-111300[]' id='answer-id-459963' class='answer answer-3  answerof-111300' value='459963' \/>&nbsp;<label for='answer-id-459963' id='answer-label-459963' class=' answer label-3'><span class='answer'>Technological<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='459964' \/><div class='watu-question-choice'><input type='radio' name='answer-111300[]' id='answer-id-459964' class='answer answer-3  answerof-111300' value='459964' \/>&nbsp;<label for='answer-id-459964' id='answer-label-459964' class=' answer label-3'><span class='answer'>Analytic<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType3' value='radio' class=''><\/div><div class='watu-question' id='question-4'><div class='question-content'><p><span class='watu_num'>4. <\/span>When asked why a certain behavior happened, the behavior analyst states that the behavior \u201ccame out of nowhere.\u201d<br \/>\n<br \/>If the behavior analyst meant what he said, he is violating the assumption of __________________.<\/p>\n<\/div><input type='hidden' name='question_id[]' value='111301' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='459965' \/><div class='watu-question-choice'><input type='radio' name='answer-111301[]' id='answer-id-459965' class='answer answer-4  answerof-111301' value='459965' \/>&nbsp;<label for='answer-id-459965' id='answer-label-459965' class=' answer label-4'><span class='answer'>Philosophical doubt<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='459966' \/><div class='watu-question-choice'><input type='radio' name='answer-111301[]' id='answer-id-459966' class='answer answer-4  answerof-111301' value='459966' \/>&nbsp;<label for='answer-id-459966' id='answer-label-459966' class=' answer label-4'><span class='answer'>Determinism<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='459967' \/><div class='watu-question-choice'><input type='radio' name='answer-111301[]' id='answer-id-459967' class='answer answer-4  answerof-111301' value='459967' \/>&nbsp;<label for='answer-id-459967' id='answer-label-459967' class=' answer label-4'><span class='answer'>Technological<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='459968' \/><div class='watu-question-choice'><input type='radio' name='answer-111301[]' id='answer-id-459968' class='answer answer-4  answerof-111301' value='459968' \/>&nbsp;<label for='answer-id-459968' id='answer-label-459968' class=' answer label-4'><span class='answer'>Being conceptually systematic<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType4' value='radio' class=''><\/div><div class='watu-question' id='question-5'><div class='question-content'><p><span class='watu_num'>5. <\/span>Which of the following is NOT a dimension of applied behavior analysis?<\/p>\n<\/div><input type='hidden' name='question_id[]' value='111302' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='459969' \/><div class='watu-question-choice'><input type='radio' name='answer-111302[]' id='answer-id-459969' class='answer answer-5  answerof-111302' value='459969' \/>&nbsp;<label for='answer-id-459969' id='answer-label-459969' class=' answer label-5'><span class='answer'>Effective<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='459970' \/><div class='watu-question-choice'><input type='radio' name='answer-111302[]' id='answer-id-459970' class='answer answer-5  answerof-111302' value='459970' \/>&nbsp;<label for='answer-id-459970' id='answer-label-459970' class=' answer label-5'><span class='answer'>Technological<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='459971' \/><div class='watu-question-choice'><input type='radio' name='answer-111302[]' id='answer-id-459971' class='answer answer-5  answerof-111302' value='459971' \/>&nbsp;<label for='answer-id-459971' id='answer-label-459971' class=' answer label-5'><span class='answer'>Applied<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='459972' \/><div class='watu-question-choice'><input type='radio' name='answer-111302[]' id='answer-id-459972' class='answer answer-5  answerof-111302' value='459972' \/>&nbsp;<label for='answer-id-459972' id='answer-label-459972' class=' answer label-5'><span class='answer'>Empirical<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType5' value='radio' class=''><\/div><div class='watu-question' id='question-6'><div class='question-content'><p><span class='watu_num'>6. <\/span>A behavior analyst is measuring the time it takes for a client to say, \u201cYou\u2019re welcome\u201d after the staff says, \u201cThank you.\u201d The behavior analyst is measuring __________________.<\/p>\n<\/div><input type='hidden' name='question_id[]' value='111303' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='459973' \/><div class='watu-question-choice'><input type='radio' name='answer-111303[]' id='answer-id-459973' class='answer answer-6  answerof-111303' value='459973' \/>&nbsp;<label for='answer-id-459973' id='answer-label-459973' class=' answer label-6'><span class='answer'>Frequency<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='459974' \/><div class='watu-question-choice'><input type='radio' name='answer-111303[]' id='answer-id-459974' class='answer answer-6  answerof-111303' value='459974' \/>&nbsp;<label for='answer-id-459974' id='answer-label-459974' class=' answer label-6'><span class='answer'>Duration<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='459975' \/><div class='watu-question-choice'><input type='radio' name='answer-111303[]' id='answer-id-459975' class='answer answer-6  answerof-111303' value='459975' \/>&nbsp;<label for='answer-id-459975' id='answer-label-459975' class=' answer label-6'><span class='answer'>Inter-response time<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='459976' \/><div class='watu-question-choice'><input type='radio' name='answer-111303[]' id='answer-id-459976' class='answer answer-6  answerof-111303' value='459976' \/>&nbsp;<label for='answer-id-459976' id='answer-label-459976' class=' answer label-6'><span class='answer'>Latency<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType6' value='radio' class=''><\/div><div class='watu-question' id='question-7'><div class='question-content'><p><span class='watu_num'>7. <\/span>Which measure would probably be the best measure for crying?<\/p>\n<\/div><input type='hidden' name='question_id[]' value='111304' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='459977' \/><div class='watu-question-choice'><input type='radio' name='answer-111304[]' id='answer-id-459977' class='answer answer-7  answerof-111304' value='459977' \/>&nbsp;<label for='answer-id-459977' id='answer-label-459977' class=' answer label-7'><span class='answer'>Frequency<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='459978' \/><div class='watu-question-choice'><input type='radio' name='answer-111304[]' id='answer-id-459978' class='answer answer-7  answerof-111304' value='459978' \/>&nbsp;<label for='answer-id-459978' id='answer-label-459978' class=' answer label-7'><span class='answer'>Duration<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='459979' \/><div class='watu-question-choice'><input type='radio' name='answer-111304[]' id='answer-id-459979' class='answer answer-7  answerof-111304' value='459979' \/>&nbsp;<label for='answer-id-459979' id='answer-label-459979' class=' answer label-7'><span class='answer'>Percentage<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='459980' \/><div class='watu-question-choice'><input type='radio' name='answer-111304[]' id='answer-id-459980' class='answer answer-7  answerof-111304' value='459980' \/>&nbsp;<label for='answer-id-459980' id='answer-label-459980' class=' answer label-7'><span class='answer'>Latency<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType7' value='radio' class=''><\/div><div class='watu-question' id='question-8'><div class='question-content'><p><span class='watu_num'>8. <\/span>If a behavior analyst states, \u201cIt took four attempts, but Johnny completed the puzzle,\u201d she is using which measure?<\/p>\n<\/div><input type='hidden' name='question_id[]' value='111305' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='459981' \/><div class='watu-question-choice'><input type='radio' name='answer-111305[]' id='answer-id-459981' class='answer answer-8  answerof-111305' value='459981' \/>&nbsp;<label for='answer-id-459981' id='answer-label-459981' class=' answer label-8'><span class='answer'>Whole interval<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='459982' \/><div class='watu-question-choice'><input type='radio' name='answer-111305[]' id='answer-id-459982' class='answer answer-8  answerof-111305' value='459982' \/>&nbsp;<label for='answer-id-459982' id='answer-label-459982' class=' answer label-8'><span class='answer'>Percent of occurrence<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='459983' \/><div class='watu-question-choice'><input type='radio' name='answer-111305[]' id='answer-id-459983' class='answer answer-8  answerof-111305' value='459983' \/>&nbsp;<label for='answer-id-459983' id='answer-label-459983' class=' answer label-8'><span class='answer'>Trials to criterion<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='459984' \/><div class='watu-question-choice'><input type='radio' name='answer-111305[]' id='answer-id-459984' class='answer answer-8  answerof-111305' value='459984' \/>&nbsp;<label for='answer-id-459984' id='answer-label-459984' class=' answer label-8'><span class='answer'>Frequency<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType8' value='radio' class=''><\/div><div class='watu-question' id='question-9'><div class='question-content'><p><span class='watu_num'>9. <\/span>Jody had an access-maintained tantrum for 14 minutes and it started 3 seconds after she was told, \u201cNo.\u201d It had been 2 days since the previous tantrum.<br \/>\n<br \/>The latency is:<\/p>\n<\/div><input type='hidden' name='question_id[]' value='111306' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='459985' \/><div class='watu-question-choice'><input type='radio' name='answer-111306[]' id='answer-id-459985' class='answer answer-9  answerof-111306' value='459985' \/>&nbsp;<label for='answer-id-459985' id='answer-label-459985' class=' answer label-9'><span class='answer'>Unknown<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='459986' \/><div class='watu-question-choice'><input type='radio' name='answer-111306[]' id='answer-id-459986' class='answer answer-9  answerof-111306' value='459986' \/>&nbsp;<label for='answer-id-459986' id='answer-label-459986' class=' answer label-9'><span class='answer'>2 days<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='459987' \/><div class='watu-question-choice'><input type='radio' name='answer-111306[]' id='answer-id-459987' class='answer answer-9  answerof-111306' value='459987' \/>&nbsp;<label for='answer-id-459987' id='answer-label-459987' class=' answer label-9'><span class='answer'>14 minutes<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='459988' \/><div class='watu-question-choice'><input type='radio' name='answer-111306[]' id='answer-id-459988' class='answer answer-9  answerof-111306' value='459988' \/>&nbsp;<label for='answer-id-459988' id='answer-label-459988' class=' answer label-9'><span class='answer'>3 seconds<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType9' value='radio' class=''><\/div><div class='watu-question' id='question-10'><div class='question-content'><p><span class='watu_num'>10. <\/span>Manipulating a students chair in a classroom setting to avoid distraction fro the window is an example of a manipulation of a<\/p>\n<\/div><input type='hidden' name='question_id[]' value='111307' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='459989' \/><div class='watu-question-choice'><input type='radio' name='answer-111307[]' id='answer-id-459989' class='answer answer-10  answerof-111307' value='459989' \/>&nbsp;<label for='answer-id-459989' id='answer-label-459989' class=' answer label-10'><span class='answer'>Context variable<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='459990' \/><div class='watu-question-choice'><input type='radio' name='answer-111307[]' id='answer-id-459990' class='answer answer-10  answerof-111307' value='459990' \/>&nbsp;<label for='answer-id-459990' id='answer-label-459990' class=' answer label-10'><span class='answer'>Antecedent variable<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='459991' \/><div class='watu-question-choice'><input type='radio' name='answer-111307[]' id='answer-id-459991' class='answer answer-10  answerof-111307' value='459991' \/>&nbsp;<label for='answer-id-459991' id='answer-label-459991' class=' answer label-10'><span class='answer'>Confounding variable<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='459992' \/><div class='watu-question-choice'><input type='radio' name='answer-111307[]' id='answer-id-459992' class='answer answer-10  answerof-111307' value='459992' \/>&nbsp;<label for='answer-id-459992' id='answer-label-459992' class=' answer label-10'><span class='answer'>Ecological variable<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType10' value='radio' class=''><\/div><div class='watu-question' id='question-11'><div class='question-content'><p><span class='watu_num'>11. <\/span>The number of time intervals in a specific period of time during which a response occurs continuously for an entire interval is which measure?<\/p>\n<\/div><input type='hidden' name='question_id[]' value='111308' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='459993' \/><div class='watu-question-choice'><input type='radio' name='answer-111308[]' id='answer-id-459993' class='answer answer-11  answerof-111308' value='459993' \/>&nbsp;<label for='answer-id-459993' id='answer-label-459993' class=' answer label-11'><span class='answer'>Partial-interval recording<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='459994' \/><div class='watu-question-choice'><input type='radio' name='answer-111308[]' id='answer-id-459994' class='answer answer-11  answerof-111308' value='459994' \/>&nbsp;<label for='answer-id-459994' id='answer-label-459994' class=' answer label-11'><span class='answer'>Whole-interval recording<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='459995' \/><div class='watu-question-choice'><input type='radio' name='answer-111308[]' id='answer-id-459995' class='answer answer-11  answerof-111308' value='459995' \/>&nbsp;<label for='answer-id-459995' id='answer-label-459995' class=' answer label-11'><span class='answer'>Momentary time sampling<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='459996' \/><div class='watu-question-choice'><input type='radio' name='answer-111308[]' id='answer-id-459996' class='answer answer-11  answerof-111308' value='459996' \/>&nbsp;<label for='answer-id-459996' id='answer-label-459996' class=' answer label-11'><span class='answer'>Percentage of occurrence<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType11' value='radio' class=''><\/div><div class='watu-question' id='question-12'><div class='question-content'><p><span class='watu_num'>12. <\/span>In behavior analysis, the __________________ is usually __________________.<\/p>\n<\/div><input type='hidden' name='question_id[]' value='111309' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='459997' \/><div class='watu-question-choice'><input type='radio' name='answer-111309[]' id='answer-id-459997' class='answer answer-12  answerof-111309' value='459997' \/>&nbsp;<label for='answer-id-459997' id='answer-label-459997' class=' answer label-12'><span class='answer'>Independent variable; a measure of behavior<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='459998' \/><div class='watu-question-choice'><input type='radio' name='answer-111309[]' id='answer-id-459998' class='answer answer-12  answerof-111309' value='459998' \/>&nbsp;<label for='answer-id-459998' id='answer-label-459998' class=' answer label-12'><span class='answer'>Dependent variable; a measure of behavior<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='459999' \/><div class='watu-question-choice'><input type='radio' name='answer-111309[]' id='answer-id-459999' class='answer answer-12  answerof-111309' value='459999' \/>&nbsp;<label for='answer-id-459999' id='answer-label-459999' class=' answer label-12'><span class='answer'>Baseline measure; unrelated to the behavior<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460000' \/><div class='watu-question-choice'><input type='radio' name='answer-111309[]' id='answer-id-460000' class='answer answer-12  answerof-111309' value='460000' \/>&nbsp;<label for='answer-id-460000' id='answer-label-460000' class=' answer label-12'><span class='answer'>Independent variable; implemented before the baseline measure<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType12' value='radio' class=''><\/div><div class='watu-question' id='question-13'><div class='question-content'><p><span class='watu_num'>13. <\/span>An experimenter examines the effects of three types of prompts on compliance in a developmentally disabled person.<br \/>\n<br \/>In this experiment, what is the independent variable?<\/p>\n<\/div><input type='hidden' name='question_id[]' value='111310' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460001' \/><div class='watu-question-choice'><input type='radio' name='answer-111310[]' id='answer-id-460001' class='answer answer-13  answerof-111310' value='460001' \/>&nbsp;<label for='answer-id-460001' id='answer-label-460001' class=' answer label-13'><span class='answer'>The location of the environment<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460002' \/><div class='watu-question-choice'><input type='radio' name='answer-111310[]' id='answer-id-460002' class='answer answer-13  answerof-111310' value='460002' \/>&nbsp;<label for='answer-id-460002' id='answer-label-460002' class=' answer label-13'><span class='answer'>The three types of prompts<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460003' \/><div class='watu-question-choice'><input type='radio' name='answer-111310[]' id='answer-id-460003' class='answer answer-13  answerof-111310' value='460003' \/>&nbsp;<label for='answer-id-460003' id='answer-label-460003' class=' answer label-13'><span class='answer'>The level of compliance<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460004' \/><div class='watu-question-choice'><input type='radio' name='answer-111310[]' id='answer-id-460004' class='answer answer-13  answerof-111310' value='460004' \/>&nbsp;<label for='answer-id-460004' id='answer-label-460004' class=' answer label-13'><span class='answer'>The diagnosis of the individual<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType13' value='radio' class=''><\/div><div class='watu-question' id='question-14'><div class='question-content'><p><span class='watu_num'>14. <\/span>An experimenter examines the level of noise in a school bus full of children under the following conditions: baseline, rock music, baseline, classical music.<br \/>\n<br \/>In this experiment, the dependent variable is:<\/p>\n<\/div><input type='hidden' name='question_id[]' value='111311' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460005' \/><div class='watu-question-choice'><input type='radio' name='answer-111311[]' id='answer-id-460005' class='answer answer-14  answerof-111311' value='460005' \/>&nbsp;<label for='answer-id-460005' id='answer-label-460005' class=' answer label-14'><span class='answer'>Time<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460006' \/><div class='watu-question-choice'><input type='radio' name='answer-111311[]' id='answer-id-460006' class='answer answer-14  answerof-111311' value='460006' \/>&nbsp;<label for='answer-id-460006' id='answer-label-460006' class=' answer label-14'><span class='answer'>The number of children on the bus<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460007' \/><div class='watu-question-choice'><input type='radio' name='answer-111311[]' id='answer-id-460007' class='answer answer-14  answerof-111311' value='460007' \/>&nbsp;<label for='answer-id-460007' id='answer-label-460007' class=' answer label-14'><span class='answer'>The level of noise<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460008' \/><div class='watu-question-choice'><input type='radio' name='answer-111311[]' id='answer-id-460008' class='answer answer-14  answerof-111311' value='460008' \/>&nbsp;<label for='answer-id-460008' id='answer-label-460008' class=' answer label-14'><span class='answer'>The type of music<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType14' value='radio' class=''><\/div><div class='watu-question' id='question-15'><div class='question-content'><p><span class='watu_num'>15. <\/span>A person is asked to make his bed. His caregiver checks 30 minutes later and the bed was made. No one else was present during that time. The caregiver records that the client made his bed even though he did not observe the behavior directly.<br \/>\n<br \/>The data collection method used is:<\/p>\n<\/div><input type='hidden' name='question_id[]' value='111312' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460009' \/><div class='watu-question-choice'><input type='radio' name='answer-111312[]' id='answer-id-460009' class='answer answer-15  answerof-111312' value='460009' \/>&nbsp;<label for='answer-id-460009' id='answer-label-460009' class=' answer label-15'><span class='answer'>Duration recording<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460010' \/><div class='watu-question-choice'><input type='radio' name='answer-111312[]' id='answer-id-460010' class='answer answer-15  answerof-111312' value='460010' \/>&nbsp;<label for='answer-id-460010' id='answer-label-460010' class=' answer label-15'><span class='answer'>Whole-interval recording<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460011' \/><div class='watu-question-choice'><input type='radio' name='answer-111312[]' id='answer-id-460011' class='answer answer-15  answerof-111312' value='460011' \/>&nbsp;<label for='answer-id-460011' id='answer-label-460011' class=' answer label-15'><span class='answer'>Latency recording<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460012' \/><div class='watu-question-choice'><input type='radio' name='answer-111312[]' id='answer-id-460012' class='answer answer-15  answerof-111312' value='460012' \/>&nbsp;<label for='answer-id-460012' id='answer-label-460012' class=' answer label-15'><span class='answer'>Permanent product recording<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType15' value='radio' class=''><\/div><div class='watu-question' id='question-16'><div class='question-content'><p><span class='watu_num'>16. <\/span>Talking out in class results in a child losing a star on his star chart. The loss of a star appears to be an attempt to implement a(n) __________________ procedure.<\/p>\n<\/div><input type='hidden' name='question_id[]' value='111313' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460013' \/><div class='watu-question-choice'><input type='radio' name='answer-111313[]' id='answer-id-460013' class='answer answer-16  answerof-111313' value='460013' \/>&nbsp;<label for='answer-id-460013' id='answer-label-460013' class=' answer label-16'><span class='answer'>Response cost<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460014' \/><div class='watu-question-choice'><input type='radio' name='answer-111313[]' id='answer-id-460014' class='answer answer-16  answerof-111313' value='460014' \/>&nbsp;<label for='answer-id-460014' id='answer-label-460014' class=' answer label-16'><span class='answer'>Negative reinforcement<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460015' \/><div class='watu-question-choice'><input type='radio' name='answer-111313[]' id='answer-id-460015' class='answer answer-16  answerof-111313' value='460015' \/>&nbsp;<label for='answer-id-460015' id='answer-label-460015' class=' answer label-16'><span class='answer'>Aversion therapy<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460016' \/><div class='watu-question-choice'><input type='radio' name='answer-111313[]' id='answer-id-460016' class='answer answer-16  answerof-111313' value='460016' \/>&nbsp;<label for='answer-id-460016' id='answer-label-460016' class=' answer label-16'><span class='answer'>Errorless learning<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType16' value='radio' class=''><\/div><div class='watu-question' id='question-17'><div class='question-content'><p><span class='watu_num'>17. <\/span>A DRI schedule designed to decrease the frequency of running around class and tapping other children on the head involves:<\/p>\n<\/div><input type='hidden' name='question_id[]' value='111314' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460017' \/><div class='watu-question-choice'><input type='radio' name='answer-111314[]' id='answer-id-460017' class='answer answer-17  answerof-111314' value='460017' \/>&nbsp;<label for='answer-id-460017' id='answer-label-460017' class=' answer label-17'><span class='answer'>Arranging for the child to earn a reinforcer in the absence of these behaviors<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460018' \/><div class='watu-question-choice'><input type='radio' name='answer-111314[]' id='answer-id-460018' class='answer answer-17  answerof-111314' value='460018' \/>&nbsp;<label for='answer-id-460018' id='answer-label-460018' class=' answer label-17'><span class='answer'>Providing a reinforcer contingent on being on task and sitting quietly in his seat<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460019' \/><div class='watu-question-choice'><input type='radio' name='answer-111314[]' id='answer-id-460019' class='answer answer-17  answerof-111314' value='460019' \/>&nbsp;<label for='answer-id-460019' id='answer-label-460019' class=' answer label-17'><span class='answer'>Changing the seating arrangement of the class<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460020' \/><div class='watu-question-choice'><input type='radio' name='answer-111314[]' id='answer-id-460020' class='answer answer-17  answerof-111314' value='460020' \/>&nbsp;<label for='answer-id-460020' id='answer-label-460020' class=' answer label-17'><span class='answer'>Ensuring the child had breakfast that morning<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType17' value='radio' class=''><\/div><div class='watu-question' id='question-18'><div class='question-content'><p><span class='watu_num'>18. <\/span>Gradually transferring stimulus control from prompts to other discriminative stimuli is a process called __________________.<\/p>\n<\/div><input type='hidden' name='question_id[]' value='111315' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460021' \/><div class='watu-question-choice'><input type='radio' name='answer-111315[]' id='answer-id-460021' class='answer answer-18  answerof-111315' value='460021' \/>&nbsp;<label for='answer-id-460021' id='answer-label-460021' class=' answer label-18'><span class='answer'>Shaping<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460022' \/><div class='watu-question-choice'><input type='radio' name='answer-111315[]' id='answer-id-460022' class='answer answer-18  answerof-111315' value='460022' \/>&nbsp;<label for='answer-id-460022' id='answer-label-460022' class=' answer label-18'><span class='answer'>Modeling<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460023' \/><div class='watu-question-choice'><input type='radio' name='answer-111315[]' id='answer-id-460023' class='answer answer-18  answerof-111315' value='460023' \/>&nbsp;<label for='answer-id-460023' id='answer-label-460023' class=' answer label-18'><span class='answer'>Maintenance<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460024' \/><div class='watu-question-choice'><input type='radio' name='answer-111315[]' id='answer-id-460024' class='answer answer-18  answerof-111315' value='460024' \/>&nbsp;<label for='answer-id-460024' id='answer-label-460024' class=' answer label-18'><span class='answer'>Fading<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType18' value='radio' class=''><\/div><div class='watu-question' id='question-19'><div class='question-content'><p><span class='watu_num'>19. <\/span>Requiring a student who disrupts the class by throwing papers and tipping over chairs to clean the mess up and then clean the rest of the room by sweeping and cleaning desktops is a(n) __________________ procedure.<\/p>\n<\/div><input type='hidden' name='question_id[]' value='111316' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460025' \/><div class='watu-question-choice'><input type='radio' name='answer-111316[]' id='answer-id-460025' class='answer answer-19  answerof-111316' value='460025' \/>&nbsp;<label for='answer-id-460025' id='answer-label-460025' class=' answer label-19'><span class='answer'>Negative reinforcement<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460026' \/><div class='watu-question-choice'><input type='radio' name='answer-111316[]' id='answer-id-460026' class='answer answer-19  answerof-111316' value='460026' \/>&nbsp;<label for='answer-id-460026' id='answer-label-460026' class=' answer label-19'><span class='answer'>Negative punishment<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460027' \/><div class='watu-question-choice'><input type='radio' name='answer-111316[]' id='answer-id-460027' class='answer answer-19  answerof-111316' value='460027' \/>&nbsp;<label for='answer-id-460027' id='answer-label-460027' class=' answer label-19'><span class='answer'>Positive punishment<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460028' \/><div class='watu-question-choice'><input type='radio' name='answer-111316[]' id='answer-id-460028' class='answer answer-19  answerof-111316' value='460028' \/>&nbsp;<label for='answer-id-460028' id='answer-label-460028' class=' answer label-19'><span class='answer'>Extinction<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType19' value='radio' class=''><\/div><div class='watu-question' id='question-20'><div class='question-content'><p><span class='watu_num'>20. <\/span>The specific, or technical, name for the type of procedure used in the above question is:<\/p>\n<\/div><input type='hidden' name='question_id[]' value='111317' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460029' \/><div class='watu-question-choice'><input type='radio' name='answer-111317[]' id='answer-id-460029' class='answer answer-20  answerof-111317' value='460029' \/>&nbsp;<label for='answer-id-460029' id='answer-label-460029' class=' answer label-20'><span class='answer'>Restitution<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460030' \/><div class='watu-question-choice'><input type='radio' name='answer-111317[]' id='answer-id-460030' class='answer answer-20  answerof-111317' value='460030' \/>&nbsp;<label for='answer-id-460030' id='answer-label-460030' class=' answer label-20'><span class='answer'>Stimulus shaping<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460031' \/><div class='watu-question-choice'><input type='radio' name='answer-111317[]' id='answer-id-460031' class='answer answer-20  answerof-111317' value='460031' \/>&nbsp;<label for='answer-id-460031' id='answer-label-460031' class=' answer label-20'><span class='answer'>Over-correction<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460032' \/><div class='watu-question-choice'><input type='radio' name='answer-111317[]' id='answer-id-460032' class='answer answer-20  answerof-111317' value='460032' \/>&nbsp;<label for='answer-id-460032' id='answer-label-460032' class=' answer label-20'><span class='answer'>Corporal punishment<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType20' value='radio' class=''><\/div><div class='watu-question' id='question-21'><div class='question-content'><p><span class='watu_num'>21. <\/span>Teaching a child to match printed words to pictures, then pictures to the actual objects, and then testing to determine if the child can now match printed words to the actual objects is known as:<\/p>\n<\/div><input type='hidden' name='question_id[]' value='111318' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460033' \/><div class='watu-question-choice'><input type='radio' name='answer-111318[]' id='answer-id-460033' class='answer answer-21  answerof-111318' value='460033' \/>&nbsp;<label for='answer-id-460033' id='answer-label-460033' class=' answer label-21'><span class='answer'>PECS<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460034' \/><div class='watu-question-choice'><input type='radio' name='answer-111318[]' id='answer-id-460034' class='answer answer-21  answerof-111318' value='460034' \/>&nbsp;<label for='answer-id-460034' id='answer-label-460034' class=' answer label-21'><span class='answer'>Discrete trial training<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460035' \/><div class='watu-question-choice'><input type='radio' name='answer-111318[]' id='answer-id-460035' class='answer answer-21  answerof-111318' value='460035' \/>&nbsp;<label for='answer-id-460035' id='answer-label-460035' class=' answer label-21'><span class='answer'>Verbal behavior training<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460036' \/><div class='watu-question-choice'><input type='radio' name='answer-111318[]' id='answer-id-460036' class='answer answer-21  answerof-111318' value='460036' \/>&nbsp;<label for='answer-id-460036' id='answer-label-460036' class=' answer label-21'><span class='answer'>Stimulus equivalence<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType21' value='radio' class=''><\/div><div class='watu-question' id='question-22'><div class='question-content'><p><span class='watu_num'>22. <\/span>Placing a request that a child is least likely to perform at the end of a series of requests that the child is most likely to perform is a phenomenon known as:<\/p>\n<\/div><input type='hidden' name='question_id[]' value='111319' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460037' \/><div class='watu-question-choice'><input type='radio' name='answer-111319[]' id='answer-id-460037' class='answer answer-22  answerof-111319' value='460037' \/>&nbsp;<label for='answer-id-460037' id='answer-label-460037' class=' answer label-22'><span class='answer'>The Premack principle<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460038' \/><div class='watu-question-choice'><input type='radio' name='answer-111319[]' id='answer-id-460038' class='answer answer-22  answerof-111319' value='460038' \/>&nbsp;<label for='answer-id-460038' id='answer-label-460038' class=' answer label-22'><span class='answer'>High-probability request sequence<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460039' \/><div class='watu-question-choice'><input type='radio' name='answer-111319[]' id='answer-id-460039' class='answer answer-22  answerof-111319' value='460039' \/>&nbsp;<label for='answer-id-460039' id='answer-label-460039' class=' answer label-22'><span class='answer'>Errorless learning<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460040' \/><div class='watu-question-choice'><input type='radio' name='answer-111319[]' id='answer-id-460040' class='answer answer-22  answerof-111319' value='460040' \/>&nbsp;<label for='answer-id-460040' id='answer-label-460040' class=' answer label-22'><span class='answer'>Mediated transfer<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType22' value='radio' class=''><\/div><div class='watu-question' id='question-23'><div class='question-content'><p><span class='watu_num'>23. <\/span>The purpose of conducting a functional assessment is to:<\/p>\n<\/div><input type='hidden' name='question_id[]' value='111320' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460041' \/><div class='watu-question-choice'><input type='radio' name='answer-111320[]' id='answer-id-460041' class='answer answer-23  answerof-111320' value='460041' \/>&nbsp;<label for='answer-id-460041' id='answer-label-460041' class=' answer label-23'><span class='answer'>Complete a functional analysis<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460042' \/><div class='watu-question-choice'><input type='radio' name='answer-111320[]' id='answer-id-460042' class='answer answer-23  answerof-111320' value='460042' \/>&nbsp;<label for='answer-id-460042' id='answer-label-460042' class=' answer label-23'><span class='answer'>Manipulate variables that affect behavior<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460043' \/><div class='watu-question-choice'><input type='radio' name='answer-111320[]' id='answer-id-460043' class='answer answer-23  answerof-111320' value='460043' \/>&nbsp;<label for='answer-id-460043' id='answer-label-460043' class=' answer label-23'><span class='answer'>Obtain information from which to create a hypothesis statement<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460044' \/><div class='watu-question-choice'><input type='radio' name='answer-111320[]' id='answer-id-460044' class='answer answer-23  answerof-111320' value='460044' \/>&nbsp;<label for='answer-id-460044' id='answer-label-460044' class=' answer label-23'><span class='answer'>Determine how effective a treatment intervention is<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType23' value='radio' class=''><\/div><div class='watu-question' id='question-24'><div class='question-content'><p><span class='watu_num'>24. <\/span>Which is the best definition of a behavior function?<\/p>\n<\/div><input type='hidden' name='question_id[]' value='111322' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460047' \/><div class='watu-question-choice'><input type='radio' name='answer-111322[]' id='answer-id-460047' class='answer answer-24  answerof-111322' value='460047' \/>&nbsp;<label for='answer-id-460047' id='answer-label-460047' class=' answer label-24'><span class='answer'>What the teacher believes the reinforcer should be for the child<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460049' \/><div class='watu-question-choice'><input type='radio' name='answer-111322[]' id='answer-id-460049' class='answer answer-24  answerof-111322' value='460049' \/>&nbsp;<label for='answer-id-460049' id='answer-label-460049' class=' answer label-24'><span class='answer'>How the behavior controls antecedents<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460051' \/><div class='watu-question-choice'><input type='radio' name='answer-111322[]' id='answer-id-460051' class='answer answer-24  answerof-111322' value='460051' \/>&nbsp;<label for='answer-id-460051' id='answer-label-460051' class=' answer label-24'><span class='answer'>How the child feels concerning his or her own behavior<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460052' \/><div class='watu-question-choice'><input type='radio' name='answer-111322[]' id='answer-id-460052' class='answer answer-24  answerof-111322' value='460052' \/>&nbsp;<label for='answer-id-460052' id='answer-label-460052' class=' answer label-24'><span class='answer'>The reinforcers that maintain a behavior<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType24' value='radio' class=''><\/div><div class='watu-question' id='question-25'><div class='question-content'><p><span class='watu_num'>25. <\/span>Alternative appropriate behaviors that serve the same function for an individual:<\/p>\n<\/div><input type='hidden' name='question_id[]' value='111324' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460055' \/><div class='watu-question-choice'><input type='radio' name='answer-111324[]' id='answer-id-460055' class='answer answer-25  answerof-111324' value='460055' \/>&nbsp;<label for='answer-id-460055' id='answer-label-460055' class=' answer label-25'><span class='answer'>Always involve skills the individual already possesses<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460057' \/><div class='watu-question-choice'><input type='radio' name='answer-111324[]' id='answer-id-460057' class='answer answer-25  answerof-111324' value='460057' \/>&nbsp;<label for='answer-id-460057' id='answer-label-460057' class=' answer label-25'><span class='answer'>Produces the same reinforcer for the individual<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460059' \/><div class='watu-question-choice'><input type='radio' name='answer-111324[]' id='answer-id-460059' class='answer answer-25  answerof-111324' value='460059' \/>&nbsp;<label for='answer-id-460059' id='answer-label-460059' class=' answer label-25'><span class='answer'>Have the same topography as the problem behavior<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460060' \/><div class='watu-question-choice'><input type='radio' name='answer-111324[]' id='answer-id-460060' class='answer answer-25  answerof-111324' value='460060' \/>&nbsp;<label for='answer-id-460060' id='answer-label-460060' class=' answer label-25'><span class='answer'>Always requires the same amount of response effort as the problem behavior<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType25' value='radio' class=''><\/div><div class='watu-question' id='question-26'><div class='question-content'><p><span class='watu_num'>26. <\/span>A __________________ is derived from a descriptive analysis.<\/p>\n<\/div><input type='hidden' name='question_id[]' value='111326' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460063' \/><div class='watu-question-choice'><input type='radio' name='answer-111326[]' id='answer-id-460063' class='answer answer-26  answerof-111326' value='460063' \/>&nbsp;<label for='answer-id-460063' id='answer-label-460063' class=' answer label-26'><span class='answer'>Hypothesis<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460065' \/><div class='watu-question-choice'><input type='radio' name='answer-111326[]' id='answer-id-460065' class='answer answer-26  answerof-111326' value='460065' \/>&nbsp;<label for='answer-id-460065' id='answer-label-460065' class=' answer label-26'><span class='answer'>Statement of causation<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460067' \/><div class='watu-question-choice'><input type='radio' name='answer-111326[]' id='answer-id-460067' class='answer answer-26  answerof-111326' value='460067' \/>&nbsp;<label for='answer-id-460067' id='answer-label-460067' class=' answer label-26'><span class='answer'>Data-driven conclusion<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460068' \/><div class='watu-question-choice'><input type='radio' name='answer-111326[]' id='answer-id-460068' class='answer answer-26  answerof-111326' value='460068' \/>&nbsp;<label for='answer-id-460068' id='answer-label-460068' class=' answer label-26'><span class='answer'>Hypotenuse<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType26' value='radio' class=''><\/div><div class='watu-question' id='question-27'><div class='question-content'><p><span class='watu_num'>27. <\/span>When an observer notes everything the client does or says as well as events before and after the episode of behavior, he or she is using:<\/p>\n<\/div><input type='hidden' name='question_id[]' value='111328' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460071' \/><div class='watu-question-choice'><input type='radio' name='answer-111328[]' id='answer-id-460071' class='answer answer-27  answerof-111328' value='460071' \/>&nbsp;<label for='answer-id-460071' id='answer-label-460071' class=' answer label-27'><span class='answer'>Duration recording<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460073' \/><div class='watu-question-choice'><input type='radio' name='answer-111328[]' id='answer-id-460073' class='answer answer-27  answerof-111328' value='460073' \/>&nbsp;<label for='answer-id-460073' id='answer-label-460073' class=' answer label-27'><span class='answer'>Permanent product recording<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460075' \/><div class='watu-question-choice'><input type='radio' name='answer-111328[]' id='answer-id-460075' class='answer answer-27  answerof-111328' value='460075' \/>&nbsp;<label for='answer-id-460075' id='answer-label-460075' class=' answer label-27'><span class='answer'>ABC recording<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460076' \/><div class='watu-question-choice'><input type='radio' name='answer-111328[]' id='answer-id-460076' class='answer answer-27  answerof-111328' value='460076' \/>&nbsp;<label for='answer-id-460076' id='answer-label-460076' class=' answer label-27'><span class='answer'>Time sampling<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType27' value='radio' class=''><\/div><div class='watu-question' id='question-28'><div class='question-content'><p><span class='watu_num'>28. <\/span>A good behavior analyst always does what before authoring a behavior intervention?<\/p>\n<\/div><input type='hidden' name='question_id[]' value='111330' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460079' \/><div class='watu-question-choice'><input type='radio' name='answer-111330[]' id='answer-id-460079' class='answer answer-28  answerof-111330' value='460079' \/>&nbsp;<label for='answer-id-460079' id='answer-label-460079' class=' answer label-28'><span class='answer'>Functional analysis<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460081' \/><div class='watu-question-choice'><input type='radio' name='answer-111330[]' id='answer-id-460081' class='answer answer-28  answerof-111330' value='460081' \/>&nbsp;<label for='answer-id-460081' id='answer-label-460081' class=' answer label-28'><span class='answer'>Momentary time sampling<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460083' \/><div class='watu-question-choice'><input type='radio' name='answer-111330[]' id='answer-id-460083' class='answer answer-28  answerof-111330' value='460083' \/>&nbsp;<label for='answer-id-460083' id='answer-label-460083' class=' answer label-28'><span class='answer'>Direct observation<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460084' \/><div class='watu-question-choice'><input type='radio' name='answer-111330[]' id='answer-id-460084' class='answer answer-28  answerof-111330' value='460084' \/>&nbsp;<label for='answer-id-460084' id='answer-label-460084' class=' answer label-28'><span class='answer'>Implements the least aversive, most effective punisher<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType28' value='radio' class=''><\/div><div class='watu-question' id='question-29'><div class='question-content'><p><span class='watu_num'>29. <\/span>What are the three elements of informed consent?<\/p>\n<\/div><input type='hidden' name='question_id[]' value='111332' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460087' \/><div class='watu-question-choice'><input type='radio' name='answer-111332[]' id='answer-id-460087' class='answer answer-29  answerof-111332' value='460087' \/>&nbsp;<label for='answer-id-460087' id='answer-label-460087' class=' answer label-29'><span class='answer'>No coercion, approval, voluntariness<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460089' \/><div class='watu-question-choice'><input type='radio' name='answer-111332[]' id='answer-id-460089' class='answer answer-29  answerof-111332' value='460089' \/>&nbsp;<label for='answer-id-460089' id='answer-label-460089' class=' answer label-29'><span class='answer'>Capacity, age, voluntariness<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460091' \/><div class='watu-question-choice'><input type='radio' name='answer-111332[]' id='answer-id-460091' class='answer answer-29  answerof-111332' value='460091' \/>&nbsp;<label for='answer-id-460091' id='answer-label-460091' class=' answer label-29'><span class='answer'>Informed, age, voluntariness<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460092' \/><div class='watu-question-choice'><input type='radio' name='answer-111332[]' id='answer-id-460092' class='answer answer-29  answerof-111332' value='460092' \/>&nbsp;<label for='answer-id-460092' id='answer-label-460092' class=' answer label-29'><span class='answer'>Capacity, informed, voluntariness<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType29' value='radio' class=''><\/div><div class='watu-question' id='question-30'><div class='question-content'><p><span class='watu_num'>30. <\/span>Behavior analytic interventions that are effective in changing an individual\u2019s behavior in a socially important way are said to have:<\/p>\n<\/div><input type='hidden' name='question_id[]' value='111334' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460095' \/><div class='watu-question-choice'><input type='radio' name='answer-111334[]' id='answer-id-460095' class='answer answer-30  answerof-111334' value='460095' \/>&nbsp;<label for='answer-id-460095' id='answer-label-460095' class=' answer label-30'><span class='answer'>Parsimony<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460097' \/><div class='watu-question-choice'><input type='radio' name='answer-111334[]' id='answer-id-460097' class='answer answer-30  answerof-111334' value='460097' \/>&nbsp;<label for='answer-id-460097' id='answer-label-460097' class=' answer label-30'><span class='answer'>Social validity<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460099' \/><div class='watu-question-choice'><input type='radio' name='answer-111334[]' id='answer-id-460099' class='answer answer-30  answerof-111334' value='460099' \/>&nbsp;<label for='answer-id-460099' id='answer-label-460099' class=' answer label-30'><span class='answer'>Primary importance<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460100' \/><div class='watu-question-choice'><input type='radio' name='answer-111334[]' id='answer-id-460100' class='answer answer-30  answerof-111334' value='460100' \/>&nbsp;<label for='answer-id-460100' id='answer-label-460100' class=' answer label-30'><span class='answer'>Interobserver reliability<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType30' value='radio' class=''><\/div><div class='watu-question' id='question-31'><div class='question-content'><p><span class='watu_num'>31. <\/span>Which of the following would not be a type of function of behavior identified during a functional assessment?<\/p>\n<\/div><input type='hidden' name='question_id[]' value='111336' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460103' \/><div class='watu-question-choice'><input type='radio' name='answer-111336[]' id='answer-id-460103' class='answer answer-31  answerof-111336' value='460103' \/>&nbsp;<label for='answer-id-460103' id='answer-label-460103' class=' answer label-31'><span class='answer'>Attention<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460105' \/><div class='watu-question-choice'><input type='radio' name='answer-111336[]' id='answer-id-460105' class='answer answer-31  answerof-111336' value='460105' \/>&nbsp;<label for='answer-id-460105' id='answer-label-460105' class=' answer label-31'><span class='answer'>Escape<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460107' \/><div class='watu-question-choice'><input type='radio' name='answer-111336[]' id='answer-id-460107' class='answer answer-31  answerof-111336' value='460107' \/>&nbsp;<label for='answer-id-460107' id='answer-label-460107' class=' answer label-31'><span class='answer'>Frustration<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460108' \/><div class='watu-question-choice'><input type='radio' name='answer-111336[]' id='answer-id-460108' class='answer answer-31  answerof-111336' value='460108' \/>&nbsp;<label for='answer-id-460108' id='answer-label-460108' class=' answer label-31'><span class='answer'>Access to tangibles<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType31' value='radio' class=''><\/div><div class='watu-question' id='question-32'><div class='question-content'><p><span class='watu_num'>32. <\/span>Results of a functional assessment reveal that a child engages in hand-biting when she is in a room by herself.<br \/>\n<br \/>The likely function of behavior is:<\/p>\n<\/div><input type='hidden' name='question_id[]' value='111338' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460111' \/><div class='watu-question-choice'><input type='radio' name='answer-111338[]' id='answer-id-460111' class='answer answer-32  answerof-111338' value='460111' \/>&nbsp;<label for='answer-id-460111' id='answer-label-460111' class=' answer label-32'><span class='answer'>Attention<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460113' \/><div class='watu-question-choice'><input type='radio' name='answer-111338[]' id='answer-id-460113' class='answer answer-32  answerof-111338' value='460113' \/>&nbsp;<label for='answer-id-460113' id='answer-label-460113' class=' answer label-32'><span class='answer'>Access to tangibles<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460115' \/><div class='watu-question-choice'><input type='radio' name='answer-111338[]' id='answer-id-460115' class='answer answer-32  answerof-111338' value='460115' \/>&nbsp;<label for='answer-id-460115' id='answer-label-460115' class=' answer label-32'><span class='answer'>Escape\/avoidance<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460116' \/><div class='watu-question-choice'><input type='radio' name='answer-111338[]' id='answer-id-460116' class='answer answer-32  answerof-111338' value='460116' \/>&nbsp;<label for='answer-id-460116' id='answer-label-460116' class=' answer label-32'><span class='answer'>Automatic reinforcement<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType32' value='radio' class=''><\/div><div class='watu-question' id='question-33'><div class='question-content'><p><span class='watu_num'>33. <\/span>You are working with a child on teaching swimming. You teach the child to do the front crawl. After a few weeks of teaching, the child is doing both the front crawl and also starts doing the breast stroke.<br \/>\n<br \/>What has occurred?<\/p>\n<\/div><input type='hidden' name='question_id[]' value='111340' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460118' \/><div class='watu-question-choice'><input type='radio' name='answer-111340[]' id='answer-id-460118' class='answer answer-33  answerof-111340' value='460118' \/>&nbsp;<label for='answer-id-460118' id='answer-label-460118' class=' answer label-33'><span class='answer'>Stimulus generalization<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460120' \/><div class='watu-question-choice'><input type='radio' name='answer-111340[]' id='answer-id-460120' class='answer answer-33  answerof-111340' value='460120' \/>&nbsp;<label for='answer-id-460120' id='answer-label-460120' class=' answer label-33'><span class='answer'>Response generalization<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460122' \/><div class='watu-question-choice'><input type='radio' name='answer-111340[]' id='answer-id-460122' class='answer answer-33  answerof-111340' value='460122' \/>&nbsp;<label for='answer-id-460122' id='answer-label-460122' class=' answer label-33'><span class='answer'>Failure to generalize<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460124' \/><div class='watu-question-choice'><input type='radio' name='answer-111340[]' id='answer-id-460124' class='answer answer-33  answerof-111340' value='460124' \/>&nbsp;<label for='answer-id-460124' id='answer-label-460124' class=' answer label-33'><span class='answer'>Maintenance<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType33' value='radio' class=''><\/div><div class='watu-question' id='question-34'><div class='question-content'><p><span class='watu_num'>34. <\/span>What if you teach the child to swim in a pool and the child goes to the beach and can do the front crawl in the ocean?<\/p>\n<\/div><input type='hidden' name='question_id[]' value='111342' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460126' \/><div class='watu-question-choice'><input type='radio' name='answer-111342[]' id='answer-id-460126' class='answer answer-34  answerof-111342' value='460126' \/>&nbsp;<label for='answer-id-460126' id='answer-label-460126' class=' answer label-34'><span class='answer'>Stimulus generalization<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460128' \/><div class='watu-question-choice'><input type='radio' name='answer-111342[]' id='answer-id-460128' class='answer answer-34  answerof-111342' value='460128' \/>&nbsp;<label for='answer-id-460128' id='answer-label-460128' class=' answer label-34'><span class='answer'>Response generalization<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460130' \/><div class='watu-question-choice'><input type='radio' name='answer-111342[]' id='answer-id-460130' class='answer answer-34  answerof-111342' value='460130' \/>&nbsp;<label for='answer-id-460130' id='answer-label-460130' class=' answer label-34'><span class='answer'>Failure to generalize<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460131' \/><div class='watu-question-choice'><input type='radio' name='answer-111342[]' id='answer-id-460131' class='answer answer-34  answerof-111342' value='460131' \/>&nbsp;<label for='answer-id-460131' id='answer-label-460131' class=' answer label-34'><span class='answer'>Natural contingencies<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType34' value='radio' class=''><\/div><div class='watu-question' id='question-35'><div class='question-content'><p><span class='watu_num'>35. <\/span>In reference to maintenance, functional arrangements between behavior and antecedent and consequence events that occur in the environment in which the behavior of interest is to be maintained are called:<\/p>\n<\/div><input type='hidden' name='question_id[]' value='111344' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460134' \/><div class='watu-question-choice'><input type='radio' name='answer-111344[]' id='answer-id-460134' class='answer answer-35  answerof-111344' value='460134' \/>&nbsp;<label for='answer-id-460134' id='answer-label-460134' class=' answer label-35'><span class='answer'>Stimulus discriminates<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460136' \/><div class='watu-question-choice'><input type='radio' name='answer-111344[]' id='answer-id-460136' class='answer answer-35  answerof-111344' value='460136' \/>&nbsp;<label for='answer-id-460136' id='answer-label-460136' class=' answer label-35'><span class='answer'>Natural contingencies<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460138' \/><div class='watu-question-choice'><input type='radio' name='answer-111344[]' id='answer-id-460138' class='answer answer-35  answerof-111344' value='460138' \/>&nbsp;<label for='answer-id-460138' id='answer-label-460138' class=' answer label-35'><span class='answer'>Generalization<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460139' \/><div class='watu-question-choice'><input type='radio' name='answer-111344[]' id='answer-id-460139' class='answer answer-35  answerof-111344' value='460139' \/>&nbsp;<label for='answer-id-460139' id='answer-label-460139' class=' answer label-35'><span class='answer'>Maintenance schedules<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType35' value='radio' class=''><\/div><div class='watu-question' id='question-36'><div class='question-content'><p><span class='watu_num'>36. <\/span>A child who learns to say \u201cred\u201d when presented with a red card, also says \u201cred\u201d when presented with an orange card. This is called:<\/p>\n<\/div><input type='hidden' name='question_id[]' value='111346' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460142' \/><div class='watu-question-choice'><input type='radio' name='answer-111346[]' id='answer-id-460142' class='answer answer-36  answerof-111346' value='460142' \/>&nbsp;<label for='answer-id-460142' id='answer-label-460142' class=' answer label-36'><span class='answer'>Stimulus generalization<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460144' \/><div class='watu-question-choice'><input type='radio' name='answer-111346[]' id='answer-id-460144' class='answer answer-36  answerof-111346' value='460144' \/>&nbsp;<label for='answer-id-460144' id='answer-label-460144' class=' answer label-36'><span class='answer'>Response generalization<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460146' \/><div class='watu-question-choice'><input type='radio' name='answer-111346[]' id='answer-id-460146' class='answer answer-36  answerof-111346' value='460146' \/>&nbsp;<label for='answer-id-460146' id='answer-label-460146' class=' answer label-36'><span class='answer'>Discrimination<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460147' \/><div class='watu-question-choice'><input type='radio' name='answer-111346[]' id='answer-id-460147' class='answer answer-36  answerof-111346' value='460147' \/>&nbsp;<label for='answer-id-460147' id='answer-label-460147' class=' answer label-36'><span class='answer'>Failure to generalize<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType36' value='radio' class=''><\/div><div class='watu-question' id='question-37'><div class='question-content'><p><span class='watu_num'>37. <\/span>Which schedule of reinforcement is most effective at maintaining behaviors?<\/p>\n<\/div><input type='hidden' name='question_id[]' value='111348' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460149' \/><div class='watu-question-choice'><input type='radio' name='answer-111348[]' id='answer-id-460149' class='answer answer-37  answerof-111348' value='460149' \/>&nbsp;<label for='answer-id-460149' id='answer-label-460149' class=' answer label-37'><span class='answer'>Continuous reinforcement<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460151' \/><div class='watu-question-choice'><input type='radio' name='answer-111348[]' id='answer-id-460151' class='answer answer-37  answerof-111348' value='460151' \/>&nbsp;<label for='answer-id-460151' id='answer-label-460151' class=' answer label-37'><span class='answer'>Intermittent reinforcement<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460153' \/><div class='watu-question-choice'><input type='radio' name='answer-111348[]' id='answer-id-460153' class='answer answer-37  answerof-111348' value='460153' \/>&nbsp;<label for='answer-id-460153' id='answer-label-460153' class=' answer label-37'><span class='answer'>Extinction<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460155' \/><div class='watu-question-choice'><input type='radio' name='answer-111348[]' id='answer-id-460155' class='answer answer-37  answerof-111348' value='460155' \/>&nbsp;<label for='answer-id-460155' id='answer-label-460155' class=' answer label-37'><span class='answer'>Ratio<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType37' value='radio' class=''><\/div><div class='watu-question' id='question-38'><div class='question-content'><p><span class='watu_num'>38. <\/span>You are teaching David to clean the workshop to prepare him for working on the cleaning crew. Read the descriptions below and identify which is LEAST likely to promote generalization of the workshop cleaning skills to real-life cleaning jobs.<\/p>\n<\/div><input type='hidden' name='question_id[]' value='111350' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460157' \/><div class='watu-question-choice'><input type='radio' name='answer-111350[]' id='answer-id-460157' class='answer answer-38  answerof-111350' value='460157' \/>&nbsp;<label for='answer-id-460157' id='answer-label-460157' class=' answer label-38'><span class='answer'>Make the workshop as much like a real cleaning situation as possible<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460159' \/><div class='watu-question-choice'><input type='radio' name='answer-111350[]' id='answer-id-460159' class='answer answer-38  answerof-111350' value='460159' \/>&nbsp;<label for='answer-id-460159' id='answer-label-460159' class=' answer label-38'><span class='answer'>Transition to variable, delayed reinforcement<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460161' \/><div class='watu-question-choice'><input type='radio' name='answer-111350[]' id='answer-id-460161' class='answer answer-38  answerof-111350' value='460161' \/>&nbsp;<label for='answer-id-460161' id='answer-label-460161' class=' answer label-38'><span class='answer'>Teach David to use a checklist, which could be used on the cleaning crew<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460163' \/><div class='watu-question-choice'><input type='radio' name='answer-111350[]' id='answer-id-460163' class='answer answer-38  answerof-111350' value='460163' \/>&nbsp;<label for='answer-id-460163' id='answer-label-460163' class=' answer label-38'><span class='answer'>Make the workshop distinctive from the cleaning crew and then gradually make it more like it<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType38' value='radio' class=''><\/div><div class='watu-question' id='question-39'><div class='question-content'><p><span class='watu_num'>39. <\/span>You are working with a client who finds physical touch to be aversive. When the person is off task, the program calls for you to give a warning by counting to 10; at that point, you gently touch him if he is not back on task. The touch remains until he returns to task. Please note that being touched is aversive for this particular individual.<br \/>\n<br \/>If the person gets back on task during counting, this is an example of:<\/p>\n<\/div><input type='hidden' name='question_id[]' value='111352' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460165' \/><div class='watu-question-choice'><input type='radio' name='answer-111352[]' id='answer-id-460165' class='answer answer-39  answerof-111352' value='460165' \/>&nbsp;<label for='answer-id-460165' id='answer-label-460165' class=' answer label-39'><span class='answer'>Escape<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460167' \/><div class='watu-question-choice'><input type='radio' name='answer-111352[]' id='answer-id-460167' class='answer answer-39  answerof-111352' value='460167' \/>&nbsp;<label for='answer-id-460167' id='answer-label-460167' class=' answer label-39'><span class='answer'>Avoidance<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460169' \/><div class='watu-question-choice'><input type='radio' name='answer-111352[]' id='answer-id-460169' class='answer answer-39  answerof-111352' value='460169' \/>&nbsp;<label for='answer-id-460169' id='answer-label-460169' class=' answer label-39'><span class='answer'>Positive reinforcement<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460171' \/><div class='watu-question-choice'><input type='radio' name='answer-111352[]' id='answer-id-460171' class='answer answer-39  answerof-111352' value='460171' \/>&nbsp;<label for='answer-id-460171' id='answer-label-460171' class=' answer label-39'><span class='answer'>Stimulus fading<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType39' value='radio' class=''><\/div><div class='watu-question' id='question-40'><div class='question-content'><p><span class='watu_num'>40. <\/span>If the person gets back on task when he is touched, this is an example of:<\/p>\n<\/div><input type='hidden' name='question_id[]' value='111354' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460173' \/><div class='watu-question-choice'><input type='radio' name='answer-111354[]' id='answer-id-460173' class='answer answer-40  answerof-111354' value='460173' \/>&nbsp;<label for='answer-id-460173' id='answer-label-460173' class=' answer label-40'><span class='answer'>Escape<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460175' \/><div class='watu-question-choice'><input type='radio' name='answer-111354[]' id='answer-id-460175' class='answer answer-40  answerof-111354' value='460175' \/>&nbsp;<label for='answer-id-460175' id='answer-label-460175' class=' answer label-40'><span class='answer'>Avoidance<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460177' \/><div class='watu-question-choice'><input type='radio' name='answer-111354[]' id='answer-id-460177' class='answer answer-40  answerof-111354' value='460177' \/>&nbsp;<label for='answer-id-460177' id='answer-label-460177' class=' answer label-40'><span class='answer'>Positive reinforcement<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460179' \/><div class='watu-question-choice'><input type='radio' name='answer-111354[]' id='answer-id-460179' class='answer answer-40  answerof-111354' value='460179' \/>&nbsp;<label for='answer-id-460179' id='answer-label-460179' class=' answer label-40'><span class='answer'>Stimulus fading<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType40' value='radio' class=''><\/div><div class='watu-question' id='question-41'><div class='question-content'><p><span class='watu_num'>41. <\/span>Staff alerts you that one of their clients seems to become aggressive when he has not consumed food for several hours.<br \/>\n<br \/>This phenomenon demonstrates the effect of a(n):<\/p>\n<\/div><input type='hidden' name='question_id[]' value='111356' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460181' \/><div class='watu-question-choice'><input type='radio' name='answer-111356[]' id='answer-id-460181' class='answer answer-41  answerof-111356' value='460181' \/>&nbsp;<label for='answer-id-460181' id='answer-label-460181' class=' answer label-41'><span class='answer'>Discriminative stimulus<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460183' \/><div class='watu-question-choice'><input type='radio' name='answer-111356[]' id='answer-id-460183' class='answer answer-41  answerof-111356' value='460183' \/>&nbsp;<label for='answer-id-460183' id='answer-label-460183' class=' answer label-41'><span class='answer'>Conditioned stimulus<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460185' \/><div class='watu-question-choice'><input type='radio' name='answer-111356[]' id='answer-id-460185' class='answer answer-41  answerof-111356' value='460185' \/>&nbsp;<label for='answer-id-460185' id='answer-label-460185' class=' answer label-41'><span class='answer'>Establishing operation<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460187' \/><div class='watu-question-choice'><input type='radio' name='answer-111356[]' id='answer-id-460187' class='answer answer-41  answerof-111356' value='460187' \/>&nbsp;<label for='answer-id-460187' id='answer-label-460187' class=' answer label-41'><span class='answer'>Negative reinforcer<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType41' value='radio' class=''><\/div><div class='watu-question' id='question-42'><div class='question-content'><p><span class='watu_num'>42. <\/span>A child is exhibiting tantrum behaviors. You believe the tantrum is occurring for your attention. You therefore ignore the tantrum until it ceases while continuing daily activities. You note that the tantrums decrease over time.<br \/>\n<br \/>This is an example of:<\/p>\n<\/div><input type='hidden' name='question_id[]' value='111358' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460189' \/><div class='watu-question-choice'><input type='radio' name='answer-111358[]' id='answer-id-460189' class='answer answer-42  answerof-111358' value='460189' \/>&nbsp;<label for='answer-id-460189' id='answer-label-460189' class=' answer label-42'><span class='answer'>Positive punishment<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460191' \/><div class='watu-question-choice'><input type='radio' name='answer-111358[]' id='answer-id-460191' class='answer answer-42  answerof-111358' value='460191' \/>&nbsp;<label for='answer-id-460191' id='answer-label-460191' class=' answer label-42'><span class='answer'>Establishing operations<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460193' \/><div class='watu-question-choice'><input type='radio' name='answer-111358[]' id='answer-id-460193' class='answer answer-42  answerof-111358' value='460193' \/>&nbsp;<label for='answer-id-460193' id='answer-label-460193' class=' answer label-42'><span class='answer'>Time-out<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460195' \/><div class='watu-question-choice'><input type='radio' name='answer-111358[]' id='answer-id-460195' class='answer answer-42  answerof-111358' value='460195' \/>&nbsp;<label for='answer-id-460195' id='answer-label-460195' class=' answer label-42'><span class='answer'>Extinction<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType42' value='radio' class=''><\/div><div class='watu-question' id='question-43'><div class='question-content'><p><span class='watu_num'>43. <\/span>Tokens are generally referred to as:<\/p>\n<\/div><input type='hidden' name='question_id[]' value='111360' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460197' \/><div class='watu-question-choice'><input type='radio' name='answer-111360[]' id='answer-id-460197' class='answer answer-43  answerof-111360' value='460197' \/>&nbsp;<label for='answer-id-460197' id='answer-label-460197' class=' answer label-43'><span class='answer'>Conditioned reinforcers<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460199' \/><div class='watu-question-choice'><input type='radio' name='answer-111360[]' id='answer-id-460199' class='answer answer-43  answerof-111360' value='460199' \/>&nbsp;<label for='answer-id-460199' id='answer-label-460199' class=' answer label-43'><span class='answer'>Generalized conditioned reinforcers<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460201' \/><div class='watu-question-choice'><input type='radio' name='answer-111360[]' id='answer-id-460201' class='answer answer-43  answerof-111360' value='460201' \/>&nbsp;<label for='answer-id-460201' id='answer-label-460201' class=' answer label-43'><span class='answer'>Negative reinforcers<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460203' \/><div class='watu-question-choice'><input type='radio' name='answer-111360[]' id='answer-id-460203' class='answer answer-43  answerof-111360' value='460203' \/>&nbsp;<label for='answer-id-460203' id='answer-label-460203' class=' answer label-43'><span class='answer'>SDs<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType43' value='radio' class=''><\/div><div class='watu-question' id='question-44'><div class='question-content'><p><span class='watu_num'>44. <\/span>In self-control, where does the ultimate control lie? (Or, why is self-control a misnomer?)<\/p>\n<\/div><input type='hidden' name='question_id[]' value='111362' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460205' \/><div class='watu-question-choice'><input type='radio' name='answer-111362[]' id='answer-id-460205' class='answer answer-44  answerof-111362' value='460205' \/>&nbsp;<label for='answer-id-460205' id='answer-label-460205' class=' answer label-44'><span class='answer'>With the self<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460207' \/><div class='watu-question-choice'><input type='radio' name='answer-111362[]' id='answer-id-460207' class='answer answer-44  answerof-111362' value='460207' \/>&nbsp;<label for='answer-id-460207' id='answer-label-460207' class=' answer label-44'><span class='answer'>The choice of the person<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460209' \/><div class='watu-question-choice'><input type='radio' name='answer-111362[]' id='answer-id-460209' class='answer answer-44  answerof-111362' value='460209' \/>&nbsp;<label for='answer-id-460209' id='answer-label-460209' class=' answer label-44'><span class='answer'>In the environment<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460211' \/><div class='watu-question-choice'><input type='radio' name='answer-111362[]' id='answer-id-460211' class='answer answer-44  answerof-111362' value='460211' \/>&nbsp;<label for='answer-id-460211' id='answer-label-460211' class=' answer label-44'><span class='answer'>With a contract manager<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType44' value='radio' class=''><\/div><div class='watu-question' id='question-45'><div class='question-content'><p><span class='watu_num'>45. <\/span>Select the best staff training package:<\/p>\n<\/div><input type='hidden' name='question_id[]' value='111364' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460213' \/><div class='watu-question-choice'><input type='radio' name='answer-111364[]' id='answer-id-460213' class='answer answer-45  answerof-111364' value='460213' \/>&nbsp;<label for='answer-id-460213' id='answer-label-460213' class=' answer label-45'><span class='answer'>Staff are given a book on behavior analysis and asked to read it; comprehension tests are given after each chapter<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460215' \/><div class='watu-question-choice'><input type='radio' name='answer-111364[]' id='answer-id-460215' class='answer answer-45  answerof-111364' value='460215' \/>&nbsp;<label for='answer-id-460215' id='answer-label-460215' class=' answer label-45'><span class='answer'>Staff are given explanation of the procedures, then a weekly feedback system is implemented to sharpen their skills<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460217' \/><div class='watu-question-choice'><input type='radio' name='answer-111364[]' id='answer-id-460217' class='answer answer-45  answerof-111364' value='460217' \/>&nbsp;<label for='answer-id-460217' id='answer-label-460217' class=' answer label-45'><span class='answer'>Explanations of each procedure are given to the staff, then the supervisor demonstrates the procedures; staff are given opportunities to practice the skills with feedback from supervisors<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460219' \/><div class='watu-question-choice'><input type='radio' name='answer-111364[]' id='answer-id-460219' class='answer answer-45  answerof-111364' value='460219' \/>&nbsp;<label for='answer-id-460219' id='answer-label-460219' class=' answer label-45'><span class='answer'>The supervisor conducts role playing sessions with the staff with weekly feedback provided for performance<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType45' value='radio' class=''><\/div><div class='watu-question' id='question-46'><div class='question-content'><p><span class='watu_num'>46. <\/span>You are designing a treatment program for Susan. Before getting into details, you wish to identify some ultimate outcomes towards which Susan will progress.<br \/>\n<br \/>Which of the following is NOT an appropriate ultimate outcome for Susan?<\/p>\n<\/div><input type='hidden' name='question_id[]' value='111366' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460221' \/><div class='watu-question-choice'><input type='radio' name='answer-111366[]' id='answer-id-460221' class='answer answer-46  answerof-111366' value='460221' \/>&nbsp;<label for='answer-id-460221' id='answer-label-460221' class=' answer label-46'><span class='answer'>The variety and diversity of events in Susan\u2019s life<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460223' \/><div class='watu-question-choice'><input type='radio' name='answer-111366[]' id='answer-id-460223' class='answer answer-46  answerof-111366' value='460223' \/>&nbsp;<label for='answer-id-460223' id='answer-label-460223' class=' answer label-46'><span class='answer'>Susan\u2019s access to reinforcers in the community<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460225' \/><div class='watu-question-choice'><input type='radio' name='answer-111366[]' id='answer-id-460225' class='answer answer-46  answerof-111366' value='460225' \/>&nbsp;<label for='answer-id-460225' id='answer-label-460225' class=' answer label-46'><span class='answer'>The range of interpersonal interactions with others<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460227' \/><div class='watu-question-choice'><input type='radio' name='answer-111366[]' id='answer-id-460227' class='answer answer-46  answerof-111366' value='460227' \/>&nbsp;<label for='answer-id-460227' id='answer-label-460227' class=' answer label-46'><span class='answer'>The convenience of staff with whom Susan works<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType46' value='radio' class=''><\/div><div class='watu-question' id='question-47'><div class='question-content'><p><span class='watu_num'>47. <\/span>Non-contingent reinforcement is this type of intervention:<\/p>\n<\/div><input type='hidden' name='question_id[]' value='111368' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460229' \/><div class='watu-question-choice'><input type='radio' name='answer-111368[]' id='answer-id-460229' class='answer answer-47  answerof-111368' value='460229' \/>&nbsp;<label for='answer-id-460229' id='answer-label-460229' class=' answer label-47'><span class='answer'>Antecedent intervention<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460231' \/><div class='watu-question-choice'><input type='radio' name='answer-111368[]' id='answer-id-460231' class='answer answer-47  answerof-111368' value='460231' \/>&nbsp;<label for='answer-id-460231' id='answer-label-460231' class=' answer label-47'><span class='answer'>Consequent intervention<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460233' \/><div class='watu-question-choice'><input type='radio' name='answer-111368[]' id='answer-id-460233' class='answer answer-47  answerof-111368' value='460233' \/>&nbsp;<label for='answer-id-460233' id='answer-label-460233' class=' answer label-47'><span class='answer'>Punishment strategy<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460235' \/><div class='watu-question-choice'><input type='radio' name='answer-111368[]' id='answer-id-460235' class='answer answer-47  answerof-111368' value='460235' \/>&nbsp;<label for='answer-id-460235' id='answer-label-460235' class=' answer label-47'><span class='answer'>Behavioral momentum intervention<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType47' value='radio' class=''><\/div><div class='watu-question' id='question-48'><div class='question-content'><p><span class='watu_num'>48. <\/span>A teacher uses a group contingency with her students. She states the following rule: \u201cIf everyone gets 100% on their spelling test the week, I will turn cartwheels down the hall for you.\u201d<br \/>\n<br \/>What type of group contingency is this?<\/p>\n<\/div><input type='hidden' name='question_id[]' value='111370' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460237' \/><div class='watu-question-choice'><input type='radio' name='answer-111370[]' id='answer-id-460237' class='answer answer-48  answerof-111370' value='460237' \/>&nbsp;<label for='answer-id-460237' id='answer-label-460237' class=' answer label-48'><span class='answer'>This is not a group contingency<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460238' \/><div class='watu-question-choice'><input type='radio' name='answer-111370[]' id='answer-id-460238' class='answer answer-48  answerof-111370' value='460238' \/>&nbsp;<label for='answer-id-460238' id='answer-label-460238' class=' answer label-48'><span class='answer'>Independent group contingency<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460240' \/><div class='watu-question-choice'><input type='radio' name='answer-111370[]' id='answer-id-460240' class='answer answer-48  answerof-111370' value='460240' \/>&nbsp;<label for='answer-id-460240' id='answer-label-460240' class=' answer label-48'><span class='answer'>Interdependent group contingency<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460242' \/><div class='watu-question-choice'><input type='radio' name='answer-111370[]' id='answer-id-460242' class='answer answer-48  answerof-111370' value='460242' \/>&nbsp;<label for='answer-id-460242' id='answer-label-460242' class=' answer label-48'><span class='answer'>Dependent group contingency<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType48' value='radio' class=''><\/div><div class='watu-question' id='question-49'><div class='question-content'><p><span class='watu_num'>49. <\/span>A teacher says: \u201cEveryone, you have math homework tonight. Tomorrow, I will draw a name from a hat. If that person has completed his or her homework and remembered to bring it back to school, everyone will get extra recess.\u201d<br \/>\n<br \/>What type of group contingency is this?<\/p>\n<\/div><input type='hidden' name='question_id[]' value='111371' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460244' \/><div class='watu-question-choice'><input type='radio' name='answer-111371[]' id='answer-id-460244' class='answer answer-49  answerof-111371' value='460244' \/>&nbsp;<label for='answer-id-460244' id='answer-label-460244' class=' answer label-49'><span class='answer'>This is not a group contingency<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460246' \/><div class='watu-question-choice'><input type='radio' name='answer-111371[]' id='answer-id-460246' class='answer answer-49  answerof-111371' value='460246' \/>&nbsp;<label for='answer-id-460246' id='answer-label-460246' class=' answer label-49'><span class='answer'>Independent group contingency<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460248' \/><div class='watu-question-choice'><input type='radio' name='answer-111371[]' id='answer-id-460248' class='answer answer-49  answerof-111371' value='460248' \/>&nbsp;<label for='answer-id-460248' id='answer-label-460248' class=' answer label-49'><span class='answer'>Interdependent group contingency<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460250' \/><div class='watu-question-choice'><input type='radio' name='answer-111371[]' id='answer-id-460250' class='answer answer-49  answerof-111371' value='460250' \/>&nbsp;<label for='answer-id-460250' id='answer-label-460250' class=' answer label-49'><span class='answer'>Dependent group contingency<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType49' value='radio' class=''><\/div><div class='watu-question' id='question-50'><div class='question-content'><p><span class='watu_num'>50. <\/span>Self-management is best defined as the:<\/p>\n<\/div><input type='hidden' name='question_id[]' value='111373' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460252' \/><div class='watu-question-choice'><input type='radio' name='answer-111373[]' id='answer-id-460252' class='answer answer-50  answerof-111373' value='460252' \/>&nbsp;<label for='answer-id-460252' id='answer-label-460252' class=' answer label-50'><span class='answer'>Personal application of behavior change tactics that produces a desired change in behavior<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460254' \/><div class='watu-question-choice'><input type='radio' name='answer-111373[]' id='answer-id-460254' class='answer answer-50  answerof-111373' value='460254' \/>&nbsp;<label for='answer-id-460254' id='answer-label-460254' class=' answer label-50'><span class='answer'>Personal application of behavior change tactics that produces an increase in a desired behavior<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460256' \/><div class='watu-question-choice'><input type='radio' name='answer-111373[]' id='answer-id-460256' class='answer answer-50  answerof-111373' value='460256' \/>&nbsp;<label for='answer-id-460256' id='answer-label-460256' class=' answer label-50'><span class='answer'>Personal application of behavior change tactics that produces an decrease in a desired behavior<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460258' \/><div class='watu-question-choice'><input type='radio' name='answer-111373[]' id='answer-id-460258' class='answer answer-50  answerof-111373' value='460258' \/>&nbsp;<label for='answer-id-460258' id='answer-label-460258' class=' answer label-50'><span class='answer'>Application of behavior change tactics that causes changes to a particular behavior<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType50' value='radio' class=''><\/div><div class='watu-question' id='question-51'><div class='question-content'><p><span class='watu_num'>51. <\/span>A study was undertaken to determine the effectiveness of time-out for physical aggression.<br \/>\n<br \/>The time-out procedure would be considered the:<\/p>\n<\/div><input type='hidden' name='question_id[]' value='111375' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460260' \/><div class='watu-question-choice'><input type='radio' name='answer-111375[]' id='answer-id-460260' class='answer answer-51  answerof-111375' value='460260' \/>&nbsp;<label for='answer-id-460260' id='answer-label-460260' class=' answer label-51'><span class='answer'>baseline measure.<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460262' \/><div class='watu-question-choice'><input type='radio' name='answer-111375[]' id='answer-id-460262' class='answer answer-51  answerof-111375' value='460262' \/>&nbsp;<label for='answer-id-460262' id='answer-label-460262' class=' answer label-51'><span class='answer'>dependent variable.<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460264' \/><div class='watu-question-choice'><input type='radio' name='answer-111375[]' id='answer-id-460264' class='answer answer-51  answerof-111375' value='460264' \/>&nbsp;<label for='answer-id-460264' id='answer-label-460264' class=' answer label-51'><span class='answer'>independent variable.<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460266' \/><div class='watu-question-choice'><input type='radio' name='answer-111375[]' id='answer-id-460266' class='answer answer-51  answerof-111375' value='460266' \/>&nbsp;<label for='answer-id-460266' id='answer-label-460266' class=' answer label-51'><span class='answer'>response measure.<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType51' value='radio' class=''><\/div><div class='watu-question' id='question-52'><div class='question-content'><p><span class='watu_num'>52. <\/span>When conducting an analogue functional analysis, the condition commonly used as a control is the:<\/p>\n<\/div><input type='hidden' name='question_id[]' value='111377' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460268' \/><div class='watu-question-choice'><input type='radio' name='answer-111377[]' id='answer-id-460268' class='answer answer-52  answerof-111377' value='460268' \/>&nbsp;<label for='answer-id-460268' id='answer-label-460268' class=' answer label-52'><span class='answer'>home condition.<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460269' \/><div class='watu-question-choice'><input type='radio' name='answer-111377[]' id='answer-id-460269' class='answer answer-52  answerof-111377' value='460269' \/>&nbsp;<label for='answer-id-460269' id='answer-label-460269' class=' answer label-52'><span class='answer'>play condition.<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460271' \/><div class='watu-question-choice'><input type='radio' name='answer-111377[]' id='answer-id-460271' class='answer answer-52  answerof-111377' value='460271' \/>&nbsp;<label for='answer-id-460271' id='answer-label-460271' class=' answer label-52'><span class='answer'>social attention condition.<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460273' \/><div class='watu-question-choice'><input type='radio' name='answer-111377[]' id='answer-id-460273' class='answer answer-52  answerof-111377' value='460273' \/>&nbsp;<label for='answer-id-460273' id='answer-label-460273' class=' answer label-52'><span class='answer'>demand condition.<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType52' value='radio' class=''><\/div><div class='watu-question' id='question-53'><div class='question-content'><p><span class='watu_num'>53. <\/span>Which method is the BEST to use when presenting categorical data from a functional analysis?<\/p>\n<\/div><input type='hidden' name='question_id[]' value='111379' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460276' \/><div class='watu-question-choice'><input type='radio' name='answer-111379[]' id='answer-id-460276' class='answer answer-53  answerof-111379' value='460276' \/>&nbsp;<label for='answer-id-460276' id='answer-label-460276' class=' answer label-53'><span class='answer'>a bar graph<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460278' \/><div class='watu-question-choice'><input type='radio' name='answer-111379[]' id='answer-id-460278' class='answer answer-53  answerof-111379' value='460278' \/>&nbsp;<label for='answer-id-460278' id='answer-label-460278' class=' answer label-53'><span class='answer'>anecdotal report<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460280' \/><div class='watu-question-choice'><input type='radio' name='answer-111379[]' id='answer-id-460280' class='answer answer-53  answerof-111379' value='460280' \/>&nbsp;<label for='answer-id-460280' id='answer-label-460280' class=' answer label-53'><span class='answer'>scatter plot<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460282' \/><div class='watu-question-choice'><input type='radio' name='answer-111379[]' id='answer-id-460282' class='answer answer-53  answerof-111379' value='460282' \/>&nbsp;<label for='answer-id-460282' id='answer-label-460282' class=' answer label-53'><span class='answer'>standard celeration chart<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType53' value='radio' class=''><\/div><div class='watu-question' id='question-54'><div class='question-content'><p><span class='watu_num'>54. <\/span>What is the next step in the assessment process if data from the functional analysis do NOT support the original hypothesis?<\/p>\n<\/div><input type='hidden' name='question_id[]' value='111381' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460284' \/><div class='watu-question-choice'><input type='radio' name='answer-111381[]' id='answer-id-460284' class='answer answer-54  answerof-111381' value='460284' \/>&nbsp;<label for='answer-id-460284' id='answer-label-460284' class=' answer label-54'><span class='answer'>Base the intervention on the original hypothesis and re-assess after a time lapse.<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460286' \/><div class='watu-question-choice'><input type='radio' name='answer-111381[]' id='answer-id-460286' class='answer answer-54  answerof-111381' value='460286' \/>&nbsp;<label for='answer-id-460286' id='answer-label-460286' class=' answer label-54'><span class='answer'>Design a package intervention to address all possible functions of the behavior.<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460288' \/><div class='watu-question-choice'><input type='radio' name='answer-111381[]' id='answer-id-460288' class='answer answer-54  answerof-111381' value='460288' \/>&nbsp;<label for='answer-id-460288' id='answer-label-460288' class=' answer label-54'><span class='answer'>Continue to conduct the functional assessment until the data coincides with the original hypothesis.<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460290' \/><div class='watu-question-choice'><input type='radio' name='answer-111381[]' id='answer-id-460290' class='answer answer-54  answerof-111381' value='460290' \/>&nbsp;<label for='answer-id-460290' id='answer-label-460290' class=' answer label-54'><span class='answer'>Alter the hypothesis regarding the maintaining variable of the behavior based on the results of the functional assessment.<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType54' value='radio' class=''><\/div><div class='watu-question' id='question-55'><div class='question-content'><p><span class='watu_num'>55. <\/span>When developing a task analysis, a behavior analyst would first:<\/p>\n<\/div><input type='hidden' name='question_id[]' value='111383' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460292' \/><div class='watu-question-choice'><input type='radio' name='answer-111383[]' id='answer-id-460292' class='answer answer-55  answerof-111383' value='460292' \/>&nbsp;<label for='answer-id-460292' id='answer-label-460292' class=' answer label-55'><span class='answer'>assess the mastery level of the individual.<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460293' \/><div class='watu-question-choice'><input type='radio' name='answer-111383[]' id='answer-id-460293' class='answer answer-55  answerof-111383' value='460293' \/>&nbsp;<label for='answer-id-460293' id='answer-label-460293' class=' answer label-55'><span class='answer'>conduct a functional assessment of the target skills.<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460295' \/><div class='watu-question-choice'><input type='radio' name='answer-111383[]' id='answer-id-460295' class='answer answer-55  answerof-111383' value='460295' \/>&nbsp;<label for='answer-id-460295' id='answer-label-460295' class=' answer label-55'><span class='answer'>determine the necessary component steps.<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460297' \/><div class='watu-question-choice'><input type='radio' name='answer-111383[]' id='answer-id-460297' class='answer answer-55  answerof-111383' value='460297' \/>&nbsp;<label for='answer-id-460297' id='answer-label-460297' class=' answer label-55'><span class='answer'>observe the individual to collect baseline data.<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType55' value='radio' class=''><\/div><div class='watu-question' id='question-56'><div class='question-content'><p><span class='watu_num'>56. <\/span>In general, when a behavior analyst is asked to help someone make friends, the behavior analyst should:<\/p>\n<\/div><input type='hidden' name='question_id[]' value='111385' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460300' \/><div class='watu-question-choice'><input type='radio' name='answer-111385[]' id='answer-id-460300' class='answer answer-56  answerof-111385' value='460300' \/>&nbsp;<label for='answer-id-460300' id='answer-label-460300' class=' answer label-56'><span class='answer'>avoid interfering in interpersonal relationships.<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460301' \/><div class='watu-question-choice'><input type='radio' name='answer-111385[]' id='answer-id-460301' class='answer answer-56  answerof-111385' value='460301' \/>&nbsp;<label for='answer-id-460301' id='answer-label-460301' class=' answer label-56'><span class='answer'>refer the person to a counselor, social worker, or other professional.<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460303' \/><div class='watu-question-choice'><input type='radio' name='answer-111385[]' id='answer-id-460303' class='answer answer-56  answerof-111385' value='460303' \/>&nbsp;<label for='answer-id-460303' id='answer-label-460303' class=' answer label-56'><span class='answer'>evaluate the current social repertoire.<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460305' \/><div class='watu-question-choice'><input type='radio' name='answer-111385[]' id='answer-id-460305' class='answer answer-56  answerof-111385' value='460305' \/>&nbsp;<label for='answer-id-460305' id='answer-label-460305' class=' answer label-56'><span class='answer'>set up a social skills training program.<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType56' value='radio' class=''><\/div><div class='watu-question' id='question-57'><div class='question-content'><p><span class='watu_num'>57. <\/span>Holly is learning to use a spoon to feed herself. Applesauce is known to function as a reinforcer. Her teacher has selected the following objective for Holly: &quot;Given a spoon and a 3-ounce dish of applesauce, Holly will independently scoop the applesauce to her mouth.&quot; This objective is incomplete.<br \/>\n<br \/>Which component is missing?<\/p>\n<\/div><input type='hidden' name='question_id[]' value='111387' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460308' \/><div class='watu-question-choice'><input type='radio' name='answer-111387[]' id='answer-id-460308' class='answer answer-57  answerof-111387' value='460308' \/>&nbsp;<label for='answer-id-460308' id='answer-label-460308' class=' answer label-57'><span class='answer'>antecedent stimulus<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460309' \/><div class='watu-question-choice'><input type='radio' name='answer-111387[]' id='answer-id-460309' class='answer answer-57  answerof-111387' value='460309' \/>&nbsp;<label for='answer-id-460309' id='answer-label-460309' class=' answer label-57'><span class='answer'>consequence condition<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460310' \/><div class='watu-question-choice'><input type='radio' name='answer-111387[]' id='answer-id-460310' class='answer answer-57  answerof-111387' value='460310' \/>&nbsp;<label for='answer-id-460310' id='answer-label-460310' class=' answer label-57'><span class='answer'>prerequisite skill criteria<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460312' \/><div class='watu-question-choice'><input type='radio' name='answer-111387[]' id='answer-id-460312' class='answer answer-57  answerof-111387' value='460312' \/>&nbsp;<label for='answer-id-460312' id='answer-label-460312' class=' answer label-57'><span class='answer'>standard of performance<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType57' value='radio' class=''><\/div><div class='watu-question' id='question-58'><div class='question-content'><p><span class='watu_num'>58. <\/span>Speed, magnitude, durability and generality of effect are some of the MOST important<\/p>\n<\/div><input type='hidden' name='question_id[]' value='111389' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460316' \/><div class='watu-question-choice'><input type='radio' name='answer-111389[]' id='answer-id-460316' class='answer answer-58  answerof-111389' value='460316' \/>&nbsp;<label for='answer-id-460316' id='answer-label-460316' class=' answer label-58'><span class='answer'>dimensions of behavior that lend themselves to quantification more readily than others.<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460317' \/><div class='watu-question-choice'><input type='radio' name='answer-111389[]' id='answer-id-460317' class='answer answer-58  answerof-111389' value='460317' \/>&nbsp;<label for='answer-id-460317' id='answer-label-460317' class=' answer label-58'><span class='answer'>variables that are overlooked by other social sciences in solving problems.<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460319' \/><div class='watu-question-choice'><input type='radio' name='answer-111389[]' id='answer-id-460319' class='answer answer-58  answerof-111389' value='460319' \/>&nbsp;<label for='answer-id-460319' id='answer-label-460319' class=' answer label-58'><span class='answer'>variables to consider when selecting reinforcers and punishers.<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460321' \/><div class='watu-question-choice'><input type='radio' name='answer-111389[]' id='answer-id-460321' class='answer answer-58  answerof-111389' value='460321' \/>&nbsp;<label for='answer-id-460321' id='answer-label-460321' class=' answer label-58'><span class='answer'>components of treatment packages used in treating the most severe behavior problems.<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType58' value='radio' class=''><\/div><div class='watu-question' id='question-59'><div class='question-content'><p><span class='watu_num'>59. <\/span>Jim&#8217;s teacher has taught him to say, &quot;Hello, how are you?&quot; and when he does this, she delivers praise. Now Jim says this whenever he meets anyone, and some people say, &quot;Fine, how are you?&quot;<br \/>\n<br \/>What is the natural consequence for Jim&#8217;s behavior?<\/p>\n<\/div><input type='hidden' name='question_id[]' value='111391' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460324' \/><div class='watu-question-choice'><input type='radio' name='answer-111391[]' id='answer-id-460324' class='answer answer-59  answerof-111391' value='460324' \/>&nbsp;<label for='answer-id-460324' id='answer-label-460324' class=' answer label-59'><span class='answer'>increased number of friends<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460325' \/><div class='watu-question-choice'><input type='radio' name='answer-111391[]' id='answer-id-460325' class='answer answer-59  answerof-111391' value='460325' \/>&nbsp;<label for='answer-id-460325' id='answer-label-460325' class=' answer label-59'><span class='answer'>continuous reinforcement<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460326' \/><div class='watu-question-choice'><input type='radio' name='answer-111391[]' id='answer-id-460326' class='answer answer-59  answerof-111391' value='460326' \/>&nbsp;<label for='answer-id-460326' id='answer-label-460326' class=' answer label-59'><span class='answer'>improved social repertoire for Jim<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460328' \/><div class='watu-question-choice'><input type='radio' name='answer-111391[]' id='answer-id-460328' class='answer answer-59  answerof-111391' value='460328' \/>&nbsp;<label for='answer-id-460328' id='answer-label-460328' class=' answer label-59'><span class='answer'>the responses of the people he meets<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType59' value='radio' class=''><\/div><div class='watu-question' id='question-60'><div class='question-content'><p><span class='watu_num'>60. <\/span>When shopping with her dad, Sally knocks items off the shelf, especially canned goods. The cans make a loud noise when they hit the floor. Her dad decides to teach her an alternative behavior.<br \/>\n<br \/>What alternative behavior is the BEST choice to teach?<\/p>\n<\/div><input type='hidden' name='question_id[]' value='111393' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460332' \/><div class='watu-question-choice'><input type='radio' name='answer-111393[]' id='answer-id-460332' class='answer answer-60  answerof-111393' value='460332' \/>&nbsp;<label for='answer-id-460332' id='answer-label-460332' class=' answer label-60'><span class='answer'>Sally pushes the shopping cart with both hands.<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460333' \/><div class='watu-question-choice'><input type='radio' name='answer-111393[]' id='answer-id-460333' class='answer answer-60  answerof-111393' value='460333' \/>&nbsp;<label for='answer-id-460333' id='answer-label-460333' class=' answer label-60'><span class='answer'>Sally drops items into the cart when her dad gives them to her.<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460335' \/><div class='watu-question-choice'><input type='radio' name='answer-111393[]' id='answer-id-460335' class='answer answer-60  answerof-111393' value='460335' \/>&nbsp;<label for='answer-id-460335' id='answer-label-460335' class=' answer label-60'><span class='answer'>Sally keeps her hands in her pockets while in the store.<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460337' \/><div class='watu-question-choice'><input type='radio' name='answer-111393[]' id='answer-id-460337' class='answer answer-60  answerof-111393' value='460337' \/>&nbsp;<label for='answer-id-460337' id='answer-label-460337' class=' answer label-60'><span class='answer'>Sally holds dad&#8217;s hand while shopping and gets to let go when quiet.<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType60' value='radio' class=''><\/div><div class='watu-question' id='question-61'><div class='question-content'><p><span class='watu_num'>61. <\/span>When setting criteria for behavior change, behavior analysts attempt to implement the simplest mode of intervention necessary to elicit the desired outcome.<br \/>\n<br \/>As such, the identified outcome criteria should be<\/p>\n<\/div><input type='hidden' name='question_id[]' value='111395' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460340' \/><div class='watu-question-choice'><input type='radio' name='answer-111395[]' id='answer-id-460340' class='answer answer-61  answerof-111395' value='460340' \/>&nbsp;<label for='answer-id-460340' id='answer-label-460340' class=' answer label-61'><span class='answer'>applied to ecological assessments to generalize skills.<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460341' \/><div class='watu-question-choice'><input type='radio' name='answer-111395[]' id='answer-id-460341' class='answer answer-61  answerof-111395' value='460341' \/>&nbsp;<label for='answer-id-460341' id='answer-label-460341' class=' answer label-61'><span class='answer'>developed prior to the identified intervention.<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460343' \/><div class='watu-question-choice'><input type='radio' name='answer-111395[]' id='answer-id-460343' class='answer answer-61  answerof-111395' value='460343' \/>&nbsp;<label for='answer-id-460343' id='answer-label-460343' class=' answer label-61'><span class='answer'>initially broad in focus with subsequent reduction to a target response.<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460345' \/><div class='watu-question-choice'><input type='radio' name='answer-111395[]' id='answer-id-460345' class='answer answer-61  answerof-111395' value='460345' \/>&nbsp;<label for='answer-id-460345' id='answer-label-460345' class=' answer label-61'><span class='answer'>measured independent of practice effects or reactivity.<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType61' value='radio' class=''><\/div><div class='watu-question' id='question-62'><div class='question-content'><p><span class='watu_num'>62. <\/span>Jamie and Morgan have similar behavior challenges and similar daily schedules. A behavior analyst has spent extensive time and effort on developing and implementing Morgan&#8217;s plan, which is proving to be very successful.<br \/>\n<br \/>How should the behavior analyst proceed with developing a treatment plan for Jamie?<\/p>\n<\/div><input type='hidden' name='question_id[]' value='111397' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460348' \/><div class='watu-question-choice'><input type='radio' name='answer-111397[]' id='answer-id-460348' class='answer answer-62  answerof-111397' value='460348' \/>&nbsp;<label for='answer-id-460348' id='answer-label-460348' class=' answer label-62'><span class='answer'>Because the behaviors are topographically similar, implementing the plan designed for Morgan would be appropriate as it is the least restrictive option.<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460349' \/><div class='watu-question-choice'><input type='radio' name='answer-111397[]' id='answer-id-460349' class='answer answer-62  answerof-111397' value='460349' \/>&nbsp;<label for='answer-id-460349' id='answer-label-460349' class=' answer label-62'><span class='answer'>Complete a separate functional assessment and plan for Jamie.<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460351' \/><div class='watu-question-choice'><input type='radio' name='answer-111397[]' id='answer-id-460351' class='answer answer-62  answerof-111397' value='460351' \/>&nbsp;<label for='answer-id-460351' id='answer-label-460351' class=' answer label-62'><span class='answer'>Use the same plan for both, just ensure the ecological variables correspond to the student.<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460353' \/><div class='watu-question-choice'><input type='radio' name='answer-111397[]' id='answer-id-460353' class='answer answer-62  answerof-111397' value='460353' \/>&nbsp;<label for='answer-id-460353' id='answer-label-460353' class=' answer label-62'><span class='answer'>Do a separate functional analysis, but the same behavior supports can be applied to both students.<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType62' value='radio' class=''><\/div><div class='watu-question' id='question-63'><div class='question-content'><p><span class='watu_num'>63. <\/span>The use of a withdrawal design is LEAST appropriate when:<\/p>\n<\/div><input type='hidden' name='question_id[]' value='111399' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460356' \/><div class='watu-question-choice'><input type='radio' name='answer-111399[]' id='answer-id-460356' class='answer answer-63  answerof-111399' value='460356' \/>&nbsp;<label for='answer-id-460356' id='answer-label-460356' class=' answer label-63'><span class='answer'>evaluating an intervention for severe problem behavior.<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460357' \/><div class='watu-question-choice'><input type='radio' name='answer-111399[]' id='answer-id-460357' class='answer answer-63  answerof-111399' value='460357' \/>&nbsp;<label for='answer-id-460357' id='answer-label-460357' class=' answer label-63'><span class='answer'>evaluating the effects of an intervention for behavior that has multiple functions.<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460359' \/><div class='watu-question-choice'><input type='radio' name='answer-111399[]' id='answer-id-460359' class='answer answer-63  answerof-111399' value='460359' \/>&nbsp;<label for='answer-id-460359' id='answer-label-460359' class=' answer label-63'><span class='answer'>extraneous variables cannot be controlled.<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460361' \/><div class='watu-question-choice'><input type='radio' name='answer-111399[]' id='answer-id-460361' class='answer answer-63  answerof-111399' value='460361' \/>&nbsp;<label for='answer-id-460361' id='answer-label-460361' class=' answer label-63'><span class='answer'>multiple participants are being evaluated.<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType63' value='radio' class=''><\/div><div class='watu-question' id='question-64'><div class='question-content'><p><span class='watu_num'>64. <\/span>When using an alternating treatments design it is important to randomly:<\/p>\n<\/div><input type='hidden' name='question_id[]' value='111401' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460364' \/><div class='watu-question-choice'><input type='radio' name='answer-111401[]' id='answer-id-460364' class='answer answer-64  answerof-111401' value='460364' \/>&nbsp;<label for='answer-id-460364' id='answer-label-460364' class=' answer label-64'><span class='answer'>assign participants to treatment conditions.<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460365' \/><div class='watu-question-choice'><input type='radio' name='answer-111401[]' id='answer-id-460365' class='answer answer-64  answerof-111401' value='460365' \/>&nbsp;<label for='answer-id-460365' id='answer-label-460365' class=' answer label-64'><span class='answer'>select participants from the population of interest.<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460367' \/><div class='watu-question-choice'><input type='radio' name='answer-111401[]' id='answer-id-460367' class='answer answer-64  answerof-111401' value='460367' \/>&nbsp;<label for='answer-id-460367' id='answer-label-460367' class=' answer label-64'><span class='answer'>order treatment conditions presented during each phase.<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460369' \/><div class='watu-question-choice'><input type='radio' name='answer-111401[]' id='answer-id-460369' class='answer answer-64  answerof-111401' value='460369' \/>&nbsp;<label for='answer-id-460369' id='answer-label-460369' class=' answer label-64'><span class='answer'>change each criterion level.<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType64' value='radio' class=''><\/div><div class='watu-question' id='question-65'><div class='question-content'><p><span class='watu_num'>65. <\/span>When using a changing criterion design, the BEST demonstration of experimental control would be produced if the:<\/p>\n<\/div><input type='hidden' name='question_id[]' value='111403' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460372' \/><div class='watu-question-choice'><input type='radio' name='answer-111403[]' id='answer-id-460372' class='answer answer-65  answerof-111403' value='460372' \/>&nbsp;<label for='answer-id-460372' id='answer-label-460372' class=' answer label-65'><span class='answer'>criterion level is changed in equal increments.<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460373' \/><div class='watu-question-choice'><input type='radio' name='answer-111403[]' id='answer-id-460373' class='answer answer-65  answerof-111403' value='460373' \/>&nbsp;<label for='answer-id-460373' id='answer-label-460373' class=' answer label-65'><span class='answer'>criterion level is changed slightly on each manipulation.<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460375' \/><div class='watu-question-choice'><input type='radio' name='answer-111403[]' id='answer-id-460375' class='answer answer-65  answerof-111403' value='460375' \/>&nbsp;<label for='answer-id-460375' id='answer-label-460375' class=' answer label-65'><span class='answer'>criterion level is set well above that of the behavior.<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460377' \/><div class='watu-question-choice'><input type='radio' name='answer-111403[]' id='answer-id-460377' class='answer answer-65  answerof-111403' value='460377' \/>&nbsp;<label for='answer-id-460377' id='answer-label-460377' class=' answer label-65'><span class='answer'>behavior changes concurrently with the criterion level.<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType65' value='radio' class=''><\/div><div class='watu-question' id='question-66'><div class='question-content'><p><span class='watu_num'>66. <\/span>The PRIMARY advantage of using a multiple baseline design across subjects is that:<\/p>\n<\/div><input type='hidden' name='question_id[]' value='111405' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460380' \/><div class='watu-question-choice'><input type='radio' name='answer-111405[]' id='answer-id-460380' class='answer answer-66  answerof-111405' value='460380' \/>&nbsp;<label for='answer-id-460380' id='answer-label-460380' class=' answer label-66'><span class='answer'>an intervention may be applied to more than one individual.<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460381' \/><div class='watu-question-choice'><input type='radio' name='answer-111405[]' id='answer-id-460381' class='answer answer-66  answerof-111405' value='460381' \/>&nbsp;<label for='answer-id-460381' id='answer-label-460381' class=' answer label-66'><span class='answer'>experimental control can be demonstrated without a reversal.<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460382' \/><div class='watu-question-choice'><input type='radio' name='answer-111405[]' id='answer-id-460382' class='answer answer-66  answerof-111405' value='460382' \/>&nbsp;<label for='answer-id-460382' id='answer-label-460382' class=' answer label-66'><span class='answer'>it is the most effective method for establishing functional relations.<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460384' \/><div class='watu-question-choice'><input type='radio' name='answer-111405[]' id='answer-id-460384' class='answer answer-66  answerof-111405' value='460384' \/>&nbsp;<label for='answer-id-460384' id='answer-label-460384' class=' answer label-66'><span class='answer'>more individuals benefit from the effects of an intervention.<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType66' value='radio' class=''><\/div><div class='watu-question' id='question-67'><div class='question-content'><p><span class='watu_num'>67. <\/span>Jamie frequently falls to the floor and screams at school. Preliminary behavioral assessment data indicate that his tantrums are maintained by attention and escape from demand situations. Jamie&#8217;s behavior analyst wants to examine precisely how attention and escape conditions affect these behaviors. The behavior analyst does not want to conduct the analysis in Jamie&#8217;s classroom because she would not be able to control for potentially important factors.<br \/>\n<br \/>Relating to this scenario, which statement is TRUE?<\/p>\n<\/div><input type='hidden' name='question_id[]' value='111407' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460388' \/><div class='watu-question-choice'><input type='radio' name='answer-111407[]' id='answer-id-460388' class='answer answer-67  answerof-111407' value='460388' \/>&nbsp;<label for='answer-id-460388' id='answer-label-460388' class=' answer label-67'><span class='answer'>Analyses that involve experimental conditions are almost always conducted in the person&#8217;s natural environment.<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460389' \/><div class='watu-question-choice'><input type='radio' name='answer-111407[]' id='answer-id-460389' class='answer answer-67  answerof-111407' value='460389' \/>&nbsp;<label for='answer-id-460389' id='answer-label-460389' class=' answer label-67'><span class='answer'>The behavior analyst could conduct the analysis in a vacant classroom, but the generality of the findings is an issue to be considered.<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460391' \/><div class='watu-question-choice'><input type='radio' name='answer-111407[]' id='answer-id-460391' class='answer answer-67  answerof-111407' value='460391' \/>&nbsp;<label for='answer-id-460391' id='answer-label-460391' class=' answer label-67'><span class='answer'>The behavior analyst should conduct detailed interviews with the teacher and school staff to determine functional relations.<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460393' \/><div class='watu-question-choice'><input type='radio' name='answer-111407[]' id='answer-id-460393' class='answer answer-67  answerof-111407' value='460393' \/>&nbsp;<label for='answer-id-460393' id='answer-label-460393' class=' answer label-67'><span class='answer'>Only if the analysis is conducted in Jamie&#8217;s classroom can a reasonable hypothesis be generated.<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType67' value='radio' class=''><\/div><div class='watu-question' id='question-68'><div class='question-content'><p><span class='watu_num'>68. <\/span>Carlos participated in a toothbrushing skill acquisition program. When he started the program, he needed physical assistance to perform each step. After two weeks, he met all objectives and was able to complete each step independently. The program involved the use of graduated guidance, praise, and token reinforcement. In the future, the behavior analyst would like to examine which procedures made the program most effective (i.e., guidance, praise, or token reinforcement).<br \/>\n<br \/>To determine this, the behavior analyst could use a<\/p>\n<\/div><input type='hidden' name='question_id[]' value='111409' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460396' \/><div class='watu-question-choice'><input type='radio' name='answer-111409[]' id='answer-id-460396' class='answer answer-68  answerof-111409' value='460396' \/>&nbsp;<label for='answer-id-460396' id='answer-label-460396' class=' answer label-68'><span class='answer'>component analysis.<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460397' \/><div class='watu-question-choice'><input type='radio' name='answer-111409[]' id='answer-id-460397' class='answer answer-68  answerof-111409' value='460397' \/>&nbsp;<label for='answer-id-460397' id='answer-label-460397' class=' answer label-68'><span class='answer'>discriminant analysis.<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460398' \/><div class='watu-question-choice'><input type='radio' name='answer-111409[]' id='answer-id-460398' class='answer answer-68  answerof-111409' value='460398' \/>&nbsp;<label for='answer-id-460398' id='answer-label-460398' class=' answer label-68'><span class='answer'>nonparametric analysis.<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460400' \/><div class='watu-question-choice'><input type='radio' name='answer-111409[]' id='answer-id-460400' class='answer answer-68  answerof-111409' value='460400' \/>&nbsp;<label for='answer-id-460400' id='answer-label-460400' class=' answer label-68'><span class='answer'>parametric analysis.<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType68' value='radio' class=''><\/div><div class='watu-question' id='question-69'><div class='question-content'><p><span class='watu_num'>69. <\/span>The behavior analyst has had good results with an intervention she designed that makes access to video games contingent upon playing with other children. She now wants to compare the effects of differing amounts of video game access time. She should conduct a<\/p>\n<\/div><input type='hidden' name='question_id[]' value='111411' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460404' \/><div class='watu-question-choice'><input type='radio' name='answer-111411[]' id='answer-id-460404' class='answer answer-69  answerof-111411' value='460404' \/>&nbsp;<label for='answer-id-460404' id='answer-label-460404' class=' answer label-69'><span class='answer'>changing criterion study.<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460405' \/><div class='watu-question-choice'><input type='radio' name='answer-111411[]' id='answer-id-460405' class='answer answer-69  answerof-111411' value='460405' \/>&nbsp;<label for='answer-id-460405' id='answer-label-460405' class=' answer label-69'><span class='answer'>nonparametric study.<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460407' \/><div class='watu-question-choice'><input type='radio' name='answer-111411[]' id='answer-id-460407' class='answer answer-69  answerof-111411' value='460407' \/>&nbsp;<label for='answer-id-460407' id='answer-label-460407' class=' answer label-69'><span class='answer'>parametric study.<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460409' \/><div class='watu-question-choice'><input type='radio' name='answer-111411[]' id='answer-id-460409' class='answer answer-69  answerof-111411' value='460409' \/>&nbsp;<label for='answer-id-460409' id='answer-label-460409' class=' answer label-69'><span class='answer'>reversal study.<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType69' value='radio' class=''><\/div><div class='watu-question' id='question-70'><div class='question-content'><p><span class='watu_num'>70. <\/span>Which of the following measures would be the MOST appropriate for reporting head banging during each 5-minute interval of work?<\/p>\n<\/div><input type='hidden' name='question_id[]' value='111413' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460412' \/><div class='watu-question-choice'><input type='radio' name='answer-111413[]' id='answer-id-460412' class='answer answer-70  answerof-111413' value='460412' \/>&nbsp;<label for='answer-id-460412' id='answer-label-460412' class=' answer label-70'><span class='answer'>duration of head banging<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460413' \/><div class='watu-question-choice'><input type='radio' name='answer-111413[]' id='answer-id-460413' class='answer answer-70  answerof-111413' value='460413' \/>&nbsp;<label for='answer-id-460413' id='answer-label-460413' class=' answer label-70'><span class='answer'>latency from a request to the first response<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460415' \/><div class='watu-question-choice'><input type='radio' name='answer-111413[]' id='answer-id-460415' class='answer answer-70  answerof-111413' value='460415' \/>&nbsp;<label for='answer-id-460415' id='answer-label-460415' class=' answer label-70'><span class='answer'>rate of head banging<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460417' \/><div class='watu-question-choice'><input type='radio' name='answer-111413[]' id='answer-id-460417' class='answer answer-70  answerof-111413' value='460417' \/>&nbsp;<label for='answer-id-460417' id='answer-label-460417' class=' answer label-70'><span class='answer'>inter-response time<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType70' value='radio' class=''><\/div><div class='watu-question' id='question-71'><div class='question-content'><p><span class='watu_num'>71. <\/span>A person &quot;getting wet&quot; in the rain is NOT considered an occurrence of behavior because &quot;getting wet&quot;<\/p>\n<\/div><input type='hidden' name='question_id[]' value='111415' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460420' \/><div class='watu-question-choice'><input type='radio' name='answer-111415[]' id='answer-id-460420' class='answer answer-71  answerof-111415' value='460420' \/>&nbsp;<label for='answer-id-460420' id='answer-label-460420' class=' answer label-71'><span class='answer'>does not specify an interaction between an organism and its environment.<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460421' \/><div class='watu-question-choice'><input type='radio' name='answer-111415[]' id='answer-id-460421' class='answer answer-71  answerof-111415' value='460421' \/>&nbsp;<label for='answer-id-460421' id='answer-label-460421' class=' answer label-71'><span class='answer'>can occur under only one, very specific environmental condition.<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460422' \/><div class='watu-question-choice'><input type='radio' name='answer-111415[]' id='answer-id-460422' class='answer answer-71  answerof-111415' value='460422' \/>&nbsp;<label for='answer-id-460422' id='answer-label-460422' class=' answer label-71'><span class='answer'>is a hypothetical construct and cannot therefore meet the criteria for an occurrence of behavior.<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460424' \/><div class='watu-question-choice'><input type='radio' name='answer-111415[]' id='answer-id-460424' class='answer answer-71  answerof-111415' value='460424' \/>&nbsp;<label for='answer-id-460424' id='answer-label-460424' class=' answer label-71'><span class='answer'>does not have social or clinical significance in a science of human behavior.<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType71' value='radio' class=''><\/div><div class='watu-question' id='question-72'><div class='question-content'><p><span class='watu_num'>72. <\/span>The BEST definition for mouthing behavior would be any instance of Luke.<\/p>\n<\/div><input type='hidden' name='question_id[]' value='111417' \/><div class='watu-questions-wrap '><input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460427' \/><div class='watu-question-choice'><input type='radio' name='answer-111417[]' id='answer-id-460427' class='answer answer-72  answerof-111417' value='460427' \/>&nbsp;<label for='answer-id-460427' id='answer-label-460427' class=' answer label-72'><span class='answer'>placing his mouth on any object for at least 5 seconds.<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460429' \/><div class='watu-question-choice'><input type='radio' name='answer-111417[]' id='answer-id-460429' class='answer answer-72  answerof-111417' value='460429' \/>&nbsp;<label for='answer-id-460429' id='answer-label-460429' class=' answer label-72'><span class='answer'>placing his open mouth on a non-nutritive object or placing a non-nutritive object in his mouth.<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460430' \/><div class='watu-question-choice'><input type='radio' name='answer-111417[]' id='answer-id-460430' class='answer answer-72  answerof-111417' value='460430' \/>&nbsp;<label for='answer-id-460430' id='answer-label-460430' class=' answer label-72'><span class='answer'>making contact with his mouth to any non-nutritive object.<\/span><\/label><\/div>\n<input type='hidden' name='answer_ids[]' class='watu-answer-ids' value='460432' \/><div class='watu-question-choice'><input type='radio' name='answer-111417[]' id='answer-id-460432' class='answer answer-72  answerof-111417' value='460432' \/>&nbsp;<label for='answer-id-460432' id='answer-label-460432' class=' answer label-72'><span class='answer'>mouthing a non-nutritive item for 3 or more consecutive instances within a 30 second interval.<\/span><\/label><\/div>\n<\/div><input type='hidden' id='questionType72' value='radio' class=''><\/div><div style='display:none' id='question-73'><br \/><div class='question-content'><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.dumpsbase.com\/freedumps\/wp-content\/plugins\/watu\/loading.gif\" width=\"16\" height=\"16\" alt=\"Loading ...\" title=\"Loading ...\" \/>&nbsp;Loading &#8230;<\/div><\/div><br \/>\n<input type=\"button\" name=\"action\" onclick=\"Watu.submitResult()\" id=\"action-button\" value=\"Submit\"  class=\"watu-submit-button\" \/>\n<input type=\"hidden\" name=\"no_ajax\" value=\"0\"><input type=\"hidden\" name=\"quiz_id\" value=\"1914\" \/>\n<input type=\"hidden\" id=\"watuStartTime\" name=\"start_time\" value=\"2026-07-15 12:27:46\" \/>\n<\/form>\n<\/div>\n<div id=\"watu-loading-result\" style=\"display:none;\">\n\t<p align=\"center\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.dumpsbase.com\/freedumps\/wp-content\/plugins\/watu\/loading.gif\" width=\"16\" height=\"16\" alt=\"Loading\" title=\"Loading\" \/><\/p>\n<\/div>\t\n<script type=\"text\/javascript\">\nvar exam_id=0;\nvar question_ids='';\nvar watuURL='';\njQuery(function($){\nquestion_ids = \"111298,111299,111300,111301,111302,111303,111304,111305,111306,111307,111308,111309,111310,111311,111312,111313,111314,111315,111316,111317,111318,111319,111320,111322,111324,111326,111328,111330,111332,111334,111336,111338,111340,111342,111344,111346,111348,111350,111352,111354,111356,111358,111360,111362,111364,111366,111368,111370,111371,111373,111375,111377,111379,111381,111383,111385,111387,111389,111391,111393,111395,111397,111399,111401,111403,111405,111407,111409,111411,111413,111415,111417\";\nexam_id = 1914;\nWatu.exam_id = exam_id;\nWatu.qArr = question_ids.split(',');\nWatu.post_id = 4544;\nWatu.singlePage = '1';\nWatu.hAppID = \"0.45195300 1784118466\";\nwatuURL = \"https:\/\/www.dumpsbase.com\/freedumps\/wp-admin\/admin-ajax.php\";\nWatu.noAlertUnanswered = 0;\n});\n<\/script>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[503,504],"tags":[7748,7749,7752,7750,7751],"class_list":["post-4544","post","type-post","status-publish","format-standard","hentry","category-bacb","category-bacb-certification","tag-bcba","tag-bcba-dumps","tag-bcba-dumps-questions","tag-bcba-exam-dumps","tag-bcba-exam-questions"],"_links":{"self":[{"href":"https:\/\/www.dumpsbase.com\/freedumps\/wp-json\/wp\/v2\/posts\/4544","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dumpsbase.com\/freedumps\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dumpsbase.com\/freedumps\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.dumpsbase.com\/freedumps\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dumpsbase.com\/freedumps\/wp-json\/wp\/v2\/comments?post=4544"}],"version-history":[{"count":1,"href":"https:\/\/www.dumpsbase.com\/freedumps\/wp-json\/wp\/v2\/posts\/4544\/revisions"}],"predecessor-version":[{"id":4546,"href":"https:\/\/www.dumpsbase.com\/freedumps\/wp-json\/wp\/v2\/posts\/4544\/revisions\/4546"}],"wp:attachment":[{"href":"https:\/\/www.dumpsbase.com\/freedumps\/wp-json\/wp\/v2\/media?parent=4544"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dumpsbase.com\/freedumps\/wp-json\/wp\/v2\/categories?post=4544"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dumpsbase.com\/freedumps\/wp-json\/wp\/v2\/tags?post=4544"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}